{"id":1470959,"date":"2026-02-06T14:03:56","date_gmt":"2026-02-06T22:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/"},"modified":"2026-02-06T14:03:56","modified_gmt":"2026-02-06T22:03:56","slug":"china-prueba-nuclear-secreta-acuerdo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/reno\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","title":{"rendered":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio"},"content":{"rendered":"<p>Estados Unidos acus\u00f3 este viernes a China de llevar a cabo una prueba nuclear secreta en 2020, mientras el Gobierno de Trump solicita un acuerdo de armas nucleares m\u00e1s amplio que incluya tanto a China como a Rusia.<\/p>\n<p>La acusaci\u00f3n se produce un d\u00eda despu\u00e9s de que el \u00faltimo tratado de control de armas nucleares entre Estados Unidos y Rusia expirara, dejando a las mayores potencias nucleares del mundo sin l\u00edmites para sus arsenales por primera vez en d\u00e9cadas.<\/p>\n<p>El presidente Donald Trump y otros altos funcionarios de su Gobierno han dejado claro que ya no respetar\u00e1n las limitaciones del Tratado New START y, en cambio, han argumentado que necesitan un nuevo acuerdo para abordar las amenazas de Mosc\u00fa y Beijing. Adem\u00e1s, el a\u00f1o pasado Trump pidi\u00f3 la reanudaci\u00f3n de las pruebas estadounidenses de armas nucleares.<\/p>\n<p>\u201cHoy puedo revelar que el Gobierno de Estados Unidos sabe que China ha llevado a cabo pruebas explosivas nucleares, incluyendo preparativos para pruebas con rendimientos designados en cientos de toneladas\u201d, dijo el subsecretario de Estado para el Control de Armas y la Seguridad Internacional, Thomas DiNanno, en declaraciones durante una conferencia mundial de Desarme en Viena este viernes.<\/p>\n<p>\u201cChina realiz\u00f3 una de estas pruebas nucleares de producci\u00f3n de rendimiento el 22 de junio de 2020\u201d, a\u00f1adi\u00f3, sin aportar m\u00e1s detalles. Un ex alto funcionario estadounidense dijo a CNN que la informaci\u00f3n sobre la prueba de China en 2020 hab\u00eda sido desclasificada.<\/p>\n<p>DiNanno acus\u00f3 a los militares chinos de intentar \u201cocultar las pruebas confundiendo las explosiones nucleares porque reconoc\u00edan que estas pruebas violan los compromisos de prohibici\u00f3n de pruebas\u201d.<\/p>\n<p>\u201cChina ha utilizado el desacoplamiento \u2014un m\u00e9todo para reducir la eficacia del monitoreo s\u00edsmico\u2014 para ocultar sus actividades al mundo\u201d, dijo. Seg\u00fan los expertos, el desacoplamiento ocurre cuando se excava una gran caverna para disminuir la actividad s\u00edsmica de una explosi\u00f3n nuclear, lo que hace m\u00e1s dif\u00edcil su detecci\u00f3n.<\/p>\n<p>Un alto funcionario de una organizaci\u00f3n que trabaja para supervisar pruebas de armas nucleares en todo el mundo dijo en un comunicado este viernes que su sistema \u201cno detect\u00f3 ning\u00fan evento consistente con las caracter\u00edsticas de una explosi\u00f3n de prueba de arma nuclear\u201d el 22 de junio de 2020.<\/p>\n<p>\u201cAn\u00e1lisis posteriores y m\u00e1s detallados no han alterado esa determinaci\u00f3n\u201d, dijo Rob Floyd, secretario ejecutivo de la Organizaci\u00f3n del Tratado de Prohibici\u00f3n Completa de los Ensayos Nucleares (CTBTO, por sus siglas en ingl\u00e9s).<\/p>\n<p>Floyd dijo que el Sistema Internacional de Vigilancia (IMS, por sus siglas en ingl\u00e9s) de la organizaci\u00f3n \u201ces capaz de detectar explosiones de pruebas nucleares con un rendimiento equivalente a o superior a aproximadamente 500 toneladas de TNT\u201d. Se\u00f1al\u00f3 que hab\u00eda detectado \u201ctodas las seis pruebas realizadas y declaradas por\u201d Corea del Norte.<\/p>\n<p>Un rendimiento inferior a 500 toneladas, que el sistema no podr\u00eda detectar, \u201crepresenta aproximadamente el 3 % del rendimiento de la explosi\u00f3n que devast\u00f3 Hiroshima\u201d, dijo. Floyd se\u00f1al\u00f3 que existen mecanismos previstos por el Tratado de Prohibici\u00f3n Completa de los Ensayos Nucleares (CTBT, por sus siglas en ingl\u00e9s), que proh\u00edbe \u201ccualquier explosi\u00f3n de prueba de arma nuclear o cualquier otra explosi\u00f3n nuclear\u201d. Sin embargo, esos mecanismos solo pueden usarse cuando el tratado entre en vigor.<\/p>\n<p>La mayor\u00eda del mundo se ha adherido y ha ratificado el tratado. Aunque tanto Estados Unidos como China lo firmaron, no lo han ratificado y Rusia retir\u00f3 su ratificaci\u00f3n en 2023. Por tanto, el tratado no puede entrar en vigor.<\/p>\n<p>En el pasado, Estados Unidos y China hab\u00edan declarado que se adhieren a una moratoria sobre las pruebas nucleares, pero el a\u00f1o pasado Trump pidi\u00f3 que se reanuden las pruebas nucleares estadounidenses \u201cen igualdad de condiciones\u201d.<\/p>\n<p>En sus comentarios de este viernes, DiNanno sugiri\u00f3 que las presuntas pruebas chinas motivaron el decreto de Trump. Tambi\u00e9n afirm\u00f3 que \u201cel informe anual de cumplimiento de Estados Unidos ha evaluado previamente que Rusia no ha mantenido su moratoria sobre pruebas al realizar pruebas nucleares supercr\u00edticas\u201d.<\/p>\n<p>Al ser consultado sobre la acusaci\u00f3n de pruebas nucleares secretas, el portavoz de la embajada china en Washington dijo que China \u201csigue una pol\u00edtica de \u2018no primer uso\u2019 de armas nucleares y una estrategia nuclear centrada en la autodefensa, y se adhiere a su moratoria de pruebas nucleares\u201d.<\/p>\n<p>\u201cEstamos preparados para trabajar con todas las partes para defender conjuntamente la autoridad del Tratado de Prohibici\u00f3n Completa de los Ensayos Nucleares y salvaguardar el r\u00e9gimen internacional de desarme y no proliferaci\u00f3n nuclear\u201d, dijo Liu Pengyu.<\/p>\n<p>\u201cEsperamos que Estados Unidos cumpla sinceramente con sus obligaciones bajo el tratado y con su compromiso de moratoria sobre pruebas nucleares, y que tome acciones concretas para defender el r\u00e9gimen internacional de desarme y no proliferaci\u00f3n nuclear, as\u00ed como el equilibrio y la estabilidad estrat\u00e9gica mundial\u201d, dijo a CNN.<\/p>\n<p>En sus declaraciones de este viernes, DiNanno dijo que \u201cel 5 de febrero de 2026 marca, en efecto, el fin de una era: el fin de la contenci\u00f3n unilateral de Estados Unidos\u201d, haciendo referencia al t\u00e9rmino del tratado New START. Aunque no dijo expl\u00edcitamente que Estados Unidos desplegar\u00eda m\u00e1s armas nucleares ahora que ya no est\u00e1 sujeto al acuerdo, indic\u00f3 que era probable.<\/p>\n<p>\u201cCompletaremos nuestros programas de modernizaci\u00f3n nuclear en curso que se iniciaron cuando New START entr\u00f3 en vigor. Estados Unidos tambi\u00e9n mantiene una capacidad nuclear no desplegada que puede ser utilizada para hacer frente al entorno de seguridad emergente, si as\u00ed lo indica el presidente\u201d, dijo.<\/p>\n<p>Estados Unidos \u201cmantendr\u00e1 una disuasi\u00f3n nuclear robusta, cre\u00edble y modernizada para garantizar que nuestra seguridad preserve la paz y la estabilidad, y negociar desde una posici\u00f3n de fuerza\u201d, agreg\u00f3.<\/p>\n<p>\u201cLa pr\u00f3xima era de control de armas puede y debe continuar con un enfoque claro, pero requerir\u00e1 la participaci\u00f3n de m\u00e1s que solo Rusia en la mesa de negociaciones\u201d, dijo DiNanno.<\/p>\n<p>No est\u00e1 claro c\u00f3mo Estados Unidos planea llevar a China a esa mesa de negociaciones. Beijing ha rechazado de manera constante las negociaciones trilaterales sobre control de armas, argumentando que sus arsenales no est\u00e1n a la par de los de Mosc\u00fa y Washington.<\/p>\n<p>Matthew Kroenig, vicepresidente y director senior del Scowcroft Center for Strategy and Security en el Atlantic Council, se\u00f1al\u00f3 que si esa es realmente la preocupaci\u00f3n de China, \u201c\u00bfno deber\u00edan querer el control de armas?\u201d<\/p>\n<p>\u201cSi logran que limitemos nuestras armas, eso deber\u00eda ser mejor para ellos\u201d, argument\u00f3. Afirm\u00f3 que cree que Beijing no quiere negociar porque \u201cquieren una fuerza nuclear de superpotencia\u201d.<\/p>\n<p>\u201cHan invertido mucho en construir esta fuerza. No gastaron todo este dinero ni manipularon todo este metal para simplemente cederlo\u201d, dijo.<\/p>\n<p>Algunos funcionarios estadounidenses creen que la expiraci\u00f3n del New START allana el camino para la expansi\u00f3n del arsenal de Estados Unidos, lo cual podr\u00eda provocar suficiente preocupaci\u00f3n en China como para llevar a la creciente potencia nuclear a la mesa, de acuerdo con un funcionario estadounidense.<\/p>\n<p>Daryl Kimball, director ejecutivo de la Asociaci\u00f3n para el Control de Armas, se\u00f1al\u00f3 que \u201csi hay una verdadera violaci\u00f3n del tratado de prohibici\u00f3n de pruebas, eso es un gran problema, pero simplemente quejarse no resuelve el problema\u201d.<\/p>\n<p>Pidi\u00f3 a Estados Unidos que proponga un \u201cenfoque sensato\u201d, como conversaciones bilaterales sobre el control de armas.<\/p>\n<p>\u201cMientras tanto, no hay raz\u00f3n para que Estados Unidos y Rusia no deban ni puedan seguir respetando los l\u00edmites centrales de New START\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos acus\u00f3 este viernes a China de llevar a cabo una prueba nuclear secreta en 2020, mientras el Gobierno de Trump solicita un acuerdo de armas nucleares m\u00e1s amplio que incluya tanto a China como a Rusia. La acusaci\u00f3n se produce un d\u00eda despu\u00e9s de que el \u00faltimo tratado de control de armas nucleares [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470959","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos acus\u00f3 este viernes a China de llevar a cabo una prueba nuclear secreta en 2020, mientras el Gobierno de Trump solicita un acuerdo de armas nucleares m\u00e1s amplio que incluya tanto a China como a Rusia. La acusaci\u00f3n se produce un d\u00eda despu\u00e9s de que el \u00faltimo tratado de control de armas nucleares [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T22:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio\",\"datePublished\":\"2026-02-06T22:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\"},\"wordCount\":1312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\",\"name\":\"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-06T22:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias","og_description":"Estados Unidos acus\u00f3 este viernes a China de llevar a cabo una prueba nuclear secreta en 2020, mientras el Gobierno de Trump solicita un acuerdo de armas nucleares m\u00e1s amplio que incluya tanto a China como a Rusia. La acusaci\u00f3n se produce un d\u00eda despu\u00e9s de que el \u00faltimo tratado de control de armas nucleares [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-06T22:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio","datePublished":"2026-02-06T22:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/"},"wordCount":1312,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","name":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-06T22:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/reno\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio","url":"http:\/\/noticiasya.com\/reno\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/reno\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-06T22:03:56Z","datePublished":"2026-02-06T22:03:56Z","dateModified":"2026-02-06T22:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\\u00e1s amplio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/06\\\/china-prueba-nuclear-secreta-acuerdo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/reno\\\/2026\\\/02\\\/06\\\/china-prueba-nuclear-secreta-acuerdo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-06T22:03:56Z\",\"datePublished\":\"2026-02-06T22:03:56Z\",\"dateModified\":\"2026-02-06T22:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468391,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/16\/tratado-nuclear-ee-uu-rusia-expirar-trax\/","url_meta":{"origin":1470959,"position":0},"title":"El \u00faltimo pacto nuclear entre EE.UU. y Rusia est\u00e1 por expirar en medio de amenazas de Trump y Putin y pruebas nucleares","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, y el presidente de Rusia, Vladimir Putin, llevan semanas intercambiando amenazas de reanudar las pruebas nucleares, una escalada que se inici\u00f3 con las fanfarronadas de Putin sobre las pruebas del misil de propulsi\u00f3n nuclear Poseid\u00f3n a finales de octubre.D\u00edas despu\u00e9s, Trump declar\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470880,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/05\/aumentan-temores-carrera-armamentista-nuclear-trax\/","url_meta":{"origin":1470959,"position":1},"title":"Aumentan los temores de una carrera armamentista nuclear despu\u00e9s de expirar el tratado entre Estados Unidos y Rusia","author":"","date":"febrero 5, 2026","format":false,"excerpt":"La expiraci\u00f3n este jueves del \u00faltimo tratado nuclear restante entre Estados Unidos y Rusia ha despertado temores de una posible carrera armamentista nuclear, debido a que las dos mayores superpotencias nucleares no tienen limitados sus arsenales por primera vez en d\u00e9cadas.\u201cEl peor de los casos es que la situaci\u00f3n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471507,"url":"https:\/\/noticiasya.com\/reno\/2026\/02\/21\/exclusiva-inteligencia-ee-uu-detonacion-china-arsenal-nuclear-trax\/","url_meta":{"origin":1470959,"position":2},"title":"Exclusivo: inteligencia de EE.UU. vincula detonaci\u00f3n de prueba china con impulso a un arsenal nuclear completamente nuevo","author":"","date":"febrero 21, 2026","format":false,"excerpt":"Las agencias de inteligencia de EE.UU. creen que China est\u00e1 desarrollando una nueva generaci\u00f3n de armas nucleares y ha llevado a cabo al menos una prueba explosiva encubierta en los \u00faltimos a\u00f1os como parte de un impulso m\u00e1s amplio para transformar completamente su arsenal en el m\u00e1s avanzado tecnol\u00f3gicamente del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467953,"url":"https:\/\/noticiasya.com\/reno\/2025\/11\/02\/por-que-armas-nucleares-esta-semana-trax\/","url_meta":{"origin":1470959,"position":3},"title":"\u00bfPor qu\u00e9 se habla tanto de armas nucleares esta semana?","author":"","date":"noviembre 2, 2025","format":false,"excerpt":"Esta fue una gran semana para tener m\u00e1s miedo a las armas nucleares.El presidente de Rusia, Vladimir Putin, anunci\u00f3 la prueba de un nuevo misil con capacidad nuclear.El presidente Donald Trump respondi\u00f3 pidiendo a Estados Unidos que reanudara las pruebas de armas nucleares.Ninguno de los dos pa\u00edses ha probado armas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467887,"url":"https:\/\/noticiasya.com\/reno\/2025\/10\/30\/trump-armas-nucleares-sorpresa-asesores-trax\/","url_meta":{"origin":1470959,"position":4},"title":"Trump dijo que Estados Unidos comenzar\u00eda a probar armas nucleares, tomando por sorpresa incluso a algunos de sus asesores","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Cuando el l\u00edder chino Xi Jinping incluy\u00f3 una referencia a los \u201caltibajos\u201d en su relaci\u00f3n con el presidente Donald Trump en las declaraciones de apertura de su cumbre esta semana, dif\u00edcilmente podr\u00eda haber imaginado el giro que ocurri\u00f3 minutos antes de que comenzaran las conversaciones.Escribiendo desde el Marine One, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470135,"url":"https:\/\/noticiasya.com\/reno\/2026\/01\/15\/record-mundial-pausa-pruebas-nucleares-trax\/","url_meta":{"origin":1470959,"position":5},"title":"R\u00e9cord mundial de paz nuclear: por qu\u00e9 la mayor pausa en ensayos est\u00e1 en grave riesgo","author":"","date":"enero 15, 2026","format":false,"excerpt":"El mundo acaba de alcanzar un hito nuclear hist\u00f3rico. A pesar de la creciente tensi\u00f3n y las amenazas de guerra entre potencias como Rusia y Estados Unidos, el planeta ha logrado su periodo m\u00e1s largo sin detonaciones at\u00f3micas desde el inicio de la era nuclear en 1945. Este r\u00e9cord, marcado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/reno\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/comments?post=1470959"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/posts\/1470959\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/media?parent=1470959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/categories?post=1470959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/reno\/wp-json\/wp\/v2\/tags?post=1470959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}