{"id":1443210,"date":"2024-01-05T16:33:32","date_gmt":"2024-01-06T00:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443210"},"modified":"2024-01-05T16:33:32","modified_gmt":"2024-01-06T00:33:32","slug":"nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","title":{"rendered":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas"},"content":{"rendered":"<p>(CNN) &#8212; Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes.<\/p>\n<p>La demanda, que nombra a 17 compa\u00f1\u00edas de autobuses ch\u00e1rter de Texas, Luisiana, Ohio e Indiana, fue presentada el mi\u00e9rcoles ante la Corte Suprema de Nueva York y busca US$ 708 millones en da\u00f1os para cubrir la atenci\u00f3n brindada a al menos 33.600 solicitantes de asilo que han llegado a la ciudad desde 2022.<\/p>\n<p>CNN se ha comunicado con las oficinas de las 17 compa\u00f1\u00edas de autobuses.<\/p>\n<p>\u00bfPor qu\u00e9 los migrantes haitianos son discriminados en M\u00e9xico? Esto dicen las autoridades y organizaciones<\/p>\n<p>La \u00faltima acci\u00f3n legal del alcalde Adams para frenar el flujo de solicitantes de asilo a la ciudad de Nueva York tiene como objetivo abordar la carga financiera que pesa sobre la ciudad como resultado de la creciente crisis migratoria que est\u00e1 agotando los recursos locales.<\/p>\n<p>La semana pasada, Adams firm\u00f3 un decreto que exige que todos los autobuses ch\u00e1rter que transportan a solicitantes de asilo a la ciudad cumplan con las directrices que regulan cu\u00e1ndo y d\u00f3nde se puede dejar a los inmigrantes, y exige una notificaci\u00f3n escrita previa de su llegada bajo amenaza de confiscaci\u00f3n, multas e incluso c\u00e1rcel. Pero \u201cni un solo autob\u00fas de Texas\u201d hab\u00eda cumplido, dijo el martes la abogada principal de Adams, Lisa Zornberg.<\/p>\n<p>Bajo la direcci\u00f3n del gobernador republicano de Texas, Greg Abbott, el estado ha transportado en autob\u00fas a m\u00e1s de 90.000 inmigrantes a \u201cciudades santuario\u201d dirigidas por funcionarios electos dem\u00f3cratas como Nueva York, Washington, Chicago, Filadelfia, Denver y Los \u00c1ngeles desde abril de 2022, seg\u00fan cifras publicadas por la oficina del gobernador el viernes.<\/p>\n<p>La demanda, presentada por la comisionada de Servicios Sociales de la ciudad de Nueva York, Molly Wasow Park, se\u00f1ala a 17 compa\u00f1\u00edas de autobuses ch\u00e1rter, alegando que actuaron de &#171;mala fe&#187; al transportar intencionalmente &#171;personas a Nueva York con la &#8216;mala intenci\u00f3n&#8217; de trasladar los costos del cuidado\u201d de ellos al estado de Nueva York.<\/p>\n<p>Desde abril de 2022 hasta el 29 de diciembre de 2023, las compa\u00f1\u00edas de autobuses transportaron personas sabiendo que \u201cestaban transportando personas que probablemente buscar\u00edan refugio y servicios de emergencia en la ciudad de Nueva York, y de hecho lo hicieron\u201d, alega la demanda.<\/p>\n<p>Migrantes desaparecidos en Tamaulipas fueron hallados con ayuda de perros y conexi\u00f3n de celulares, dicen autoridades<\/p>\n<p>Abbott desestim\u00f3 la demanda en comentarios que public\u00f3 en el sitio web estatal del gobernador.<\/p>\n<p>&#171;Esta demanda no tiene fundamento y merece ser sancionada&#187;, dijo Abbott en un comunicado en l\u00ednea este jueves en respuesta a la demanda. \u201cEst\u00e1 claro que el alcalde Adams no sabe nada sobre la Cl\u00e1usula de Comercio de la Constituci\u00f3n de Estados Unidos, ni sobre el derecho constitucional a viajar que ha sido reconocido por la Corte Suprema de Estados Unidos\u201d.<\/p>\n<p>\u201cCada migrante transportado en autob\u00fas o en avi\u00f3n a la ciudad de Nueva York lo hizo voluntariamente, despu\u00e9s de haber sido autorizado por la Administraci\u00f3n Biden a permanecer en Estados Unidos\u201d, continu\u00f3. \u201cComo tales, tienen autoridad constitucional para viajar por todo el pa\u00eds, algo en lo que el alcalde Adams est\u00e1 interfiriendo. Si el alcalde persiste en esta demanda, puede ser considerado legalmente responsable por sus violaciones\u201d.<\/p>\n<p>La demanda cita la Secci\u00f3n 149 de la Ley de Servicios Sociales de Nueva York, que dice, cualquier persona \u201cque a sabiendas traiga, o haga traer, a una persona necesitada de fuera del estado a este estado con el fin de convertirla en una carga p\u00fablica\u201d estar\u00e1 obligado a \u201csacar a dicha persona del estado o a sustentarla por su propia cuenta\u201d.<\/p>\n<p>Las compa\u00f1\u00edas de autobuses ch\u00e1rter \u201chan violado la ley estatal al no pagar el costo de cuidar a estos migrantes, y es por eso que estamos demandando para recuperar aproximadamente US$ 700 millones ya gastados para cuidar a los migrantes enviados aqu\u00ed en los \u00faltimos dos a\u00f1os por Texas\u201d, dijo Adams en un comunicado este jueves.<\/p>\n<p>La demanda alega que las compa\u00f1\u00edas de autobuses ch\u00e1rter \u201chan obtenido millones de d\u00f3lares en ingresos de Texas\u201d por ayudar en la implementaci\u00f3n del plan de Abbott para transportar en autob\u00fas a inmigrantes a ciudades santuario para aliviar a sus abrumadas ciudades fronterizas.<\/p>\n<p>Abbott ha dicho que al abordar los solicitantes de asilo eligieron libremente ir a Nueva York, &#171;tras haber firmado una renuncia de consentimiento voluntario, disponible en varios idiomas, en la que acordaban el destino&#187;.<\/p>\n<p>Los l\u00edderes de varios suburbios de Chicago tambi\u00e9n votaron a favor de impedir que los autobuses dejen a los inmigrantes sin previo aviso.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes. La demanda, que nombra a 17 compa\u00f1\u00edas de autobuses ch\u00e1rter de Texas, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443210","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes. La demanda, que nombra a 17 compa\u00f1\u00edas de autobuses ch\u00e1rter de Texas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T00:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas\",\"datePublished\":\"2024-01-06T00:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\"},\"wordCount\":843,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\",\"name\":\"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-06T00:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias","og_description":"(CNN) &#8212; Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes. La demanda, que nombra a 17 compa\u00f1\u00edas de autobuses ch\u00e1rter de Texas, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","og_site_name":"Noticias","article_published_time":"2024-01-06T00:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/"},"author":{"name":"","@id":""},"headline":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas","datePublished":"2024-01-06T00:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/"},"wordCount":843,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","url":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","name":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-06T00:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-06T00:33:32Z","datePublished":"2024-01-06T00:33:32Z","dateModified":"2024-01-06T00:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-06T00:33:32Z\",\"datePublished\":\"2024-01-06T00:33:32Z\",\"dateModified\":\"2024-01-06T00:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443215,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/nueva-york-demanda-a-17-empresas-de-autobuses-por-us-700-millones-por-transportar-a-solicitantes-de-asilo-desde-texas-2\/","url_meta":{"origin":1443210,"position":0},"title":"Nueva York demanda a 17 empresas de autobuses por US$ 700 millones por transportar a solicitantes de asilo desde Texas","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) -- Despu\u00e9s de intentar frenar a los \u201cautobuses rebeldes\u201d de Texas que dejan a miles de inmigrantes en la ciudad, el alcalde de Nueva York, Eric Adams, ha presentado una demanda contra una docena de empresas de autobuses ch\u00e1rter que transportaban inmigrantes.La demanda, que nombra a 17 compa\u00f1\u00edas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442921,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/30\/texas-envia-solicitantes-de-asilo-a-las-principales-ciudades-en-autobus-sin-previo-aviso-estos-alcaldes-quieren-pisar-el-freno\/","url_meta":{"origin":1443210,"position":1},"title":"Texas env\u00eda solicitantes de asilo a las principales ciudades en autob\u00fas sin previo aviso. Estos alcaldes quieren pisar el freno","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN) -- Frustrados por los \u201cautobuses deshonestos\u201d de Texas que dejan a miles de inmigrantes, los alcaldes de Nueva York, Chicago y Denver est\u00e1n tratando de frenar el aumento exigiendo a los operadores de autobuses que coordinen las llegadas bajo la amenaza de confiscaciones, multas e incluso penas de c\u00e1rcel.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455674,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/08\/nueva-york-migrantes-tarjetas-debito-pepagadas-trax\/","url_meta":{"origin":1443210,"position":2},"title":"Nueva York dejar\u00e1 de distribuir tarjetas de d\u00e9bito prepagadas a migrantes","author":"","date":"noviembre 8, 2024","format":false,"excerpt":"(CNN) -- Un programa piloto que distribu\u00eda tarjetas de d\u00e9bito prepagadas a migrantes en la ciudad de Nueva York ser\u00e1 descontinuado en enero, dijeron este jueves funcionarios de la ciudad.El contrato de un a\u00f1o para el programa terminar\u00e1 en enero y no ser\u00e1 renovado, seg\u00fan un comunicado del Ayuntamiento obtenido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443826,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/16\/chicago-se-esfuerza-por-albergar-a-migrantes-en-un-frio-extremo-mientras-el-gobernador-de-texas-se-niega-a-detener-los-envios-de-personas\/","url_meta":{"origin":1443210,"position":3},"title":"Chicago se esfuerza por albergar a migrantes en un fr\u00edo extremo mientras el gobernador de Texas se niega a detener los env\u00edos de personas","author":"","date":"enero 16, 2024","format":false,"excerpt":"(CNN) -- Con la esperanza de detener la llegada de migrantes mientras el tiempo invernal azota a Chicago, el gobernador dem\u00f3crata de Illinois advirti\u00f3 en una carta el viernes a su hom\u00f3logo republicano en Texas que enviar migrantes ahora a \u201cla ciudad de los vientos\u201d podr\u00eda costar vidas, lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468037,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/11\/04\/ideas-politicas-zohran-mamdani-trax\/","url_meta":{"origin":1443210,"position":4},"title":"Un vistazo a las ideas pol\u00edticas de Zohran Mamdani","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Zohran Mamdani, el candidato dem\u00f3crata y favorito en la carrera por la alcald\u00eda de la ciudad de Nueva York, tiene m\u00faltiples propuestas que han generado un inter\u00e9s significativo durante una campa\u00f1a en la que busc\u00f3 que la ciudad sea m\u00e1s asequible.Sus propuestas incluyen un plan para crear el primer programa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442428,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/21\/el-gobernador-de-texas-greg-abbott-inicia-vuelos-de-migrantes-a-chicago\/","url_meta":{"origin":1443210,"position":5},"title":"El gobernador de Texas, Greg Abbott, inicia vuelos de migrantes a Chicago","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"(CNN) -- El gobernador de Texas, Greg Abbott, est\u00e1 subiendo la apuesta en sus esfuerzos por transportar inmigrantes a ciudades santuario, llev\u00e1ndolos en avi\u00f3n a Chicago, dijo a CNN el secretario de prensa del gobernador, Andrew Mahaleris.\"Hasta que el presidente Biden d\u00e9 un paso al frente y haga su trabajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443210"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443210\/revisions"}],"predecessor-version":[{"id":1443227,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443210\/revisions\/1443227"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}