{"id":1443221,"date":"2024-01-05T21:33:32","date_gmt":"2024-01-06T05:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443221"},"modified":"2024-01-05T21:33:32","modified_gmt":"2024-01-06T05:33:32","slug":"fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","title":{"rendered":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Omar Marchant, empresario de televisi\u00f3n y radio, muri\u00f3 en la madrugada de este viernes en la ciudad de Miami y a la edad de 88 a\u00f1os, seg\u00fan confirm\u00f3 la familia en redes sociales y tambi\u00e9n una fuente de CNN en Espa\u00f1ol, cercana a la familia.<\/p>\n<p>Sus inicios profesionales fueron en su Cuba natal. Ya asentado en Miami, comenz\u00f3 a trabajar en la radio y luego en la televisi\u00f3n locales, convirti\u00e9ndose en uno de los grandes creadores de lo que hoy es la estructura televisiva nacional hispana en Estados Unidos.<\/p>\n<p>&#171;Un tipo dichoso&#187;, as\u00ed dijo alguna vez que le gustar\u00eda que lo describieran. Una dicha que conquist\u00f3, en parte, gracias a una notable carrera profesional junto a otras figuras de relieve como Mario Kreutzberger, m\u00e1s conocido como Don Francisco. Y justamente como Don Francisco, Marchant tambi\u00e9n lleg\u00f3 a ponerse frente a las c\u00e1maras para transformarse en animador de programas de variedades.<\/p>\n<p>Cortes\u00eda historiasdelatv.com<\/p>\n<p>Su amistad con el cantante espa\u00f1ol Julio Iglesias le brind\u00f3, seg\u00fan lleg\u00f3 a decir Marchant, satisfacciones profesionales y personales. Y el propio Julio Iglesias admiti\u00f3 haber aprendido mucho del empresario cubano al inicio de su carrera.<\/p>\n<p>Otra celebridad, su compatriota Emilio Estefan, dijo alguna vez que cuando se hablara de televisi\u00f3n en espa\u00f1ol de Miami, se tendr\u00eda que hablar de Marchant. y Estefan no termin\u00f3 all\u00ed su elogio: de hecho, le agradeci\u00f3 el apoyo que recibi\u00f3 de su parte, justo cuando comenzaba su carrera musical con quien luego se convertir\u00eda en su esposa, la cantante Gloria Estefan.<\/p>\n<p>Marchant fue vicepresidente y director de promociones y eventos especiales de Univisi\u00f3n entre 1972 y 1994. Tambi\u00e9n trabaj\u00f3 en la cadena Telemundo. A lo largo de su extensa carrera, con sus incontables proyectos e iniciativas pioneras vinculadas a los medios en espa\u00f1ol en Miami, dej\u00f3 una huella imborrable en la cultura latina en Estados Unidos.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Omar Marchant, empresario de televisi\u00f3n y radio, muri\u00f3 en la madrugada de este viernes en la ciudad de Miami y a la edad de 88 a\u00f1os, seg\u00fan confirm\u00f3 la familia en redes sociales y tambi\u00e9n una fuente de CNN en Espa\u00f1ol, cercana a la familia. Sus inicios profesionales fueron en su Cuba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443221","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Omar Marchant, empresario de televisi\u00f3n y radio, muri\u00f3 en la madrugada de este viernes en la ciudad de Miami y a la edad de 88 a\u00f1os, seg\u00fan confirm\u00f3 la familia en redes sociales y tambi\u00e9n una fuente de CNN en Espa\u00f1ol, cercana a la familia. Sus inicios profesionales fueron en su Cuba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T05:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos\",\"datePublished\":\"2024-01-06T05:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\",\"name\":\"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-06T05:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","og_locale":"es_ES","og_type":"article","og_title":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Omar Marchant, empresario de televisi\u00f3n y radio, muri\u00f3 en la madrugada de este viernes en la ciudad de Miami y a la edad de 88 a\u00f1os, seg\u00fan confirm\u00f3 la familia en redes sociales y tambi\u00e9n una fuente de CNN en Espa\u00f1ol, cercana a la familia. Sus inicios profesionales fueron en su Cuba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","og_site_name":"Noticias","article_published_time":"2024-01-06T05:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/"},"author":{"name":"","@id":""},"headline":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos","datePublished":"2024-01-06T05:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","url":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","name":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-06T05:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-06T05:33:32Z","datePublished":"2024-01-06T05:33:32Z","dateModified":"2024-01-06T05:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fallece Omar Marchant, uno de los pioneros de la televisi\\u00f3n hispana en Estados Unidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-06T05:33:32Z\",\"datePublished\":\"2024-01-06T05:33:32Z\",\"dateModified\":\"2024-01-06T05:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443232,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/06\/fallece-omar-marchant-uno-de-los-pioneros-de-la-television-hispana-en-estados-unidos-2\/","url_meta":{"origin":1443221,"position":0},"title":"Fallece Omar Marchant, uno de los pioneros de la televisi\u00f3n hispana en Estados Unidos","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Omar Marchant, empresario de televisi\u00f3n y radio, muri\u00f3 en la madrugada de este viernes en la ciudad de Miami y a la edad de 88 a\u00f1os, seg\u00fan confirm\u00f3 la familia en redes sociales y tambi\u00e9n una fuente de CNN en Espa\u00f1ol, cercana a la familia.Sus inicios profesionales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455514,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/01\/cnn-en-espanol-ofrecera-una-cobertura-inigualable-integral-y-multiplataforma-durante-las-elecciones-presidenciales-en-estados-unidos\/","url_meta":{"origin":1443221,"position":1},"title":"CNN en Espa\u00f1ol ofrecer\u00e1 una cobertura inigualable, integral y multiplataforma durante las elecciones presidenciales en Estados Unidos","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(Comunicado de prensa) --\u00a0CNN en Espa\u00f1ol prepara una gran cobertura multiplataforma para las elecciones presidenciales en Estados Unidos el pr\u00f3ximo martes 5 de noviembre a partir de las 5 p.m. (hora de Miami).El equipo de presentadores, corresponsales, analistas y comentaristas de la cadena estar\u00e1 donde se produzca la noticia: en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453228,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/30\/opinion-eduardo-suarez-de-la-habana-a-times-square-orix\/","url_meta":{"origin":1443221,"position":2},"title":"OPINION | Eduardo Su\u00e1rez, de La Habana a Times Square","author":"","date":"septiembre 30, 2024","format":false,"excerpt":"Jorge D\u00e1vila Miguel es licenciado en Periodismo desde 1973 y ha mantenido una carrera continuada en su profesi\u00f3n hasta la fecha. Ostenta posgrados en Ciencias de la Informaci\u00f3n Social y Medios de Comunicaci\u00f3n Sociales, as\u00ed como estudios superiores posuniversitarios en Relaciones Internacionales, Econom\u00eda Pol\u00edtica e Historia Latinoamericana. Es de nacionalidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452704,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/15\/mes-herencia-hispana-que-es-comienza-septiembre-trax\/","url_meta":{"origin":1443221,"position":3},"title":"Mes de la Herencia Hispana: \u00bfqu\u00e9 es, por qu\u00e9 es importante y por qu\u00e9 se celebra desde mediados de septiembre?","author":"","date":"septiembre 15, 2024","format":false,"excerpt":"(CNN) -- El Mes Nacional de la Herencia Hispana comienza este 15 de septiembre y se extender\u00e1 hasta el 15 de octubre, dando a Estados Unidos la oportunidad de reconocer y celebrar a los miembros de nuestras comunidades y a sus antepasados que proceden de M\u00e9xico, partes del Caribe, Centroam\u00e9rica,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468466,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/11\/18\/latinos-diversidad-identidad-comunidad-hispana-orix\/","url_meta":{"origin":1443221,"position":4},"title":"M\u00e1s estadounidenses que nunca, m\u00e1s latinos que siempre: la diversidad de la inmensa comunidad hispana en EE.UU.","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"Muy lejos del concepto de \u201cgigante dormido\u201d que le era atribuido, de un bloque monol\u00edtico o una estad\u00edstica fija, la comunidad latina en Estados Unidos es un r\u00edo de historias, idiomas y generaciones que crece con fuerza. Hoy, con el 20 % de la poblaci\u00f3n estadounidense, los latinos moldean el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470868,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/04\/puerto-rico-show-bad-bunny-super-bowl-espanol-trax\/","url_meta":{"origin":1443221,"position":5},"title":"Los puertorrique\u00f1os est\u00e1n entusiasmados por el show de Bad Bunny en el Super Bowl en espa\u00f1ol. No son los \u00fanicos","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Cuando Bad Bunny suba al escenario del Super Bowl este domingo, har\u00e1 historia como el primer artista de habla hispana en encabezar el espect\u00e1culo de medio tiempo.Eso tiene a los puertorrique\u00f1os rebosantes de anticipaci\u00f3n y orgullo.\u201cCreo que es un orgullo, un orgullo enorme, que sea as\u00ed, en nuestro idioma, con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443221"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443221\/revisions"}],"predecessor-version":[{"id":1443236,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443221\/revisions\/1443236"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}