{"id":1443222,"date":"2024-01-05T22:33:36","date_gmt":"2024-01-06T06:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443222"},"modified":"2024-01-05T22:33:36","modified_gmt":"2024-01-06T06:33:36","slug":"que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","title":{"rendered":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 La mayor\u00eda de los jubilados cobra el haber m\u00ednimo en Argentina, alrededor de US$ 123 mensuales, si tomamos como referencia la cotizaci\u00f3n oficial de la moneda estadounidense. Son m\u00e1s de cinco millones de personas, seg\u00fan estimaciones de expertos previsionales.<\/p>\n<p>Pero lo que muchos no saben es que, al mismo tiempo, los jubilados son due\u00f1os de una caja cotizada en cerca de US$ 76.000 millones, seg\u00fan un comunicado difundido en diciembre por las autoridades salientes de la Administraci\u00f3n Nacional de la Seguridad Social (ANSES).<\/p>\n<p>La suma pertenece al Fondo de Garant\u00eda de Sustentabilidad (FGS) que, en el marco de la emergencia previsional decretada por el presidente Javier Milei, podr\u00eda pasar a ser administrado por el Tesoro Nacional, de aprobarse el cap\u00edtulo siete del apartado de reorganizaci\u00f3n econ\u00f3mica del proyecto Ley de Bases y Puntos de Partida para la Libertad de los Argentinos, que el Poder Ejecutivo envi\u00f3 hace unos d\u00edas al Congreso para su abordaje en sesiones extraordinarias.<\/p>\n<p>\u00bfQu\u00e9 es el Fondo de Garant\u00eda de Sustentabilidad (FGS)?<\/p>\n<p>Este fondo financiero fue creado por el presidente N\u00e9stor Kirchner en 2007. Su objetivo es preservar al sistema previsional de las crisis econ\u00f3micas y est\u00e1 compuesto por diferentes instrumentos financieros. Con el fondo no se pagan las jubilaciones y pensiones mes a mes, pero fue creado para ese fin en caso de ser necesario.<\/p>\n<p>La justicia de Argentina suspendi\u00f3 la reforma laboral del presidente Javier Milei, pero el gobierno apel\u00f3 y crecen las dudas sobre su vigencia<\/p>\n<p>Adem\u00e1s, el fondo funcion\u00f3 todo este tiempo para la inversi\u00f3n en proyectos productivos para fomentar el desarrollo de la econom\u00eda nacional, promover la generaci\u00f3n de empleo registrado que fortalezca el sistema y generar rentabilidad.<\/p>\n<p>\u201cLa idea del fondo siempre fue tener recursos para el pago de prestaciones, porque se cre\u00f3 con el dinero que aportaron los jubilados en el sistema de AFJP\u201d, afirma Andrea Falcone, abogada especialista en asuntos previsionales. Aunque aclara que \u201csiempre el fondo fue utilizado para diferentes planes que no estaban necesariamente destinados a los jubilados\u201d.<\/p>\n<p>El doctor Cristian Gonzalez D\u2019Alessandro, experto en temas de seguridad social, reafirma este concepto. \u201cEl fondo nunca se us\u00f3 con el objetivo original\u201d, dice el previsionalista. Recuerda adem\u00e1s que el FGS est\u00e1 compuesto por acciones que el Estado tiene en empresas privadas, entre otros activos.<\/p>\n<p>Javier Milei, presidente de la Argentina.<\/p>\n<p>\u00bfPara qu\u00e9 quiere el gobierno el FGS?<\/p>\n<p>El cap\u00edtulo en cuesti\u00f3n, que es parte del proyecto que debatir\u00e1 el Congreso no hace referencia a ning\u00fan objetivo espec\u00edfico. A\u00fan no ha habido definiciones del Gobierno sobre la necesidad de esta norma. Mientras tanto, los especialistas sostienen diferentes posibilidades.<\/p>\n<p>\u201cLa ley que cre\u00f3 el fondo dice que el \u00fanico destino que puede tener el FGS es evitar la crisis del sistema. Hoy los jubilados est\u00e1n en una crisis humanitaria. Pero evidentemente lo que se pretende es hacer m\u00e1s de lo mismo, pero, con esto de ingresar el FGS al tesoro nacional\u201d, opina Eugenio Semino, defensor de la Tercera Edad.<\/p>\n<p>Por otro lado, la Falcone se refiere al d\u00e9ficit del sistema como variante para la utilizaci\u00f3n del FGS. \u201cSi se compara el ingreso de aportes de trabajadores y empleadores con lo que ANSES paga en jubilaciones y pensiones se tiene un d\u00e9ficit de alrededor del 51%, y eso lo financia el Tesoro, con lo cual creo que est\u00e1n pensando en cubrir el d\u00e9ficit con el dinero del FGS\u201d.<\/p>\n<p>La abogada sostiene adem\u00e1s que, si eso pasa, la ausencia de un fondo antic\u00edclico, caracter\u00edstica esencial del FGS, va a complicar a\u00fan m\u00e1s un sistema que tiene problemas de \u00edndole demogr\u00e1ficas y coyunturales, por la situaci\u00f3n econ\u00f3mica de Argentina.<\/p>\n<p>Subsisten las dudas sobre el destino del FGS. Gonz\u00e1lez D\u2019Alessandro piensa que puede servirle al Gobierno para otro fin.<\/p>\n<p>\u201cEntiendo que se van a licuar los recursos del FGS, se van a usar para pagar deuda, malvender las acciones y que sirva tambi\u00e9n para iniciar el proceso de dolarizaci\u00f3n\u201d. Sostiene adem\u00e1s que el sistema puede perder sustentabilidad y derivar inexorablemente en una privatizaci\u00f3n.<\/p>\n<p>El futuro de este fondo est\u00e1 en manos del Congreso. Una vez que se apruebe la ley, si es que ocurre, el FGS pasar\u00e1 a manos del Tesoro Nacional y se conocer\u00e1 su destino.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 La mayor\u00eda de los jubilados cobra el haber m\u00ednimo en Argentina, alrededor de US$ 123 mensuales, si tomamos como referencia la cotizaci\u00f3n oficial de la moneda estadounidense. Son m\u00e1s de cinco millones de personas, seg\u00fan estimaciones de expertos previsionales. Pero lo que muchos no saben es que, al mismo tiempo, los jubilados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443222","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 La mayor\u00eda de los jubilados cobra el haber m\u00ednimo en Argentina, alrededor de US$ 123 mensuales, si tomamos como referencia la cotizaci\u00f3n oficial de la moneda estadounidense. Son m\u00e1s de cinco millones de personas, seg\u00fan estimaciones de expertos previsionales. Pero lo que muchos no saben es que, al mismo tiempo, los jubilados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T06:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?\",\"datePublished\":\"2024-01-06T06:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\"},\"wordCount\":771,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\",\"name\":\"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-06T06:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 La mayor\u00eda de los jubilados cobra el haber m\u00ednimo en Argentina, alrededor de US$ 123 mensuales, si tomamos como referencia la cotizaci\u00f3n oficial de la moneda estadounidense. Son m\u00e1s de cinco millones de personas, seg\u00fan estimaciones de expertos previsionales. Pero lo que muchos no saben es que, al mismo tiempo, los jubilados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","og_site_name":"Noticias","article_published_time":"2024-01-06T06:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?","datePublished":"2024-01-06T06:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/"},"wordCount":771,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","url":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","name":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-06T06:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-06T06:33:36Z","datePublished":"2024-01-06T06:33:36Z","dateModified":"2024-01-06T06:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 quiere hacer el Gobierno de Milei con los US$ 76.000 millones de los jubilados?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/05\\\/que-quiere-hacer-el-gobierno-de-milei-con-los-us-76-000-millones-de-los-jubilados\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-06T06:33:36Z\",\"datePublished\":\"2024-01-06T06:33:36Z\",\"dateModified\":\"2024-01-06T06:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442827,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/28\/como-afecta-a-las-jubilaciones-el-megaproyecto-de-ley-de-javier-milei-en-argentina\/","url_meta":{"origin":1443222,"position":0},"title":"\u00bfC\u00f3mo afecta a las jubilaciones el megaproyecto de ley de Javier Milei en Argentina?","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013\u00a0 El megaproyecto de ley del gobierno del presidente Javier Milei tiene m\u00e1s de 600 art\u00edculos que implicar\u00edan una profunda reforma del Estado argentino y afectar\u00eda directamente a los jubilados en caso de aprobarse en su versi\u00f3n actual.5 claves del megaproyecto de ley de Javier Milei en ArgentinaEn\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460180,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/20\/ana-valverde-de-jubilados-en-lucha-el-gobierno-nos-tiene-en-la-pobreza\/","url_meta":{"origin":1443222,"position":1},"title":"Ana Valverde, referente de los jubilados: &#171;El Gobierno nos tiene en la pobreza&#187;","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Ana Valverde, integrante de la Uni\u00f3n de Trabajadores Jubilados En Lucha (UTJEL), convers\u00f3 con Nacho Gir\u00f3n en La Ma\u00f1ana de CNN sobre las jubilaciones, las marchas de jubilados, el Gobierno Nacional y los precios.\u201cNos tienen bajo la l\u00ednea de pobreza. La jubilaci\u00f3n no son 349 mil pesos porque a eso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443224,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/05\/argentina-en-venta-la-polemica-tras-el-decreto-de-milei-que-elimina-el-limite-para-que-los-extranjeros-compren-tierras\/","url_meta":{"origin":1443222,"position":2},"title":"\u00bfArgentina en venta? La pol\u00e9mica tras el decreto de Milei que elimina el l\u00edmite para que los extranjeros compren tierras","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El decreto de necesidad y urgencia (DNU) que emiti\u00f3 el presidente de Argentina, Javier Milei, el 21 de diciembre, incluy\u00f3 la derogaci\u00f3n de la llamada Ley de Tierras, que bajo el argumento de la soberan\u00eda nacional establec\u00eda un l\u00edmite a la compra y posesi\u00f3n de tierra por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443253,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/06\/argentina-en-venta-la-polemica-tras-el-decreto-de-milei-que-elimina-el-limite-para-que-los-extranjeros-compren-tierras-2\/","url_meta":{"origin":1443222,"position":3},"title":"\u00bfArgentina en venta? La pol\u00e9mica tras el decreto de Milei que elimina el l\u00edmite para que los extranjeros compren tierras","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El decreto de necesidad y urgencia (DNU) que emiti\u00f3 el presidente de Argentina, Javier Milei, el 21 de diciembre, incluy\u00f3 la derogaci\u00f3n de la llamada Ley de Tierras, que bajo el argumento de la soberan\u00eda nacional establec\u00eda un l\u00edmite a la compra y posesi\u00f3n de tierra por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459933,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/14\/victoria-tolosa-paz-hay-un-aparato-del-estado-dispuesto-a-implementar-violencia-contra-jubilados\/","url_meta":{"origin":1443222,"position":4},"title":"Victoria Tolosa Paz: &#171;Hay un aparato del Estado dispuesto a implementar violencia contra jubilados&#187;","author":"","date":"marzo 14, 2025","format":false,"excerpt":"Victoria Tolosa Paz, diputada nacional de Uni\u00f3n por la Patria, habl\u00f3 este viernes en CNN Radio sobre la represi\u00f3n policial frente al Congreso, la agresi\u00f3n a Pablo Grillo y los dichos de Lilia Lemoine, el reclamo por las jubilaciones, el eventual acuerdo con el FMI y el esc\u00e1ndalo libra.En La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459878,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/13\/protesta-jubilados-violencia-fotografo-herido-orix\/","url_meta":{"origin":1443222,"position":5},"title":"Qu\u00e9 pas\u00f3 en la protesta de jubilados en Argentina que acab\u00f3 con violencia policial y un fotoperiodista gravemente herido","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Las manifestaciones que se llevaron a cabo este mi\u00e9rcoles frente al Congreso de Argentina en reclamo por los recortes a las pensiones de los jubilados terminaron con cientos de detenidos y decenas de heridos.Ya van varias semanas en las que los d\u00edas mi\u00e9rcoles los jubilados se concentran frente al Congreso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443222"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443222\/revisions"}],"predecessor-version":[{"id":1443238,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443222\/revisions\/1443238"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}