{"id":1443280,"date":"2024-01-07T03:33:28","date_gmt":"2024-01-07T11:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443280"},"modified":"2024-01-07T03:33:28","modified_gmt":"2024-01-07T11:33:28","slug":"no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","title":{"rendered":"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0&#171;\u00bfQu\u00e9 define la vida? \u00bfQu\u00e9 significa estar vivo? \u00bfAcaso hemos involucionado tanto como para pensar que estar vivo es un coraz\u00f3n que late y un cuerpo que sigue estando caliente?&#187;; son algunas de las preguntas que hace la ecuatoriana Paola Rold\u00e1n, de 42 a\u00f1os, para quien la vida se ha convertido en una monta\u00f1a rusa y un desaf\u00edo constante.<\/p>\n<p>Rold\u00e1n, quien est\u00e1 casada y es madre de un ni\u00f1o de 5 a\u00f1os, est\u00e1 a la espera de un fallo de la Corte Constitucional que podr\u00eda ser un hito en Ecuador y que tiene que ver con la posibilidad de acceder a la eutanasia, que actualmente no es legal en el pa\u00eds.\u00a0\u00a0En agosto del a\u00f1o pasado, Rold\u00e1n, quien padece esclerosis lateral amiotr\u00f3fica (ELA), emprendi\u00f3 esta lucha legal a la que define \u2013en un texto enviado a CNN\u2013 como &#171;emocionalmente intensa&#187; para lograr una muerte digna.<\/p>\n<p>La eutanasia \u2013seg\u00fan la RAE\u2013 es la &#171;intervenci\u00f3n deliberada para poner fin a la vida de un paciente sin perspectiva de cura&#187;. Mientras que para el Instituto Nacional del C\u00e1ncer de Estados Unidos es la &#171;terminaci\u00f3n intencional de la vida de una persona que padece una enfermedad incurable o dolorosa, a solicitud de la misma&#187;.<\/p>\n<p>La ELA toc\u00f3 r\u00e1pidamente la puerta de Paola<\/p>\n<p>Paola Rold\u00e1n fue diagnosticada en 2020 con ELA luego de haber disfrutado de una vida que ella denomina &#171;intensa, profunda, amplia y colorida&#187;. Actualmente tiene una discapacidad del 95% y depende de una m\u00e1quina de respiraci\u00f3n, asistencia de enfermer\u00eda en casa, cuidados paliativos y una cama hospitalaria, entre otros recursos de ayuda.<\/p>\n<p>La ELA &#171;es un tipo mortal de enfermedad de la neurona motora que se caracteriza por la degeneraci\u00f3n progresiva de las c\u00e9lulas nerviosas de la m\u00e9dula espinal y el cerebro. Es uno de los trastornos m\u00e1s devastadores que afecta la funci\u00f3n de los nervios y los m\u00fasculos&#187;, seg\u00fan lo define el Hospital Johns Hopkins, uno de los m\u00e1s prestigiosos del mundo.<\/p>\n<p>\u00bfQu\u00e9 es la esclerosis lateral amiotr\u00f3fica (ELA)?<\/p>\n<p>&#171;A aquellos que comparten esta espera conmigo, quiero transmitirles un mensaje de solidaridad y esperanza. Este proceso ha sido desafiante, pero nuestra perseverancia refleja el deseo compartido de vivir con dignidad hasta el final&#187;, se\u00f1ala Rold\u00e1n en su respuesta a algunas inquietudes que le hizo CNN y que fueron remitidas por escrito a trav\u00e9s de su equipo.<\/p>\n<p>Paola Rold\u00e1n padece de Esclerosis Lateral Amiotr\u00f3fica y espera obtener acceso a la eutanasia en Ecuador. (Cr\u00e9dito: Cortes\u00eda Paola Rold\u00e1n)<\/p>\n<p>\u00bfQu\u00e9 plantea la demanda de Paola Rold\u00e1n?<\/p>\n<p>Paola Rold\u00e1n present\u00f3 una demanda ante la Corte Constitucional en agosto de 2023 solicitando la inconstitucionalidad del art\u00edculo 144 del C\u00f3digo Integral Penal que tiene relaci\u00f3n con el homicidio simple y donde se blinda la imposibilidad de que una persona pueda decidir sobre la eutanasia.\u00a0&#171;La persona que mate a otra ser\u00e1 sancionada con pena privativa de libertad de 10 a 13 a\u00f1os&#187;, establece la legislaci\u00f3n ecuatoriana.\u00a0La demanda fue admitida en septiembre.<\/p>\n<p>En Ecuador, un pa\u00eds profundamente religioso, Paola Rold\u00e1n ha abierto un amplio debate entre quienes defienden la vida a pesar del dolor de una enfermedad incurable y quienes creen que los pacientes con un diagn\u00f3stico mortal pueden tomar una decisi\u00f3n sobre la continuidad o no de su vida.<\/p>\n<p>\u201cLo que Paola est\u00e1 diciendo es yo quiero decidir, morir bien y no hacerlo en secreto sino abiertamente con mi familia acompa\u00f1ada por un m\u00e9dico, acompa\u00f1ada por la gente que quiero y no temer por las consecuencias que les pueda pasar a ellos porque ella ya no va a estar\u201d, dijo a CNN el jurista Farith Simon, uno de los miembros del equipo legal de Rold\u00e1n.<\/p>\n<p>\u201cLo que vivo es doloroso, solitario y cruel\u201d<\/p>\n<p>El pasado 20 de noviembre, Paola Rold\u00e1n compareci\u00f3 a trav\u00e9s de Zoom desde su cama y tomada de la mano de su esposo, en la audiencia p\u00fablica ante la Corte Constitucional, donde expuso su caso y su deseo de morir debido a su enfermedad. El juez ponente Enrique Herrer\u00eda escuch\u00f3 sus razones.<\/p>\n<p>En la misma audiencia diferentes juristas, miembros de organizaciones m\u00e9dicas y miembros de la sociedad civil presentaron sus argumentos a favor y en contra de la demanda de Paola.<\/p>\n<p>\u201cLo que vivo es doloroso, solitario, y cruel. Sin embargo, no vengo a exponerme para que me tengan l\u00e1stima. Eso ser\u00eda injusto y revictimizante (\u2026) Esta no es la lucha por morir, yo s\u00e9 que estoy muriendo. Es una lucha de c\u00f3mo hacerlo\u201d, insisti\u00f3 Rold\u00e1n a la Corte el d\u00eda de la audiencia.<\/p>\n<p>La Corte Constitucional no tiene un plazo establecido para pronunciarse sobre el caso, aunque Rold\u00e1n y su defensa han reconocido que la Corte muestra sensibilidad frente al tema al haber fijado la audiencia en un plazo relativamente corto.<\/p>\n<p>\u201cSocialmente Paola ya gan\u00f3 buena parte de la batalla. Si bien hay muchas personas que est\u00e1n en contra, son mucho menos que las voces a favor (\u2026) El tema de la autonom\u00eda, de la libertad personal y de que no afecte a nadie m\u00e1s que a ella misma, est\u00e1 muy claro en la sociedad como derecho, se\u00f1al\u00f3 Farith Simon.<\/p>\n<p>Rold\u00e1n respondi\u00f3 a CNN que espera que la Corte act\u00fae con la misma sensibilidad en su dictamen.<\/p>\n<p>\u201cEste proceso ha significado enfrentar mis propios miedos, reflexionar sobre la calidad de vida y confrontar las realidades m\u00e9dicas que me han llevado a tomar esta decisi\u00f3n (\u2026) A lo largo de estos d\u00edas he experimentado una mezcla de esperanza y ansiedad\u201d, asegura Rold\u00e1n.<\/p>\n<p>Posiciones contrarias: \u00bfatentar contra la vida?<\/p>\n<p>Sobre el caso se han presentado ante la Corte argumentos en rechazo a su pedido de legalizaci\u00f3n de la eutanasia. Varias organizaciones e integrantes de la sociedad civil que defendieron la muerte como consecuencia natural de una enfermedad, indicaron que la demanda no cumple con los requisitos legales sobre la defensa a la vida estipulados en la Constituci\u00f3n ecuatoriana\u00a0y consideraron que \u201catentar\u201d contra la vida es tambi\u00e9n hacerlo contra la dignidad que reclama Paola. Insistieron en que la vida no es renunciable y que la muerte no puede considerarse algo indigno.<\/p>\n<p>Paola Rold\u00e1n est\u00e1 convencida de que el debate sobre la eutanasia no es f\u00e1cil, pero cree que es peor no hablarlo o tratarlo. Considera que las opiniones contrarias que se presentaron contra su demanda son respetables pero que su planteamiento tiene que ver con una decisi\u00f3n arraigada en la esfera m\u00e1s \u00edntima de la vida.<\/p>\n<p>\u201cAunque esta realidad nos incomode y con el profundo respeto que tengo hacia las opiniones propias, es momento de debatir y tomar decisiones desde un enfoque t\u00e9cnico, respetando la laicidad del Estado ecuatoriano\u201d, precisa Rold\u00e1n.<\/p>\n<p>Farith Simon sostiene que los argumentos presentados ante la Corte esconden inevitablemente un trasfondo religioso.<\/p>\n<p>\u201cMuchos de esos argumentos se presentaron en formas laicas. Se convirtieron en argumentos laicos. No se us\u00f3 religi\u00f3n como palabra o concepto. Sin embargo, muchos de los argumentos son derivados de las convicciones religiosas y se detecta claramente\u201d, seg\u00fan Simon.<\/p>\n<p>Papa Francisco habla de la eutanasia: \u201cLa muerte no es un derecho, no podemos programarla\u201d<\/p>\n<p>Una lucha contra el tiempo<\/p>\n<p>Paola recibe alimentaci\u00f3n parenteral desde hace dos a\u00f1os a trav\u00e9s de un cat\u00e9ter que conduce los nutrientes a su coraz\u00f3n pues su est\u00f3mago ya no los absorbe. Confiesa que tiene temor de morir atragantada o asfixiada debido a alg\u00fan accidente desencadenado por su enfermedad. Otro de sus miedos, remarca, es no poder volver a hablar.<\/p>\n<p>\u201cMi caso particular es apremiante, dado el avance de la ELA y la posibilidad de que mi capacidad de comunicarme se vea limitada en el corto plazo. El d\u00eda que no pueda expresar mi voluntad o no me permitan decidir cu\u00e1ndo poner fin a mi vida, dejar\u00eda de ejercer mi libertad, perder\u00eda la dignidad. No se puede tener una vida digna sin una muerte digna\u201d, enfatiza Rold\u00e1n a CNN.<\/p>\n<p>Por eso, cree que la Corte Constitucional se encuentra frente a una oportunidad hist\u00f3rica que permita que no solo Paola Rold\u00e1n, sino otras personas que padezcan una situaci\u00f3n igual o peor que la suya puedan decidir sobre su vida en el futuro y aliviar su sufrimiento.<\/p>\n<p>\u201cPaola no se puede mover, pero siente todo. F\u00edsicamente siente todos los dolores. No es que ha perdido la sensibilidad. No solo es sufrimiento psicol\u00f3gico sino sufrimiento f\u00edsico, real\u201d, explic\u00f3 Simon.<\/p>\n<p>El equipo legal de Rold\u00e1n plantea al menos cuatro requisitos para el acceso a la eutanasia: declaraci\u00f3n de consentimiento libre e informado de la persona; padecimiento de intenso sufrimiento f\u00edsico y emocional; diagn\u00f3stico de enfermedad o lesi\u00f3n grave incurable; realizaci\u00f3n de la eutanasia por parte de un profesional.<\/p>\n<p>Una lucha contra el tiempo en la que Paola espera que la muerte no le llegue antes que la decisi\u00f3n de la Corte Constitucional, independientemente de su dictamen.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0&#171;\u00bfQu\u00e9 define la vida? \u00bfQu\u00e9 significa estar vivo? \u00bfAcaso hemos involucionado tanto como para pensar que estar vivo es un coraz\u00f3n que late y un cuerpo que sigue estando caliente?&#187;; son algunas de las preguntas que hace la ecuatoriana Paola Rold\u00e1n, de 42 a\u00f1os, para quien la vida se ha convertido en una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443280","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;No se puede tener una vida digna sin una muerte digna&quot;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;No se puede tener una vida digna sin una muerte digna&quot;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0&#171;\u00bfQu\u00e9 define la vida? \u00bfQu\u00e9 significa estar vivo? \u00bfAcaso hemos involucionado tanto como para pensar que estar vivo es un coraz\u00f3n que late y un cuerpo que sigue estando caliente?&#187;; son algunas de las preguntas que hace la ecuatoriana Paola Rold\u00e1n, de 42 a\u00f1os, para quien la vida se ha convertido en una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-07T11:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador\",\"datePublished\":\"2024-01-07T11:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\"},\"wordCount\":1582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\",\"name\":\"\\\"No se puede tener una vida digna sin una muerte digna\\\": la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-07T11:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"No se puede tener una vida digna sin una muerte digna\": la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","og_locale":"es_ES","og_type":"article","og_title":"\"No se puede tener una vida digna sin una muerte digna\": la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0&#171;\u00bfQu\u00e9 define la vida? \u00bfQu\u00e9 significa estar vivo? \u00bfAcaso hemos involucionado tanto como para pensar que estar vivo es un coraz\u00f3n que late y un cuerpo que sigue estando caliente?&#187;; son algunas de las preguntas que hace la ecuatoriana Paola Rold\u00e1n, de 42 a\u00f1os, para quien la vida se ha convertido en una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","og_site_name":"Noticias","article_published_time":"2024-01-07T11:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/"},"author":{"name":"","@id":""},"headline":"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador","datePublished":"2024-01-07T11:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/"},"wordCount":1582,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","url":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","name":"\"No se puede tener una vida digna sin una muerte digna\": la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-07T11:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-07T11:33:28Z","datePublished":"2024-01-07T11:33:28Z","dateModified":"2024-01-07T11:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\\u00e1n por la legalizaci\\u00f3n de la eutanasia en Ecuador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/07\\\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/07\\\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-07T11:33:28Z\",\"datePublished\":\"2024-01-07T11:33:28Z\",\"dateModified\":\"2024-01-07T11:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443176,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/04\/no-se-puede-tener-una-vida-digna-sin-una-muerte-digna-la-lucha-de-paola-roldan-por-la-legalizacion-de-la-eutanasia-en-ecuador\/","url_meta":{"origin":1443280,"position":0},"title":"&#171;No se puede tener una vida digna sin una muerte digna&#187;: la lucha de Paola Rold\u00e1n por la legalizaci\u00f3n de la eutanasia en Ecuador","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 \"\u00bfQu\u00e9 define la vida? \u00bfQu\u00e9 significa estar vivo? \u00bfAcaso hemos involucionado tanto como para pensar que estar vivo es un coraz\u00f3n que late y un cuerpo que sigue estando caliente?\"; son algunas de las preguntas que hace la ecuatoriana Paola Rold\u00e1n, de 42 a\u00f1os, para quien la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446804,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/11\/paola-roldan-muerte-eutanasia-ecuador-orix\/","url_meta":{"origin":1443280,"position":1},"title":"Muere Paola Rold\u00e1n, la mujer cuya lucha logr\u00f3 la despenalizaci\u00f3n de la eutanasia en Ecuador","author":"","date":"marzo 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Paola Rold\u00e1n, la mujer que luch\u00f3 por la despenalizaci\u00f3n de la eutanasia en Ecuador, falleci\u00f3 este lunes a los 42 a\u00f1os tras padecer una esclerosis lateral amiotr\u00f3fica (ELA) que le diagnosticaron en 2020, confirm\u00f3 su abogado Farith Simon a CNN sin dar m\u00e1s detalles. La enfermedad manten\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445072,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/07\/corte-constitucional-de-ecuador-despenaliza-la-eutanasia-tras-el-reclamo-de-paola-roldan\/","url_meta":{"origin":1443280,"position":2},"title":"Corte Constitucional de Ecuador despenaliza la eutanasia tras el reclamo de Paola Rold\u00e1n","author":"","date":"febrero 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 La Corte Constitucional de Ecuador\u00a0aprob\u00f3 la\u00a0despenalizaci\u00f3n\u00a0de la eutanasia tras una batalla legal de cinco meses emprendida por Paola Rold\u00e1n, una mujer de 42 a\u00f1os quien padece esclerosis lateral amiotr\u00f3fica (ELA).Rold\u00e1n present\u00f3 en agosto de 2023 una demanda de inconstitucionalidad del\u00a0art\u00edculo 144 del C\u00f3digo Integral Penal, que amenazaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446875,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/12\/5-cosas-12-marzo-haiti-bukele-orix\/","url_meta":{"origin":1443280,"position":3},"title":"Las 5 cosas que debes saber este 12 de marzo: Dimite el primer ministro de Hait\u00ed","author":"","date":"marzo 12, 2024","format":false,"excerpt":"Ola de violencia en Rosario, Argentina. Adi\u00f3s a Paola Rold\u00e1n, luchadora por la eutanasia en Ecuador. La princesa Kate se disculpa por haber editado una foto. Esto\u00a0es lo que debes saber para comenzar el d\u00eda.\u00a0Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. Dimite el primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448377,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/04\/22\/murio-ana-estrada-eutanasia-peru-orix\/","url_meta":{"origin":1443280,"position":4},"title":"La peruana Ana Estrada ejerci\u00f3 su derecho a la eutanasia y muri\u00f3 luego de luchar durante a\u00f1os en los tribunales","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Ana Estrada \u201cmuri\u00f3 en sus propios t\u00e9rminos, conforme a su idea de dignidad y en pleno control de su autonom\u00eda hasta el final\u201d, inform\u00f3 su familia en un comunicado este lunes, tras una larga batalla judicial en Per\u00fa.Seg\u00fan el documento, \u201cAna ejerci\u00f3 este domingo su derecho fundamental\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465557,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/08\/16\/eutanasia-uruguay-beatriz-gelos-orix\/","url_meta":{"origin":1443280,"position":5},"title":"Tiene ELA hace m\u00e1s de 15 a\u00f1os. Con el avance de la eutanasia en Uruguay, siente que por fin podr\u00e1 decidir","author":"","date":"agosto 16, 2025","format":false,"excerpt":"A Beatriz Gel\u00f3s le dijeron que no iba a sobrevivir 2010, v\u00edctima de una esclerosis lateral amiotr\u00f3fica (ELA) imposible de detener. Ya por entonces dio indicaciones claras: no quer\u00eda intervenciones m\u00e9dicas que alargaran su vida. Quince a\u00f1os despu\u00e9s, con una calidad de vida cada vez m\u00e1s empobrecida, celebra el avance\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443280"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443280\/revisions"}],"predecessor-version":[{"id":1443296,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443280\/revisions\/1443296"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}