{"id":1443308,"date":"2024-01-07T17:33:28","date_gmt":"2024-01-08T01:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443308"},"modified":"2024-01-07T17:33:28","modified_gmt":"2024-01-08T01:33:28","slug":"milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","title":{"rendered":"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB"},"content":{"rendered":"<p>(CNN) &#8212; Los investigadores federales buscan la pieza que falta del fuselaje de un avi\u00f3n de Alaska Airlines que se desprendi\u00f3, al tiempo que investigan lo que condujo a una terrible experiencia en pleno vuelo que llev\u00f3 a la inmovilizaci\u00f3n de algunos Boeing 737 MAX 9 en todo Estados Unidos y a una serie de cancelaciones de vuelos.<\/p>\n<p>Ning\u00fan pasajero estaba sentado directamente junto a la secci\u00f3n del avi\u00f3n que se desprendi\u00f3, dijo este s\u00e1bado la presidenta de la Junta Nacional de Seguridad en el Transporte (NTSB por sus siglas en ingl\u00e9s), Jennifer Homendy.<\/p>\n<p>Homendy pidi\u00f3 durante una rueda de prensa la ayuda del p\u00fablico para localizar la &#171;puerta tap\u00f3n&#187; o el tap\u00f3n de fuselaje y otros componentes del avi\u00f3n que se desprendieron durante el vuelo.<\/p>\n<p>&#171;Creemos, por los datos del radar, que la puerta est\u00e1 en los alrededores de Barnes Road, cerca de la I-217, en el barrio de Cedar Hills. Si la encuentran, por favor, p\u00f3nganse en contacto con las autoridades locales&#187;, dijo Homendy.<\/p>\n<p>Cedar Hills est\u00e1 a poco m\u00e1s de 11 kil\u00f3metros de Portland.<\/p>\n<p>El agujero del tama\u00f1o de un refrigerador que se abri\u00f3 de repente en el avi\u00f3n que transportaba a 177 personas de Portland (Oreg\u00f3n) a Ontario (California) el viernes sembr\u00f3 el p\u00e1nico en todo el avi\u00f3n mientras la cabina se despresurizaba, las m\u00e1scaras de ox\u00edgeno descend\u00edan y los pasajeros gritaban y se desped\u00edan por SMS. El avi\u00f3n aterriz\u00f3 sin novedad y no se registraron heridos graves, seg\u00fan las autoridades.<\/p>\n<p>&#171;Somos muy, muy afortunados de que esto no haya acabado en algo m\u00e1s tr\u00e1gico&#187;, declar\u00f3 Homendy.<\/p>\n<p>Se desprende una parte de un avi\u00f3n en pleno vuelo de Alaska 1:24<\/p>\n<p>La terrible experiencia oblig\u00f3 a la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA por sus siglas en ingl\u00e9s) a inmovilizar temporalmente algunos Boeing 737 MAX 9 hasta que sean inspeccionados minuciosamente. Boeing se ha enfrentado a una serie de contratiempos en los \u00faltimos a\u00f1os, sobre todo una inmovilizaci\u00f3n en tierra en 2019 en decenas de pa\u00edses tras dos tr\u00e1gicos accidentes.<\/p>\n<p>Alaska Airlines dijo este s\u00e1bado por la noche que las inspecciones de emergencia de su flota de aviones Boeing 737 MAX 9 &#171;tomar\u00e1n m\u00e1s tiempo&#187;, advirtiendo que las interrupciones de vuelos probablemente continuar\u00e1n.<\/p>\n<p>\u00bfQu\u00e9 pas\u00f3 en el vuelo de Alaska Airlines? Lo que sabemos sobre el incidente que dej\u00f3 un hueco en el avi\u00f3n<\/p>\n<p>La aerol\u00ednea dijo que hab\u00eda cancelado 160 vuelos \u2014afectando a unos 23.000 viajeros\u2014 hasta el s\u00e1bado por la tarde, y que podr\u00eda haber m\u00e1s cancelaciones para este domingo.<\/p>\n<p>&#171;Estamos identificando las cancelaciones necesarias para ma\u00f1ana y esperamos que la interrupci\u00f3n dure al menos hasta mediados de semana&#187;, dijo la aerol\u00ednea en el comunicado.<\/p>\n<p>United Airlines tambi\u00e9n dijo que est\u00e1 suspendiendo los servicios en todos sus aviones Boeing 737 MAX 9 y &#171;trabajando con la FAA para aclarar el proceso de inspecci\u00f3n y los requisitos para devolver todos los aviones MAX 9 al servicio&#187;. United dijo que tiene 79 de estos aviones en su flota.<\/p>\n<p>Mientras tanto, los investigadores est\u00e1n empezando a indagar en los registros de mantenimiento del avi\u00f3n de Alaska, entre otros componentes, a medida que investigan el percance.<\/p>\n<p>Los reposacabezas de algunos asientos volaron por los aires<\/p>\n<p>El vuelo 1282 de Alaska Airlines hab\u00eda alcanzado los 16.000 pies tras despegar de Portland cuando se desat\u00f3 el caos. El avi\u00f3n llevaba en el aire solo unos 20 minutos, seg\u00fan FlightAware.<\/p>\n<p>Con un estruendo, el tap\u00f3n del fuselaje -que desde dentro del avi\u00f3n parece el interior t\u00edpico de un avi\u00f3n comercial- vol\u00f3 por los aires, succionando objetos fuera del aparato, seg\u00fan el video y los relatos de los pasajeros.<\/p>\n<p>Algunos aviones tienen una abertura intencionada que puede taparse con un tap\u00f3n o con una puerta de emergencia, dependiendo de la configuraci\u00f3n de asientos ordenada por la aerol\u00ednea.<\/p>\n<p>Milagrosamente, nadie estaba sentado en 26A y 26B, los dos asientos del avi\u00f3n situados justo al lado de la puerta con tap\u00f3n que estall\u00f3, dijo Homendy este s\u00e1bado por la noche.<\/p>\n<p>El respaldo del asiento 26A desapareci\u00f3 por completo, al igual que los reposacabezas de los asientos 25A y 26A, explic\u00f3 Homendy. Tambi\u00e9n hab\u00eda ropa esparcida por la zona.<\/p>\n<p>Lo que tambi\u00e9n evit\u00f3 un desenlace m\u00e1s desastroso fue que ocurri\u00f3 antes de que el avi\u00f3n alcanzara la altitud de crucero, cuando los pasajeros suelen empezar a desabrocharse los cinturones y a pasear, explic\u00f3 Homendy.<\/p>\n<p>Aun as\u00ed, el incidente sembr\u00f3 el p\u00e1nico en el avi\u00f3n.<\/p>\n<p>El pasajero Nick Hoch, de 33 a\u00f1os, describi\u00f3 haber o\u00eddo un &#171;boom&#187; antes de que el avi\u00f3n &#171;se sacudiera&#187;. &#171;Se nos cayeron las m\u00e1scaras de ox\u00edgeno de arriba y nos las pusimos inmediatamente, pero fue una experiencia desorientadora&#187;, dijo Hoch a CNN este s\u00e1bado.<\/p>\n<p>Hoch cont\u00f3 que estaba sentado en el lado izquierdo del avi\u00f3n, unas filas por delante de donde estall\u00f3 el panel y &#171;pas\u00f3 una niebla o nube que como que me dio en la cara&#187;.<\/p>\n<p>Ordenan inspecci\u00f3n de 171 aviones del modelo de avi\u00f3n Boeing implicado en el incidente de la explosi\u00f3n de Alaska Airlines<\/p>\n<p>&#171;Hab\u00eda gente mucho m\u00e1s cerca con la que habl\u00e9 que perdi\u00f3 AirPods de sus orejas&#187;, dijo.<\/p>\n<p>Varios invitados a bordo del avi\u00f3n requirieron atenci\u00f3n m\u00e9dica debido a lesiones, y todos &#171;ya fueron dados de alta m\u00e9dicamente&#187;, dijo Alaska Airlines en el comunicado del s\u00e1bado por la noche.<\/p>\n<p>&#171;Imagino que fue un suceso bastante aterrador&#187;, dijo Homendy. &#171;No solemos hablar de lesiones psicol\u00f3gicas, pero estoy seguro de que eso ocurri\u00f3 aqu\u00ed&#187;.<\/p>\n<p>Alaska Airlines dijo que estaba trabajando con Boeing para entender lo que sucedi\u00f3 en el vuelo 1282.<\/p>\n<p>El Boeing 737 MAX 9 involucrado en el incidente del viernes ha estado en servicio durante unos tres meses y ha volado unas 150 veces desde octubre de 2023, seg\u00fan el sitio de seguimiento de vuelos FlightAware y los registros de la FAA.<\/p>\n<p>Alaska Airlines inform\u00f3 que inspeccion\u00f3 18 de los aviones Boeing 737 MAX 9 de su flota este s\u00e1bado y los devolvi\u00f3 al servicio, pero horas m\u00e1s tarde dio marcha atr\u00e1s y dijo que esos aviones ser\u00edan retirados &#171;hasta que se confirmen con la FAA los detalles sobre posibles trabajos de mantenimiento adicionales&#187;.<\/p>\n<p>\u00daltimos mensajes a los seres queridos<\/p>\n<p>Stephanie King dijo a CNN que estaba en un asiento de pasillo en la fila 12 en el vuelo a su casa en California cuando escuch\u00f3 un fuerte rugido del viento.<\/p>\n<p>&#171;Simplemente supe que algo malo hab\u00eda ocurrido&#187;, dijo a CNN por tel\u00e9fono este s\u00e1bado.<\/p>\n<p>King dijo que los auxiliares de vuelo hicieron anuncios, pero, debido a que el avi\u00f3n estaba abierto, hab\u00eda demasiado ruido para que ella pudiera o\u00edr gran parte de lo que se dec\u00eda.<\/p>\n<p>Una pasajera de Alaska Airlines redact\u00f3 mensajes de texto de despedida para sus seres queridos despu\u00e9s de que una secci\u00f3n del avi\u00f3n explotara en pleno vuelo<\/p>\n<p>Varios pasajeros que se encontraban m\u00e1s cerca del agujero en el avi\u00f3n estaban fren\u00e9ticos y se trasladaron a asientos vac\u00edos lejos del incidente, dijo King a CNN.<\/p>\n<p>&#171;Una de las se\u00f1oras gritaba y lloraba. Estaba inconsolable. No paraba de decir: &#8216;\u00a1Mi hijo! \u00a1Mi hijo! Le arrancaron la camisa'&#187;. dijo King. &#171;Era absolutamente surrealista&#187;.<\/p>\n<p>Temiendo por su seguridad, King sac\u00f3 su tel\u00e9fono para grabar un video y redactar los \u00faltimos mensajes de texto para sus seres queridos.<\/p>\n<p>&#171;Escrib\u00ed algunos mensajes de texto a mi novio y a mi madre para decirles que estaba pasando algo, que ten\u00eda miedo y que les amaba&#187;, dijo.<\/p>\n<p>Aunque le pareci\u00f3 &#171;una eternidad&#187;, el avi\u00f3n aterriz\u00f3 sano y salvo menos de 10 minutos despu\u00e9s del incidente, seg\u00fan King.<\/p>\n<p>&#171;Despu\u00e9s todo se calm\u00f3. Todo el mundo estaba en estado de shock&#8230; Fue espeluznante&#187;, dijo.<\/p>\n<p>Los aviones 737 MAX de Boeing ya hab\u00edan tenido problemas anteriormente<\/p>\n<p>Despu\u00e9s de que la FAA ordenara la inmovilizaci\u00f3n temporal de los aviones Boeing 737 MAX 9 a la luz del incidente de Alaska Airlines, Boeing dijo que la compa\u00f1\u00eda apoyaba la decisi\u00f3n de la FAA.<\/p>\n<p>&#171;La seguridad es nuestra principal prioridad y lamentamos profundamente el impacto que este evento ha tenido en nuestros clientes y sus pasajeros&#187;, dijo Boeing en un comunicado. &#171;Estamos de acuerdo y apoyamos plenamente la decisi\u00f3n de la FAA de exigir inspecciones inmediatas de los aviones 737-9 con la misma configuraci\u00f3n que el avi\u00f3n afectado&#187;.<\/p>\n<p>La reciente inmovilizaci\u00f3n se produce tras una serie de contratiempos para Boeing.<\/p>\n<p>El mes pasado, Boeing pidi\u00f3 a las aerol\u00edneas que inspeccionaran todos sus aviones 737 MAX en busca de un posible perno suelto en el sistema del tim\u00f3n, despu\u00e9s de que una aerol\u00ednea descubriera un posible problema con una pieza clave en dos aviones.<\/p>\n<p>Los problemas de ingenier\u00eda y calidad de Boeing han planteado grandes retos a la empresa. Los accidentes de dos de los aviones 737-8 MAX en los que murieron las 346 personas que iban a bordo llevaron a la paralizaci\u00f3n del avi\u00f3n durante 20 meses.<\/p>\n<p>El Max volvi\u00f3 al aire transportando pasajeros en la mayor\u00eda de los mercados de todo el mundo a partir de finales de diciembre de 2020. Pero se ha encontrado con otros problemas, como en abril, cuando Boeing dijo que hab\u00eda descubierto un problema de fabricaci\u00f3n con algunos aviones 737 MAX despu\u00e9s de que un proveedor utilizara un &#171;proceso de fabricaci\u00f3n no est\u00e1ndar&#187; durante la instalaci\u00f3n de dos accesorios en el fuselaje trasero, aunque Boeing insisti\u00f3 en que el problema no constitu\u00eda un riesgo para la seguridad.<\/p>\n<p>Sara Smart, Jillian Sykes, Sharif Paget, Pete Muntean, Raja Razek, Eva Rothenberg y Tina Burnside de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los investigadores federales buscan la pieza que falta del fuselaje de un avi\u00f3n de Alaska Airlines que se desprendi\u00f3, al tiempo que investigan lo que condujo a una terrible experiencia en pleno vuelo que llev\u00f3 a la inmovilizaci\u00f3n de algunos Boeing 737 MAX 9 en todo Estados Unidos y a una serie de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443308","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Milagrosamente&quot; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Milagrosamente&quot; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los investigadores federales buscan la pieza que falta del fuselaje de un avi\u00f3n de Alaska Airlines que se desprendi\u00f3, al tiempo que investigan lo que condujo a una terrible experiencia en pleno vuelo que llev\u00f3 a la inmovilizaci\u00f3n de algunos Boeing 737 MAX 9 en todo Estados Unidos y a una serie de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T01:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB\",\"datePublished\":\"2024-01-08T01:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\"},\"wordCount\":1704,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\",\"name\":\"\\\"Milagrosamente\\\" no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-08T01:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Milagrosamente\" no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","og_locale":"es_ES","og_type":"article","og_title":"\"Milagrosamente\" no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias","og_description":"(CNN) &#8212; Los investigadores federales buscan la pieza que falta del fuselaje de un avi\u00f3n de Alaska Airlines que se desprendi\u00f3, al tiempo que investigan lo que condujo a una terrible experiencia en pleno vuelo que llev\u00f3 a la inmovilizaci\u00f3n de algunos Boeing 737 MAX 9 en todo Estados Unidos y a una serie de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","og_site_name":"Noticias","article_published_time":"2024-01-08T01:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/"},"author":{"name":"","@id":""},"headline":"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB","datePublished":"2024-01-08T01:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/"},"wordCount":1704,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","url":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","name":"\"Milagrosamente\" no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-08T01:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Milagrosamente&#187; no hab\u00eda nadie sentado justo al lado de la parte del avi\u00f3n de Alaska Airlines que explot\u00f3 en pleno vuelo, dice el presidente de la NTSB","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/07\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-08T01:33:28Z","datePublished":"2024-01-08T01:33:28Z","dateModified":"2024-01-08T01:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Milagrosamente&#187; no hab\\u00eda nadie sentado justo al lado de la parte del avi\\u00f3n de Alaska Airlines que explot\\u00f3 en pleno vuelo, dice el presidente de la NTSB\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/07\\\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/07\\\/milagrosamente-no-habia-nadie-sentado-justo-al-lado-de-la-parte-del-avion-de-alaska-airlines-que-exploto-en-pleno-vuelo-dice-el-presidente-de-la-ntsb\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-08T01:33:28Z\",\"datePublished\":\"2024-01-08T01:33:28Z\",\"dateModified\":\"2024-01-08T01:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443393,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/encuentran-la-pieza-de-avion-de-alaska-airlines-que-se-desprendio-en-pleno-vuelo\/","url_meta":{"origin":1443308,"position":0},"title":"Encuentran la pieza de avi\u00f3n de Alaska Airlines que se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) --\u00a0 Funcionarios federales que examinan la terrible explosi\u00f3n en pleno vuelo de parte del fuselaje de un avi\u00f3n de Alaska Airlines dijeron que encontraron la pieza perdida, un detalle clave en la investigaci\u00f3n de lo que ocurri\u00f3 durante la \"descompresi\u00f3n explosiva\" del avi\u00f3n. Por su parte, United Airlines dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443338,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/encuentran-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo\/","url_meta":{"origin":1443308,"position":1},"title":"Encuentran la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"ext(CNN) -- La parte faltante del avi\u00f3n de Alaska Airlines que vol\u00f3 en pleno vuelo fue encontrada en un patio trasero en Portland, anunci\u00f3 la Junta Nacional de Seguridad en el Transporte.Un maestro de escuela de Portland identificado como Bob contact\u00f3 a la agencia despu\u00e9s de encontrar el tap\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443341,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/encuentran-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo-2\/","url_meta":{"origin":1443308,"position":2},"title":"Encuentran la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"ext(CNN) -- La parte faltante del avi\u00f3n de Alaska Airlines que vol\u00f3 en pleno vuelo fue encontrada en un patio trasero en Portland, anunci\u00f3 la Junta Nacional de Seguridad en el Transporte.Un maestro de escuela de Portland identificado como Bob contact\u00f3 a la agencia despu\u00e9s de encontrar el tap\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443254,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/06\/vuelo-de-alaska-airlines-hace-un-aterrizaje-de-emergencia-luego-de-que-un-tapon-del-fuselaje-aparentemente-reventara-en-el-aire\/","url_meta":{"origin":1443308,"position":3},"title":"Vuelo de Alaska Airlines hace un aterrizaje de emergencia luego de que un tap\u00f3n del fuselaje aparentemente reventara en el aire","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Un vuelo de Alaska Airlines realiz\u00f3 un aterrizaje de emergencia despu\u00e9s de que un tap\u00f3n del fuselaje se desprendiera en pleno vuelo el viernes por la noche, dijo a CNN un pasajero.Alaska Airlines confirm\u00f3 que hubo un incidente en el vuelo 1282 que se dirig\u00eda de Portland, Oregon, a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443334,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/se-encontro-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo\/","url_meta":{"origin":1443308,"position":4},"title":"Se encontr\u00f3 la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) -- La presidenta de la NTSB, Jennifer Homendy, anunci\u00f3 en una conferencia de prensa que se ha encontrado el tap\u00f3n de la puerta del vuelo 1282 de Alaska Airlines.Seg\u00fan Homendy, un residente encontr\u00f3 el tap\u00f3n de la puerta en su patio trasero.Homendy solo dijo que el nombre del residente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443337,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/se-encontro-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo-2\/","url_meta":{"origin":1443308,"position":5},"title":"Se encontr\u00f3 la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) -- La presidenta de la NTSB, Jennifer Homendy, anunci\u00f3 en una conferencia de prensa que se ha encontrado el tap\u00f3n de la puerta del vuelo 1282 de Alaska Airlines.Seg\u00fan Homendy, un residente encontr\u00f3 el tap\u00f3n de la puerta en su patio trasero.Homendy solo dijo que el nombre del residente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443308"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443308\/revisions"}],"predecessor-version":[{"id":1443324,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443308\/revisions\/1443324"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}