{"id":1443390,"date":"2024-01-08T20:33:34","date_gmt":"2024-01-09T04:33:34","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443390"},"modified":"2024-01-08T20:33:34","modified_gmt":"2024-01-09T04:33:34","slug":"el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","title":{"rendered":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco"},"content":{"rendered":"<p>(CNN) &#8212; El papa Francisco calific\u00f3 de &#171;cr\u00edmenes de guerra&#187; los ataques contra civiles durante las guerras, incluidas las de Gaza y Ucrania, y advirti\u00f3 que el mundo se est\u00e1 deslizando hacia un conflicto global.<\/p>\n<p>&#171;No hay conflicto que no acabe de alguna manera golpeando indiscriminadamente a la poblaci\u00f3n civil. Los sucesos de Ucrania y Gaza son una clara prueba de ello&#187;, dijo Francisco a diplom\u00e1ticos acreditados ante la Santa Sede en su discurso sobre el &#171;estado del mundo&#187; pronunciado el lunes en el Vaticano.<\/p>\n<p>&#171;No debemos olvidar que las graves violaciones del derecho internacional humanitario son cr\u00edmenes de guerra, y que no basta con se\u00f1alarlas, sino que tambi\u00e9n hay que prevenirlas&#187;.<\/p>\n<p>La hambruna en Gaza est\u00e1 &#171;a la vuelta de la esquina&#187;, seg\u00fan la ONU<\/p>\n<p>El pont\u00edfice, de 87 a\u00f1os, ha dicho a menudo que se est\u00e1 produciendo una Tercera Guerra Mundial &#171;por partes&#187;. El lunes, sin embargo, dijo que se estaba convirtiendo en un &#171;aut\u00e9ntico conflicto global&#187;, afirmando que las instituciones establecidas tras la Segunda Guerra Mundial con el objetivo de mantener la paz se han debilitado. No nombr\u00f3 estas instituciones, pero el papa ha pedido reformas en las Naciones Unidas y una renovaci\u00f3n de la Uni\u00f3n Europea.<\/p>\n<p>&#171;La situaci\u00f3n actual es tambi\u00e9n el resultado del debilitamiento de las estructuras de la diplomacia multilateral que surgieron tras la Segunda Guerra Mundial&#187;, dijo el papa. &#171;Las organizaciones creadas para fomentar la seguridad, la paz y la cooperaci\u00f3n ya no son capaces de unir a todos sus miembros en torno a una mesa&#187;.<\/p>\n<p>Francisco, que reiter\u00f3 su condena al ataque del 7 de octubre de 2023 contra Israel y al auge del antisemitismo, volvi\u00f3 a pedir un &#171;alto el fuego en todos los frentes&#187; en la guerra entre Israel y Hamas, junto con la liberaci\u00f3n de todos los rehenes retenidos por Hamas en Gaza.<\/p>\n<p>&#171;El actual conflicto en Gaza desestabiliza a\u00fan m\u00e1s una regi\u00f3n fr\u00e1gil y llena de tensiones&#187;, dijo el papa. &#171;Espero que la comunidad internacional persiga con determinaci\u00f3n la soluci\u00f3n de dos Estados, uno israel\u00ed y otro palestino, as\u00ed como un estatuto especial garantizado internacionalmente para la ciudad de Jerusal\u00e9n, para que israel\u00edes y palestinos puedan vivir finalmente en paz y seguridad&#187;.<\/p>\n<p>El papa tambi\u00e9n expres\u00f3 su preocupaci\u00f3n por la &#171;situaci\u00f3n social y econ\u00f3mica&#187; en L\u00edbano, junto con la esperanza de que el pa\u00eds pueda elegir pronto un nuevo presidente.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El papa Francisco calific\u00f3 de &#171;cr\u00edmenes de guerra&#187; los ataques contra civiles durante las guerras, incluidas las de Gaza y Ucrania, y advirti\u00f3 que el mundo se est\u00e1 deslizando hacia un conflicto global. &#171;No hay conflicto que no acabe de alguna manera golpeando indiscriminadamente a la poblaci\u00f3n civil. Los sucesos de Ucrania y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443390","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El papa Francisco calific\u00f3 de &#171;cr\u00edmenes de guerra&#187; los ataques contra civiles durante las guerras, incluidas las de Gaza y Ucrania, y advirti\u00f3 que el mundo se est\u00e1 deslizando hacia un conflicto global. &#171;No hay conflicto que no acabe de alguna manera golpeando indiscriminadamente a la poblaci\u00f3n civil. Los sucesos de Ucrania y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-09T04:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El mundo se desliza hacia un conflicto global, advierte el papa Francisco\",\"datePublished\":\"2024-01-09T04:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\",\"name\":\"El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-09T04:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mundo se desliza hacia un conflicto global, advierte el papa Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","og_locale":"es_ES","og_type":"article","og_title":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias","og_description":"(CNN) &#8212; El papa Francisco calific\u00f3 de &#171;cr\u00edmenes de guerra&#187; los ataques contra civiles durante las guerras, incluidas las de Gaza y Ucrania, y advirti\u00f3 que el mundo se est\u00e1 deslizando hacia un conflicto global. &#171;No hay conflicto que no acabe de alguna manera golpeando indiscriminadamente a la poblaci\u00f3n civil. Los sucesos de Ucrania y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","og_site_name":"Noticias","article_published_time":"2024-01-09T04:33:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/"},"author":{"name":"","@id":""},"headline":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco","datePublished":"2024-01-09T04:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","url":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","name":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-09T04:33:34+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El mundo se desliza hacia un conflicto global, advierte el papa Francisco","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/08\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-09T04:33:34Z","datePublished":"2024-01-09T04:33:34Z","dateModified":"2024-01-09T04:33:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El mundo se desliza hacia un conflicto global, advierte el papa Francisco\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/08\\\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/08\\\/el-mundo-se-desliza-hacia-un-conflicto-global-advierte-el-papa-francisco\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-09T04:33:34Z\",\"datePublished\":\"2024-01-09T04:33:34Z\",\"dateModified\":\"2024-01-09T04:33:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456949,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/25\/papa-francisco-navidad-ucrania-gaza-trax\/","url_meta":{"origin":1443390,"position":0},"title":"El papa Francisco pide una &#171;paz duradera&#187; en Ucrania en su mensaje de Navidad","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"El papa Francisco llam\u00f3 a una \u201cnegociaci\u00f3n\u201d para poner fin a la guerra en Ucrania en un mensaje del d\u00eda de Navidad en el que apel\u00f3 a deponer las armas en los conflictos mundiales y a la reconciliaci\u00f3n entre enemigos.Las declaraciones del pont\u00edfice, de 88 a\u00f1os, se produjeron horas despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461979,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/05\/05\/papamovil-papa-francisco-clinica-salud-ninos-gaza-trax\/","url_meta":{"origin":1443390,"position":1},"title":"El papam\u00f3vil del papa Francisco se convertir\u00e1 en una cl\u00ednica de salud para ni\u00f1os de Gaza","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Uno de los \u201cpapam\u00f3viles\u201d del papa Francisco ser\u00e1 transformado en una unidad sanitaria m\u00f3vil para ni\u00f1os y enviado a Gaza, inform\u00f3 este domingo el medio de comunicaci\u00f3n oficial del Vaticano.En uno de sus \u00faltimos deseos antes de su muerte, Francisco confi\u00f3 el papam\u00f3vil utilizado durante su peregrinaci\u00f3n a las Tierras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444106,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/19\/ucrania-esta-presionando-a-china-para-que-ayude-a-poner-fin-a-la-guerra-pero-los-planes-de-paz-de-beijing-estan-enfocados-en-otro-lado\/","url_meta":{"origin":1443390,"position":2},"title":"Ucrania est\u00e1 presionando a China para que ayude a poner fin a la guerra. Pero los planes de paz de Beijing est\u00e1n enfocados en otro lado","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- Mientras Ucrania lucha por mantener el apoyo internacional frente a la invasi\u00f3n rusa que llega a su tercer a\u00f1o, su l\u00edder ha dejado claro un pa\u00eds que le gustar\u00eda que se uniera a su impulso por la paz: China.Aumentar la presi\u00f3n sobre Beijing, el aliado pol\u00edtico m\u00e1s poderoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444108,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/19\/ucrania-esta-presionando-a-china-para-que-ayude-a-poner-fin-a-la-guerra-pero-los-planes-de-paz-de-beijing-estan-enfocados-en-otro-lado-2\/","url_meta":{"origin":1443390,"position":3},"title":"Ucrania est\u00e1 presionando a China para que ayude a poner fin a la guerra. Pero los planes de paz de Beijing est\u00e1n enfocados en otro lado","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- Mientras Ucrania lucha por mantener el apoyo internacional frente a la invasi\u00f3n rusa que llega a su tercer a\u00f1o, su l\u00edder ha dejado claro un pa\u00eds que le gustar\u00eda que se uniera a su impulso por la paz: China.Aumentar la presi\u00f3n sobre Beijing, el aliado pol\u00edtico m\u00e1s poderoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452655,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/13\/papa-francisco-advierte-venezuela-dictadura-no-sirve-trax\/","url_meta":{"origin":1443390,"position":4},"title":"El papa Francisco advierte a Venezuela que &#171;una dictadura no sirve a nadie y termina mal&#187;","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN) --\u00a0El papa Francisco llam\u00f3 este viernes en una conferencia de prensa al Gobierno del presidente Nicol\u00e1s Maduro en Venezuela a trabajar por la paz, advirtiendo que \"una dictadura no sirve a nadie y termina mal\".Maduro reclam\u00f3 un tercer mandato en el cargo despu\u00e9s de unas controvertidas elecciones el 28\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466710,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/23\/analisis-2026-naciones-unidas-asamblea-trax\/","url_meta":{"origin":1443390,"position":5},"title":"Por qu\u00e9 2026 podr\u00eda ser uno de los a\u00f1os m\u00e1s cruciales de una generaci\u00f3n","author":"","date":"septiembre 23, 2025","format":false,"excerpt":"Mientras los l\u00edderes mundiales se re\u00fanen esta semana en Nueva York para la Asamblea General de las Naciones Unidas (AGNU), su atenci\u00f3n se centrar\u00e1 en las crisis inmediatas, incluidas Gaza y Ucrania, y ambos conflictos se prev\u00e9n que se prolonguen durante el resto de este a\u00f1o y hasta 2026.He participado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443390"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443390\/revisions"}],"predecessor-version":[{"id":1443405,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443390\/revisions\/1443405"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}