{"id":1443418,"date":"2024-01-09T10:33:47","date_gmt":"2024-01-09T18:33:47","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443418"},"modified":"2024-01-09T10:33:47","modified_gmt":"2024-01-09T18:33:47","slug":"guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","title":{"rendered":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s"},"content":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed<\/p>\n<p>(Cr\u00e9dito:Anadolu\/ Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed (Cr\u00e9dito:Anadolu\/ Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443418","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed (Cr\u00e9dito:Anadolu\/ Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-09T18:33:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s\",\"datePublished\":\"2024-01-09T18:33:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\"},\"wordCount\":47,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\",\"name\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-09T18:33:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","og_description":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed (Cr\u00e9dito:Anadolu\/ Getty Images) The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","og_url":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","og_site_name":"Noticias","article_published_time":"2024-01-09T18:33:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/"},"author":{"name":"","@id":""},"headline":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","datePublished":"2024-01-09T18:33:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/"},"wordCount":47,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","url":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","name":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-09T18:33:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/09\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-09T18:33:47Z","datePublished":"2024-01-09T18:33:47Z","dateModified":"2024-01-09T18:33:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\\u00f3n de los civiles y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/09\\\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/09\\\/guerra-entre-israel-y-hamas-en-vivo-combates-en-gaza-situacion-de-los-civiles-y-mas-35\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-09T18:33:47Z\",\"datePublished\":\"2024-01-09T18:33:47Z\",\"dateModified\":\"2024-01-09T18:33:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456499,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/11\/mas-buscado-google-2024-eurocopa-trump-payne-orix\/","url_meta":{"origin":1443418,"position":0},"title":"Lo m\u00e1s buscado en Google en 2024: Copa Am\u00e9rica, Eurocopa, Trump y Liam Payne dominaron las tendencias globales","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Importantes torneos deportivos, eventos pol\u00edticos decisivos y fen\u00f3menos naturales dominaron las b\u00fasquedas en Google a lo largo de 2024. La compa\u00f1\u00eda tecnol\u00f3gica public\u00f3 este mi\u00e9rcoles su tradicional informe \u201cEl a\u00f1o en b\u00fasquedas\u201d, que ofrece una radiograf\u00eda de las tendencias y preocupaciones que las personas de todo el mundo consultaron en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1409563,"url":"https:\/\/noticiasya.com\/sacramento\/2022\/07\/03\/sabes-cual-es-la-tecnica-perfecta-para-depilar-tus-cejas\/","url_meta":{"origin":1443418,"position":1},"title":"\u00bfSabes cu\u00e1l es la t\u00e9cnica perfecta para depilar tus cejas?","author":"agomez","date":"julio 3, 2022","format":false,"excerpt":"En la actualidad han ganado protagonismo y se dedica mucho m\u00e1s mucho tiempo a dise\u00f1arlas, cuidarlas y maquillarlas para que est\u00e9n perfectas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442641,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/25\/guerra-entre-israel-y-hamas-en-vivo-muertes-y-ataques-en-gaza-noticias-y-mas-2\/","url_meta":{"origin":1443418,"position":2},"title":"Guerra entre Israel y Hamas en vivo: muertes y ataques en Gaza, noticias y m\u00e1s","author":"agomez","date":"diciembre 25, 2023","format":false,"excerpt":"\ud83d\udd04Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed(Cr\u00e9dito: Ahmad Hasaballah\/Getty Images)The-CNN-Wire\u2122 & \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455095,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/14\/guerra-israel-y-hezbollah-en-vivo-situacion-en-gaza-y-mas-trax\/","url_meta":{"origin":1443418,"position":3},"title":"\u00daltima hora de la Guerra entre Israel y Hezbollah en vivo: situaci\u00f3n en Gaza, noticias y m\u00e1s","author":"","date":"octubre 14, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesThe-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445042,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/07\/guerra-entre-israel-y-hamas-en-vivo-noticias-ataques-represalia-de-ee-uu-en-iraq-y-siria-tension-en-medio-oriente-y-mas-7\/","url_meta":{"origin":1443418,"position":4},"title":"Guerra entre Israel y Hamas en vivo: noticias, ataques represalia de EE.UU. en Iraq y Siria, tensi\u00f3n en Medio Oriente y m\u00e1s","author":"","date":"febrero 7, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edLos palestinos han estado viviendo en tiendas de campa\u00f1a improvisadas en Rafah, mientras una campa\u00f1a terrestre de las FDI se acerca a la ciudad m\u00e1s meridional de Gaza. (Cr\u00e9dito: Abed Zagout\/Anadolu v\u00eda Getty Images)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445044,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/07\/guerra-entre-israel-y-hamas-en-vivo-noticias-ataques-represalia-de-ee-uu-en-iraq-y-siria-tension-en-medio-oriente-y-mas-8\/","url_meta":{"origin":1443418,"position":5},"title":"Guerra entre Israel y Hamas en vivo: noticias, ataques represalia de EE.UU. en Iraq y Siria, tensi\u00f3n en Medio Oriente y m\u00e1s","author":"","date":"febrero 7, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edLos palestinos han estado viviendo en tiendas de campa\u00f1a improvisadas en Rafah, mientras una campa\u00f1a terrestre de las FDI se acerca a la ciudad m\u00e1s meridional de Gaza. (Cr\u00e9dito: Abed Zagout\/Anadolu v\u00eda Getty Images)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443418"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443418\/revisions"}],"predecessor-version":[{"id":1443439,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443418\/revisions\/1443439"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}