{"id":1443674,"date":"2024-01-14T06:33:32","date_gmt":"2024-01-14T14:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443674"},"modified":"2024-01-14T06:33:32","modified_gmt":"2024-01-14T14:33:32","slug":"se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","title":{"rendered":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas"},"content":{"rendered":"<p>(CNN) &#8212; El Comisionado Nacional de Polic\u00eda de Islandia orden\u00f3 a los residentes del pueblo pesquero de Grindav\u00edk, evacuado por primera vez en noviembre , que evacuen nuevamente el lunes por la noche despu\u00e9s de que se abrieran fisuras volc\u00e1nicas en las carreteras de la zona.<\/p>\n<p>Grindav\u00edk, a unos 70 kil\u00f3metros\u00a0 al suroeste de la capital de Islandia, Reykjav\u00edk, en la pen\u00ednsula de Reykjanes, fue evacuada previamente luego de semanas de actividad s\u00edsmica que culmin\u00f3 en una dram\u00e1tica erupci\u00f3n volc\u00e1nica que expuls\u00f3 r\u00e1fagas de lava y envi\u00f3 enormes columnas de humo al cielo.<\/p>\n<p>La ciudad tambi\u00e9n alberga la famosa Laguna Azul de Islandia , que atrae a los turistas por sus humeantes aguas geotermales y es una de las atracciones m\u00e1s visitadas del pa\u00eds.<\/p>\n<p>&#171;Se puede suponer que la orden estar\u00e1 en vigor durante las pr\u00f3ximas tres semanas&#187;, dijo la Agencia de Protecci\u00f3n Civil del pa\u00eds en un comunicado el s\u00e1bado, a\u00f1adiendo que las \u00fanicas excepciones a la orden ser\u00edan para las autoridades para realizar asuntos oficiales o para los residentes &#171;. por per\u00edodos cortos mientras rescatamos objetos de valor\u201d.<\/p>\n<p>La \u00faltima orden de evacuaci\u00f3n se produce despu\u00e9s de que la Oficina Meteorol\u00f3gica de Islandia informara el viernes que los peligros asociados con las fisuras volc\u00e1nicas se consideraban de mayor riesgo que en su evaluaci\u00f3n anterior.<\/p>\n<p>&#171;Seg\u00fan la evaluaci\u00f3n de peligros del Departamento de Protecci\u00f3n Civil emitida el 12 de enero, no se considera justificable seguir viviendo en Grindav\u00edk, a la luz de consideraciones de seguridad p\u00fablica&#187;, dijo la agencia gubernamental.<\/p>\n<p>La cantidad de magma hab\u00eda alcanzado un nivel similar al de la erupci\u00f3n anterior en diciembre, dijo la agencia. Pero en el caso de la \u00faltima erupci\u00f3n, el magma podr\u00eda \u201cmigrar m\u00e1s al sur\u201d \u2013en comparaci\u00f3n con la erupci\u00f3n anterior\u2013 y posiblemente llegar a la ciudad de Grindav\u00edk.<\/p>\n<p>Se cree que la erupci\u00f3n de diciembre fue la mayor hasta ahora, seg\u00fan las autoridades.<\/p>\n<p>En noviembre se declar\u00f3 el estado de emergencia.<\/p>\n<p>Los volcanes de Islandia<\/p>\n<p>Islandia alberga 32 volcanes activos y se asienta sobre el l\u00edmite de una placa tect\u00f3nica que se divide continuamente, alejando a Am\u00e9rica del Norte y Eurasia a lo largo de la l\u00ednea de la Cordillera del Atl\u00e1ntico Medio.<\/p>\n<p>Como tal, el pa\u00eds est\u00e1 acostumbrado a las erupciones volc\u00e1nicas, aunque a menudo ocurren en zonas salvajes, lejos de zonas pobladas.<\/p>\n<p>El sistema volc\u00e1nico B\u00e1r\u00f0arbunga en el centro del pa\u00eds entr\u00f3 en erupci\u00f3n en 2014, produciendo lava que cubri\u00f3 84 kil\u00f3metros cuadrados (32 millas cuadradas) de tierras altas pero no da\u00f1\u00f3 a ninguna comunidad.<\/p>\n<p>Los expertos no esperan que la \u00faltima serie de erupciones cause el mismo nivel de caos que el observado en 2010, cuando el volc\u00e1n Eyjafjallaj\u00f6kull entr\u00f3 en erupci\u00f3n, ya que es poco probable que se trate de hielo glacial que provoc\u00f3 una enorme nube de cenizas.<\/p>\n<p>Unos 100.000 vuelos fueron cancelados, lo que afect\u00f3 a 2 millones de personas, como consecuencia de las cenizas arrojadas por la erupci\u00f3n de 2010, que amenazaba con calar los motores de los aviones y provocar fallos el\u00e9ctricos.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El Comisionado Nacional de Polic\u00eda de Islandia orden\u00f3 a los residentes del pueblo pesquero de Grindav\u00edk, evacuado por primera vez en noviembre , que evacuen nuevamente el lunes por la noche despu\u00e9s de que se abrieran fisuras volc\u00e1nicas en las carreteras de la zona. Grindav\u00edk, a unos 70 kil\u00f3metros\u00a0 al suroeste de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443674","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El Comisionado Nacional de Polic\u00eda de Islandia orden\u00f3 a los residentes del pueblo pesquero de Grindav\u00edk, evacuado por primera vez en noviembre , que evacuen nuevamente el lunes por la noche despu\u00e9s de que se abrieran fisuras volc\u00e1nicas en las carreteras de la zona. Grindav\u00edk, a unos 70 kil\u00f3metros\u00a0 al suroeste de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-14T14:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas\",\"datePublished\":\"2024-01-14T14:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\"},\"wordCount\":586,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\",\"name\":\"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-14T14:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","og_locale":"es_ES","og_type":"article","og_title":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias","og_description":"(CNN) &#8212; El Comisionado Nacional de Polic\u00eda de Islandia orden\u00f3 a los residentes del pueblo pesquero de Grindav\u00edk, evacuado por primera vez en noviembre , que evacuen nuevamente el lunes por la noche despu\u00e9s de que se abrieran fisuras volc\u00e1nicas en las carreteras de la zona. Grindav\u00edk, a unos 70 kil\u00f3metros\u00a0 al suroeste de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","og_site_name":"Noticias","article_published_time":"2024-01-14T14:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/"},"author":{"name":"","@id":""},"headline":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas","datePublished":"2024-01-14T14:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/"},"wordCount":586,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","name":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-14T14:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se ordena evacuar nuevamente a una ciudad de Islandia despu\u00e9s de que se abrieran nuevas fisuras volc\u00e1nicas en las cercan\u00edas","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-14T14:33:32Z","datePublished":"2024-01-14T14:33:32Z","dateModified":"2024-01-14T14:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se ordena evacuar nuevamente a una ciudad de Islandia despu\\u00e9s de que se abrieran nuevas fisuras volc\\u00e1nicas en las cercan\\u00edas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/14\\\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/14\\\/se-ordena-evacuar-nuevamente-a-una-ciudad-de-islandia-despues-de-que-se-abrieran-nuevas-fisuras-volcanicas-en-las-cercanias\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-14T14:33:32Z\",\"datePublished\":\"2024-01-14T14:33:32Z\",\"dateModified\":\"2024-01-14T14:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443685,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/un-volcan-en-islandia-entra-en-erupcion-cuando-se-ordena-evacuar-nuevamente-a-un-pueblo-pesquero\/","url_meta":{"origin":1443674,"position":0},"title":"Un volcan en Islandia entra en erupci\u00f3n cuando se ordena evacuar nuevamente a un pueblo pesquero","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) -- Un volc\u00e1n entr\u00f3 en erupci\u00f3n en el suroeste de Islandia apenas unas semanas despu\u00e9s de otra erupci\u00f3n en la zona, poniendo a los residentes de una ciudad cercana bajo un nuevo riesgo.El s\u00e1bado, el Comisionado Nacional de Polic\u00eda de Islandia hab\u00eda ordenado a los residentes del pueblo pesquero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443697,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/un-volcan-en-islandia-entra-en-erupcion-cuando-se-ordena-evacuar-nuevamente-a-un-pueblo-pesquero-2\/","url_meta":{"origin":1443674,"position":1},"title":"Un volc\u00e1n en Islandia entra en erupci\u00f3n cuando se ordena evacuar nuevamente a un pueblo pesquero","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) -- Un volc\u00e1n entr\u00f3 en erupci\u00f3n en el suroeste de Islandia apenas unas semanas despu\u00e9s de otra erupci\u00f3n en la zona, poniendo a los residentes de una ciudad cercana bajo un nuevo riesgo.El s\u00e1bado, el Comisionado Nacional de Polic\u00eda de Islandia hab\u00eda ordenado a los residentes del pueblo pesquero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446441,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/04\/evacuan-laguna-azul-islandia-inminente-erupcion-volcanica-trax\/","url_meta":{"origin":1443674,"position":2},"title":"Evac\u00faan la Laguna Azul de Islandia ante una \u201cinminente\u201d erupci\u00f3n volc\u00e1nica","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- Islandia evacu\u00f3 su mundialmente famosa Laguna Azul debido a una actividad s\u00edsmica cercana que sugiere una \u201cinminente\u201d erupci\u00f3n volc\u00e1nica, inform\u00f3 el s\u00e1bado la emisora \u200b\u200bp\u00fablica del pa\u00eds R\u00daV.El magma ha comenzado a fluir despu\u00e9s de una \u201cintensa actividad s\u00edsmica\u201d en el \u00e1rea alrededor de la laguna, un popular\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449851,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/29\/volcan-islandia-vuelve-a-entrar-erupcion-dramaticamente-cuando-corrientes-lava-alcanzan-murallas-defensivas-ciudad-trax\/","url_meta":{"origin":1443674,"position":3},"title":"El volc\u00e1n de Islandia vuelve a entrar en erupci\u00f3n dram\u00e1ticamente cuando corrientes de lava alcanzan las murallas defensivas de la ciudad","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- Un volc\u00e1n en el suroeste de Islandia entr\u00f3 en erupci\u00f3n este mi\u00e9rcoles por quinta vez desde diciembre, arrojando enormes flujos de lava que amenazan con aislar la ciudad de Grindav\u00edk y provocando la evacuaci\u00f3n de la mundialmente famosa Laguna Azul.Videos e im\u00e1genes espectaculares de la escena mostraban fuentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452162,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/26\/un-turista-muere-derrumbe-cueva-de-hielo-mientras-rescatistas-buscan-a-dos-desaparecidos-islandia-ap\/","url_meta":{"origin":1443674,"position":4},"title":"Un turista muere en un derrumbe de una cueva de hielo mientras los rescatistas buscan a dos desaparecidos en Islandia","author":"","date":"agosto 26, 2024","format":false,"excerpt":"(CNN) -- Al menos una persona muri\u00f3 y otras dos est\u00e1n desaparecidas despu\u00e9s de que una cueva de hielo se derrumbara parcialmente mientras un grupo de turistas visitaba el glaciar Breidamerkurjokull en el sur de Islandia.En un comunicado publicado en las redes sociales, la Polic\u00eda local dijo que los socorristas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460295,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/22\/ministra-infancia-islandia-dimite-relacion-adolescente-trax\/","url_meta":{"origin":1443674,"position":5},"title":"La ministra de Infancia de Islandia dimite por su relaci\u00f3n con un adolescente cuando ella ten\u00eda 22 a\u00f1os","author":"","date":"marzo 22, 2025","format":false,"excerpt":"La ministra de Infancia y Educaci\u00f3n de Islandia dimiti\u00f3 tras admitir que tuvo un hijo con un adolescente hace m\u00e1s de tres d\u00e9cadas y media, seg\u00fan medios islandeses.\u00c1sthildur L\u00f3a Th\u00f3rsd\u00f3ttir revel\u00f3 que hab\u00eda comenzado una relaci\u00f3n con un chico, de 15 a\u00f1os, cuando ten\u00eda 22 y que tuvo un hijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443674"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443674\/revisions"}],"predecessor-version":[{"id":1443690,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443674\/revisions\/1443690"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}