{"id":1443707,"date":"2024-01-14T22:33:38","date_gmt":"2024-01-15T06:33:38","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443707"},"modified":"2024-01-14T22:33:38","modified_gmt":"2024-01-15T06:33:38","slug":"bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","title":{"rendered":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este domingo Bernardo Ar\u00e9valo asumir\u00e1 la presidencia de Guatemala, con el combate a la corrupci\u00f3n como una de sus principales banderas.<\/p>\n<p>Desde su triunfo en segunda vuelta en las elecciones del 20 de agosto ha crecido la expectativa entre los guatemaltecos sobre lo que puede lograr, ya que, seg\u00fan ciudadanos y analistas consultados por CNN, no ser\u00e1 f\u00e1cil que Ar\u00e9valo pueda llevar a cabo muchos de sus proyectos, sobre todo cuando requieran de la aprobaci\u00f3n de un Congreso de mayor\u00eda opositora.<\/p>\n<p>\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, candidato ganador de las elecciones en Guatemala?<\/p>\n<p>Algunos guatemaltecos esperan que Ar\u00e9valo cumpla con su promesa de combatir la corrupci\u00f3n, una tarea que, dicen, ser\u00e1 tit\u00e1nica. \u201cEs una situaci\u00f3n bien dif\u00edcil que tiene que manejar porque la corrupci\u00f3n est\u00e1 enraizada desde hace muchos a\u00f1os\u201d, dice Constantino Hurtado a CNN.<\/p>\n<p>Otros esperan que impulse medidas que permitan mejorar las condiciones de vida. \u201cQue apoye a las personas de escasos recursos, a quienes no tienen trabajo\u201d, se\u00f1ala Jhony Bran en la Ciudad de Guatemala.<\/p>\n<p>El presidente electo de Guatemala, Bernardo Ar\u00e9valo, participa en la &#171;Marcha por la Democracia&#187; para exigir la renuncia de la fiscal general Consuelo Porras y del fiscal Rafael Curruchiche. Cr\u00e9dito: JOHAN ORDONEZ\/AFP v\u00eda Getty Images<\/p>\n<p>Ar\u00e9valo, doctor en filosof\u00eda y licenciado en sociolog\u00eda, ha prometido impulsar acciones para generar desarrollo para las grandes mayor\u00edas en Guatemala en la salud, educaci\u00f3n, infraestructura, entre otros. Sin embargo, frenar la corrupci\u00f3n lo considera urgente porque, de lo contrario, dice, las instituciones no har\u00e1n un buen trabajo.<\/p>\n<p>Uno de los principales retos que tendr\u00e1 el nuevo Gobierno, para poder llevar a cabo algunas de sus propuestas de campa\u00f1a, es que deber\u00e1 lograr el apoyo del Congreso, cuya correlaci\u00f3n no le ser\u00e1 favorable.<\/p>\n<p>Edgar Guti\u00e9rrez, analista pol\u00edtico y excanciller de Guatemala, considera que la gobernabilidad ser\u00e1 clave en la pr\u00f3xima administraci\u00f3n, pero advierte que los apoyos que sume Ar\u00e9valo en el Legislativo no deben ser el resultado de pactos o acuerdos bajo la mesa.<\/p>\n<p>Capturan a exministro de Gobernaci\u00f3n de Guatemala por no disolver protestas y bloqueos de v\u00edas que exig\u00edan la renuncia de la fiscal general y otros funcionarios<\/p>\n<p>\u201cSer\u00eda el veneno para el partido de Gobierno y para el propio Ar\u00e9valo porque la confianza que le ha depositado la poblaci\u00f3n a trav\u00e9s del voto justamente es la transparencia y el uso correcto de los recursos p\u00fablicos\u201d, dice a CNN.<\/p>\n<p>Diputado: Movimiento Semilla est\u00e1 llegando a acuerdos en el Congreso 3:39<\/p>\n<p>Ar\u00e9valo reconoce que no es una tarea f\u00e1cil, pero dice que junto a su equipo ha dise\u00f1ado una estrategia para implementar su plan de trabajo y as\u00ed cumplir con las principales promesas de la campa\u00f1a.<\/p>\n<p>En agosto dijo a CNN que buscar\u00e1 acuerdos con los nuevos congresistas, pero adelant\u00f3 que el desarrollo del pa\u00eds no se detendr\u00e1 por la falta de apoyo.<\/p>\n<p>\u201cNo vamos a dejar secuestrar el desarrollo nacional por el Congreso y avanzaremos, dentro de las potestades que nos permite la ley, en la ejecuci\u00f3n desde el organismo Ejecutivo\u201d, explic\u00f3.<\/p>\n<p>La relaci\u00f3n con el Ministerio P\u00fablico<\/p>\n<p>Otro frente abierto del venidero Gobierno es la relaci\u00f3n que tendr\u00e1 con el Ministerio P\u00fablico, que ha presentado dos solicitudes para retirarle la inmunidad a Ar\u00e9valo. La primera, por su presunta responsabilidad en promover la toma y posteriores protestas en la Universidad San Carlos; la segunda, por las posibles irregularidades en la formaci\u00f3n del partido Movimiento Semilla.<\/p>\n<p>Ar\u00e9valo ha rechazado ambos se\u00f1alamientos y acusado a las autoridades de promover un golpe de Estado.<\/p>\n<p>En ese turbulento ambiente, los principales aliados de Ar\u00e9valo han sido las comunidades ind\u00edgenas \u2014encabezadas por la organizaci\u00f3n 48 Cantones de Totonicap\u00e1n\u2014 que han respaldado el triunfo de Semilla con marchas, bloqueos de carreteras y concentraciones frente al Ministerio P\u00fablico.<\/p>\n<p>Sin embargo, ese respaldo no es un cheque en blanco, seg\u00fan los movimientos ind\u00edgenas.<\/p>\n<p>\u201cEl Gobierno no va a estar solo, ah\u00ed lo vamos a estar velando y, si no va a cumplir lo que prometi\u00f3, afuera tambi\u00e9n lo vamos a sacar, que lo sepa de una vez\u201d, dice Bl\u00e1sida D\u00edaz, representante de aldea Tacan\u00e1, durante una concentraci\u00f3n el pasado noviembre.<\/p>\n<p>Por esa raz\u00f3n, dicen algunos analistas, Ar\u00e9valo debe trabajar bien y r\u00e1pido para comenzar a atender las demandas de los diferentes sectores, o de lo contrario, advierten, la nueva primavera que ha prometido se puede convertir en la continua decepci\u00f3n de los guatemaltecos.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este domingo Bernardo Ar\u00e9valo asumir\u00e1 la presidencia de Guatemala, con el combate a la corrupci\u00f3n como una de sus principales banderas. Desde su triunfo en segunda vuelta en las elecciones del 20 de agosto ha crecido la expectativa entre los guatemaltecos sobre lo que puede lograr, ya que, seg\u00fan ciudadanos y analistas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443707","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Este domingo Bernardo Ar\u00e9valo asumir\u00e1 la presidencia de Guatemala, con el combate a la corrupci\u00f3n como una de sus principales banderas. Desde su triunfo en segunda vuelta en las elecciones del 20 de agosto ha crecido la expectativa entre los guatemaltecos sobre lo que puede lograr, ya que, seg\u00fan ciudadanos y analistas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-15T06:33:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?\",\"datePublished\":\"2024-01-15T06:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\"},\"wordCount\":825,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\",\"name\":\"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-15T06:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","og_locale":"es_ES","og_type":"article","og_title":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Este domingo Bernardo Ar\u00e9valo asumir\u00e1 la presidencia de Guatemala, con el combate a la corrupci\u00f3n como una de sus principales banderas. Desde su triunfo en segunda vuelta en las elecciones del 20 de agosto ha crecido la expectativa entre los guatemaltecos sobre lo que puede lograr, ya que, seg\u00fan ciudadanos y analistas [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","og_site_name":"Noticias","article_published_time":"2024-01-15T06:33:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/"},"author":{"name":"","@id":""},"headline":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?","datePublished":"2024-01-15T06:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/"},"wordCount":825,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","name":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-15T06:33:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?","url":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-15T06:33:38Z","datePublished":"2024-01-15T06:33:38Z","dateModified":"2024-01-15T06:33:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bernardo Ar\\u00e9valo asume como presidente de Guatemala. \\u00bfCu\\u00e1les son los retos del nuevo gobierno?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/14\\\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/01\\\/14\\\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-15T06:33:38Z\",\"datePublished\":\"2024-01-15T06:33:38Z\",\"dateModified\":\"2024-01-15T06:33:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443701,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/bernardo-arevalo-asume-como-presidente-de-guatemala-cuales-son-los-retos-del-nuevo-gobierno\/","url_meta":{"origin":1443707,"position":0},"title":"Bernardo Ar\u00e9valo asume como presidente de Guatemala. \u00bfCu\u00e1les son los retos del nuevo gobierno?","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este domingo Bernardo Ar\u00e9valo asumir\u00e1 la presidencia de Guatemala, con el combate a la corrupci\u00f3n como una de sus principales banderas.Desde su triunfo en segunda vuelta en las elecciones del 20 de agosto ha crecido la expectativa entre los guatemaltecos sobre lo que puede lograr, ya que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443691,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/14\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala\/","url_meta":{"origin":1443707,"position":1},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, gan\u00f3 en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra Torres, de la Unidad Nacional de la Esperanza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443724,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-2\/","url_meta":{"origin":1443707,"position":2},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443728,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-3\/","url_meta":{"origin":1443707,"position":3},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443730,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/15\/quien-es-y-que-propone-bernardo-arevalo-el-presidente-electo-de-guatemala-4\/","url_meta":{"origin":1443707,"position":4},"title":"\u00bfQui\u00e9n es y qu\u00e9 propone Bernardo Ar\u00e9valo, el presidente electo de Guatemala?","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Bernardo Ar\u00e9valo de Le\u00f3n, de 64 a\u00f1os, es el nuevo presidente de Guatemala tras haber ganado en segunda vuelta las elecciones presidenciales de Guatemala. Es diplom\u00e1tico de carrera y no figuraba como favorito entre las encuestas por lo que su pase a la segunda ronda, contra Sandra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457517,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/14\/presidente-guatemala-plan-migrantes-deportados-orix\/","url_meta":{"origin":1443707,"position":5},"title":"El presidente de Guatemala, Bernardo Ar\u00e9valo, anuncia plan para atender a migrantes guatemaltecos deportados","author":"","date":"enero 14, 2025","format":false,"excerpt":"El presidente de Guatemala, Bernardo Ar\u00e9valo, anunci\u00f3 este martes que su gobierno implementar\u00e1 una serie de acciones para apoyar a los migrantes que ser\u00e1n deportados, principalmente desde Estados Unidos y M\u00e9xico, en su informe de Gobierno presentado ante el Congreso, en el primer aniversario al frente del Ejecutivo.Ar\u00e9valo dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1443707"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443707\/revisions"}],"predecessor-version":[{"id":1443723,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1443707\/revisions\/1443723"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1443707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1443707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1443707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}