{"id":1450905,"date":"2024-07-05T11:03:41","date_gmt":"2024-07-05T18:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/"},"modified":"2024-07-05T11:03:41","modified_gmt":"2024-07-05T18:03:41","slug":"nucleo-tierra-desacelerado-retrocediendo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","title":{"rendered":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar"},"content":{"rendered":"<p>(CNN) &#8212; En las profundidades de la Tierra hay una bola de metal s\u00f3lido que gira independientemente de nuestro planeta, como una peonza que gira dentro de otra peonza m\u00e1s grande, envuelta en el misterio.<\/p>\n<p>Este n\u00facleo interno ha intrigado a los investigadores desde su descubrimiento por la sism\u00f3loga danesa Inge Lehmann en 1936, y su movimiento (velocidad y direcci\u00f3n de rotaci\u00f3n) ha sido el centro de un debate que ha durado d\u00e9cadas. Cada vez hay m\u00e1s pruebas de que el giro del n\u00facleo ha cambiado dr\u00e1sticamente en los \u00faltimos a\u00f1os, pero los cient\u00edficos siguen divididos sobre lo que ocurre exactamente y lo que significa.<\/p>\n<p>El derretimiento del hielo polar cambia la rotaci\u00f3n de la Tierra: afecta el tiempo mismo, dice nuevo estudio<\/p>\n<p>Parte del problema radica en que es imposible observar o tomar muestras directas del interior de la Tierra. Los sism\u00f3logos han obtenido informaci\u00f3n sobre el movimiento del n\u00facleo interno examinando c\u00f3mo se comportan las ondas de los grandes terremotos que sacuden esta zona. Las variaciones entre las ondas de fuerza similar que atravesaron el n\u00facleo en distintos momentos permitieron a los cient\u00edficos medir los cambios en la posici\u00f3n del n\u00facleo interno y calcular su giro.<\/p>\n<p>&#171;La rotaci\u00f3n diferencial del n\u00facleo interno se propuso como fen\u00f3meno en las d\u00e9cadas de 1970 y 80, pero hasta la d\u00e9cada de 1990 no se publicaron pruebas sismol\u00f3gicas&#187;, explica Lauren Waszek, profesora titular de Ciencias F\u00edsicas en la Universidad James Cook de Australia.<\/p>\n<p>Pero los investigadores discut\u00edan sobre c\u00f3mo interpretar estos hallazgos, &#171;sobre todo por la dificultad de realizar observaciones detalladas del n\u00facleo interno, debido a su lejan\u00eda y a la escasez de datos disponibles&#187;, explic\u00f3 Waszek. Como resultado, &#171;los estudios que se sucedieron durante los a\u00f1os y d\u00e9cadas siguientes discreparon sobre la velocidad de rotaci\u00f3n, y tambi\u00e9n sobre su direcci\u00f3n con respecto al manto&#187;, a\u00f1adi\u00f3. Algunos an\u00e1lisis propusieron incluso que el n\u00facleo no rotaba en absoluto.<\/p>\n<p>Un modelo prometedor propuesto en 2023 describ\u00eda un n\u00facleo interno que en el pasado hab\u00eda girado m\u00e1s r\u00e1pido que la propia Tierra, pero que ahora lo hac\u00eda m\u00e1s despacio. Durante un tiempo, seg\u00fan los cient\u00edficos, la rotaci\u00f3n del n\u00facleo coincid\u00eda con la de la Tierra. Despu\u00e9s se ralentiz\u00f3 a\u00fan m\u00e1s, hasta que el n\u00facleo retrocedi\u00f3 con respecto a las capas de fluido que lo rodeaban.<\/p>\n<p>En aquel momento, algunos expertos advirtieron que se necesitaban m\u00e1s datos para reforzar esta conclusi\u00f3n, y ahora otro equipo de cient\u00edficos ha aportado nuevas y convincentes pruebas a favor de esta hip\u00f3tesis sobre la velocidad de rotaci\u00f3n del n\u00facleo interno. La investigaci\u00f3n publicada el 12 de junio en la revista acad\u00e9mica Nature no s\u00f3lo confirma la ralentizaci\u00f3n del n\u00facleo, sino que apoya la propuesta de 2023 de que esta desaceleraci\u00f3n del n\u00facleo forma parte de un patr\u00f3n de d\u00e9cadas de ralentizaci\u00f3n y aceleraci\u00f3n.<\/p>\n<p>Nuevas investigaciones confirman que la rotaci\u00f3n del n\u00facleo interno de la Tierra se ha ido frenando como parte de un patr\u00f3n de d\u00e9cadas de duraci\u00f3n. C\u00f3mo podr\u00eda afectar esta ralentizaci\u00f3n a nuestro planeta sigue siendo una inc\u00f3gnita. Cr\u00e9dito: Edward Sotelo\/Cortes\u00eda USC<\/p>\n<p>Los nuevos hallazgos tambi\u00e9n confirman que los cambios en la velocidad de rotaci\u00f3n siguen un ciclo de 70 a\u00f1os, dijo el coautor del estudio, el Dr. John Vidale, profesor decano de Ciencias de la Tierra en el Colegio Dornsife de Letras, Artes y Ciencias de la Universidad del Sur de California.<\/p>\n<p>&#171;Llevamos 20 a\u00f1os discutiendo sobre este tema, y creo que esto lo zanja&#187;, afirm\u00f3 Vidale. &#171;Creo que hemos puesto fin al debate sobre si el n\u00facleo interno se mueve, y cu\u00e1l ha sido su patr\u00f3n durante las dos \u00faltimas d\u00e9cadas&#187;.<\/p>\n<p>Pero no todos est\u00e1n convencidos de que el asunto est\u00e9 zanjado, y c\u00f3mo podr\u00eda afectar a nuestro planeta una ralentizaci\u00f3n del n\u00facleo interno sigue siendo una cuesti\u00f3n abierta, aunque algunos expertos afirman que el campo magn\u00e9tico de la Tierra podr\u00eda entrar en juego.<\/p>\n<p>\u00bfPor qu\u00e9 Venus no es como la Tierra? Nueva misi\u00f3n espacial pretende descubrirlo<\/p>\n<p>Atracci\u00f3n magn\u00e9tica<\/p>\n<p>Enterrado a unos 5.180 kil\u00f3metros de profundidad en el interior de la Tierra, el n\u00facleo interno de metal s\u00f3lido est\u00e1 rodeado por un n\u00facleo externo de metal l\u00edquido. El n\u00facleo interno est\u00e1 formado principalmente por hierro y n\u00edquel, y se calcula que est\u00e1 tan caliente como la superficie del Sol: unos 5.400 \u00b0C (9.800 \u00b0F).<\/p>\n<p>El campo magn\u00e9tico de la Tierra tira de esta bola s\u00f3lida de metal caliente, haci\u00e9ndola girar. Al mismo tiempo, la gravedad y el flujo del fluido del n\u00facleo externo y del manto arrastran al n\u00facleo. A lo largo de muchas d\u00e9cadas, el empuje y la atracci\u00f3n de estas fuerzas provocan variaciones en la velocidad de rotaci\u00f3n del n\u00facleo, explica Vidale.<\/p>\n<p>La agitaci\u00f3n del fluido rico en metales del n\u00facleo externo genera corrientes el\u00e9ctricas que alimentan el campo magn\u00e9tico de la Tierra, que protege al planeta de la mort\u00edfera radiaci\u00f3n solar. Aunque se desconoce la influencia directa del n\u00facleo interno en el campo magn\u00e9tico, los cient\u00edficos ya hab\u00edan informado en 2023 de que un n\u00facleo que girara m\u00e1s despacio podr\u00eda afectarlo y tambi\u00e9n acortar fraccionadamente la duraci\u00f3n de un d\u00eda.<\/p>\n<p>Cuando los cient\u00edficos intentan &#171;ver&#187; a trav\u00e9s de todo el planeta, generalmente est\u00e1n rastreando dos tipos de ondas s\u00edsmicas: las ondas de presi\u00f3n, u ondas P, y las ondas de corte, u ondas S. Las ondas P atraviesan todo tipo de materia, mientras que las ondas S s\u00f3lo atraviesan s\u00f3lidos o l\u00edquidos extremadamente viscosos, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos.<\/p>\n<p>En la d\u00e9cada de 1880, los sism\u00f3logos observaron que las ondas S generadas por los terremotos no atravesaban toda la Tierra, por lo que llegaron a la conclusi\u00f3n de que el n\u00facleo terrestre estaba fundido. Pero algunas ondas P, tras atravesar el n\u00facleo terrestre, emerg\u00edan en lugares inesperados, una &#171;zona de sombra&#187;, como la llam\u00f3 Lehmann, creando anomal\u00edas imposibles de explicar.<\/p>\n<p>Lehmann fue el primero en sugerir que las ondas P pod\u00edan estar interactuando con un n\u00facleo interno s\u00f3lido dentro del n\u00facleo externo l\u00edquido, bas\u00e1ndose en los datos de un gran terremoto ocurrido en Nueva Zelandia en 1929.<\/p>\n<p>Al rastrear las ondas s\u00edsmicas de los terremotos que han atravesado el n\u00facleo interno de la Tierra siguiendo trayectorias similares desde 1964, los autores del estudio de 2023 descubrieron que el giro segu\u00eda un ciclo de 70 a\u00f1os. En la d\u00e9cada de 1970, el n\u00facleo interno giraba un poco m\u00e1s r\u00e1pido que el planeta. Se ralentiz\u00f3 en torno a 2008, y de 2008 a 2023 comenz\u00f3 a moverse ligeramente a la inversa, en relaci\u00f3n con el manto.<\/p>\n<p>Futuro giro del n\u00facleo<\/p>\n<p>Para el nuevo estudio, Vidale y sus coautores observaron las ondas s\u00edsmicas producidas por terremotos en los mismos lugares en diferentes momentos. Encontraron 121 ejemplos de terremotos de este tipo ocurridos entre 1991 y 2023 en las islas Sandwich del Sur, un archipi\u00e9lago de islas volc\u00e1nicas situado en el oc\u00e9ano Atl\u00e1ntico, al este del extremo sur de Sudam\u00e9rica. Los investigadores tambi\u00e9n analizaron las ondas de choque que penetraron en el n\u00facleo de las pruebas nucleares sovi\u00e9ticas realizadas entre 1971 y 1974.<\/p>\n<p>Seg\u00fan Vidale, el giro del n\u00facleo afecta al tiempo de llegada de la onda. La comparaci\u00f3n de los tiempos de las se\u00f1ales s\u00edsmicas al tocar el n\u00facleo revel\u00f3 cambios en la rotaci\u00f3n del n\u00facleo a lo largo del tiempo, confirmando el ciclo de rotaci\u00f3n de 70 a\u00f1os. Seg\u00fan los c\u00e1lculos de los investigadores, el n\u00facleo est\u00e1 a punto de empezar a acelerarse de nuevo.<\/p>\n<p>En comparaci\u00f3n con otros estudios sismogr\u00e1ficos del n\u00facleo que miden terremotos individuales a su paso por el n\u00facleo independientemente del momento en que se produzcan, utilizar s\u00f3lo terremotos emparejados reduce la cantidad de datos utilizables, &#171;lo que hace que el m\u00e9todo sea m\u00e1s dif\u00edcil&#187;, dijo Waszek. Sin embargo, seg\u00fan Vidale, este m\u00e9todo tambi\u00e9n permiti\u00f3 a los cient\u00edficos medir con mayor precisi\u00f3n los cambios en la rotaci\u00f3n del n\u00facleo. Si el modelo de su equipo es correcto, la rotaci\u00f3n del n\u00facleo empezar\u00e1 a acelerarse de nuevo en unos cinco a diez a\u00f1os.<\/p>\n<p>Observaciones del telescopio Webb insin\u00faan una colisi\u00f3n de asteroides gigantes en un sistema planetario cercano<\/p>\n<p>Los sism\u00f3grafos tambi\u00e9n revelaron que, durante su ciclo de 70 a\u00f1os, el giro del n\u00facleo se ralentiza y acelera a ritmos diferentes, &#171;lo que va a necesitar una explicaci\u00f3n&#187;, dijo Vidale. Una posibilidad es que el n\u00facleo interno met\u00e1lico no sea tan s\u00f3lido como se esperaba.<\/p>\n<p>Si se deforma al girar, podr\u00eda afectar a la simetr\u00eda de su velocidad de rotaci\u00f3n, explic\u00f3.<\/p>\n<p>Los c\u00e1lculos del equipo tambi\u00e9n sugieren que el n\u00facleo tiene diferentes velocidades de rotaci\u00f3n para el movimiento hacia delante y hacia atr\u00e1s, lo que a\u00f1ade &#171;una interesante contribuci\u00f3n al discurso&#187;, dijo Waszek.<\/p>\n<p>Pero la profundidad y la inaccesibilidad del n\u00facleo interno hacen que persistan las incertidumbres, a\u00f1adi\u00f3. En cuanto a si el debate sobre la rotaci\u00f3n del n\u00facleo ha llegado realmente a su fin, &#171;necesitamos m\u00e1s datos y mejores herramientas interdisciplinarias para seguir investigando&#187;, afirm\u00f3 Waszek.<\/p>\n<p>Lleno de potencial<\/p>\n<p>Los cambios en el giro del n\u00facleo, aunque pueden seguirse y medirse, son casi imperceptibles para los habitantes de la superficie terrestre, seg\u00fan Vidale. Cuando el n\u00facleo gira m\u00e1s despacio, el manto se acelera. Este cambio acelera la rotaci\u00f3n de la Tierra y acorta la duraci\u00f3n del d\u00eda. Pero estos cambios de rotaci\u00f3n se traducen en meras mil\u00e9simas de segundo en la duraci\u00f3n del d\u00eda.<\/p>\n<p>&#171;En t\u00e9rminos de ese efecto en la vida de una persona&#8230;&#187;, dijo. &#171;No puedo imaginar que signifique mucho&#187;.<\/p>\n<p>Los cient\u00edficos estudian el n\u00facleo interno para saber c\u00f3mo se form\u00f3 el interior profundo de la Tierra y c\u00f3mo se conecta la actividad en todas las capas subsuperficiales del planeta. La misteriosa regi\u00f3n donde el n\u00facleo externo l\u00edquido envuelve al n\u00facleo interno s\u00f3lido es especialmente interesante, a\u00f1adi\u00f3 Vidale. Como lugar de encuentro entre lo l\u00edquido y lo s\u00f3lido, este l\u00edmite est\u00e1 &#171;lleno de potencial de actividad&#187;, al igual que el l\u00edmite entre el n\u00facleo y el manto y el l\u00edmite entre el manto y la corteza.<\/p>\n<p>&#171;Podr\u00edamos tener volcanes en el l\u00edmite del n\u00facleo interno, por ejemplo, donde el s\u00f3lido y el fluido se encuentran y se mueven&#187;, explic\u00f3.<\/p>\n<p>Dado que el giro del n\u00facleo interno afecta al movimiento del n\u00facleo externo, se cree que la rotaci\u00f3n del n\u00facleo interno ayuda a impulsar el campo magn\u00e9tico de la Tierra, aunque se necesitan m\u00e1s investigaciones para desentra\u00f1ar su papel exacto. Seg\u00fan Waszek, a\u00fan queda mucho por aprender sobre la estructura general del n\u00facleo interno.<\/p>\n<p>&#171;Las metodolog\u00edas novedosas y de pr\u00f3xima aparici\u00f3n ser\u00e1n fundamentales para responder a las preguntas actuales sobre el n\u00facleo interno de la Tierra, incluida la de la rotaci\u00f3n&#187;.<\/p>\n<p>&#8212; Mindy Weisberger es una escritora cient\u00edfica y productora de medios de comunicaci\u00f3n cuyos trabajos han aparecido en Live Science, Scientific American y la revista How It Works.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; En las profundidades de la Tierra hay una bola de metal s\u00f3lido que gira independientemente de nuestro planeta, como una peonza que gira dentro de otra peonza m\u00e1s grande, envuelta en el misterio. Este n\u00facleo interno ha intrigado a los investigadores desde su descubrimiento por la sism\u00f3loga danesa Inge Lehmann en 1936, y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450905","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; En las profundidades de la Tierra hay una bola de metal s\u00f3lido que gira independientemente de nuestro planeta, como una peonza que gira dentro de otra peonza m\u00e1s grande, envuelta en el misterio. Este n\u00facleo interno ha intrigado a los investigadores desde su descubrimiento por la sism\u00f3loga danesa Inge Lehmann en 1936, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T18:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar\",\"datePublished\":\"2024-07-05T18:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\"},\"wordCount\":2065,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\",\"name\":\"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-05T18:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias","og_description":"(CNN) &#8212; En las profundidades de la Tierra hay una bola de metal s\u00f3lido que gira independientemente de nuestro planeta, como una peonza que gira dentro de otra peonza m\u00e1s grande, envuelta en el misterio. Este n\u00facleo interno ha intrigado a los investigadores desde su descubrimiento por la sism\u00f3loga danesa Inge Lehmann en 1936, y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-05T18:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/"},"author":{"name":"","@id":""},"headline":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar","datePublished":"2024-07-05T18:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/"},"wordCount":2065,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","name":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-05T18:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-05T18:03:41Z","datePublished":"2024-07-05T18:03:41Z","dateModified":"2024-07-05T18:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El n\\u00facleo de la Tierra se ha desacelerado tanto que est\\u00e1 retrocediendo, confirman los cient\\u00edficos. Esto es lo que podr\\u00eda significar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/05\\\/nucleo-tierra-desacelerado-retrocediendo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/05\\\/nucleo-tierra-desacelerado-retrocediendo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-05T18:03:41Z\",\"datePublished\":\"2024-07-05T18:03:41Z\",\"dateModified\":\"2024-07-05T18:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458548,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","url_meta":{"origin":1450905,"position":0},"title":"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando","author":"","date":"febrero 10, 2025","format":false,"excerpt":"Cient\u00edficos que hace solo unos meses confirmaron que el n\u00facleo interno de la Tierra recientemente invirti\u00f3 su giro tienen una nueva revelaci\u00f3n sobre los secretos m\u00e1s profundos de nuestro planeta: identificaron cambios en la forma del n\u00facleo interno.La capa m\u00e1s interna de la Tierra es una bola de metal caliente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464736,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/07\/21\/tierra-gira-mas-rapido-dias-mas-cortos-trax\/","url_meta":{"origin":1450905,"position":1},"title":"La Tierra gira m\u00e1s r\u00e1pido, lo que lleva a los cronometradores a considerar una medida sin precedentes","author":"","date":"julio 21, 2025","format":false,"excerpt":"La Tierra est\u00e1 girando m\u00e1s r\u00e1pido este verano, lo que hace que los d\u00edas sean ligeramente m\u00e1s cortos y atrae la atenci\u00f3n de cient\u00edficos y cronometradores.El 10 de julio fue el d\u00eda m\u00e1s corto del a\u00f1o hasta la fecha, con una duraci\u00f3n de 1,36 milisegundos menos que 24 horas, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471094,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/10\/nucleo-tierra-deposito-descubrimiento-hidrogeno-elemento-vida-trax\/","url_meta":{"origin":1450905,"position":2},"title":"El gran secreto del centro de la Tierra: encuentran dep\u00f3sito de un elemento vital que supera 45 veces a los oc\u00e9anos","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El n\u00facleo de la Tierra podr\u00eda ser el dep\u00f3sito de hidr\u00f3geno m\u00e1s grande jam\u00e1s imaginado. Investigaciones recientes estiman que el centro de nuestro planeta alberga hasta nueve veces m\u00e1s hidr\u00f3geno que todos los oc\u00e9anos de la superficie combinados. Este hallazgo redefine la estructura interna de la Tierra, sugiriendo que las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462780,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/05\/25\/pablo-minini-querian-asegurarse-que-la-ciencia-que-iban-a-usar-en-la-actualizacion-fuera-correcta\/","url_meta":{"origin":1450905,"position":3},"title":"Pablo Minini: &#171;Quer\u00edan asegurarse que la ciencia que iban a usar en la actualizaci\u00f3n fuera correcta&#187;","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Pablo Minini, profesor, habl\u00f3 este domingo con CNN Radio sobre la asesor\u00eda que realizaron los graduados y docentes de la Facultad de Ciencias Exactas y Naturales en el Eternauta.En Mundo UBA con Ricardo Bragisnki indic\u00f3: \u201dHace varios a\u00f1os, cuando empezaron a escribir el gui\u00f3n Bruno Stagnaro, que es el director\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457705,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/21\/nueva-posicion-polo-norte-magnetico-tierra-trax\/","url_meta":{"origin":1450905,"position":4},"title":"El polo norte magn\u00e9tico de la Tierra se est\u00e1 moviendo y los cient\u00edficos acaban de actualizar su posici\u00f3n","author":"","date":"enero 21, 2025","format":false,"excerpt":"Si usas tu tel\u00e9fono inteligente para navegar, tu sistema acaba de recibir una actualizaci\u00f3n importante. Los cient\u00edficos han publicado un nuevo modelo que rastrea la posici\u00f3n del polo norte magn\u00e9tico, y revela que el polo ahora est\u00e1 m\u00e1s cerca de Siberia que hace cinco a\u00f1os y contin\u00faa desplaz\u00e1ndose hacia Rusia.A\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469371,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/12\/17\/cometa-interestelar-3iatlas-aproximacion-tierra-orix\/","url_meta":{"origin":1450905,"position":5},"title":"El cometa interestelar 3I\/ATLAS har\u00e1 su aproximaci\u00f3n m\u00e1s cercana a la Tierra: as\u00ed capt\u00f3 la atenci\u00f3n del mundo","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"El cometa 3I\/ATLAS ha captado la atenci\u00f3n del mundo este a\u00f1o debido a que se sabe muy poco de su origen: proviene del espacio profundo y es tan solo el tercer objeto interestelar jam\u00e1s observado despu\u00e9s del 1I\/\u02bbOumuamua en 2017 y el 2I\/Borisov en 2019.Se infiere que es un objeto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450905"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450905\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}