{"id":1450913,"date":"2024-07-05T18:03:44","date_gmt":"2024-07-06T01:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/"},"modified":"2024-07-05T18:03:44","modified_gmt":"2024-07-06T01:03:44","slug":"investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","title":{"rendered":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Alrededor de 60 personas supuestamente involucradas en el intento de golpe de Estado en Brasil del 8 de enero de 2023 ingresaron a Argentina, al tiempo que el presidente de Argentina Javier Milei se niega a pedirle disculpas a su hom\u00f3logo Lula Da Silva y viaja a encontrarse con Jair Bolsonaro en el marco de la Conferencia Pol\u00edtica de Acci\u00f3n Conservadora (CPAC) que se celebrar\u00e1 en Brasil.<\/p>\n<p>La embajada de Brasil en Buenos Aires confirm\u00f3 a CNN esta informaci\u00f3n, que surge de un pedido del Supremo Tribunal de Justicia (STJ) al gobierno argentino sobre 143 pr\u00f3fugos acusados y condenados por irrumpir en edificios p\u00fablicos como el Congreso, el palacio presidencial e instalaciones del Poder Judicial, a una semana de la asunci\u00f3n de Lula Da Silva.<\/p>\n<p>Este escenario, y algunas declaraciones de personas afines al bolsonarismo ponen sobre la mesa la posibilidad de que los forajidos pidan refugio o asilo pol\u00edtico en Argentina.<\/p>\n<p>Consultado por esta posibilidad, el vocero presidencial de Argentina Manuel Adorni fue enf\u00e1tico: &#171;No nos inmiscuimos en temas que est\u00e1n fuera del Poder Ejecutivo Nacional. La calidad de los refugiados la determina una comisi\u00f3n independiente, no definimos qui\u00e9n es refugiado y qui\u00e9n no&#187;, dijo a SBT News.<br \/>\nLas redes del bolsonarismo en Argentina<\/p>\n<p>La afinidad entre Milei y Bolsonaro es p\u00fablica. En diciembre pasado Bolsonaro asisti\u00f3 a la asunci\u00f3n de Milei y ocup\u00f3 un lugar al lado de mandatarios de distintos pa\u00edses que tambi\u00e9n formaron parte del convite.<\/p>\n<p>El mensaje de apoyo de Jair Bolsonaro a Javier Milei a d\u00edas de las elecciones en Argentina<\/p>\n<p>Pero los v\u00ednculos con el Partido Liberal brasile\u00f1o, que responde al expresidente, trascienden esa relaci\u00f3n.<\/p>\n<p>A fines de mayo, la diputada de La Libertad Avanza Mar\u00eda Celeste Ponce ofici\u00f3 un encuentro en el Congreso argentino en el que participaron Eduardo Bolsonaro junto con los legisladores Julia Zanatta, Marcel van Hattem y Rodrigo Valadares, en el que denunciaron una supuesta persecuci\u00f3n pol\u00edtica y arrebatos contra la libertad de expresi\u00f3n en Brasil por parte del Gobierno de Da Silva en presunta connivencia con el Poder Judicial.<\/p>\n<p>Fue un encuentro de bajo perfil y muy poco difundido. Durante su exposici\u00f3n, Bolsonaro hijo se refiri\u00f3 a los \u201ccondenados o investigados injustamente\u201d -siempre seg\u00fan sus declaraciones- que estaban \u201cviniendo a Argentina como consecuencia de estas persecuciones\u201d. &#171;Nuestra generaci\u00f3n, con Mar\u00eda Celeste (Ponce), con (Javier) Milei, con todo el que est\u00e1 con (Donald) Trump en EE.UU. tiene la responsabilidad de poner basta (sic) a todo esto&#187;, agreg\u00f3.<\/p>\n<p>Despu\u00e9s, le toc\u00f3 el turno a Van Hattem, quien confirm\u00f3 que ya hab\u00eda pedidos de asilo pol\u00edtico en Argentina.<\/p>\n<p>Seg\u00fan un comunicado de la Polic\u00eda Federal de Brasil, que investiga el paradero de 159 pr\u00f3fugos, los acusados son responsables de \u201cabolici\u00f3n violenta del Estado democr\u00e1tico de derecho, golpe de Estado, da\u00f1os agravados, asociaci\u00f3n delictuosa, instigaci\u00f3n al delito, destrucci\u00f3n y deterioro o inutilizaci\u00f3n de bienes especialmente protegidos\u201d.<\/p>\n<p>CNN se contact\u00f3 con la diputada Ponce para pedir m\u00e1s detalles sobre la audiencia organizada en el Congreso Nacional argentino, pero respondi\u00f3 que no ten\u00eda tiempo de atender la consulta porque se encontraba viajando a Brasil para asistir a la cumbre de ultraderecha CPAC, en el balneario de Cambori\u00fa, con organizaci\u00f3n del bolsonarismo.<\/p>\n<p>\u00bfPodr\u00edan conseguir asilo pol\u00edtico los pr\u00f3fugos brasile\u00f1os en Argentina?<\/p>\n<p>Mart\u00edn Arias Duval, abogado integrante del Instituto de Pol\u00edtica Migratoria y Asilo (IMA) de la Universidad de Tres de Febrero, marca una diferencia: \u201cNo es lo mismo un pedido de asilo pol\u00edtico que un pedido de refugio\u201d.<\/p>\n<p>\u201cEl caso del asilo pol\u00edtico constituye una decisi\u00f3n discrecional del Estado que lo otorga y es \u00e9ste el que le brinda protecci\u00f3n al asilado, mientras que con el pedido de refugio, si bien la decisi\u00f3n tambi\u00e9n la toma cada Estado, la situaci\u00f3n tiene que encuadrar en las disposiciones de la Convenci\u00f3n de Ginebra relativa al Estatuto de los Refugiados\u201d, explica. \u201cQuien recibe el estatus de refugiado no solo recibe protecci\u00f3n del Estado que lo admite, sino del sistema internacional para la protecci\u00f3n de los refugiados, y el pa\u00eds en cuyo territorio se encuentra asume responsabilidad internacional por la seguridad del refugiado\u201d.<\/p>\n<p>Ante la consulta de CNN, desde la Jefatura de Gabinete derivaron el asunto a la Comisi\u00f3n Nacional para Refugiados (Conare).<\/p>\n<p>La Conare es el organismo gubernamental que analiza los pedidos de refugio, pero esta informaci\u00f3n es de car\u00e1cter confidencial por lo que no se conoce si efectivamente existen solicitudes en curso. Si las hubiera, durante el periodo de an\u00e1lisis, el solicitante goza de la condici\u00f3n de refugiado hasta tanto no se resuelva lo contrario y no hay un plazo establecido para dar una resoluci\u00f3n.<\/p>\n<p>La Comisi\u00f3n est\u00e1 integrada por funcionarios del Ministerio del Interior -actualmente absorbido por Jefatura de Gabinete-, del Ministerio de Relaciones Exteriores, Comercio Internacional y Culto, del Ministerio de Justicia, Seguridad y Derechos Humanos, del Ministerio de Desarrollo Social, del Instituto Nacional contra la Discriminaci\u00f3n, Xenofobia y el Racismo (Inadi) -organismo disuelto por la actual administraci\u00f3n-, del Alto Comisionado de Naciones Unidas para los Refugiados y de una organizaci\u00f3n no gubernamental sin fines de lucro. Estos dos \u00faltimos participan pero no tienen voto. Es decir que quienes resuelven los pedidos son miembros del Gobierno, salvo el Acnur.<\/p>\n<p>Ezequiel Silveira es abogado de la Asociaci\u00f3n de Familiares y V\u00edctimas del 8 de enero (Asfav) que busca amnist\u00eda para los imputados de las causas del asalto a edificios p\u00fablicos en Brasilia y fue uno de los invitados de Ponce al encuentro en el Congreso argentino a fines de mayo.<\/p>\n<p>Silveira dijo a CNN que durante su visita en Buenos Aires presentaron un informe a la Conare para que \u201clos documentos puedan sustentar las decisiones del gobierno argentino en la materia\u201d, es decir de los pedidos de refugio.<\/p>\n<p>El abogado aclar\u00f3 que no es representante de los brasile\u00f1os pr\u00f3fugos que se encuentran en el pa\u00eds, pero que en Asfav asisten cerca de 300 familias de \u201cpresos pol\u00edticos\u201d en Brasil, siempre seg\u00fan su testimonio.<br \/>\nSilveira y representantes de Asfav asistir\u00e1n al evento CPAC, al igual que Jair Bolsonaro y Javier Milei.<\/p>\n<p>S\u00ed a CPAC, no al Mercosur<\/p>\n<p>En el encuentro conservador de ultraderecha, se espera que Milei tenga una reuni\u00f3n con el expresidente de Brasil.<\/p>\n<p>Sin embargo, no asistir\u00e1 a la cumbre del Mercosur en Asunci\u00f3n, en donde estar\u00e1n sus pares de Brasil, Paraguay y Uruguay.<\/p>\n<p>Consultado al respecto, Adorni argument\u00f3 que la decisi\u00f3n de Milei nada ten\u00eda que ver con los entredichos de los \u00faltimos d\u00edas entre el presidente de Argentina y Lula da Silva, a quien volvi\u00f3 a tratar de corrupto y comunista despu\u00e9s de que el mandatario brasile\u00f1o dijera que esperaba unas disculpas por parte de su par argentino: \u201c\u00c9l dijo muchas estupideces, solo quiero que pida disculpas\u201d.<\/p>\n<p>\u00bfPuede la situaci\u00f3n de los pr\u00f3fugos bolsonaristas en Argentina romper definitivamente la relaci\u00f3n bilateral?<\/p>\n<p>El embajador brasile\u00f1o en Argentina, Julio Bitelli, explic\u00f3 a la prensa que \u201cno hay informaci\u00f3n de que Milei vaya a ayudar a brasile\u00f1os que huyeron\u201d al pa\u00eds y que dejaron \u201cclara la gravedad del asunto y hay un procedimiento legal a seguir&#187;.<\/p>\n<p>El expresidente de la Asociaci\u00f3n de Jueces para la Democracia de Brasil, Marcelo Semer, reflexiona en la misma l\u00ednea: \u201cNo creo que la cuesti\u00f3n de la proximidad entre Milei y Bolsonaro vaya a determinar que Milei le niegue la extradici\u00f3n. Pero es muy complicado para un presidente proteger a decenas de condenados o procesados por la justicia, ser\u00eda un est\u00edmulo a muchas personas para huir a la Argentina\u201d, dice a CNN.<\/p>\n<p>\u201cLa relaci\u00f3n entre Milei y Lula es terrible, pero creo que no hay un problema diplom\u00e1tico entre los pa\u00edses. Las relaciones entre Argentina y Brasil permanecen igual. Las disparidades son ret\u00f3ricas, son de propaganda, de pol\u00edtica\u201d, reflexiona.<\/p>\n<p>El pr\u00f3ximo paso de esta situaci\u00f3n es el pedido de extradici\u00f3n de los pr\u00f3fugos en Argentina, algo que la Corte Suprema de Brasil a\u00fan no realiz\u00f3, pero, seg\u00fan los especialistas, esto ocurre dentro de los tiempos procesales.<\/p>\n<p>Este fin de semana, Bolsonaro y Milei se encontrar\u00e1n cara a cara. El lunes, el presidente de Argentina ser\u00e1 el gran ausente en la capital paraguaya. Habr\u00e1 que prestar atenci\u00f3n. Una declaraci\u00f3n en falso podr\u00eda abrir un nuevo cap\u00edtulo m\u00e1s en la tensa relaci\u00f3n de Milei y Lula.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0Alrededor de 60 personas supuestamente involucradas en el intento de golpe de Estado en Brasil del 8 de enero de 2023 ingresaron a Argentina, al tiempo que el presidente de Argentina Javier Milei se niega a pedirle disculpas a su hom\u00f3logo Lula Da Silva y viaja a encontrarse con Jair Bolsonaro en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450913","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0Alrededor de 60 personas supuestamente involucradas en el intento de golpe de Estado en Brasil del 8 de enero de 2023 ingresaron a Argentina, al tiempo que el presidente de Argentina Javier Milei se niega a pedirle disculpas a su hom\u00f3logo Lula Da Silva y viaja a encontrarse con Jair Bolsonaro en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-06T01:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina\",\"datePublished\":\"2024-07-06T01:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\"},\"wordCount\":1507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\",\"name\":\"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-06T01:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0Alrededor de 60 personas supuestamente involucradas en el intento de golpe de Estado en Brasil del 8 de enero de 2023 ingresaron a Argentina, al tiempo que el presidente de Argentina Javier Milei se niega a pedirle disculpas a su hom\u00f3logo Lula Da Silva y viaja a encontrarse con Jair Bolsonaro en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-06T01:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/"},"author":{"name":"","@id":""},"headline":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina","datePublished":"2024-07-06T01:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/"},"wordCount":1507,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","name":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-06T01:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\u00edan pedir asilo pol\u00edtico en Argentina","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-06T01:03:44Z","datePublished":"2024-07-06T01:03:44Z","dateModified":"2024-07-06T01:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 60 personas investigadas por el intento de golpe en Brasil podr\\u00edan pedir asilo pol\\u00edtico en Argentina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/05\\\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/05\\\/investigados-intento-golpe-estado-brasil-asilo-politico-argentina-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-06T01:03:44Z\",\"datePublished\":\"2024-07-06T01:03:44Z\",\"dateModified\":\"2024-07-06T01:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455869,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/15\/ordenan-argentina-arrestar-brasilenos-intento-golpe-de-estado-orix\/","url_meta":{"origin":1450913,"position":0},"title":"Ordenan en Argentina arrestar a 61 brasile\u00f1os presuntamente vinculados con el intento de golpe de Estado de 2023","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Justicia de Argentina emiti\u00f3 \u00f3rdenes de arresto contra 61 brasile\u00f1os presuntamente vinculados con el intento de golpe de Estado del 8 de enero de 2023 en Brasilia, dijo a CNN este viernes una fuente del sistema judicial.Estas personas son se\u00f1aladas por la Justicia brasile\u00f1a de haber\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459910,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/13\/tribunal-brasil-denuncia-bolsonaro-por-intento-golpe-de-estado-orix\/","url_meta":{"origin":1450913,"position":1},"title":"El Supremo Tribunal de Brasil comenzar\u00e1 el 25 de marzo a analizar la denuncia contra Bolsonaro por intento de golpe de Estado","author":"","date":"marzo 13, 2025","format":false,"excerpt":"El Supremo Tribunal Federal de Brasil cit\u00f3 al 25 de marzo para comenzar el an\u00e1lisis de la denuncia contra el expresidente Jair Bolsonaro y otras siete personas por su presunta participaci\u00f3n en un intento de golpe de Estado.La revisi\u00f3n del caso estar\u00e1 a cargo del Primer Panel del Supremo Tribunal,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455994,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/21\/brasil-bolsonaro-golpe-estado-complot-matar-lula-trax\/","url_meta":{"origin":1450913,"position":2},"title":"Polic\u00eda federal de Brasil imputa a Bolsonaro y dice que el expresidente ten\u00eda &#171;pleno conocimiento&#187; de un complot para matar a Lula","author":"","date":"noviembre 21, 2024","format":false,"excerpt":"(CNN) -- La Polic\u00eda Federal de Brasil imput\u00f3 este jueves a 37 personas, entre ellas el expresidente Jair Bolsonaro, en el marco de la investigaci\u00f3n sobre un intento de golpe de Estado tras las elecciones presidenciales de 2022, en las que Bolsonaro fue derrotado, informa CNN Brasil.Seg\u00fan la Polic\u00eda Federal,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450832,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/01\/gobierno-bolivia-convoca-embajador-argentina-declaraciones-milei-intento-golpe-estado-orix\/","url_meta":{"origin":1450913,"position":3},"title":"El Gobierno de Bolivia convoca a su embajador en Argentina tras declaraciones de Milei sobre intento de golpe de Estado","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Bolivia convoc\u00f3 este lunes a consulta a su embajador en Argentina, Ramiro Tapia, ante las declaraciones de la Oficina del presidente Javier Milei que se\u00f1al\u00f3 como \u201cfalsa\u201d la denuncia de golpe de Estado del 26 de junio.La ministra de la Presidencia de Bolivia, Maria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458886,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/02\/18\/acusan-jair-bolsonaro-brasil-presunto-golpe-de-estado-trax\/","url_meta":{"origin":1450913,"position":4},"title":"Acusan al expresidente de Brasil Jair Bolsonaro en relaci\u00f3n con un presunto intento de golpe de Estado","author":"","date":"febrero 18, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro fue acusado en relaci\u00f3n con un intento de golpe de Estado, seg\u00fan documentos presentados por fiscales este martes por la noche.Bolsonaro estaba entre las 34 personas acusadas de cargos, incluidos los de organizaci\u00f3n criminal armada, intento de abolici\u00f3n violenta del estado de derecho democr\u00e1tico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456131,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/28\/policia-de-brasil-informe-supuesto-plan-para-matar-a-lula-bolsonaro-orix\/","url_meta":{"origin":1450913,"position":5},"title":"La Polic\u00eda de Brasil desclasifica extenso informe que detalla supuesto plan para matar a Lula y mantener a Bolsonaro en el poder","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Polic\u00eda Federal de Brasil desclasific\u00f3 este martes un informe de 884 p\u00e1ginas que detalla una supuesta trama golpista cuyo fin era matar al entonces presidente electo Luiz In\u00e1cio Lula da Silva, y sostiene que el entonces mandatario Jair Bolsonaro ten\u00eda pleno conocimiento de ella, el cual sustenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450913"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450913\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}