{"id":1450942,"date":"2024-07-07T19:03:44","date_gmt":"2024-07-08T02:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/"},"modified":"2024-07-07T19:03:44","modified_gmt":"2024-07-08T02:03:44","slug":"coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","title":{"rendered":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?"},"content":{"rendered":"<p>(CNN) &#8212; Hace un mes, el Nuevo Frente Popular (NFP) no exist\u00eda. Ahora gan\u00f3 la mayor\u00eda de los esca\u00f1os en el parlamento franc\u00e9s y podr\u00eda proporcionar a Francia su pr\u00f3ximo primer ministro.<\/p>\n<p>La coalici\u00f3n de izquierda eligi\u00f3 su nombre en un intento de resucitar el Frente Popular original que impidi\u00f3 que la ultraderecha llegara al poder en 1936. Tras la votaci\u00f3n en la segunda vuelta de este domingo, el NFP lo hizo nuevamente.<\/p>\n<p>Pero la coalici\u00f3n formada a toda prisa est\u00e1 compuesta por partidos pol\u00edticos dispares que no siempre jugaron limpio y han hecho campa\u00f1a con una plataforma de alto gasto p\u00fablico que asust\u00f3 a los mercados financieros y podr\u00eda llevar a Francia al caos econ\u00f3mico.<\/p>\n<p>Entonces, \u00bfqu\u00e9 es el NFP, qu\u00e9 representa y qui\u00e9nes son sus actores clave?<\/p>\n<p>\u00bfQui\u00e9nes conforman el NFP?<\/p>\n<p>El NFP est\u00e1 formado por varios partidos: el partido de ultraizquierda Francia Insumisa; el Partido Socialista, m\u00e1s moderado; el partido verde Ecologista; el Partido Comunista Franc\u00e9s; el partido de centroizquierda Place Publique, y otros partidos peque\u00f1os.<\/p>\n<p>Se form\u00f3 apenas unos d\u00edas despu\u00e9s de que el presidente Emmanuel Macron convocara elecciones parlamentarias anticipadas, a ra\u00edz de la vergonzosa derrota de su partido centrista ante el grupo de ultraderecha Agrupaci\u00f3n Nacional (RN) de Marine Le Pen en las elecciones al Parlamento Europeo del mes pasado.<\/p>\n<p>Estas son 5 conclusiones de las elecciones al Parlamento Europeo<\/p>\n<p>\u201cTras la derrota de su partido en las elecciones europeas, Emmanuel Macron opt\u00f3 por una apuesta en un momento en el que la ultraderecha est\u00e1 en su punto m\u00e1s poderoso y corre el riesgo de verla llegar al poder por primera vez desde Vichy\u201d, dijo el l\u00edder socialista Olivier Faure el mes pasado, en referencia al gobierno franc\u00e9s que colabor\u00f3 \u200b\u200bcon los ocupantes nazis durante la Segunda Guerra Mundial.<\/p>\n<p>\u201cS\u00f3lo una izquierda unida puede interponerse en su camino\u201d, afirm\u00f3.<\/p>\n<p>Una bandera francesa gigante dice &#171;Francia nace de la migraci\u00f3n&#187;, en un evento en la Plaza de la Rep\u00fablica en Par\u00eds. Cr\u00e9dito: Emmanuel Dunand\/AFP\/Getty Images.<\/p>\n<p>\u00bfQui\u00e9n est\u00e1 a cargo del NFP?<\/p>\n<p>Es dif\u00edcil saberlo. Cada partido celebr\u00f3 los resultados en sus propias sedes y en actos de campa\u00f1a separados, en lugar de hacerlo juntos. Antes de la segunda vuelta, no estaba claro a qui\u00e9n designar\u00eda la coalici\u00f3n para primer ministro.<\/p>\n<p>Su figura m\u00e1s prominente \u2013y divisiva\u2013 es Jean-Luc M\u00e9lenchon, un agitador populista de 72 a\u00f1os, quien fue l\u00edder durante mucho tiempo del partido Francia Insumisa.<\/p>\n<p>Francia Insumisa es el partido m\u00e1s grande dentro de la coalici\u00f3n, con 74 esca\u00f1os.<\/p>\n<p>Pero los l\u00edderes del partido Ensemble de Macron dijeron repetidamente que se negar\u00edan a trabajar con Francia Insumisa, y argumentaron que es tan extremista \u2013 y por lo tanto tan incapaz de gobernar \u2013 como el RN.<\/p>\n<p>Este lunes, Gabriel Attal anunci\u00f3 su intenci\u00f3n de dimitir como primer ministro, en un aparente ataque a Francia Insumisa: \u201cNinguna mayor\u00eda absoluta puede ser dirigida por los extremos. Se lo debemos al esp\u00edritu franc\u00e9s, tan profundamente apegado a la Rep\u00fablica y a sus valores\u201d.<\/p>\n<p>\u00bfCu\u00e1les son las funciones del Parlamento y del presidente en Francia?<\/p>\n<p>Las tres campa\u00f1as presidenciales de M\u00e9lenchon se vieron acosadas por acusaciones de antisemitismo. En una encuesta reciente realizada por Ifop entre votantes jud\u00edos franceses, el 57% afirm\u00f3 que abandonar\u00eda Francia si el partido de M\u00e9lenchon llegara a gobernar.<\/p>\n<p>Una cara m\u00e1s aceptable de la coalici\u00f3n podr\u00eda ser el socialista Faure o Rapha\u00ebl Glucksmann, el l\u00edder moderado de Place Publique y miembro del Parlamento Europeo.<\/p>\n<p>La gente se re\u00fane en la plaza de la Rep\u00fablica en Par\u00eds despu\u00e9s de la segunda vuelta electoral. Cr\u00e9dito: Louise Delmotte\/AP.<\/p>\n<p>\u00bfCu\u00e1les son las pol\u00edticas del NFP?<\/p>\n<p>En pol\u00edtica exterior, el NFP se comprometi\u00f3 a \u201creconocer inmediatamente\u201d un Estado palestino y presionar\u00e1 para que Israel y Hamas cesen el fuego en Gaza.<\/p>\n<p>El NFP hizo campa\u00f1a sobre una plataforma econ\u00f3mica expansiva, y prometi\u00f3 aumentar el salario m\u00ednimo mensual a \u20ac 1.600 euros (m\u00e1s de US$ 1.700) y limitar el precio de los alimentos esenciales, la electricidad, el combustible y el gas.<\/p>\n<p>Tambi\u00e9n se comprometi\u00f3 a desechar la reforma de las pensiones de Macron, una pol\u00edtica profundamente impopular que aument\u00f3 la edad de jubilaci\u00f3n francesa \u2013una de las m\u00e1s bajas del mundo occidental\u2013 de 62 a 64 a\u00f1os.<\/p>\n<p>Si bien estas promesas tuvieron apoyo populares, se hicieron en un momento en que Francia podr\u00eda estar encamin\u00e1ndose hacia un per\u00edodo de austeridad.<\/p>\n<p>Qui\u00e9n es Jordan Bardella, el joven de 28 a\u00f1os que podr\u00eda ser primer ministro de Francia y llevar a la extrema derecha al poder<\/p>\n<p>Francia tiene uno de los d\u00e9ficits m\u00e1s altos de la eurozona y ahora corre el riesgo de infringir las nuevas reglas fiscales de la Comisi\u00f3n Europea, que fueron suspendidas para ayudar a los pa\u00edses a recuperarse de la pandemia de covid-19 y la crisis energ\u00e9tica.<\/p>\n<p>Desde que Macron convoc\u00f3 a elecciones, los mercados financieros se asustaron, primero ante la perspectiva de un gobierno extremista y luego por las pol\u00edticas econ\u00f3micas de la ultraizquierda y la derecha, ya que el RN prometi\u00f3 tambi\u00e9n un programa fiscal expansivo.<\/p>\n<p>Como el NFP no logr\u00f3 suficientes esca\u00f1os como para formar una mayor\u00eda absoluta, tendr\u00e1 que formar otra coalici\u00f3n \u2013probablemente con Ensemble, que podr\u00eda tratar de diluir algunas de sus pol\u00edticas de gasto m\u00e1s radicales\u2013 para aprobar leyes. Es probable que este proceso sea frustrante, ya que varios partidos \u2013que tienen enormes divisiones ideol\u00f3gicas\u2013 tratar\u00e1n de encontrar un terreno com\u00fan.<\/p>\n<p>Xiaofei Xu y Saskya Vandoorne de CNN contribuyeron con este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Hace un mes, el Nuevo Frente Popular (NFP) no exist\u00eda. Ahora gan\u00f3 la mayor\u00eda de los esca\u00f1os en el parlamento franc\u00e9s y podr\u00eda proporcionar a Francia su pr\u00f3ximo primer ministro. La coalici\u00f3n de izquierda eligi\u00f3 su nombre en un intento de resucitar el Frente Popular original que impidi\u00f3 que la ultraderecha llegara al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450942","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Hace un mes, el Nuevo Frente Popular (NFP) no exist\u00eda. Ahora gan\u00f3 la mayor\u00eda de los esca\u00f1os en el parlamento franc\u00e9s y podr\u00eda proporcionar a Francia su pr\u00f3ximo primer ministro. La coalici\u00f3n de izquierda eligi\u00f3 su nombre en un intento de resucitar el Frente Popular original que impidi\u00f3 que la ultraderecha llegara al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T02:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?\",\"datePublished\":\"2024-07-08T02:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\"},\"wordCount\":1027,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\",\"name\":\"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-08T02:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias","og_description":"(CNN) &#8212; Hace un mes, el Nuevo Frente Popular (NFP) no exist\u00eda. Ahora gan\u00f3 la mayor\u00eda de los esca\u00f1os en el parlamento franc\u00e9s y podr\u00eda proporcionar a Francia su pr\u00f3ximo primer ministro. La coalici\u00f3n de izquierda eligi\u00f3 su nombre en un intento de resucitar el Frente Popular original que impidi\u00f3 que la ultraderecha llegara al [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-08T02:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?","datePublished":"2024-07-08T02:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/"},"wordCount":1027,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","name":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-08T02:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es la coalici\u00f3n de izquierda NFP y qui\u00e9n ser\u00e1 el pr\u00f3ximo primer ministro de Francia?","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-08T02:03:44Z","datePublished":"2024-07-08T02:03:44Z","dateModified":"2024-07-08T02:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es la coalici\\u00f3n de izquierda NFP y qui\\u00e9n ser\\u00e1 el pr\\u00f3ximo primer ministro de Francia?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/07\\\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/07\\\/coalicion-izquierda-nfp-proximo-primer-ministro-francia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-08T02:03:44Z\",\"datePublished\":\"2024-07-08T02:03:44Z\",\"dateModified\":\"2024-07-08T02:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451163,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/16\/francia-macron-acepta-renuncia-primer-ministro-attal-trax\/","url_meta":{"origin":1450942,"position":0},"title":"El presidente de Francia Emmanuel Macron acepta la renuncia de su primer ministro Gabriel Attal, sin un sucesor a la vista","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) -- El primer ministro franc\u00e9s, Gabriel Attal, renunci\u00f3 este martes, pero permanecer\u00e1 en el cargo para encabezar un gobierno interino.Attal\u00a0 ofreci\u00f3 su renuncia la semana pasada despu\u00e9s de que la alianza centrista Ensemble del presidente Emmanuel Macron fuera derrotada en la segunda vuelta de las elecciones parlamentarias anticipadas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450943,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/resultados-elecciones-legislativas-francia-derrota-ultraderecha-macron-le-pen-melenchon-bardella-trax\/","url_meta":{"origin":1450942,"position":1},"title":"Resultados elecciones legislativas de Francia: derrota de la ultraderecha, pero ning\u00fan partido logra mayor\u00eda absoluta","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- Una alianza de izquierda gan\u00f3 la mayor cantidad de esca\u00f1os en el parlamento franc\u00e9s despu\u00e9s de que la votaci\u00f3n en la segunda vuelta de las elecciones del domingo frustrara al partido de ultraderecha de Marine Le Pen, pero Francia quedar\u00e1 en un limbo pol\u00edtico despu\u00e9s de que ning\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450809,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/06\/30\/macron-derrota-primera-vuelta-elecciones-legislativas-francia-trax\/","url_meta":{"origin":1450942,"position":2},"title":"La ultraderecha lidera en la primera vuelta de las elecciones legislativas en Francia en un golpe a Macron, seg\u00fan las proyecciones","author":"","date":"junio 30, 2024","format":false,"excerpt":"(CNN) -- El partido ultraderechista Agrupaci\u00f3n Nacional (RN) de Marine Le Pen tom\u00f3 la delantera en la primera vuelta de las elecciones legislativas de Francia de este domingo, seg\u00fan las primeras proyecciones, mientras que el partido del presidente Emmanuel Macron cay\u00f3 al tercer puesto.AN\u00c1LISIS | Por qu\u00e9 la juventud europea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450929,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/07\/se-abren-urnas-para-segunda-vuelta-de-las-elecciones-parlamentarias-francia-trax\/","url_meta":{"origin":1450942,"position":3},"title":"Los votantes franceses acuden a las urnas para la crucial segunda vuelta de las elecciones parlamentarias anticipadas","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- Los votantes se dirigen a las urnas en toda Francia para votar en la segunda vuelta de una elecci\u00f3n anticipada convocada por el presidente Emmanuel Macron , quien corre el riesgo de perder franjas de sus aliados centristas en el parlamento y verse obligado a pasar los tres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451033,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/macron-insta-coalicion-mayoritaria-parece-descartar-trabajar-con-extrema-izquierda-trax\/","url_meta":{"origin":1450942,"position":4},"title":"Macron insta a una nueva coalici\u00f3n mayoritaria y parece descartar trabajar con la extrema izquierda","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN) -- Tres d\u00edas despu\u00e9s de que la segunda vuelta de las elecciones legislativas francesas terminara en un punto muerto, el presidente Emmanuel Macron rompi\u00f3 su silencio para instar a los partidos mayoritarios a formar una mayor\u00eda s\u00f3lida en la Asamblea Nacional y dejar fuera a los extremos.La votaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450888,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/04\/mbappe-primera-vuelta-elecciones-francia-derecha-trax\/","url_meta":{"origin":1450942,"position":5},"title":"Kylian Mbapp\u00e9 califica de &#171;catastr\u00f3fica&#187; la primera vuelta de las elecciones en Francia tras el giro del pa\u00eds hacia la extrema derecha","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- La estrella del f\u00fatbol Kylian Mbapp\u00e9 calific\u00f3 de \"catastr\u00f3fica\" la primera vuelta de las elecciones de Francia despu\u00e9s de que los resultados del domingo pasado vieran al pa\u00eds tambalearse hacia la extrema derecha ya que el partido antiinmigraci\u00f3n Agrupaci\u00f3n Nacional (RN) lider\u00f3 el primer lugar.El capit\u00e1n de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450942"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450942\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}