{"id":1450956,"date":"2024-07-08T16:03:40","date_gmt":"2024-07-08T23:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/"},"modified":"2024-07-08T16:03:40","modified_gmt":"2024-07-08T23:03:40","slug":"bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","title":{"rendered":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Estaba destinado a ser uno de los aviones m\u00e1s avanzados de su \u00e9poca, acabar con la amenaza de los bombarderos nucleares sovi\u00e9ticos y convertir a Canad\u00e1 en l\u00edder mundial de la aviaci\u00f3n y la ingenier\u00eda militares.<\/p>\n<p>El Avro Arrow, tambi\u00e9n conocido como CF-105, ten\u00eda mucho en juego.<\/p>\n<p>Sin embargo, el sue\u00f1o se convirti\u00f3 en pesadilla cuando el programa se cancel\u00f3 menos de un a\u00f1o despu\u00e9s del primer vuelo del avi\u00f3n, y mucho antes de que entrara en servicio.<\/p>\n<p>A d\u00eda de hoy, 65 a\u00f1os despu\u00e9s, el Avro Arrow sigue siendo uno de los mayores pesares colectivos de Canad\u00e1 y sigue alimentando el discurso p\u00fablico, ya que documentos recientemente desvelados han arrojado algo de luz sobre lo que ocurri\u00f3 exactamente con el condenado proyecto.<\/p>\n<p>&#171;Este avi\u00f3n era completamente canadiense&#187;, afirma Richard Mayne, historiador jefe de la Real Fuerza A\u00e9rea Canadiense, &#171;y los marcadores de rendimiento durante su desarrollo demostraban con creces que estaba, como m\u00ednimo, a la altura de los dise\u00f1os m\u00e1s avanzados de la \u00e9poca&#187;.<\/p>\n<p>&#171;Cuando se cancel\u00f3, fue uno de los momentos &#8216;y si&#8230;&#8217; de Canad\u00e1&#187;, a\u00f1ade. &#171;El Arrow sigue teniendo un gran peso en nuestra psique nacional&#187;.<\/p>\n<p>Amenaza de la Guerra Fr\u00eda<\/p>\n<p>Se construyeron un total de seis Arrows, pero ninguno sobrevive intacto, ya que fueron destruidos intencionadamente para evitar cualquier forma de espionaje por parte de la Uni\u00f3n Sovi\u00e9tica. Cr\u00e9dito: DND Image\/Archivo de Historia y Patrimonio de la RCAF<\/p>\n<p>El Avro Arrow fue una respuesta directa a la amenaza percibida de la Uni\u00f3n Sovi\u00e9tica, tras el final de la Segunda Guerra Mundial, de bombarderos capaces de sobrevolar el \u00c1rtico y llegar a Norteam\u00e9rica con una carga nuclear.<\/p>\n<p>&#171;La Real Fuerza A\u00e9rea Canadiense solicit\u00f3 en 1952 un interceptor capaz de alcanzar una velocidad de Mach 2 y una altitud de 50.000 pies&#187;, explica Mayne a CNN.<\/p>\n<p>&#171;Necesitaban algo r\u00e1pido que tuviera el alcance y la altitud para interceptar estos bombarderos sovi\u00e9ticos lo m\u00e1s al norte posible, antes de que llegaran a Canad\u00e1&#187;.<\/p>\n<p>El fabricante de aviones Avro Canada acababa de poner en servicio con \u00e9xito el CF-100 Canuck, un caza bimotor vers\u00e1til dise\u00f1ado y construido en Canad\u00e1, y se le encarg\u00f3 desarrollar una versi\u00f3n mucho m\u00e1s avanzada del mismo.<\/p>\n<p>Era un plan ambicioso que llegaba en un momento importante para Canad\u00e1.<\/p>\n<p>&#171;El pa\u00eds hab\u00eda salido de la Segunda Guerra Mundial como un actor importante&#187;, dice Mayne. &#171;Ten\u00edamos la tercera armada del mundo y la cuarta fuerza a\u00e9rea. Pero la ciudadan\u00eda canadiense no existi\u00f3 hasta 1947: Canad\u00e1 acababa de alcanzar la mayor\u00eda de edad&#187;.<\/p>\n<p>El desarrollo comenz\u00f3 en 1955 y, en un tiempo r\u00e9cord, el primer Arrow se present\u00f3 al p\u00fablico el 4 de octubre de 1957, el mismo d\u00eda del lanzamiento del Sputnik I, el primer sat\u00e9lite artificial del mundo, que marc\u00f3 el inicio de la era espacial.<\/p>\n<p>&#171;Fue una coincidencia&#187;, dice Mayne, &#171;pero horrible, porque el Sputnik demostr\u00f3 que se pod\u00eda poner una carga nuclear en el cohete que lo pon\u00eda en \u00f3rbita. Y el Arrow no podr\u00eda hacer nada contra los misiles bal\u00edsticos intercontinentales&#187;.<\/p>\n<p>Condenado desde el inicio<\/p>\n<p>El Arrow med\u00eda 23,70 m (77 pies 9 pulgadas) de largo, 15 m (50 pies) de envergadura y 6,45 m (21 pies 2 pulgadas) de altura, por lo que era m\u00e1s grande que el caza estadounidense de la misma \u00e9poca Phantom F-4. Cr\u00e9dito: DND Image\/Archivo de Historia y Patrimonio de la RCAF<\/p>\n<p>El Arrow, concebido para una tripulaci\u00f3n de dos personas y dotado de un dise\u00f1o de ala &#171;delta&#187; y una librea blanca que le confer\u00eda un aspecto elegante, med\u00eda algo menos de 23,7 m (78 pies) de largo y una envergadura de 15 m (50 pies), lo que lo hac\u00eda comparativamente m\u00e1s grande que su predecesor, el CF-100 Canuck, y que el Phantom F4, un avi\u00f3n de combate estadounidense dominante que entrar\u00eda en servicio en 1961.<\/p>\n<p>As\u00ed es el \u00e9pico vuelo del bombardero B-52 que Estados Unidos quiere que Rusia conozca<\/p>\n<p>Vol\u00f3 por primera vez el 25 de marzo de 1958, pero para entonces, dice Mayne, los pensadores estrat\u00e9gicos, el personal militar de alto rango y los pol\u00edticos ya cre\u00edan que el mundo hab\u00eda entrado en un escenario de guerra de &#171;pulsar un bot\u00f3n&#187;, donde la amenaza nuclear se limitaba a los misiles de largo alcance, y los interceptores y bombarderos ya no desempe\u00f1aban un papel dominante.<\/p>\n<p>&#171;Eso result\u00f3 ser falso, porque la amenaza de los bombarderos continu\u00f3 y contin\u00faa hasta el d\u00eda de hoy, pero esa era la idea en ese momento&#187;, dice Mayne.<\/p>\n<p>El avi\u00f3n hab\u00eda perdido relevancia, y los costos exorbitantes del proyecto y el cambiante clima pol\u00edtico hicieron el resto.<\/p>\n<p>El 29 de febrero de 1959, el primer ministro John Diefenbaker cancel\u00f3 el programa, y en pocas semanas los cinco aviones que se hab\u00edan construido, junto con la mayor parte de la cadena de montaje, fueron destruidos por temor a que pudieran ser objeto de espionaje sovi\u00e9tico. Como consecuencia, se perdieron miles de empleos y Avro Canada acab\u00f3 hundi\u00e9ndose por completo.<\/p>\n<p>&#171;Si el Reino Unido hubiera comprado algunos Arrows, el programa se habr\u00eda salvado&#187;, afirma Mayne.<\/p>\n<p>&#171;Pero sin contratos extranjeros, nuestro pa\u00eds era demasiado peque\u00f1o para mantener una tecnolog\u00eda tan avanzada. Apunt\u00e1bamos a las estrellas, lo cual es ir\u00f3nico porque muchos ingenieros de Avro fueron m\u00e1s tarde a la NASA y ayudaron en el programa Apolo.&#187;<\/p>\n<p>Una vida propia<\/p>\n<p>El dise\u00f1o del avi\u00f3n estaba dominado por las grandes alas &#171;delta&#187;, destinadas a facilitar el vuelo a velocidades supers\u00f3nicas a expensas de la maniobrabilidad a bajas velocidades. Cr\u00e9dito: DND Image \/Archivo de Historia y Patrimonio de la RCAF<\/p>\n<p>Inmediatamente comenzaron a surgir rumores y mitos en torno a las razones de la abrupta cancelaci\u00f3n del programa, algunos de los cuales persisten hasta el d\u00eda de hoy.<\/p>\n<p>&#171;El avi\u00f3n ha adquirido un car\u00e1cter casi mitol\u00f3gico en Canad\u00e1&#187;, afirma Alan Barnes, profesor de la Universidad Carleton de Ottawa que ha estudiado el papel desempe\u00f1ado por los servicios de inteligencia en la decisi\u00f3n de detener el desarrollo del avi\u00f3n.<\/p>\n<p>Una serie de mitos, seg\u00fan Barnes, culpa esencialmente a Estados Unidos de enga\u00f1ar a Canad\u00e1 sobre la cambiante amenaza sovi\u00e9tica, supuestamente porque no quer\u00edan que Canad\u00e1 produjera un avi\u00f3n que superara a los estadounidenses.<\/p>\n<p>Otro dice que los analistas de inteligencia canadienses malinterpretaron deliberadamente la informaci\u00f3n para apoyar una decisi\u00f3n que el gobierno hab\u00eda tomado esencialmente, proporcionando una excusa para ello.<\/p>\n<p>&#171;Pero todo esto eran especulaciones, ya que nadie hab\u00eda visto realmente los informes de inteligencia&#187;, afirma.<\/p>\n<p>Pero en 2023, Barnes public\u00f3 un art\u00edculo sobre esos informes, tras recuperar documentos de archivo que muestran un claro v\u00ednculo entre la inteligencia y c\u00f3mo la utilizaron los responsables de la \u00e9poca.<\/p>\n<p>&#171;Al principio, la Fuerza A\u00e9rea realmente no prestaba ninguna atenci\u00f3n a la inteligencia&#187;, dice a CNN. &#171;Decidieron que quer\u00edan un nuevo avi\u00f3n grande y elegante, as\u00ed que idearon todos los requisitos operativos en gran medida de forma aislada, sin prestar realmente atenci\u00f3n a lo que dec\u00edan los informes&#187;.<\/p>\n<p>El \u00faltimo Arrow que se construy\u00f3, el 206 de la foto, fue el primero en recibir motores m\u00e1s potentes dise\u00f1ados espec\u00edficamente para \u00e9l, pero el programa se cancel\u00f3 antes de que pudiera volar. Cr\u00e9dito: DND Image\/Archivo de Historia y Patrimonio de la RCAF<\/p>\n<p>A finales de la d\u00e9cada de 1950, a\u00f1ade, la flecha Arrow se estaba volviendo muy cara y bastante retrasada.<\/p>\n<p>&#171;A principios de 1958, los servicios de inteligencia canadienses elaboraron una evaluaci\u00f3n de muy alta calidad en la que se afirmaba que la amenaza de los bombarderos no era ni mucho menos tan grave como se pensaba, y que los sovi\u00e9ticos no estaban creando una fuerza masiva de bombarderos y probablemente orientar\u00edan su producci\u00f3n e investigaci\u00f3n hacia los misiles&#187;, explica Barnes.<\/p>\n<p>La implicaci\u00f3n pol\u00edtica era que si se estaba reduciendo la amenaza, hab\u00eda muy pocas razones para gastar tanto dinero en un avi\u00f3n que no podr\u00eda hacer frente a los misiles bal\u00edsticos.<\/p>\n<p>&#171;En el verano de 1958, la Comisi\u00f3n de Jefes de Estado Mayor lleg\u00f3 a la conclusi\u00f3n de que no pod\u00edan seguir recomendando la continuaci\u00f3n del programa, pero no quer\u00edan cancelarlo en ese momento por sus repercusiones pol\u00edticas&#187;, explica Barnes.<\/p>\n<p>&#171;En cierto modo, retrasaron las cosas hasta principios de 1959, cuando todav\u00eda se ve\u00eda p\u00fablicamente como un desastre para la industria canadiense, adem\u00e1s de un esc\u00e1ndalo pol\u00edtico. El gobierno hizo lo que ten\u00eda que hacer, pero le explot\u00f3 en la cara. Perdieron las elecciones un par de a\u00f1os despu\u00e9s, en cierta medida por estas cuestiones de defensa&#187;.<\/p>\n<p>Seg\u00fan Barnes, el avi\u00f3n nunca fue tan bueno como la gente hac\u00eda creer.<\/p>\n<p>&#171;Se cancel\u00f3 en el momento justo para mantener este tipo de mitolog\u00eda&#187;, afirma. &#171;Nunca vol\u00f3 con ninguno de sus armamentos ni con los motores reales para los que fue dise\u00f1ado. Todo era potencial, as\u00ed que muchos canadienses a\u00fan pueden fingir que \u00e9ste habr\u00eda sido el mejor avi\u00f3n del mundo&#187;.<\/p>\n<p>Impacto duradero<\/p>\n<p>Una r\u00e9plica del malogrado Avro Arrow, vista aqu\u00ed expuesta en 2013, fue construida por voluntarios del Museo Canadiense del Aire y el Espacio. Cr\u00e9dito: Keith Beaty\/Toronto Star\/Getty Images<\/p>\n<p>En 1997, la CBC (Canadian Broadcasting Corporation) encarg\u00f3 una miniserie de televisi\u00f3n sobre el avi\u00f3n titulada &#171;The Arrow&#187;, protagonizada por Dan Aykroyd en el papel de Crawford Gordon, presidente de Avro Canada. Para la producci\u00f3n se construy\u00f3 un modelo de madera a tama\u00f1o real del avi\u00f3n, que actualmente se conserva en los archivos del Museo Reynolds de Wetaskiwin en Alberta.<\/p>\n<p>Otro modelo, fabricado en aluminio de calidad aeron\u00e1utica, est\u00e1 expuesto en el aeropuerto de Edenvale, cerca de Muskoka, Ontario. Un tercer modelo, aproximadamente dos tercios del tama\u00f1o de un Arrow real, se est\u00e1 construyendo en el aeropuerto de Springbank, en Calgary, pero \u00e9ste est\u00e1 pensado para volar de verdad. Es el proyecto apasionante de un grupo de ingenieros que esperan llevarlo a los cielos en 2026.<\/p>\n<p>Aunque ninguno de los Arrows reales sobrevivi\u00f3 intacto, la cabina y el morro originales de uno de ellos, as\u00ed como partes de las alas de otro, est\u00e1n expuestos en el Museo de la Aviaci\u00f3n y el Espacio de Canad\u00e1, en Ottawa.<\/p>\n<p>Tal vez el indicio m\u00e1s fuerte de la obsesi\u00f3n de Canad\u00e1 con el Arrow se produjo en 2018, cuando despu\u00e9s de un a\u00f1o de b\u00fasqueda, se recuperaron modelos de Arrow hundidos en el fondo del lago Ontario. Los modelos fueron disparados a trav\u00e9s del lago como parte de las pruebas de vuelo a mediados de la d\u00e9cada de 1950, y numerosos grupos los hab\u00edan estado buscando antes sin \u00e9xito.<\/p>\n<p>John Burzynski, un empresario minero canadiense, financi\u00f3 el proyecto.<\/p>\n<p>&#171;La importancia del hallazgo radica en que recuerda a los canadienses el gran esfuerzo que supuso dise\u00f1ar, probar, construir y hacer volar un avi\u00f3n de tecnolog\u00eda avanzada, todo ello en un breve plazo de seis a\u00f1os&#187;, afirma Burzynski, quien a\u00f1ade que entre las piezas descubiertas se encuentra uno de los primeros modelos de prueba, pr\u00e1cticamente intacto, que ahora se expone en el Museo Canadiense de la Aviaci\u00f3n y el Espacio de Ottawa.<\/p>\n<p>Hablando de la importancia y el papel del Arrow en la historia de Canad\u00e1, Burzynski dice que todo era posible para la generaci\u00f3n que sigui\u00f3 a la Segunda Guerra Mundial, y el mundo estaba cambiando r\u00e1pidamente.<\/p>\n<p>&#171;El enorme esfuerzo que se dedic\u00f3 al programa Arrow fue esencialmente un ejercicio en vivo, demostrando que todo es posible cuando se aplica suficiente esfuerzo e ingenio a un problema&#187;, afirma. &#171;A muchos les parece que habr\u00eda sido un punto de inflexi\u00f3n para que Canad\u00e1 desarrollara un vigoroso programa a\u00e9reo y posiblemente incluso espacial, si no se hubiera cancelado abruptamente&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Estaba destinado a ser uno de los aviones m\u00e1s avanzados de su \u00e9poca, acabar con la amenaza de los bombarderos nucleares sovi\u00e9ticos y convertir a Canad\u00e1 en l\u00edder mundial de la aviaci\u00f3n y la ingenier\u00eda militares. El Avro Arrow, tambi\u00e9n conocido como CF-105, ten\u00eda mucho en juego. Sin embargo, el sue\u00f1o se convirti\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450956","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Estaba destinado a ser uno de los aviones m\u00e1s avanzados de su \u00e9poca, acabar con la amenaza de los bombarderos nucleares sovi\u00e9ticos y convertir a Canad\u00e1 en l\u00edder mundial de la aviaci\u00f3n y la ingenier\u00eda militares. El Avro Arrow, tambi\u00e9n conocido como CF-105, ten\u00eda mucho en juego. Sin embargo, el sue\u00f1o se convirti\u00f3 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T23:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional\",\"datePublished\":\"2024-07-08T23:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\"},\"wordCount\":2082,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\",\"name\":\"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-08T23:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias","og_description":"(CNN) &#8212;\u00a0Estaba destinado a ser uno de los aviones m\u00e1s avanzados de su \u00e9poca, acabar con la amenaza de los bombarderos nucleares sovi\u00e9ticos y convertir a Canad\u00e1 en l\u00edder mundial de la aviaci\u00f3n y la ingenier\u00eda militares. El Avro Arrow, tambi\u00e9n conocido como CF-105, ten\u00eda mucho en juego. Sin embargo, el sue\u00f1o se convirti\u00f3 en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-08T23:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional","datePublished":"2024-07-08T23:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/"},"wordCount":2082,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","name":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-08T23:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo el bombardero supers\u00f3nico Avro Arrow so\u00f1ado por Canad\u00e1 se convirti\u00f3 en una pesadilla nacional","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-08T23:03:40Z","datePublished":"2024-07-08T23:03:40Z","dateModified":"2024-07-08T23:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo el bombardero supers\\u00f3nico Avro Arrow so\\u00f1ado por Canad\\u00e1 se convirti\\u00f3 en una pesadilla nacional\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/bombardero-supersonico-avro-arrow-canada-pesadilla-nacional-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-08T23:03:40Z\",\"datePublished\":\"2024-07-08T23:03:40Z\",\"dateModified\":\"2024-07-08T23:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472486,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/03\/24\/accidente-avion-laguardia-air-canada-trax\/","url_meta":{"origin":1450956,"position":0},"title":"\u00bfQu\u00e9 pas\u00f3 con el avi\u00f3n de Air Canada y c\u00f3mo se estrell\u00f3 en el aeropuerto LaGuardia con un cami\u00f3n?","author":"","date":"marzo 24, 2026","format":false,"excerpt":"Un avi\u00f3n de Air Canada colision\u00f3 con un veh\u00edculo de emergencia en la pista del aeropuerto LaGuardia de la ciudad de Nueva York a altas horas de la noche del domingo, causando la muerte de dos pilotos e hiriendo a decenas de personas, entre ellas una azafata que sali\u00f3 despedida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449670,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/22\/se-desato-el-infierno-pasajeros-del-vuelo-de-singapore-airlines-describen-una-pesadilla-trax\/","url_meta":{"origin":1450956,"position":1},"title":"&#171;Se desat\u00f3 el infierno&#187;: los pasajeros del vuelo de Singapore Airlines describen una pesadilla a 11.300 metros","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) --\u00a0\u00a0 Los pasajeros de un vuelo de Singapore Airlines afectado por graves turbulencias este martes describieron una ca\u00edda repentina y dram\u00e1tica cuando \u201cse desat\u00f3 el infierno\u201d a bordo del avi\u00f3n Boeing que transportaba a 229 pasajeros y tripulaci\u00f3n.El vuelo SQ321 navegaba a 11.300 metros de Londres a Singapur cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449664,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/22\/se-desato-el-infierno-pasajeros-del-vuelo-de-singapore-airlines-describen-una-pesadilla-a-37-000-pies-trax\/","url_meta":{"origin":1450956,"position":2},"title":"&#171;Se desat\u00f3 el infierno&#187;: los pasajeros del vuelo de Singapore Airlines describen una pesadilla a 37.000 pies","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) --\u00a0\u00a0 Los pasajeros de un vuelo de Singapore Airlines afectado por graves turbulencias este martes describieron una ca\u00edda repentina y dram\u00e1tica cuando \u201cse desat\u00f3 el infierno\u201d a bordo del avi\u00f3n Boeing que transportaba a 229 pasajeros y tripulaci\u00f3n.El vuelo SQ321 navegaba a 37.000 pies de Londres a Singapur cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462252,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/05\/12\/air-force-one-avion-qatar-asuntos-legales-trax\/","url_meta":{"origin":1450956,"position":3},"title":"\u00bfDonaci\u00f3n? \u00bfRegalo? Asuntos legales del avi\u00f3n de Qatar para que sea el Air Force One est\u00e1n por resolverse, dice Casa Blanca","author":"","date":"mayo 12, 2025","format":false,"excerpt":"La secretaria de prensa de la Casa Blanca, Karoline Leavitt, dijo este lunes que los detalles legales sobre la aceptaci\u00f3n de un jet Boeing 747-8 para reemplazar el Air Force One como un regalo de la familia real catar\u00ed \u201ca\u00fan se est\u00e1n trabajando\u201d.\u201cCualquier donaci\u00f3n a este gobierno siempre se realiza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447317,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","url_meta":{"origin":1450956,"position":4},"title":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) -- Los informes de incidentes aterradores y a veces tr\u00e1gicos a bordo de aviones se aceleraron este a\u00f1o, llevando a muchos a preguntarse si todav\u00eda es seguro volar.Un tap\u00f3n de puerta se desprendi\u00f3 en un vuelo de Alaska Airlines dejando un agujero enorme en el fuselaje del Boeing 737\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449729,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/23\/heridos-turbulento-vuelo-singapore-airlines-lesiones-medulares-trax\/","url_meta":{"origin":1450956,"position":5},"title":"M\u00e1s de 20 heridos en un turbulento vuelo de Singapore Airlines tienen lesiones medulares, seg\u00fan un hospital","author":"","date":"mayo 23, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de 20 personas a bordo de un vuelo de Singapore Airlines que sufri\u00f3 fuertes turbulencias el martes permanecen en cuidados intensivos con lesiones medulares, cerebrales y craneales, seg\u00fan un hospital de Bangkok que atendi\u00f3 a algunos de los pasajeros.El hospital Samitivej Srinakarin de la capital tailandesa est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450956"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450956\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}