{"id":1450964,"date":"2024-07-08T17:03:48","date_gmt":"2024-07-09T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/"},"modified":"2024-07-08T17:03:48","modified_gmt":"2024-07-09T00:03:48","slug":"tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","title":{"rendered":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva"},"content":{"rendered":"<p>(CNN) &#8212; Los Juegos Ol\u00edmpicos estar\u00e1n repletos de im\u00e1genes emblem\u00e1ticas de Par\u00eds: la Torre Eiffel, Versalles, el puente Alejandro III y el H\u00f4tel des Invalides ser\u00e1n los protagonistas.<\/p>\n<p>Pero uno de los escenarios m\u00e1s impresionantes de la competici\u00f3n cuatrienal no estar\u00e1 en Par\u00eds ni en Francia. Ni siquiera estar\u00e1 en el mismo hemisferio.<\/p>\n<p>Las mundialmente famosas olas de Teahupo&#8217;o, en Tahit\u00ed, ser\u00e1n uno de los escenarios m\u00e1s pintorescos y singulares de los pr\u00f3ximos Juegos, cuando la isla se convierta en sede de la competici\u00f3n de surf, que dar\u00e1 comienzo el 27 de julio.<\/p>\n<p>Calendario de los Juegos Ol\u00edmpicos de Par\u00eds 2024: horarios, competiciones y fechas<\/p>\n<p>La selecci\u00f3n de Tahit\u00ed cumple uno de los compromisos de los organizadores de Par\u00eds, que prometieron extender las Olimpiadas por todo el territorio franc\u00e9s. Tahit\u00ed se convirti\u00f3 en colonia francesa en 1880 y ahora est\u00e1 clasificada como pa\u00eds aut\u00f3nomo de ultramar de la Rep\u00fablica Francesa.<\/p>\n<p>Mientras que otras ciudades francesas acogen competiciones de f\u00fatbol, baloncesto y otras competiciones de alto nivel, la elecci\u00f3n de la isla m\u00e1s grande de la Polinesia Francesa para celebrar la competici\u00f3n de surf ha dado lugar a una de las sedes m\u00e1s singulares y controvertidas de esta edici\u00f3n de los Juegos Ol\u00edmpicos.<\/p>\n<p>Pero es un lugar muy conocido en la comunidad surfera, ya que el oleaje de la costa suroccidental de Tahit\u00ed forma parte desde hace tiempo de las paradas del circuito de competici\u00f3n.<\/p>\n<p>Teahupo&#8217;o, situada a unos 15.600 kil\u00f3metros de Par\u00eds y a 21 horas de vuelo, ser\u00e1 una de las sedes ol\u00edmpicas m\u00e1s lejanas de la historia.<br \/>\n&#171;Este es un lugar m\u00e1gico, y las olas de Teahupo&#8217;o son impresionantes&#187;, dijo el presidente de Par\u00eds 2024, Tony Estanguet, tras una visita al lugar del evento en 2022. &#171;Nuestra visi\u00f3n siempre ha sido proporcionar las condiciones m\u00e1s espectaculares para los surfistas y el deporte. No tengo ninguna duda de que Tahit\u00ed cumplir\u00e1 esa visi\u00f3n&#187;.<\/p>\n<p>Teahupo&#8217;o fue seleccionado tercero en la lista de CNN de los 50 mejores lugares para surfear en el mundo en 2013, descrito como un paseo corto e intenso que crea olas incre\u00edbles para el surf. El nombre significa &#171;Muro de Cabezas&#187; y puede ser peligroso.<\/p>\n<p>Dado que la ubicaci\u00f3n de la competici\u00f3n de los Juegos lleva mucho tiempo en el circuito mundial de surf, hace tiempo que cuenta con una torre de madera que se construye para las competiciones en la laguna frente a la costa.<\/p>\n<p>Es esta torre de arbitraje &#8211;y la determinaci\u00f3n de que no iba a cumplir con las expectativas de seguridad de la competici\u00f3n ol\u00edmpica, especialmente el arbitraje y la cobertura de las transmisiones&#8211; lo que ha desatado una pol\u00e9mica en Tahit\u00ed y en los c\u00edrculos del surf.<\/p>\n<p>En cambio, los organizadores ol\u00edmpicos construyeron una torre de aluminio en la laguna que se ha convertido en una fuente de escrutinio durante toda la preparaci\u00f3n de los Juegos Ol\u00edmpicos.<\/p>\n<p>Presentaron podios ecol\u00f3gicos para los Juegos Ol\u00edmpicos de Par\u00eds 2024<\/p>\n<p>Tras anunciar inicialmente sus planes de construir una torre de 14 toneladas y 150 metros cuadrados con espacio para 40 personas y conexiones de agua potable y aguas residuales, el equipo de Par\u00eds 2024 anunci\u00f3 el a\u00f1o pasado que reducir\u00eda el proyecto tras las reacciones en contra.<\/p>\n<p>&#171;Dado que la actual torre de jueces no cumple las normas de seguridad vigentes, dejar\u00e1 de utilizarse y deber\u00e1 ser sustituida si Teahupo&#8217;o quiere seguir organizando pruebas de surf, ya sea para los Juegos Ol\u00edmpicos o para cualquier otra competici\u00f3n&#187;, explicaron los organizadores en un comunicado de prensa en noviembre. &#171;La segunda cuesti\u00f3n es que la torre debe poder garantizar unas buenas condiciones para el arbitraje de la competici\u00f3n, en particular ofreciendo a los jueces la visibilidad necesaria sobre toda la ola&#187;.<\/p>\n<p>Los planes para la nueva torre de aluminio fueron criticados por causar potencialmente da\u00f1os al delicado arrecife de coral frente a Teahupo&#8217;o en un momento en que el calentamiento global ya est\u00e1 da\u00f1ando los arrecifes de coral en todo el mundo.<\/p>\n<p>Un video publicado el a\u00f1o pasado por Save Teahupo&#8217;o Reef mostraba una barcaza utilizada durante la construcci\u00f3n de la torre atascada en el arrecife, as\u00ed como pruebas de corales rotos.<\/p>\n<p>Algunos cr\u00edticos tacharon la torre de s\u00edmbolo de colonialismo y acusaron a los organizadores del evento de no estar a la altura de sus afirmaciones de que la competici\u00f3n ser\u00eda sostenible y respetuosa con el medio ambiente.<\/p>\n<p>Alexandra Dempsey, ecologista de arrecifes de coral y CEO de la Fundaci\u00f3n Khaled bin Sultan Living Oceans, afirm\u00f3 que la formaci\u00f3n coralina que hace de Tahit\u00ed un lugar ideal para el surf profesional podr\u00eda resultar da\u00f1ada por la torre.<\/p>\n<p>&#171;Las comunidades locales de all\u00ed son incre\u00edblemente apasionadas y est\u00e1n culturalmente ligadas al oc\u00e9ano, y en particular a los sistemas de arrecifes y a los arrecifes que causan la acci\u00f3n de las olas en esa zona. Y la ola perfecta&#8230; es&#8230; un efecto natural de c\u00f3mo es el arrecife y se ha formado de forma natural durante millones de a\u00f1os&#187;, dijo a CNN.<\/p>\n<p>&#171;No s\u00f3lo se est\u00e1 da\u00f1ando la ecolog\u00eda del arrecife, sino tambi\u00e9n la estructura que ha estado all\u00ed, que ha sido capaz de crear las maravillosas olas por las que se eligi\u00f3 ese lugar. Y no estamos seguros de cu\u00e1les ser\u00edan las consecuencias de da\u00f1ar el sistema de arrecifes&#187;, a\u00f1adi\u00f3.<\/p>\n<p>En la Polinesia Francesa hay m\u00e1s de 1.000 especies de peces y 150 de coral, seg\u00fan la oficina de turismo de Tahit\u00ed. Los corales amenazados por los efectos del cambio clim\u00e1tico y el turismo de masas son especies muy protegidas.<\/p>\n<p>Los corales del mundo registran uno de los peores eventos de blanqueamiento registrado<\/p>\n<p>La comisi\u00f3n de Par\u00eds 2024 se\u00f1al\u00f3 en un comunicado de prensa de noviembre que se hab\u00edan barajado otras opciones, como reforzar los cimientos de la torre actual, certificar la seguridad de la torre y los cimientos existentes, construir una nueva torre de madera y hacer que los jueces juzgaran la competici\u00f3n desde tierra o desde barco.<\/p>\n<p>Todas esas opciones se descartaron y se decidi\u00f3 construir una versi\u00f3n reducida de la nueva torre de aluminio.<\/p>\n<p>&#171;La protecci\u00f3n del entorno natural de Teahupo&#8217;o ha sido siempre una prioridad en la concepci\u00f3n de todas las soluciones previstas para el lugar&#187;, afirma el comunicado de prensa.<\/p>\n<p>&#171;Todos los planes de desarrollo en Teahupo&#8217;o se han estudiado para minimizar el impacto en el medio ambiente. Este ha sido el objetivo de todos los estudios realizados con vistas a la organizaci\u00f3n de los Juegos, y en particular de la misi\u00f3n de apoyo medioambiental durante la fase de dise\u00f1o y construcci\u00f3n de la nueva torre&#187;.<\/p>\n<p>&#171;La nueva torre, menos imponente y de tama\u00f1o y peso reducidos, instalada sobre nuevos cimientos permanentes, es la soluci\u00f3n que asegurar\u00e1 la longevidad de la torre y garantizar\u00e1 la celebraci\u00f3n de futuros acontecimientos deportivos en Teahupo&#8217;o&#187;, a\u00f1adieron los organizadores.\u00a0&#171;Esta torre y los nuevos cimientos podr\u00e1n recibir una certificaci\u00f3n de 10 a\u00f1os, que es esencial a efectos de seguros&#187;.<\/p>\n<p>La decisi\u00f3n suscit\u00f3 la indignaci\u00f3n de los activistas y la condena de la Asociaci\u00f3n Internacional de Surf, el organismo rector mundial de este deporte.<\/p>\n<p>La nueva torre de nueve toneladas, 50 metros cuadrados y tres pisos se asienta ahora en las aguas de Teahupo&#8217;o y como inform\u00f3 Surfer Magazine en abril est\u00e1 en una zona que no afecta directamente a gran parte del coral, aunque a\u00fan est\u00e1n por ver los efectos a largo plazo.<\/p>\n<p>&#171;La zona donde se construye la torre tiene muy poco coral. Es una plataforma plana con peque\u00f1as cabezas de coral esparcidas y algunas rocas m\u00e1s grandes cubiertas de coral&#187;, escribi\u00f3 Tim McKenna, un fot\u00f3grafo con residencia en Tahit\u00ed, en un post de Instagram en el que mostraba fotos del aspecto de la nueva torre tras su construcci\u00f3n.<\/p>\n<p>&#171;Con los a\u00f1os, los corales (han) cubierto incluso la anterior estructura de concreto de la base de la torre&#187;. Y a\u00f1adi\u00f3: &#171;La nueva torre nunca fue solo para los Juegos Ol\u00edmpicos. Es una torre plegable que se montar\u00e1 cada a\u00f1o mientras dure el acontecimiento&#187;.<\/p>\n<p>&#171;La estructura de aluminio dise\u00f1ada y construida exclusivamente en Tahit\u00ed puede certificarse por fin por motivos de seguros y seguridad. Es una inversi\u00f3n que el gobierno tahitiano ha hecho para los&#8230; pr\u00f3ximos 20 a\u00f1os de eventos de surf en Teahupo&#8217;o&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los Juegos Ol\u00edmpicos estar\u00e1n repletos de im\u00e1genes emblem\u00e1ticas de Par\u00eds: la Torre Eiffel, Versalles, el puente Alejandro III y el H\u00f4tel des Invalides ser\u00e1n los protagonistas. Pero uno de los escenarios m\u00e1s impresionantes de la competici\u00f3n cuatrienal no estar\u00e1 en Par\u00eds ni en Francia. Ni siquiera estar\u00e1 en el mismo hemisferio. Las mundialmente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450964","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los Juegos Ol\u00edmpicos estar\u00e1n repletos de im\u00e1genes emblem\u00e1ticas de Par\u00eds: la Torre Eiffel, Versalles, el puente Alejandro III y el H\u00f4tel des Invalides ser\u00e1n los protagonistas. Pero uno de los escenarios m\u00e1s impresionantes de la competici\u00f3n cuatrienal no estar\u00e1 en Par\u00eds ni en Francia. Ni siquiera estar\u00e1 en el mismo hemisferio. Las mundialmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva\",\"datePublished\":\"2024-07-09T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\"},\"wordCount\":1513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\",\"name\":\"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-09T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias","og_description":"(CNN) &#8212; Los Juegos Ol\u00edmpicos estar\u00e1n repletos de im\u00e1genes emblem\u00e1ticas de Par\u00eds: la Torre Eiffel, Versalles, el puente Alejandro III y el H\u00f4tel des Invalides ser\u00e1n los protagonistas. Pero uno de los escenarios m\u00e1s impresionantes de la competici\u00f3n cuatrienal no estar\u00e1 en Par\u00eds ni en Francia. Ni siquiera estar\u00e1 en el mismo hemisferio. Las mundialmente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-09T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva","datePublished":"2024-07-09T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/"},"wordCount":1513,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","name":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-09T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-09T00:03:48Z","datePublished":"2024-07-09T00:03:48Z","dateModified":"2024-07-09T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 Tahit\\u00ed ser\\u00e1 sede de parte de los Juegos Ol\\u00edmpicos de Par\\u00eds y la pol\\u00e9mica que conlleva\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/tahiti-sede-surf-juegos-olimpicos-paris-polemica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-09T00:03:48Z\",\"datePublished\":\"2024-07-09T00:03:48Z\",\"dateModified\":\"2024-07-09T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451509,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/30\/foto-surf-gabriel-medina-ola-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1450964,"position":0},"title":"La foto viral del surfista brasile\u00f1o Gabriel Medina tras un (casi) 10 perfecto en los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) -- Fue una celebraci\u00f3n para la posteridad, o al menos para la fama viral.El surfista brasile\u00f1o Gabriel Medina se enfrentaba al japon\u00e9s Kanoa Igarashi, el hombre que lo hab\u00eda vencido en los Juegos Ol\u00edmpicos de Tokio, y buscaba que esta vez la historia fuera diferente.El brasile\u00f1o no solo consigui\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451361,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/23\/donde-competira-deportes-juegos-olimpicos-paris-trax\/","url_meta":{"origin":1450964,"position":1},"title":"D\u00f3nde competir\u00e1 cada uno de los deportes de los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"julio 23, 2024","format":false,"excerpt":"(CNN) -- Este verano est\u00e1n pasando muchas cosas a la vez en Par\u00eds.Los Juegos Ol\u00edmpicos llegan a la capital francesa y ya se conoce d\u00f3nde se desarrollar\u00e1n las 32 disciplinas.Muchos de los recintos ya exist\u00edan antes de los Juegos. La \u00fanica instalaci\u00f3n deportiva permanente construida para los Juegos Ol\u00edmpicos es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451337,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/22\/lebron-james-abanderado-masculino-ee-uu-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1450964,"position":2},"title":"LeBron James ser\u00e1 el abanderado masculino de EE.UU. en los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- La leyenda de la NBA LeBron James fue elegido como el abanderado masculino del Equipo de Estados Unidos (Team USA) para la ceremonia de apertura de los Juegos Ol\u00edmpicos de Par\u00eds, anunci\u00f3 este lunes el Comit\u00e9 Ol\u00edmpico y Paral\u00edmpico de EE.UU.La ceremonia inaugural se celebrar\u00e1 a orillas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451275,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","url_meta":{"origin":1450964,"position":3},"title":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados","author":"","date":"julio 19, 2024","format":false,"excerpt":"Nueva York (CNN) -- El pardo y anta\u00f1o contaminado r\u00edo Sena de Par\u00eds no es el m\u00e1s brillante ni el m\u00e1s glamuroso, especialmente en una ciudad llena de lugares emblem\u00e1ticos. Pero Chase espera que este curso de agua se convierta en todo un espect\u00e1culo.En los Juegos Ol\u00edmpicos de Verano de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451427,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/25\/por-que-rusia-no-participa-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1450964,"position":4},"title":"\u00bfPor qu\u00e9 Rusia no participa en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- El Comit\u00e9 Ol\u00edmpico Internacional (COI) decidi\u00f3 en octumbre de 2023 suspender la participaci\u00f3n en los Juegos Ol\u00edmpicos de Par\u00eds que est\u00e1n a punto de comenzar al Comit\u00e9 Ol\u00edmpico Ruso, lo que implic\u00f3 la p\u00e9rdida de financiamiento y el hecho de que el COI se reserva el derecho de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451447,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/donde-cuando-proximos-juegos-olimpicos-novedades-orix\/","url_meta":{"origin":1450964,"position":5},"title":"D\u00f3nde y cu\u00e1ndo se celebran los pr\u00f3ximos Juegos Ol\u00edmpicos (en 2028) y qu\u00e9 novedades tendr\u00e1n","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Faltan otros cuatro a\u00f1os para que los pr\u00f3ximos Juegos Ol\u00edmpicos de verano se celebren pero las dos ciudades sede que siguen ya se preparan para albergar a los mejores atletas del mundo que competir\u00e1n en una diversidad de deportes: desde los cl\u00e1sicos como la nataci\u00f3n o el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450964"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450964\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}