{"id":1450969,"date":"2024-07-08T22:03:46","date_gmt":"2024-07-09T05:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/"},"modified":"2024-07-08T22:03:46","modified_gmt":"2024-07-09T05:03:46","slug":"paises-mas-medallas-olimpicas-ganado-historia-juegos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","title":{"rendered":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Los Juegos Ol\u00edmpicos de Par\u00eds 2024 est\u00e1n a la vuelta de la esquina y la Ciudad de la Luz se prepara para recibir a miles de atletas de todo el mundo. Esta edici\u00f3n de los Juegos Ol\u00edmpicos de verano se celebra del 26 de julio al 11 de agosto de 2024, siendo la tercera vez que Par\u00eds es anfitriona, despu\u00e9s de las ediciones de 1900 y 1924.<\/p>\n<p>En esta ocasi\u00f3n, m\u00e1s de 200 pa\u00edses competir\u00e1n en busca de la gloria ol\u00edmpica, en un evento donde, dice la organizaci\u00f3n, &#171;el mundo viene a competir, sentirse inspirado y estar juntos&#187;.<\/p>\n<p>Las cinco cosas que debes saber de los Juegos Ol\u00edmpicos de Par\u00eds 2024<\/p>\n<p>La historia muestra que Estados Unidos, la Uni\u00f3n Sovi\u00e9tica, Reino Unido y China han sido los pa\u00edses dominantes del medallero ol\u00edmpico, mientras que Europa es el continente que mayor n\u00famero de medallas ol\u00edmpicas ha conseguido. Estos son datos del Comit\u00e9 Ol\u00edmpico Internacional (COI) y Olympedia.<\/p>\n<p>\ud83c\uddfa\ud83c\uddf8 Estados Unidos: 2.655<br \/>\nOro: 1.070<br \/>\nPlata: 841<br \/>\nBronce: 744<\/p>\n<p>\ud83d\udfe5 Uni\u00f3n Sovi\u00e9tica: 1.010<br \/>\nOro: 395<br \/>\nPlata: 319<br \/>\nBronce: 286<\/p>\n<p>\ud83c\uddec\ud83c\udde7 Reino Unido: 930<br \/>\nOro: 292<br \/>\nPlata: 323<br \/>\nBronce: 315<\/p>\n<p>\ud83c\udde9\ud83c\uddea Alemania: 797<br \/>\nOro: 239<br \/>\nPlata: 267<br \/>\nBronce: 291<\/p>\n<p>\ud83c\uddeb\ud83c\uddf7 Francia: 773<br \/>\nOro: 231<br \/>\nPlata: 257<br \/>\nBronce: 285<\/p>\n<p>\ud83c\udde8\ud83c\uddf3 China: 636<br \/>\nOro: 263<br \/>\nPlata: 199<br \/>\nBronce: 174<\/p>\n<p>Estados Unidos: el l\u00edder en medallas de los Juegos Ol\u00edmpicos<\/p>\n<p>En la historia de los Juegos Ol\u00edmpicos de verano, Estados Unidos se erige en el ranking como el pa\u00eds con m\u00e1s medallas conseguidas. Desde su primera participaci\u00f3n en los Juegos Ol\u00edmpicos modernos en 1896, los estadounidenses han acumulado un total de 2.522 medallas, incluyendo 1.070 de oro, 841 de plata y 744 de bronce. Este dominio se ha visto reflejado en diferentes disciplinas deportivas, pero particularmente en atletismo y nataci\u00f3n.<\/p>\n<p>El atletismo, con estrellas como Carl Lewis, quien gan\u00f3 nueve medallas de oro entre 1984 y 1996, y Jesse Owens, quien consigui\u00f3 cuatro oros en Berl\u00edn 1936. En nataci\u00f3n, por su parte, Michael Phelps es el atleta ol\u00edmpico m\u00e1s condecorado de todos los tiempos con 23 medallas de oro.<\/p>\n<p>Reino Unido<\/p>\n<p>Es la \u00fanica naci\u00f3n que ha participado en todos los Juegos Ol\u00edmpicos. El ciclista Jason Kenny es el el brit\u00e1nico con m\u00e1s medallas de oro en la historia de los Juegos (7 medallas) y el m\u00e1s laureado en total (9). Steven Redgrave es considerado el mejor deportista en remo de la historia, con medallas de oro en cinco ediciones consecutivas de los Ol\u00edmpicos.<\/p>\n<p>La Uni\u00f3n Sovi\u00e9tica y Rusia<\/p>\n<p>La Uni\u00f3n Sovi\u00e9tica, que compiti\u00f3 por primera vez en los Juegos Ol\u00edmpicos de Helsinki en 1952, acumul\u00f3 un total de 1.010 medallas hasta su disoluci\u00f3n en 1991. Los atletas sovi\u00e9ticos destacaron en diferentes modalidades deportivas, incluyendo gimnasia y lucha, donde sobresalen gimnastas como Larisa Latyina, quien gan\u00f3 18 medallas entre 1956 y 1964.<\/p>\n<p>Desde entonces, Rusia continu\u00f3 conquistando el medallero ol\u00edmpico con los triunfos de boxeadores como Aleksandr Karelin, con tres medallas de oro y una de planta entre 1988 y 2000.<\/p>\n<p>Tras la suspensi\u00f3n en 2017 por un esc\u00e1ndalo de dopaje, los deportistas rusos no compiten en representaci\u00f3n de su pa\u00eds, sino que lo han hecho como Atletas Ol\u00edmpicos de Rusia (2018), ROC (entre 2020 y 2022) y Atletas Individuales Neutrales \u2014en conjunto con los bielorrusos\u2014 para Par\u00eds 2024.<\/p>\n<p>As\u00ed qued\u00f3 el medallero de los Juegos ol\u00edmpicos de Tokio 2020<\/p>\n<p>China<\/p>\n<p>Desde su debut en Helsinki 1952 y su regreso ininterrumpido desde la edici\u00f3n de Los \u00c1ngeles en 1984, China ha emergido como un gran pa\u00eds ol\u00edmpico. Hasta la fecha, China ha conseguido un total de 636 medallas, con 263 de oro. Los deportes en los que m\u00e1s destaca incluyen las modalidades de saltos ornamentales y tenis de mesa.<\/p>\n<p>China es el pa\u00eds dominante del tenis de mesa desde que este deporte se incluy\u00f3 en el programa ol\u00edmpico en Se\u00fal 1988. Jugadores como Deng Yaping y Ma Long han contribuido con m\u00faltiples oros para el palmar\u00e9s de su pa\u00eds.<\/p>\n<p>China supera a Alemania y Francia en medallas de oro.<\/p>\n<p>Europa: el continente con mayor n\u00famero de medallas ol\u00edmpicas<\/p>\n<p>Aunque Estados Unidos sea el pa\u00eds que lidera el ranking de medallas ol\u00edmpicas, Europa es el continente con mayor n\u00famero de medallas si agrupamos los pa\u00edses por territorio. Hasta la fecha, los pa\u00edses europeos han acumulado un total de 12.436 medallas, de las cuales 3.947 son de oro, 4.094 de plata y 4.395 de bronce. Le siguen las regiones de Am\u00e9rica del Norte con un total de 4.306 medallas y Asia con 2.341.<\/p>\n<p>Los pa\u00edses europeos han destacado en diversas disciplinas. Reino Unido, por ejemplo, ha sido el pa\u00eds dominante en deportes como remo. Alemania, por su parte, ha tenido un gran \u00e9xito en ciclismo, con atletas como Kristina Vogel, con dos medallas de oro en 2012 y 2016.<\/p>\n<p>Francia, el pa\u00eds anfitri\u00f3n de los Juegos Ol\u00edmpicos 2024, tambi\u00e9n ha sido un gran competidor en deportes como judo o esgrima, con atletas como Teddy Riner, ganador de dos medallas de oro en judo.<\/p>\n<p>Con informaci\u00f3n del equipo editorial de CNN<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Los Juegos Ol\u00edmpicos de Par\u00eds 2024 est\u00e1n a la vuelta de la esquina y la Ciudad de la Luz se prepara para recibir a miles de atletas de todo el mundo. Esta edici\u00f3n de los Juegos Ol\u00edmpicos de verano se celebra del 26 de julio al 11 de agosto de 2024, siendo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450969","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Los Juegos Ol\u00edmpicos de Par\u00eds 2024 est\u00e1n a la vuelta de la esquina y la Ciudad de la Luz se prepara para recibir a miles de atletas de todo el mundo. Esta edici\u00f3n de los Juegos Ol\u00edmpicos de verano se celebra del 26 de julio al 11 de agosto de 2024, siendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T05:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos\",\"datePublished\":\"2024-07-09T05:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\"},\"wordCount\":873,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\",\"name\":\"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-09T05:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Los Juegos Ol\u00edmpicos de Par\u00eds 2024 est\u00e1n a la vuelta de la esquina y la Ciudad de la Luz se prepara para recibir a miles de atletas de todo el mundo. Esta edici\u00f3n de los Juegos Ol\u00edmpicos de verano se celebra del 26 de julio al 11 de agosto de 2024, siendo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-09T05:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/"},"author":{"name":"","@id":""},"headline":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos","datePublished":"2024-07-09T05:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/"},"wordCount":873,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","name":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-09T05:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los pa\u00edses que m\u00e1s medallas ol\u00edmpicas han ganado en la historia de los Juegos","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/08\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-09T05:03:46Z","datePublished":"2024-07-09T05:03:46Z","dateModified":"2024-07-09T05:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los pa\\u00edses que m\\u00e1s medallas ol\\u00edmpicas han ganado en la historia de los Juegos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/08\\\/paises-mas-medallas-olimpicas-ganado-historia-juegos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-09T05:03:46Z\",\"datePublished\":\"2024-07-09T05:03:46Z\",\"dateModified\":\"2024-07-09T05:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451406,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/25\/origen-historia-juegos-olimpicos-orix\/","url_meta":{"origin":1450969,"position":0},"title":"\u00bfCu\u00e1l es el origen de los Juegos Ol\u00edmpicos y por qu\u00e9 se celebran cada cuatro a\u00f1os?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los Juegos Ol\u00edmpicos, uno de los eventos m\u00e1s importantes a nivel mundial, que vincula el deporte y la cultura, tiene una historia que se remonta a m\u00e1s de 2.000 de a\u00f1os.Desde sus comienzos en la antigua Grecia hasta su resurgimiento en la era moderna, los Juegos Ol\u00edmpicos han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451370,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/24\/ministerio-interior-francia-rechazo-solicitudes-acreditacion-juegos-olimpicos-trax\/","url_meta":{"origin":1450969,"position":1},"title":"El Ministerio del Interior franc\u00e9s rechaz\u00f3 unas 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, de las cuales unas 1.000 fueron bloqueadas por sospechas de intromisi\u00f3n o espionaje","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- El Ministerio del Interior de Francia rechaz\u00f3 alrededor de 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, y aproximadamente 1.000 de esos casos fueron bloqueados debido a sospechas de intromisi\u00f3n o espionaje.El Ministerio del Interior indic\u00f3 en un comunicado este martes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451447,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/donde-cuando-proximos-juegos-olimpicos-novedades-orix\/","url_meta":{"origin":1450969,"position":2},"title":"D\u00f3nde y cu\u00e1ndo se celebran los pr\u00f3ximos Juegos Ol\u00edmpicos (en 2028) y qu\u00e9 novedades tendr\u00e1n","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Faltan otros cuatro a\u00f1os para que los pr\u00f3ximos Juegos Ol\u00edmpicos de verano se celebren pero las dos ciudades sede que siguen ya se preparan para albergar a los mejores atletas del mundo que competir\u00e1n en una diversidad de deportes: desde los cl\u00e1sicos como la nataci\u00f3n o el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451413,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/25\/quienes-son-abanderados-mexico-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1450969,"position":3},"title":"\u00bfQui\u00e9nes son Alejandra Orozco y Emiliano Hern\u00e1ndez, abanderados de M\u00e9xico en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Alejandra Orozco y Emiliano Hern\u00e1ndez ser\u00e1n los abanderados de la delegaci\u00f3n mexicana en la ceremonia de apertura de los Juegos Ol\u00edmpicos de Par\u00eds 2024 el 26 de julio. Esta es la segunda ocasi\u00f3n que algunos pa\u00edses, incluido M\u00e9xico, tienen dos abanderados. El Comit\u00e9 Ol\u00edmpico Internacional (COI) implement\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451436,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/medallero-juegos-olimpicos-paris-2024-resultados-paises-oro-plata-bronce-orix\/","url_meta":{"origin":1450969,"position":4},"title":"Medallero de los Juegos Ol\u00edmpicos de Par\u00eds 2024, en vivo: tabla de pa\u00edses que ganan m\u00e1s medallas","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Consulta el medallero de los Juegos Ol\u00edmpicos de Par\u00eds 2024 para conocer qu\u00e9 pa\u00edses est\u00e1n ganando m\u00e1s medallas y qui\u00e9nes lideran la tabla de medallas de oro, plata y bronce.Calendario de los Juegos Ol\u00edmpicos de Par\u00eds 2024: horarios, competiciones y fechasEsta tabla se actualiza autom\u00e1ticamente con los resultados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451441,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/cuantas-medallas-tiene-eeuu-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1450969,"position":5},"title":"\u00bfCu\u00e1ntas medallas lleva Estados Unidos en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos es toda una potencia en los Juegos Ol\u00edmpicos y lidera el medallero hist\u00f3rico como el pa\u00eds con m\u00e1s metales obtenidos. Antes del comienzo de Paris 2024, EE.UU. acumula en su haber un total de 2.650 medallas (1070 de oro), una cifra que continuar\u00e1 ampliando en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1450969"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1450969\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1450969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1450969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1450969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}