{"id":1451009,"date":"2024-07-10T13:03:46","date_gmt":"2024-07-10T20:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/"},"modified":"2024-07-10T13:03:46","modified_gmt":"2024-07-10T20:03:46","slug":"salida-nina-gazati-enfermedad-neurologica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","title":{"rendered":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;"},"content":{"rendered":"<p>Arish, Egipto (CNN) &#8212; Con apenas cuatro a\u00f1os, Julia Abu Zeiter padece una rara enfermedad neurol\u00f3gica que puede ser mortal si no recibe tratamiento.<\/p>\n<p>Los nueve meses de guerra en Gaza estuvieron a punto de costarle la vida, ya que los combates y los desplazamientos le impidieron acceder a los medicamentos.<\/p>\n<p>Tras un arduo viaje, finalmente fue evacuada del enclave asolado por la guerra el 27 de junio, acompa\u00f1ada \u00fanicamente por su t\u00eda de 21 a\u00f1os, Dareen Zeiter.<\/p>\n<p>&#171;El desplazamiento fue realmente dif\u00edcil, los acontecimientos en Gaza son muy dif\u00edciles. Lo que Julia vio fue muy duro&#187;, declar\u00f3 Dareen a CNN.<\/p>\n<p>Julia padece un raro trastorno neurol\u00f3gico llamado hemiplej\u00eda alternante de la infancia o AHC, por sus siglas en ingl\u00e9s. Provoca episodios recurrentes de par\u00e1lisis y convulsiones potencialmente mortales. No existe cura para esta enfermedad, que se calcula que afecta aproximadamente a uno de cada mill\u00f3n de nacimientos. Los afectados son considerados &#171;bombas de tiempo&#187; y deben ser vigilados constantemente para detectar posibles episodios. En cuanto se produce, deben administrarse r\u00e1pidamente medidas para salvar sus vidas.<\/p>\n<p>Familia est\u00e1 en carrera para salvar a su hijo de rara enfermedad cerebral que convierte a beb\u00e9s en &#171;bombas de tiempo humanas&#187;<\/p>\n<p>CNN se reuni\u00f3 con Julia y Dareen a bordo de un hospital flotante gestionado por Emiratos \u00c1rabes Unidos, donde llevaban una semana tras abandonar Gaza a trav\u00e9s del paso fronterizo israel\u00ed de Kerem Shalom, en el sur.<\/p>\n<p>Las dos palestinas formaban parte de la docena de pacientes que abandonaron el hospital flotante para continuar su tratamiento en Abu Dhabi, la capital emirat\u00ed. La mayor\u00eda de esos pacientes son ni\u00f1os, entre ellos dos que padecen leucemia.<\/p>\n<p>Las &#171;v\u00edctimas invisibles&#187; de Gaza<\/p>\n<p>El hospital, amarrado frente a la costa de Arish, en la costa norte de la pen\u00ednsula egipcia del Sina\u00ed, se encuentra a unos 40 kil\u00f3metros de Rafah, la ciudad m\u00e1s meridional de Gaza que ahora yace en ruinas despu\u00e9s de que Israel lanzara all\u00ed su operaci\u00f3n terrestre en mayo.<\/p>\n<p>La ciudad tambi\u00e9n albergaba el paso fronterizo de Rafah con Egipto, un puente terrestre crucial por el que pasaban dos tercios de la ayuda que entraba en Gaza. El paso est\u00e1 cerrado desde que fue tomado por el ej\u00e9rcito israel\u00ed.<\/p>\n<p>El barco de los Emiratos \u00c1rabes Unidos, con 100 camas, ha recibido a 2.400 palestinos heridos desde febrero, seg\u00fan el director del hospital, el Dr. Ahmed Mubarak.<\/p>\n<p>Julia es &#171;una v\u00edctima invisible&#187; de la guerra, dijo Mubarak, atrapada en lo que M\u00e9dicos Sin Fronteras describi\u00f3 como los &#171;homicidios silenciosos de Gaza, resultado de la privaci\u00f3n deliberada&#187;. La responsable de programas de emergencia de la organizaci\u00f3n, Mari Carmen Vi\u00f1oles, declar\u00f3 en mayo que &#171;los bloqueos, retrasos y restricciones a la ayuda humanitaria y a los suministros m\u00e9dicos esenciales&#187; por parte de Israel han hecho imposible la entrega de ayuda.<\/p>\n<p>Julia y Dareen son dos de los innumerables palestinos desplazados por la guerra de Gaza, que Israel lanz\u00f3 en respuesta al ataque de Hamas del 7 de octubre, en el que murieron 1.200 personas en Israel y m\u00e1s de 250 fueron tomadas como rehenes, seg\u00fan las autoridades israel\u00edes.<\/p>\n<p>Un palestino herido evacuado de Gaza es transportado a un avi\u00f3n emirat\u00ed en el aeropuerto egipcio de Arish, para recibir tratamiento en Emiratos \u00c1rabes Unidos, el 5 de julio. Cr\u00e9dito: Giuseppe Cacace\/AFP\/Getty Images<\/p>\n<p>La guerra de Israel ha matado a m\u00e1s de 38.000 personas en Gaza, seg\u00fan el Ministerio de Sanidad. Franjas del enclave han quedado reducidas a escombros y casi toda la poblaci\u00f3n de Gaza, de dos millones de personas, se encuentra desplazada internamente.<\/p>\n<p>Julia y Dareen se vieron obligadas a abandonar su hogar en el norte de Gaza cuando comenz\u00f3 la guerra. La ni\u00f1a de cuatro a\u00f1os fue testigo de &#171;explosiones y bombardeos&#187; en todo momento, seg\u00fan su t\u00eda.<\/p>\n<p>El duro asedio de Israel ha asfixiado el enclave, reduciendo la ayuda humanitaria a un m\u00ednimo e impidiendo la circulaci\u00f3n de los gazat\u00edes. Para Julia, esto signific\u00f3 quedarse sin su medicaci\u00f3n, lo que desencaden\u00f3 una serie de convulsiones potencialmente mortales.<\/p>\n<p>Alrededor de un mes despu\u00e9s del inicio de la guerra, Julia se qued\u00f3 sin tres de los cinco medicamentos que tomaba, seg\u00fan cont\u00f3 Dareen a CNN. Esto desencaden\u00f3 un estado de par\u00e1lisis durante seis meses.<\/p>\n<p>Con la ayuda del Fondo Palestino de Ayuda a la Infancia (PCRF, por sus siglas en ingl\u00e9s), una organizaci\u00f3n no gubernamental con sede en Estados Unidos, Julia pudo finalmente ser evacuada a trav\u00e9s del paso fronterizo israel\u00ed de Kerem Shalom, explic\u00f3 Dareen.<\/p>\n<p>Ataque a\u00e9reo de Israel mata al menos a 27 personas en complejo escolar cerca de Khan Younis, seg\u00fan el Ministerio de Salud de Gaza<\/p>\n<p>&#171;El hambre es lo que nos destruye&#187;<\/p>\n<p>Al final del pasillo de salas improvisadas donde se encontraba Julia estaba Ibrahim, que result\u00f3 herido en la casa de su familia en Jabalia, al norte de Gaza, cuando un ataque a\u00e9reo alcanz\u00f3 su edificio el 21 de noviembre. Ese d\u00eda hab\u00eda cumplido siete a\u00f1os.<\/p>\n<p>Ibrahim estaba a bordo con su t\u00eda, Alaa, de 21 a\u00f1os. Alaa e Ibrahim resultaron heridos en el ataque a\u00e9reo, pero sobrevivieron tras ser sacados de entre los escombros, seg\u00fan Alaa. La t\u00eda sufri\u00f3 quemaduras graves, mientras que Ibrahim se rompi\u00f3 un brazo y una pierna, explic\u00f3.<\/p>\n<p>Las heridas del ni\u00f1o no cicatrizaron bien, por lo que necesit\u00f3 m\u00e1s tratamiento.<\/p>\n<p>&#171;Ibrahim y yo fuimos los dos \u00fanicos sobrevivientes&#187;, declar\u00f3 Alaa a CNN, a\u00f1adiendo que el ataque a\u00e9reo mat\u00f3 a 30 miembros de su familia. Abandonaron Gaza el 28 de abril a trav\u00e9s del paso fronterizo de Rafah, justo una semana antes de que las fuerzas israel\u00edes tomaran el control.<\/p>\n<p>&#171;Mira, este es mi padre&#187;, dijo Ibrahim, mostrando una foto de su padre, que muri\u00f3 durante el ataque a\u00e9reo, en el tel\u00e9fono de su t\u00eda.<br \/>\nAntes de perder su hogar y su familia, Alaa e Ibrahim permanecieron en el norte de Gaza hasta abril, cuando los residentes pasaron mucha hambre mientras la ayuda llegaba con dificultades a ellos en medio de las operaciones militares de Israel y lo que los funcionarios de ayuda humanitaria dijeron que era un aumento de la anarqu\u00eda y el saqueo de camiones.<\/p>\n<p>A mediados de marzo, la Clasificaci\u00f3n Integrada de la Fase de Seguridad Alimentaria (CIF) consider\u00f3 que la hambruna era &#171;inminente&#187; en el norte de Gaza y dijo que se preve\u00eda que ocurriera entre esa fecha y mayo.<\/p>\n<p>Camiones de ayuda cargados con suministros para Gaza hacen fila en Arish tras el cierre del paso fronterizo de Rafah, en Arish, Egipto, el martes. Cr\u00e9dito: Ali Moustafa\/Getty Images<\/p>\n<p>El martes, Naciones Unidas, citando un informe de expertos independientes, afirm\u00f3 que la reciente muerte de m\u00e1s ni\u00f1os palestinos a causa del hambre y la desnutrici\u00f3n en Gaza indica que la hambruna se ha extendido por toda la franja, y denunci\u00f3 la &#171;campa\u00f1a de hambre intencionada y selectiva de Israel contra el pueblo palestino&#187; como una &#171;forma de violencia genocida&#187;.<\/p>\n<p>&#171;Hab\u00eda un hambre incre\u00edble&#187;, dijo Alaa a CNN, sentada en una cama de hospital mientras Ibrahim permanec\u00eda a su lado. &#171;Viv\u00edamos hambrientos, los principales ingredientes para la comida no estaban disponibles&#187;, dijo Alaa a CNN.<\/p>\n<p>&#171;El hambre fue m\u00e1s dura para nosotros que la propia guerra&#187;, dijo a CNN. &#171;Los que han muerto, han muerto. Pero el hambre es lo que nos destruye&#187;.<\/p>\n<p>La desnutrici\u00f3n se extiende por Gaza y los ni\u00f1os mueren de hambre en brazos de sus padres<\/p>\n<p>Mientras Julia e Ibrahim lograron salir, millones de personas siguen atrapadas en la zona de guerra, con pocos indicios de un acuerdo de alto el fuego a la vista.<\/p>\n<p>Casi 26.000 ni\u00f1os han muerto o han resultado heridos en Gaza en seis meses, seg\u00fan inform\u00f3 en abril la organizaci\u00f3n humanitaria Save the Children, algo m\u00e1s del 2% de toda la poblaci\u00f3n infantil de Gaza.<\/p>\n<p>&#171;Incluso en medio de las complejidades de la guerra, \u00bfc\u00f3mo no comprender una verdad universal: un ni\u00f1o es un ni\u00f1o?&#187;, declar\u00f3 el mes pasado James Elder, portavoz de la Unicef, quien pidi\u00f3 &#171;un alto el fuego (que) devuelva a los rehenes a casa y ponga fin a la matanza de ni\u00f1os&#187;.<\/p>\n<p>Dareen, t\u00eda de Julia, dijo que la responsabilidad sobre su sobrina era demasiado grande para cargar con ella. &#171;Necesita a su madre y a su padre. No puedo ser su madre y su padre al mismo tiempo&#187;, declar\u00f3 a CNN. &#171;Al fin y al cabo, soy una chica que cruz\u00f3 con una menor&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arish, Egipto (CNN) &#8212; Con apenas cuatro a\u00f1os, Julia Abu Zeiter padece una rara enfermedad neurol\u00f3gica que puede ser mortal si no recibe tratamiento. Los nueve meses de guerra en Gaza estuvieron a punto de costarle la vida, ya que los combates y los desplazamientos le impidieron acceder a los medicamentos. Tras un arduo viaje, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451009","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &quot;una entre un mill\u00f3n&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &quot;una entre un mill\u00f3n&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Arish, Egipto (CNN) &#8212; Con apenas cuatro a\u00f1os, Julia Abu Zeiter padece una rara enfermedad neurol\u00f3gica que puede ser mortal si no recibe tratamiento. Los nueve meses de guerra en Gaza estuvieron a punto de costarle la vida, ya que los combates y los desplazamientos le impidieron acceder a los medicamentos. Tras un arduo viaje, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T20:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;\",\"datePublished\":\"2024-07-10T20:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\"},\"wordCount\":1509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\",\"name\":\"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad \\\"una entre un mill\u00f3n\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-10T20:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad \"una entre un mill\u00f3n\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad \"una entre un mill\u00f3n\" - Noticias","og_description":"Arish, Egipto (CNN) &#8212; Con apenas cuatro a\u00f1os, Julia Abu Zeiter padece una rara enfermedad neurol\u00f3gica que puede ser mortal si no recibe tratamiento. Los nueve meses de guerra en Gaza estuvieron a punto de costarle la vida, ya que los combates y los desplazamientos le impidieron acceder a los medicamentos. Tras un arduo viaje, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-10T20:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/"},"author":{"name":"","@id":""},"headline":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;","datePublished":"2024-07-10T20:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/"},"wordCount":1509,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","name":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad \"una entre un mill\u00f3n\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-10T20:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ofrecen una salida del territorio a una ni\u00f1a gazat\u00ed de 4 a\u00f1os con una enfermedad &#171;una entre un mill\u00f3n&#187;","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/10\/salida-nina-gazati-enfermedad-neurologica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-10T20:03:46Z","datePublished":"2024-07-10T20:03:46Z","dateModified":"2024-07-10T20:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ofrecen una salida del territorio a una ni\\u00f1a gazat\\u00ed de 4 a\\u00f1os con una enfermedad &#171;una entre un mill\\u00f3n&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/10\\\/salida-nina-gazati-enfermedad-neurologica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/10\\\/salida-nina-gazati-enfermedad-neurologica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-10T20:03:46Z\",\"datePublished\":\"2024-07-10T20:03:46Z\",\"dateModified\":\"2024-07-10T20:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448816,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/03\/jose-pepe-mujica-padece-cancer-de-esofago-dice-medica-orix\/","url_meta":{"origin":1451009,"position":0},"title":"Jos\u00e9 \u201cPepe\u201d Mujica padece c\u00e1ncer de es\u00f3fago, confirma su m\u00e9dica tratante","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de Uruguay, Jos\u00e9 \u201cPepe\u201d Mujica, padece c\u00e1ncer de es\u00f3fago, inform\u00f3 este jueves su m\u00e9dica tratante Raquel Pannone en conferencia de prensa. El exmandatario fue sometido a una endoscop\u00eda digestiva y el resultado \u201cmostr\u00f3 que tiene un tumor al nivel del es\u00f3fago\", dijo Pannone. \"Ten\u00edamos la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444952,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/05\/celine-dion-padece-el-sindrome-de-la-persona-rigida-que-es-cuales-son-sus-sintomas-y-como-se-trata\/","url_meta":{"origin":1451009,"position":1},"title":"Celine Dion padece el s\u00edndrome de la persona r\u00edgida: \u00bfqu\u00e9 es, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?","author":"","date":"febrero 5, 2024","format":false,"excerpt":"(CNN) --\u00a0Celine Dion sorprendi\u00f3 el domingo con su aparici\u00f3n en los premios Grammy, donde present\u00f3 el premio al Album del a\u00f1o.Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar.El s\u00edndrome\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1437295,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/02\/16\/bruce-willis-fue-diagnosticado-con-demencia-frontotemporal\/","url_meta":{"origin":1451009,"position":2},"title":"Bruce Willis fue diagnosticado con demencia frontotemporal","author":"Eduardo Salinas","date":"febrero 16, 2023","format":false,"excerpt":"Hace unas horas, la familia de Bruce Willis comunic\u00f3 que el actor ha sido diagnosticado con demencia frontotemporal, una enfermedad cruel de la cual se conoce poco pero que puede afectar a cualquier persona. Una especie de demencia que afecta a los l\u00f3bulos frontales y temporales del cerebro, y que\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452251,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/28\/polio-primer-caso-gaza-25-anos-vacunas-trax\/","url_meta":{"origin":1451009,"position":3},"title":"Las vacunas contra la polio llegan a Gaza, pero para este beb\u00e9, el primer caso en 25 a\u00f1os, es demasiado tarde","author":"Eduardo Salinas","date":"agosto 28, 2024","format":false,"excerpt":"(CNN) -- Abdul Rahman duerme en un asiento de coche maltratado, mecido por su madre Niveen Abu al-Jidyan. No se da cuenta, de momento, de los drones que pasan por encima ni de la enfermedad incurable que paraliza su cuerpo.\u201cNo puede estar de pie, sentarse ni moverse como antes. Est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447081,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/18\/que-es-sindrome-persona-rigida-diagnostico-sintomas-tratamiento-trax\/","url_meta":{"origin":1451009,"position":4},"title":"\u00bfQu\u00e9 es el s\u00edndrome de la persona r\u00edgida, cu\u00e1les son sus s\u00edntomas y c\u00f3mo se trata?","author":"","date":"marzo 18, 2024","format":false,"excerpt":"(CNN) -- Celine Dion comparti\u00f3 en 2022 que le hab\u00edan diagnosticado el s\u00edndrome de la persona r\u00edgida (SPS, por sus siglas en ingl\u00e9s), una afecci\u00f3n neurol\u00f3gica rara que puede llevar a\u00f1os diagnosticar.El s\u00edndrome de la persona r\u00edgida se caracteriza por rigidez y espasmos musculares, mayor sensibilidad a est\u00edmulos como el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445072,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/07\/corte-constitucional-de-ecuador-despenaliza-la-eutanasia-tras-el-reclamo-de-paola-roldan\/","url_meta":{"origin":1451009,"position":5},"title":"Corte Constitucional de Ecuador despenaliza la eutanasia tras el reclamo de Paola Rold\u00e1n","author":"","date":"febrero 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 La Corte Constitucional de Ecuador\u00a0aprob\u00f3 la\u00a0despenalizaci\u00f3n\u00a0de la eutanasia tras una batalla legal de cinco meses emprendida por Paola Rold\u00e1n, una mujer de 42 a\u00f1os quien padece esclerosis lateral amiotr\u00f3fica (ELA).Rold\u00e1n present\u00f3 en agosto de 2023 una demanda de inconstitucionalidad del\u00a0art\u00edculo 144 del C\u00f3digo Integral Penal, que amenazaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451009"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451009\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}