{"id":1451055,"date":"2024-07-11T16:03:39","date_gmt":"2024-07-11T23:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/"},"modified":"2024-07-11T16:03:39","modified_gmt":"2024-07-11T23:03:39","slug":"venezuela-hermano-lider-tren-aragua-extraditado-espana-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","title":{"rendered":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Gerso Guerrero, hermano de \u201cNi\u00f1o Guerrero\u201d, l\u00edder del Tren de Aragua fue extraditado de Espa\u00f1a a Venezuela, inform\u00f3 el fiscal general de Venezuela, Tarek William Saab, en su cuenta de X.<\/p>\n<p>El Gobierno de Biden designa al Tren de Aragua como organizaci\u00f3n criminal trasnacional, seg\u00fan funcionario<\/p>\n<p>Saab precis\u00f3 que el hombre extraditado debe enfrentar cargos de extorsi\u00f3n agravada, legitimaci\u00f3n de capitales, asociaci\u00f3n para delinquir, tr\u00e1fico il\u00edcito de armas y municiones, terrorismo y financiamiento al terrorismo.<\/p>\n<p>El jefe del Ministerio P\u00fablico inform\u00f3 que espera su llegada este jueves. Agreg\u00f3 que para tal efecto se constituy\u00f3 una comisi\u00f3n conformada por dos fiscales en materia de delincuencia organizada, adem\u00e1s de autoridades de la Polic\u00eda cient\u00edfica y el Ministerio de Interior y Justicia.<\/p>\n<p>La Polic\u00eda de Colombia detiene al jefe del Tren de Aragua en Bogot\u00e1 y Soacha<\/p>\n<p>CNN ha solicitado m\u00e1s informaci\u00f3n a la Audiencia Nacional de Espa\u00f1a sobre el proceso judicial contra Guerrero, as\u00ed como si cuenta con representaci\u00f3n legal, y est\u00e1 a la espera de una respuesta. Gerso Guerrero hab\u00eda sido detenido en marzo en Barcelona, Espa\u00f1a y estaba en la lista de personas buscadas de Interpol.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Gerso Guerrero, hermano de \u201cNi\u00f1o Guerrero\u201d, l\u00edder del Tren de Aragua fue extraditado de Espa\u00f1a a Venezuela, inform\u00f3 el fiscal general de Venezuela, Tarek William Saab, en su cuenta de X. El Gobierno de Biden designa al Tren de Aragua como organizaci\u00f3n criminal trasnacional, seg\u00fan funcionario Saab precis\u00f3 que el hombre extraditado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451055","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Gerso Guerrero, hermano de \u201cNi\u00f1o Guerrero\u201d, l\u00edder del Tren de Aragua fue extraditado de Espa\u00f1a a Venezuela, inform\u00f3 el fiscal general de Venezuela, Tarek William Saab, en su cuenta de X. El Gobierno de Biden designa al Tren de Aragua como organizaci\u00f3n criminal trasnacional, seg\u00fan funcionario Saab precis\u00f3 que el hombre extraditado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T23:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a\",\"datePublished\":\"2024-07-11T23:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\",\"name\":\"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-11T23:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Gerso Guerrero, hermano de \u201cNi\u00f1o Guerrero\u201d, l\u00edder del Tren de Aragua fue extraditado de Espa\u00f1a a Venezuela, inform\u00f3 el fiscal general de Venezuela, Tarek William Saab, en su cuenta de X. El Gobierno de Biden designa al Tren de Aragua como organizaci\u00f3n criminal trasnacional, seg\u00fan funcionario Saab precis\u00f3 que el hombre extraditado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-11T23:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/"},"author":{"name":"","@id":""},"headline":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a","datePublished":"2024-07-11T23:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","name":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-11T23:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Llega a Venezuela el hermano del l\u00edder del Tren de Aragua, extraditado desde Espa\u00f1a","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-11T23:03:39Z","datePublished":"2024-07-11T23:03:39Z","dateModified":"2024-07-11T23:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Llega a Venezuela el hermano del l\\u00edder del Tren de Aragua, extraditado desde Espa\\u00f1a\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/11\\\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/11\\\/venezuela-hermano-lider-tren-aragua-extraditado-espana-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-11T23:03:39Z\",\"datePublished\":\"2024-07-11T23:03:39Z\",\"dateModified\":\"2024-07-11T23:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456729,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/18\/detienen-presunto-tercer-lider-tren-de-aragua-orix\/","url_meta":{"origin":1451055,"position":0},"title":"Detienen en Colombia al presunto tercer l\u00edder del Tren de Aragua a nivel internacional","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"El venezolano Johan Michael Garc\u00eda Rojas, considerado el tercer l\u00edder de la organizaci\u00f3n criminal Tren de Aragua a nivel internacional, fue detenido este mi\u00e9rcoles en Cali, Colombia, informaron la Polic\u00eda Nacional y la Fiscal\u00eda General del pa\u00eds sudamericano.Garc\u00eda Rojas, tambi\u00e9n conocido como alias \u201cGallina\u201d, se encargaba presuntamente de coordinar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456359,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/07\/detienen-presunto-jefe-tren-de-aragua-chile-orix\/","url_meta":{"origin":1451055,"position":1},"title":"Detienen en Colombia al presunto jefe del Tren de Aragua de Chile","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"Carlos Francisco G\u00f3mez Moreno, considerado jefe del grupo criminal Tren de Aragua de Chile, fue detenido este s\u00e1bado en Colombia, inform\u00f3 la Polic\u00eda de ambos pa\u00edses sudamericanos, que trabajaron en conjunto en la operaci\u00f3n que llev\u00f3 a la captura.G\u00f3mez Moreno, conocido tambi\u00e9n como alias \u201cBobby\u201d, presuntamente huy\u00f3 de Chile hace\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455888,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/17\/detienen-segundo-lider-tren-de-aragua-colombia-orix\/","url_meta":{"origin":1451055,"position":2},"title":"Detienen al segundo l\u00edder del Tren de Aragua en Colombia","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 El venezolano Jeison Alexander Lorca Salazar, considerado el segundo l\u00edder de la organizaci\u00f3n delictiva Tren de Aragua en Colombia y uno de los hombres m\u00e1s buscados en su pa\u00eds, fue detenido en el departamento colombiano de Santander, informaron este s\u00e1bado el presidente Gustavo Petro y la Polic\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458092,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/31\/colombia-integrante-tren-aragua-homicidios-venezuela-orix\/","url_meta":{"origin":1451055,"position":3},"title":"Detienen en Colombia a presunto integrante del Tren de Aragua que habr\u00eda coordinado &#171;homicidios selectivos&#187; en Venezuela","author":"","date":"enero 31, 2025","format":false,"excerpt":"La Polic\u00eda Nacional de Colombia detuvo este viernes al venezolano Bernardo Enrique Atencio Padilla, presunto integrante de la organizaci\u00f3n criminal Tren de Aragua, quien ser\u00eda el responsable de coordinar \u201chomicidios selectivos\u201d en Venezuela, seg\u00fan inform\u00f3 en un comunicado la instituci\u00f3n.El arresto de Atencio Padilla, alias \u201cChocolate\u201d, ocurri\u00f3 en la ciudad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464157,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/07\/02\/matan-socio-nino-guerrero-lider-tren-de-aragua-orix\/","url_meta":{"origin":1451055,"position":4},"title":"Matan en Venezuela a socio de Ni\u00f1o Guerrero, l\u00edder del Tren de Aragua","author":"","date":"julio 2, 2025","format":false,"excerpt":"Darwin Jos\u00e9 Mart\u00ednez Oviedo, alias \u201cel Arepita\u201d, socio de H\u00e9ctor Guerrero, conocido como \u201cNi\u00f1o Guerrero\u201d e identificado por las autoridades de Venezuela como cabecilla de la banda delictiva Tren de Aragua, muri\u00f3 este domingo, confirm\u00f3 a CNN una fuente con conocimiento del asunto \u2015sin detallar c\u00f3mo lo mataron.La misma fuente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457732,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/21\/fiscalia-desmantelar-tren-de-aragua-donde-esta-lider-orix\/","url_meta":{"origin":1451055,"position":5},"title":"La Fiscal\u00eda de Venezuela asegura haber desmantelado al Tren de Aragua, pero no han dicho d\u00f3nde est\u00e1 su l\u00edder","author":"","date":"enero 21, 2025","format":false,"excerpt":"La Fiscal\u00eda General de Venezuela afirm\u00f3 este lunes haber desmantelado al grupo criminal transnacional Tren de Aragua, de acuerdo con un comunicado publicado en sus redes sociales.El anuncio llega luego de la decisi\u00f3n del presidente de Estados Unidos de designar a los c\u00e1rteles como organizaciones terroristas extranjeras.Seg\u00fan el Ministerio P\u00fablico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451055"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451055\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}