{"id":1451069,"date":"2024-07-12T10:03:39","date_gmt":"2024-07-12T17:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/"},"modified":"2024-07-12T10:03:39","modified_gmt":"2024-07-12T17:03:39","slug":"maria-corina-machado-empresario-albergo-detenido-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","title":{"rendered":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Detuvieron al empresario Ricardo Albacete Vidal, quien aloj\u00f3 en su casa a la l\u00edder opositora venezolana Mar\u00eda Corina Machado cuando realizaba un recorrido el 27 y 28 de junio por el estado T\u00e1chira, inform\u00f3 a CNN su abogado Omar Mora Tosta.<\/p>\n<p>El penalista agreg\u00f3 que familiares del tambi\u00e9n ciudadano espa\u00f1ol le comunicaron que Albacete fue interceptado este jueves por un grupo de hombres que no se identificaron cuando caminaba por las inmediaciones del hotel donde se hospedaba en Caracas. Mora calific\u00f3 la detenci\u00f3n de \u201carbitraria\u201d y dijo que hasta este momento Albacete \u201cse encuentra desaparecido porque no hay informaci\u00f3n\u201d.<\/p>\n<p>Estos son los 10 candidatos a presidente para las elecciones de Venezuela<\/p>\n<p>El jurista advirti\u00f3 que Albacete hab\u00eda sufrido persecuci\u00f3n en los \u00faltimos d\u00edas y que incluso fueron allanadas sus empresas y propiedades ubicadas en el interior del pa\u00eds. En estos procedimientos, el abogado dijo que varios trabajadores fueron detenidos sin que las autoridades presentaran orden de arresto alguna.<\/p>\n<p>CNN se comunic\u00f3 con el Ministerio P\u00fablico para conocer detalles sobre el caso, pero hasta ahora no ha habido respuesta. Sin embargo, la Fiscal\u00eda convoc\u00f3 una rueda de prensa en las pr\u00f3ximas horas.<\/p>\n<p>Mora dijo que acudi\u00f3 a las sedes del Sebin-Helicoide y de la Polic\u00eda Nacional Bolivariana para solicitar informaci\u00f3n sobre el paradero de su cliente pero que no ha recibido respuesta.<\/p>\n<p>El abogado asegura que Albacete, de 72 a\u00f1os, en todo caso, es inocente de cualquier il\u00edcito. Y record\u00f3 que, en el caso de las personas mayores de 70 a\u00f1os, en caso de ser declaradas culpables de alg\u00fan delito, la ley contempla medidas de presentaci\u00f3n o arresto domiciliario.<\/p>\n<p>El 1x10x7 y comanditos: as\u00ed funcionan las estrategias de movilizaci\u00f3n y defensa del voto de Nicol\u00e1s Maduro y Edmundo Gonz\u00e1lez<\/p>\n<p>Agrega que han sido sistem\u00e1ticas las detenciones, acoso contra personas y cierre de restaurantes, hoteles y posadas que han atendido o tenido contacto de una manera u otra con Mar\u00eda Corina Machado y con el candidato presidencial de la Plataforma Unitaria Democr\u00e1tica, Edmundo Gonz\u00e1lez Urrutia. Asegura que incluso han decomisado los equipos de sonido, camiones o cornetas de las personas que se los alquilan.<\/p>\n<p>Candidato opositor venezolano Edmundo Gonz\u00e1lez Urrutia toma medidas para evitar represalias a restaurantes que lo atienden<\/p>\n<p>Machado ha tomado medidas como hospedarse en casas privadas para evitar el cierre de posadas y hoteles, mientras que Gonz\u00e1lez Urrutia ha recurrido a llevarse su vianda de comida para evitar el cierre de restaurantes, tal como le ocurri\u00f3 el fin de semana a un local de comida en el llanero estado Cojedes y antes a un hotel en Maracaibo donde Machado se aloj\u00f3 en mayo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Detuvieron al empresario Ricardo Albacete Vidal, quien aloj\u00f3 en su casa a la l\u00edder opositora venezolana Mar\u00eda Corina Machado cuando realizaba un recorrido el 27 y 28 de junio por el estado T\u00e1chira, inform\u00f3 a CNN su abogado Omar Mora Tosta. El penalista agreg\u00f3 que familiares del tambi\u00e9n ciudadano espa\u00f1ol le comunicaron [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451069","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Detuvieron al empresario Ricardo Albacete Vidal, quien aloj\u00f3 en su casa a la l\u00edder opositora venezolana Mar\u00eda Corina Machado cuando realizaba un recorrido el 27 y 28 de junio por el estado T\u00e1chira, inform\u00f3 a CNN su abogado Omar Mora Tosta. El penalista agreg\u00f3 que familiares del tambi\u00e9n ciudadano espa\u00f1ol le comunicaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T17:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado\",\"datePublished\":\"2024-07-12T17:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\"},\"wordCount\":497,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\",\"name\":\"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-12T17:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Detuvieron al empresario Ricardo Albacete Vidal, quien aloj\u00f3 en su casa a la l\u00edder opositora venezolana Mar\u00eda Corina Machado cuando realizaba un recorrido el 27 y 28 de junio por el estado T\u00e1chira, inform\u00f3 a CNN su abogado Omar Mora Tosta. El penalista agreg\u00f3 que familiares del tambi\u00e9n ciudadano espa\u00f1ol le comunicaron [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-12T17:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado","datePublished":"2024-07-12T17:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/"},"wordCount":497,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","name":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-12T17:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detienen a empresario venezolano que alberg\u00f3 a Mar\u00eda Corina Machado en su casa, denuncia su abogado","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/12\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-12T17:03:39Z","datePublished":"2024-07-12T17:03:39Z","dateModified":"2024-07-12T17:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detienen a empresario venezolano que alberg\\u00f3 a Mar\\u00eda Corina Machado en su casa, denuncia su abogado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/12\\\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/12\\\/maria-corina-machado-empresario-albergo-detenido-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-12T17:03:39Z\",\"datePublished\":\"2024-07-12T17:03:39Z\",\"dateModified\":\"2024-07-12T17:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451349,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/22\/maria-corina-machado-venezuela-elecciones-conclusiones-entrevista-conclu-orix\/","url_meta":{"origin":1451069,"position":0},"title":"Mar\u00eda Corina Machado en Conclusiones: Maduro ha hecho de su campa\u00f1a la violencia, es lo \u00fanico que le queda","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Mar\u00eda Corina Machado asegur\u00f3 en Conclusiones de CNN con Fernando del Rinc\u00f3n que Nicol\u00e1s Maduro ha hecho de su campa\u00f1a la violencia debido a que es lo \u00fanico que le queda, pues el r\u00e9gimen se ha desgastado tanto que \"ya est\u00e1 derrotado\".La semana pasada, el presidente Nicol\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470085,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/01\/14\/real-madrid-albacete-octavos-copa-del-rey-arbeloa-efe\/","url_meta":{"origin":1451069,"position":1},"title":"El debut de Arbeloa en el Real Madrid es un batacazo: eliminados de la Copa del Rey por un equipo de segunda divisi\u00f3n","author":"","date":"enero 14, 2026","format":false,"excerpt":"Lejos de arreglar cualquier problema del Real Madrid con Xabi Alonso, el estreno de \u00c1lvaro Arbeloa dej\u00f3 el peor sabor de boca posible con derrota y eliminaci\u00f3n de la Copa del Rey ante un Albacete que firm\u00f3 el primer triunfo de su historia frente al club blanco, encontrando el premio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451194,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/17\/maria-corina-machado-detencion-jefe-de-seguridad-orix\/","url_meta":{"origin":1451069,"position":2},"title":"Mar\u00eda Corina Machado denuncia la detenci\u00f3n de su jefe de seguridad","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 La l\u00edder opositora venezolana Mar\u00eda Corina Machado afirm\u00f3 este mi\u00e9rcoles en X que Milciades \u00c1vila, jefe de seguridad de su equipo, fue arrestado en la madrugada por presunta \"violencia de g\u00e9nero\" contra un grupo de mujeres que, seg\u00fan Machado, intentaron agredirla a ella y al candidato presidencial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462758,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/05\/24\/patricio-albacete-en-el-libro-cuento-mi-historia-deportiva-de-vida-y-pasamos-por-el-conflicto-que-hubo-en-los-pumas\/","url_meta":{"origin":1451069,"position":3},"title":"Patricio Albacete: &#171;En el libro cuento mi historia deportiva, de vida, y pasamos por el conflicto que hubo en los Pumas&#187;","author":"","date":"mayo 24, 2025","format":false,"excerpt":"Patricio Albacete, referente del rugby nacional habl\u00f3 este s\u00e1bado con CNN Radio sobre las gestas que alcanz\u00f3 en el pasado y su libro Mil Batallas.En Aire de S\u00e1bado con Guillermo Panizza indic\u00f3: \u201cEn realidad yo no ten\u00eda idea de contar sobre mi vida, cuando dej\u00e9 de jugar no me parec\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450631,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/06\/23\/alejandro-sanz-apoyo-lider-opositora-venezolana-maria-corina-machado-orix\/","url_meta":{"origin":1451069,"position":4},"title":"Alejandro Sanz expresa su apoyo a la l\u00edder opositora venezolana Mar\u00eda Corina Machado","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El cantante y compositor espa\u00f1ol Alejandro Sanz mostr\u00f3 este domingo su apoyo a la l\u00edder opositora venezolana Mar\u00eda Corina Machado a trav\u00e9s de un mensaje en sus redes sociales.\"Hay nombres que son llaves capaces de abrir las puertas a un futuro esperanzador\", escribi\u00f3 Sanz en su cuenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457319,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/maria-corina-machado-casa-madre-energia-orix\/","url_meta":{"origin":1451069,"position":5},"title":"Mar\u00eda Corina Machado denuncia que funcionarios del Gobierno rodearon la casa de su madre y quitaron la energ\u00eda en la zona","author":"","date":"enero 7, 2025","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo este martes que funcionarios del Gobierno de Venezuela rodearon la casa de su madre en Caracas e instalaron puntos de control policial en el sector donde vive, al tiempo que la zona \u2014sobrevolada con drones, seg\u00fan dijo\u2014 se qued\u00f3 sin electricidad.Machado hizo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451069"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451069\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}