{"id":1451102,"date":"2024-07-14T16:03:46","date_gmt":"2024-07-14T23:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/"},"modified":"2024-07-14T16:03:46","modified_gmt":"2024-07-14T23:03:46","slug":"servicio-secreto-preguntas-seguridad-tiroteo-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","title":{"rendered":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump"},"content":{"rendered":"<p>(CNN) &#8212; A ra\u00edz del intento de asesinato de Donald Trump, hay inquietudes y preguntas generalizadas sobre c\u00f3mo un francotirador pudo obtener acceso a la azotea a aproximadamente 150 metros de la posici\u00f3n del expresidente en el podio durante un mitin al aire libre.<\/p>\n<p>Las fuentes describieron el tiroteo como procedente de la posici\u00f3n de las &#171;tres en punto&#187; desde el podio de Trump, con disparos que proven\u00edan de su lado derecho. Segundos despu\u00e9s de que sonaran los disparos, los francotiradores del Servicio Secreto comenzaron a disparar al sospechoso que fue encontrado en lo alto de un tejado.<\/p>\n<p>Cabe destacar que la ubicaci\u00f3n del atacante estaba fuera del per\u00edmetro de seguridad, lo que plantea interrogantes sobre el tama\u00f1o del per\u00edmetro y los esfuerzos para barrer y asegurar el edificio de American Glass Research, y c\u00f3mo el tirador pudo obtener acceso a la azotea.<\/p>\n<p>\u201cMuri\u00f3 como un h\u00e9roe\u201d. El gobernador de Pensilvania habla de la v\u00edctima asesinada en el mitin de Trump<\/p>\n<p>El presidente Joe Biden dijo este domingo que le orden\u00f3 a la directora del Servicio Secreto de Estados Unidos, Kimberly Cheatle, \u201crevisar todas las medidas de seguridad para la Convenci\u00f3n Nacional Republicana\u201d.<\/p>\n<p>\u201cOrden\u00e9 una revisi\u00f3n independiente de la seguridad nacional en el mitin de ayer para evaluar exactamente lo que sucedi\u00f3. Y compartir\u00e9 los resultados de esa revisi\u00f3n independiente con el pueblo estadounidense\u201d, dijo Biden.<\/p>\n<p>Fuentes policiales afirmaron que parte de las consecuencias incluir\u00e1n una revisi\u00f3n de si el Servicio Secreto ten\u00eda suficientes activos para proteger a Trump d\u00edas antes de convertirse oficialmente en el candidato presidencial republicano y si se siguieron los procedimientos para realizar chequeos de seguridad en el edificio que ofrec\u00eda un punto de observaci\u00f3n para el presunto tirador.<\/p>\n<p>\u201cB\u00e1sicamente, uno de los elementos m\u00e1s b\u00e1sicos de la seguridad de un sitio, especialmente en un sitio que est\u00e1 al aire libre y en gran parte sin control, es eliminar las l\u00edneas de visi\u00f3n hacia este espacio donde el protegido estar\u00e1 hablando\u201d, dijo el exsubdirector del FBI Andrew McCabe en el programa \u201cState of the Union\u201d de CNN este domingo por la ma\u00f1ana. \u201cCuando miras ese mapa, se\u00f1ala claramente los edificios que est\u00e1n dentro de \u00e9l, que claramente est\u00e1n dentro del alcance de tiro\u201d.<\/p>\n<p>El FBI lidera la investigaci\u00f3n sobre el intento de asesinato<\/p>\n<p>Se deconoce c\u00f3mo el tirador pudo acceder a la azotea que estaba una distancia relativamente cercana de Trump, o por qu\u00e9 ese edificio qued\u00f3 fuera del per\u00edmetro de seguridad \u201cfuerte\u201d. El FBI es ahora la agencia principal que investiga el intento de asesinato. Pero la cuesti\u00f3n de la falla de seguridad ser\u00e1 investigada por el Departamento de Seguridad Nacional y el Servicio de Seguridad Nacional, as\u00ed como por el Congreso.<\/p>\n<p>Seg\u00fan KDKA, afiliada de CNN, un testigo dijo que les hab\u00eda comentado a los agentes que vio a un hombre armado movi\u00e9ndose \u201cde techo en techo\u201d, momentos antes del intento de asesinato.<\/p>\n<p>Ben Macer estaba junto a una valla cuando vio \u201cal tipo moverse de un tejado a otro. (Le) dije a un oficial que (el presunto atacante) estaba en el tejado\u201d, inform\u00f3 KDKA. \u201cCuando me di la vuelta para volver a donde estaba, fue cuando empezaron los disparos, y luego se desat\u00f3 el caos, y todos salimos corriendo, y eso fue todo\u201d.<\/p>\n<p>Los testigos tambi\u00e9n dijeron a los periodistas que vieron a una persona que coincid\u00eda con la descripci\u00f3n del presunto atacante que portaba un rifle fuera del cord\u00f3n de seguridad de la manifestaci\u00f3n antes del tiroteo.<\/p>\n<p>Seg\u00fan un alto funcionario policial, el atacante fue visto por la polic\u00eda local, que pens\u00f3 que podr\u00eda haber actuado de forma sospechosa cerca de los magnet\u00f3metros del evento del s\u00e1bado. Lo comentaron por intercomunicador para vigilarlo, y esa informaci\u00f3n tambi\u00e9n fue transmitida al Servicio Secreto, seg\u00fan la fuente.<\/p>\n<p>\u201c\u00a1Tiene una pistola!&#187; Escucha el audio de los asistentes al mitin de Donald Trump cuando ven al hombre armado<\/p>\n<p>Varias fuentes policiales le dijeron a CNN que el tirador ten\u00eda material explosivo en su autom\u00f3vil y en su residencia. El Servicio Secreto no permite armas dentro de las zonas acordonadas de ning\u00fan evento. AGR no respondi\u00f3 a las preguntas de CNN sobre el incidente o la seguridad.<\/p>\n<p>Las autoridades identificaron al atacante como Thomas Matthew Crooks, de 20 a\u00f1os, quien muri\u00f3 luego de que agentes del Servicio Secreto le dispararan.<\/p>\n<p>Varias fuentes policiales con profundo conocimiento de las operaciones del Servicio Secreto le dijeron a CNN que los equipos de francotiradores tienen amplia discreci\u00f3n al derribar una amenaza.<\/p>\n<p>El Servicio Secreto afirma que hab\u00eda cuatro equipos de francotiradores: dos del Servicio Secreto y dos de las fuerzas de seguridad locales. La agencia afirm\u00f3 que, en el momento del tiroteo, Cheatle se encontraba en Milwaukee, donde se celebra esta semana la Convenci\u00f3n Nacional Republicana.<\/p>\n<p>El Congreso pide que se investiguen las &#171;fallas&#187; en la seguridad<\/p>\n<p>Los legisladores republicanos y dem\u00f3cratas ya est\u00e1n exigen respuestas de la agencia sobre la postura de seguridad y audiencias sobre el incidente.<\/p>\n<p>El presidente de la C\u00e1mara de Representantes, Mike Johnson, prometi\u00f3 una \u201cinvestigaci\u00f3n completa\u201d del tiroteo, con testimonios del USSS (Servicio Secreto, por sus siglas en ingl\u00e9s), el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y el FBI. Dos republicanos del Comit\u00e9 de Seguridad Nacional del Senado tambi\u00e9n pidieron una investigaci\u00f3n.<\/p>\n<p>El presidente de la Comisi\u00f3n de Inteligencia de la C\u00e1mara de Representantes, Mike Turner, dijo tambi\u00e9n en el programa \u201cState of the Union\u201d de CNN que el Congreso ten\u00eda \u201csupervisi\u00f3n, escrutinio y responsabilidad\u201d, y dijo que hab\u00eda un \u201cfallo de la red m\u00e1s amplia en general\u201d.<\/p>\n<p>El presidente de la Comisi\u00f3n de Seguridad Nacional de la C\u00e1mara de Representantes, Mark Green, se centr\u00f3 en la cuesti\u00f3n del edificio en una carta al Departamento de Seguridad Nacional este domingo.<\/p>\n<p>Green envi\u00f3 una carta al Secretario del DHS, Alejandro Mayorkas, en la que solicitaba documentos sobre los planes de seguridad del Servicio Secreto y sus comunicaciones antes del 19 de julio y una reuni\u00f3n informativa antes del 22 de julio.<\/p>\n<p>El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, se comunic\u00f3 con el Servicio Secreto para solicitar una reuni\u00f3n informativa y convoc\u00f3 a Cheatle a una audiencia el 22 de julio.<\/p>\n<p>Los representantes de Nueva York Ritchie Torres, dem\u00f3crata, y Mike Lawler, republicano, tambi\u00e9n trabajan para presentar un proyecto de ley que, seg\u00fan dijeron, brindar\u00eda mayor protecci\u00f3n del USSS a Trump, Biden y el candidato presidencial independiente Robert F. Kennedy Jr.<\/p>\n<p>\u201cA medida que siguen surgiendo informes, queda claro que se necesita m\u00e1s protecci\u00f3n para todos los principales candidatos a la presidencia\u201d, dijeron ambos en una declaraci\u00f3n conjunta proporcionada a CNN.<\/p>\n<p>En otra carta separada enviada este domingo al director del Servicio Secreto, el representante dem\u00f3crata Rub\u00e9n Gallego dijo que hubo una \u201cfalla de seguridad al m\u00e1s alto nivel, que nos se ve\u00eda desde el intento de asesinato del presidente Reagan\u201d.<\/p>\n<p>\u201cEsto no puede suceder y exijo rendici\u00f3n de cuentas\u201d, dijo Gallego, quien se postula para un esca\u00f1o en el Senado de Arizona.<\/p>\n<p>El Servicio Secreto niega las afirmaciones de que rechaz\u00f3 las solicitudes de mayor seguridad para Trump<\/p>\n<p>El Servicio Secreto, junto con agentes locales de Pensilvania que ayudaron a proteger el lugar del mitin, as\u00ed como fuentes cercanas a la campa\u00f1a de Trump, niegan los rumores que circulan en las redes sociales de que la agencia hab\u00eda rechazado las solicitudes del equipo de Trump que exig\u00edan mayor seguridad.<\/p>\n<p>\u201cExiste una afirmaci\u00f3n falsa de que un miembro del equipo del expresidente solicit\u00f3 recursos de seguridad adicionales y que estos fueron rechazados\u201d, dijo el portavoz del Servicio Secreto, Anthony Guglielmi. \u201cEso es absolutamente falso. De hecho, agregamos recursos, tecnolog\u00eda y capacidades de protecci\u00f3n como parte del aumento del ritmo de viajes de campa\u00f1a\u201d.<\/p>\n<p>El FBI tambi\u00e9n desminti\u00f3 esta insinuaci\u00f3n este s\u00e1bado por la noche.<\/p>\n<p>Los dem\u00f3cratas analizan c\u00f3mo continuar la campa\u00f1a y salvar la candidatura de Biden tras el intento de magnicidio contra Trump<\/p>\n<p>\u201cNo hubo ninguna solicitud adicional de seguridad que fuera denegada por el FBI\u201d, dijo Kevin Rojek, el agente especial del FBI a cargo de la oficina de Pittsburgh, durante una conferencia de prensa.<\/p>\n<p>El incidente tambi\u00e9n plantea interrogantes sobre la seguridad en la pr\u00f3xima convenci\u00f3n republicana. Recientemente, en una conferencia de prensa en la que se explic\u00f3 el plan de seguridad de la Convenci\u00f3n Nacional Republicana, se plantearon interrogantes sobre c\u00f3mo tratar\u00edan el Servicio Secreto y los agentes de seguridad a quienes porten armas de fuego.<\/p>\n<p>Un funcionario local, Nick DeSiato, dej\u00f3 en claro que, debido a la ley de Wisconsin, se permitir\u00edan armas de fuego en el per\u00edmetro \u201cblando\u201d, un \u00e1rea fuera de los magnet\u00f3metros que est\u00e1 limitada al tr\u00e1fico peatonal.<\/p>\n<p>Otras fallas en la protecci\u00f3n de funcionarios de alto perfil<\/p>\n<p>El escrutinio se produce en un momento en que el Servicio Secreto ha tenido que lidiar con fallos de seguridad en los \u00faltimos meses y a\u00f1os. En mayo de 2023, un intruso accedi\u00f3 a la casa de Jake Sullivan, el asesor de seguridad nacional de la Casa Blanca, a pesar de que el Servicio Secreto lo proteg\u00eda las 24 horas del d\u00eda. Sullivan se encontr\u00f3 con el intruso en su casa y alert\u00f3 a su equipo de seguridad. Sullivan sali\u00f3 ileso.<\/p>\n<p>El 6 de enero de 2021, la entonces vicepresidenta entrante, Kamala Harris, fue conducida por su equipo de seguridad a unos metros de una bomba casera frente a la sede nacional del Partido Dem\u00f3crata. Fue evacuada despu\u00e9s de que los agentes descubrieran la bomba casera m\u00e1s de 90 minutos despu\u00e9s de su llegada.<\/p>\n<p>El Servicio Secreto utiliza inteligencia e informaci\u00f3n estrat\u00e9gica para determinar la postura de seguridad.<\/p>\n<p>La agencia no es formalmente parte de la comunidad de inteligencia y se considera un &#171;consumidor&#187; de inteligencia, dependiendo en gran medida de las relaciones con agencias como el Director de Inteligencia Nacional, la Agencia Central de Inteligencia, la Agencia de Seguridad Nacional, la Oficina Federal de Investigaciones y la Oficina de Inteligencia y An\u00e1lisis del Departamento de Seguridad Nacional.<\/p>\n<p>\u2013\u2013 John Miller, Sam Fossum, Allison Gordon, Ali Main, Kayla Gallagher y Hannah Rabinowitz de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; A ra\u00edz del intento de asesinato de Donald Trump, hay inquietudes y preguntas generalizadas sobre c\u00f3mo un francotirador pudo obtener acceso a la azotea a aproximadamente 150 metros de la posici\u00f3n del expresidente en el podio durante un mitin al aire libre. Las fuentes describieron el tiroteo como procedente de la posici\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451102","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; A ra\u00edz del intento de asesinato de Donald Trump, hay inquietudes y preguntas generalizadas sobre c\u00f3mo un francotirador pudo obtener acceso a la azotea a aproximadamente 150 metros de la posici\u00f3n del expresidente en el podio durante un mitin al aire libre. Las fuentes describieron el tiroteo como procedente de la posici\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-14T23:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump\",\"datePublished\":\"2024-07-14T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\"},\"wordCount\":1817,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\",\"name\":\"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-14T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias","og_description":"(CNN) &#8212; A ra\u00edz del intento de asesinato de Donald Trump, hay inquietudes y preguntas generalizadas sobre c\u00f3mo un francotirador pudo obtener acceso a la azotea a aproximadamente 150 metros de la posici\u00f3n del expresidente en el podio durante un mitin al aire libre. Las fuentes describieron el tiroteo como procedente de la posici\u00f3n de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-14T23:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/"},"author":{"name":"","@id":""},"headline":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump","datePublished":"2024-07-14T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/"},"wordCount":1817,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","name":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-14T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/14\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-14T23:03:46Z","datePublished":"2024-07-14T23:03:46Z","dateModified":"2024-07-14T23:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Servicio Secreto enfrenta serios cuestionamientos sobre la seguridad durante el mitin de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/14\\\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/14\\\/servicio-secreto-preguntas-seguridad-tiroteo-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-14T23:03:46Z\",\"datePublished\":\"2024-07-14T23:03:46Z\",\"dateModified\":\"2024-07-14T23:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451177,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/16\/fallo-seguridad-mitin-trump-pensilvania-trax\/","url_meta":{"origin":1451102,"position":0},"title":"Qu\u00e9 fall\u00f3 en la seguridad del mitin de Trump en Pensilvania","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) --\u00a0Errores de seguridad, fallos y oportunidades perdidas para detener a un atacante llevaron al primer tiroteo contra un presidente o expresidente de Estados Unidos en m\u00e1s de una generaci\u00f3n.Estos son varios asuntos y problemas identificados por CNN que podr\u00edan o deber\u00edan haberse abordado antes del ataque al expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451345,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/22\/intento-asesinato-trump-audiencia-directora-servicio-secreto-trax\/","url_meta":{"origin":1451102,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 el d\u00eda del intento de asesinato de Trump? Esto revela la audiencia de la directora del Servicio Secreto","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- La directora del Servicio Secreto de Estados Unidos, Kimberly Cheatle, se enfrent\u00f3 este lunes a legisladores enojados de ambos partidos, quienes la interrogaron sobre las fallas de seguridad que llevaron al reciente intento de asesinato contra Donald Trump.El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455070,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/13\/intento-asesinato-hombre-armas-mitin-trump-california-trax\/","url_meta":{"origin":1451102,"position":2},"title":"Funcionarios federales dicen que Trump no estaba en peligro despu\u00e9s de que un hombre fuera arrestado con armas ilegales cerca de un mitin de campa\u00f1a en California","author":"","date":"octubre 13, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Dos funcionarios federales le dijeron a CNN que no hay evidencia en este momento que indique que el hombre que fue arrestado por portaci\u00f3n de armas cerca del mitin de Donald Trump el s\u00e1bado en California estuviera tratando de atentar contra el expresidente.En una declaraci\u00f3n conjunta con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451233,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/18\/derecha-culpa-mujeres-servicio-secreto-seguridad-trump-trax\/","url_meta":{"origin":1451102,"position":3},"title":"Figuras de los medios de derecha culpan a las mujeres del Servicio Secreto por el fallo de seguridad en atentado contra Trump","author":"","date":"julio 18, 2024","format":false,"excerpt":"(CNN) -- En los d\u00edas posteriores al intento de magnicidio del expresidente Donald Trump, el Servicio Secreto, encargado de proteger el mitin de Pensilvania, se ha enfrentado al escrutinio por la extraordinaria falla de seguridad que condujo al peor fracaso de la agencia en d\u00e9cadas.Pero una narrativa se afianz\u00f3 r\u00e1pidamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451293,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/20\/servicio-secreto-denego-recursos-adicionales-a-trump-pese-a-que-su-equipo-se-quejo-trax\/","url_meta":{"origin":1451102,"position":4},"title":"El Servicio Secreto dice que deneg\u00f3 recursos adicionales a Trump pese a que su equipo se quej\u00f3","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN) -- El dispositivo de seguridad del expresidente Donald Trump se hab\u00eda quejado de que el Servicio Secreto no les hab\u00eda proporcionado suficientes recursos y personal en los \u00faltimos dos a\u00f1os, y la agencia reconoci\u00f3 este s\u00e1bado que deneg\u00f3 algunas peticiones.Un portavoz del Servicio Secreto dijo en un comunicado este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451167,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/16\/exclusivo-cnn-servicio-secreto-reforzo-seguridad-complot-irani-asesinar-trump-trax\/","url_meta":{"origin":1451102,"position":5},"title":"EXCLUSIVO CNN: El Servicio Secreto reforz\u00f3 la seguridad de Trump tras recibir informaci\u00f3n sobre un complot iran\u00ed para asesinarlo; no hay conexi\u00f3n conocida con el tiroteo","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) -- Las autoridades de Estados Unidos obtuvieron informaci\u00f3n de inteligencia de fuente humana en las \u00faltimas semanas sobre un complot de Ir\u00e1n para tratar de asesinar a Donald Trump, un desarrollo que llev\u00f3 al Servicio Secreto a aumentar la seguridad alrededor del expresidente en las \u00faltimas semanas, dijeron a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451102"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451102\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}