{"id":1451138,"date":"2024-07-15T16:04:00","date_gmt":"2024-07-15T23:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/"},"modified":"2024-07-15T16:04:00","modified_gmt":"2024-07-15T23:04:00","slug":"nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","title":{"rendered":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A partir de este 2024, un nuevo d\u00eda se suma a la lista de feriados en M\u00e9xico: cada seis a\u00f1os el 1 de octubre, d\u00eda de la transmisi\u00f3n del nuevo Gobierno, ser\u00e1 de descanso obligatorio para los trabajadores mexicanos.<\/p>\n<p>As\u00ed lo establece un nuevo decreto publicado en el Diario Oficial de la Federaci\u00f3n por el que se modifica el Calendario Oficial del 6 de octubre de 1993 y su posterior reforma en enero de 2006.<\/p>\n<p>El nuevo feriado oficial se da con motivo de la transici\u00f3n del Poder Ejecutivo cada seis a\u00f1os, es decir el d\u00eda en que cambia el Gobierno y asume un nuevo presidente o presidenta.<\/p>\n<p>Estos son los d\u00edas festivos y puentes en M\u00e9xico para 2024<\/p>\n<p>Seg\u00fan el calendario oficial, estos son los d\u00edas feriados oficiales en M\u00e9xico:<\/p>\n<p>1 de enero<br \/>\nEl primer lunes de febrero en conmemoraci\u00f3n del 5 de febrero<br \/>\nEl tercer lunes de marzo en conmemoraci\u00f3n del 21 de marzo<br \/>\n1 de mayo<br \/>\n5 de mayo<br \/>\n16 de septiembre<br \/>\n1 de octubre de cada seis a\u00f1os, con motivo de la transmisi\u00f3n del Poder Ejecutivo Federal<br \/>\nEl tercer lunes de noviembre en conmemoraci\u00f3n del 20 de noviembre<br \/>\n25 de diciembre<\/p>\n<p>Los feriados oficiales se establecen en la Ley Federal del Trabajo como d\u00edas de descanso obligatorio. De acuerdo con la ley, los trabajadores que laboren en estos d\u00edas deber\u00e1n recibir un salario doble aparte del correspodiente para la jornada.<\/p>\n<p>Claudia Sheinbaum, quien result\u00f3 ganadora en las elecciones del pasado 2 de junio, asumir\u00e1 este martes 1 de octubre de 2024 como nueva presidenta de M\u00e9xico.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A partir de este 2024, un nuevo d\u00eda se suma a la lista de feriados en M\u00e9xico: cada seis a\u00f1os el 1 de octubre, d\u00eda de la transmisi\u00f3n del nuevo Gobierno, ser\u00e1 de descanso obligatorio para los trabajadores mexicanos. As\u00ed lo establece un nuevo decreto publicado en el Diario Oficial de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451138","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; A partir de este 2024, un nuevo d\u00eda se suma a la lista de feriados en M\u00e9xico: cada seis a\u00f1os el 1 de octubre, d\u00eda de la transmisi\u00f3n del nuevo Gobierno, ser\u00e1 de descanso obligatorio para los trabajadores mexicanos. As\u00ed lo establece un nuevo decreto publicado en el Diario Oficial de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-15T23:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe\",\"datePublished\":\"2024-07-15T23:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\"},\"wordCount\":302,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\",\"name\":\"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-15T23:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; A partir de este 2024, un nuevo d\u00eda se suma a la lista de feriados en M\u00e9xico: cada seis a\u00f1os el 1 de octubre, d\u00eda de la transmisi\u00f3n del nuevo Gobierno, ser\u00e1 de descanso obligatorio para los trabajadores mexicanos. As\u00ed lo establece un nuevo decreto publicado en el Diario Oficial de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-15T23:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/"},"author":{"name":"","@id":""},"headline":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe","datePublished":"2024-07-15T23:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/"},"wordCount":302,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","name":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-15T23:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nuevo d\u00eda de descanso obligatorio en M\u00e9xico 2024: cu\u00e1ndo es y a qu\u00e9 se debe","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-15T23:04:00Z","datePublished":"2024-07-15T23:04:00Z","dateModified":"2024-07-15T23:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nuevo d\\u00eda de descanso obligatorio en M\\u00e9xico 2024: cu\\u00e1ndo es y a qu\\u00e9 se debe\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/15\\\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/15\\\/nuevo-dia-descanso-obligatorio-mexico-2024-cuando-es-a-que-se-debe-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-15T23:04:00Z\",\"datePublished\":\"2024-07-15T23:04:00Z\",\"dateModified\":\"2024-07-15T23:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456996,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/26\/dias-festivos-puentes-mexico-2025-orix\/","url_meta":{"origin":1451138,"position":0},"title":"Estos son los d\u00edas festivos y puentes en M\u00e9xico para 2025","author":"","date":"diciembre 26, 2024","format":false,"excerpt":"Como cada a\u00f1o, en 2025 los mexicanos tendr\u00e1n d\u00edas de descanso oficiales, seg\u00fan lo que establece la ley en el pa\u00eds.Algunos de estos d\u00edas caer\u00e1n en viernes o lunes, lo que dar\u00e1 lugar a los cl\u00e1sicos \u201cpuentes\u201d (que no son otra cosa que un descanso prolongado cuando los d\u00edas festivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442858,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/29\/feriados-en-argentina-en-2024-estos-son-los-dias-festivos-y-puentes\/","url_meta":{"origin":1451138,"position":1},"title":"Feriados en Argentina en 2024: estos son los d\u00edas festivos y puentes","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Javier Milei public\u00f3 en el Bolet\u00edn oficial el viernes 29 de diciembre, \u00faltimo d\u00eda h\u00e1bil del a\u00f1o, los feriados con fines tur\u00edsticos. Tomando como base la Ley 27.399, sobre feriados y d\u00edas no laborables y sancionada en 2017, qued\u00f3 estipulada cu\u00e1l ser\u00e1 el calendario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442873,"url":"https:\/\/noticiasya.com\/sacramento\/2023\/12\/29\/feriados-en-argentina-en-2024-estos-son-los-dias-festivos-y-puentes-2\/","url_meta":{"origin":1451138,"position":2},"title":"Feriados en Argentina en 2024: estos son los d\u00edas festivos y puentes","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Javier Milei public\u00f3 en el Bolet\u00edn oficial el viernes 29 de diciembre, \u00faltimo d\u00eda h\u00e1bil del a\u00f1o, los feriados con fines tur\u00edsticos. Tomando como base la Ley 27.399, sobre feriados y d\u00edas no laborables y sancionada en 2017, qued\u00f3 estipulada cu\u00e1l ser\u00e1 el calendario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457268,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/feriados-argentina-2025-orix\/","url_meta":{"origin":1451138,"position":3},"title":"Feriados en Argentina en 2025: estos son los d\u00edas festivos y no laborables","author":"","date":"enero 6, 2025","format":false,"excerpt":"El Gobierno de Argentina oficializ\u00f3 el 23 de diciembre los feriados y d\u00edas no laborables con fines tur\u00edsticos para 2025.A trav\u00e9s del Decreto 1027, publicado en el Bolet\u00edn Oficial, se establecieron modificaciones al r\u00e9gimen de feriados nacionales y jornadas no laborables con fines tur\u00edsticos.A partir de 2025, los llamados \u201cferiados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451039,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/11\/claudia-sheinbaum-gabinete-nuevo-miembro-mexico-orix\/","url_meta":{"origin":1451138,"position":4},"title":"Claudia Sheinbaum anuncia un nuevo miembro para su gabinete","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La ganadora de las \u00faltimas elecciones presidenciales de M\u00e9xico, Claudia Sheinbaum, anuncia este jueves un nuevo miembro designado para lo que ser\u00e1 su gabinete cuando asuma el cargo.Este es el cuarto anuncio oficial que hace Sheinbaum respecto a qui\u00e9nes la acompa\u00f1ar\u00e1n en su gesti\u00f3n. Hasta el momento,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450893,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/05\/dias-festivos-ee-uu-2024-orix\/","url_meta":{"origin":1451138,"position":5},"title":"Estos son los d\u00edas festivos en EE.UU. para 2024","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Conoce aqu\u00ed los d\u00edas festivos y feriados que hay en Estados Unidos para 2024.Los siguientes d\u00edas est\u00e1n marcados por el calendario de d\u00edas festivos federales de EE.UU.Los d\u00edas festivos en Estados Unidos para 2024Lunes, 1 de enero - D\u00eda de A\u00f1o NuevoLunes, 15 de enero - Natalicio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451138"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451138\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}