{"id":1451140,"date":"2024-07-15T17:03:50","date_gmt":"2024-07-16T00:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/"},"modified":"2024-07-15T17:03:50","modified_gmt":"2024-07-16T00:03:50","slug":"excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","title":{"rendered":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Carlos Prosperi, quien fue uno de los candidatos en las primarias de la oposici\u00f3n de Venezuela realizadas en octubre, expres\u00f3 este s\u00e1bado su apoyo al presidente Nicol\u00e1s Maduro, quien buscar\u00e1 una segunda reelecci\u00f3n y un tercer mandato en las elecciones del 28 de julio.<\/p>\n<p>\u201cEl \u00fanico que puede mantener la paz en nuestro amado pa\u00eds, el \u00fanico que garantiza el crecimiento econ\u00f3mico y el di\u00e1logo con todas las partes del pa\u00eds es el presidente Nicol\u00e1s Maduro. Es por eso, que he tomado la firme decisi\u00f3n, de manera categ\u00f3rica, de dar mi respaldo al presidente Nicolas Maduro para la reelecci\u00f3n a la presidencia de la Rep\u00fablica\u201d, dijo el dirigente pol\u00edtico en rueda de prensa a 15 d\u00edas de los comicios.<\/p>\n<p>Elecciones en Venezuela: un recorrido desde adentro de la campa\u00f1a de Edmundo Gonz\u00e1lez y Mar\u00eda Corina Machado<\/p>\n<p>Prosperi, uno de los contendientes en las primarias de la Plataforma Unitaria Democr\u00e1tica, dej\u00f3 las filas opositoras y afirm\u00f3 que ahora avala la propuesta que formul\u00f3 el presidente Maduro de convocar a un di\u00e1logo nacional despu\u00e9s de las elecciones del 28 de julio.<\/p>\n<p>\u201cCuenten con este servidor y con mi humilde aporte para devolverle la paz a trav\u00e9s del di\u00e1logo al pueblo de Venezuela. Le solicito formalmente al ciudadano presidente de la Rep\u00fablica que convoque a un gobierno de unidad nacional\u201d, agreg\u00f3 quien tambi\u00e9n fuera diputado a la Asamblea Nacional durante el per\u00edodo 2016-2021 por el partido Acci\u00f3n Democr\u00e1tica.<\/p>\n<p>Maduro reaccion\u00f3 este s\u00e1bado y asegur\u00f3 que no conoce a Prosperi, pero dijo que en su proyecto caben todos y le di\u00f3 la bienvenida al chavismo.<\/p>\n<p>Prosperi qued\u00f3 segundo con 4,45% de los votos en las primarias opositoras en 2023 en las que gan\u00f3 Mar\u00eda Corina Machado con el 92,56%.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Carlos Prosperi, quien fue uno de los candidatos en las primarias de la oposici\u00f3n de Venezuela realizadas en octubre, expres\u00f3 este s\u00e1bado su apoyo al presidente Nicol\u00e1s Maduro, quien buscar\u00e1 una segunda reelecci\u00f3n y un tercer mandato en las elecciones del 28 de julio. \u201cEl \u00fanico que puede mantener la paz en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451140","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Carlos Prosperi, quien fue uno de los candidatos en las primarias de la oposici\u00f3n de Venezuela realizadas en octubre, expres\u00f3 este s\u00e1bado su apoyo al presidente Nicol\u00e1s Maduro, quien buscar\u00e1 una segunda reelecci\u00f3n y un tercer mandato en las elecciones del 28 de julio. \u201cEl \u00fanico que puede mantener la paz en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-16T00:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales\",\"datePublished\":\"2024-07-16T00:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\",\"name\":\"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-16T00:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Carlos Prosperi, quien fue uno de los candidatos en las primarias de la oposici\u00f3n de Venezuela realizadas en octubre, expres\u00f3 este s\u00e1bado su apoyo al presidente Nicol\u00e1s Maduro, quien buscar\u00e1 una segunda reelecci\u00f3n y un tercer mandato en las elecciones del 28 de julio. \u201cEl \u00fanico que puede mantener la paz en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-16T00:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/"},"author":{"name":"","@id":""},"headline":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales","datePublished":"2024-07-16T00:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","name":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-16T00:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\u00e1s Maduro en las elecciones presidenciales","url":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2024\/07\/15\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-16T00:03:50Z","datePublished":"2024-07-16T00:03:50Z","dateModified":"2024-07-16T00:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Carlos Prosperi, excandidato en las primarias opositoras en Venezuela, expresa su respaldo a Nicol\\u00e1s Maduro en las elecciones presidenciales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/15\\\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2024\\\/07\\\/15\\\/excandidato-opositor-venezuela-respaldo-maduro-elecciones-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-16T00:03:50Z\",\"datePublished\":\"2024-07-16T00:03:50Z\",\"dateModified\":\"2024-07-16T00:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447039,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/16\/oficialismo-venezuela-nombra-nicolas-maduro-candidato-presidencial-orix\/","url_meta":{"origin":1451140,"position":0},"title":"El oficialismo en Venezuela nombra a Nicol\u00e1s Maduro como su candidato presidencial","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Partido Socialista Unido de Venezuela (PSUV) confirm\u00f3 este s\u00e1bado que el presidente Nicol\u00e1s Maduro ser\u00e1 el candidato presidencial del oficialismo para los comicios de este a\u00f1o.Maduro, quien acept\u00f3 la candidatura en una asamblea del partido celebrada en Caracas, buscar\u00e1 su segunda reelecci\u00f3n en los comicios que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457358,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/paises-reconocen-maduro-presidente-electo-venezuela-orix\/","url_meta":{"origin":1451140,"position":1},"title":"\u00bfQu\u00e9 pa\u00edses reconocen a Nicol\u00e1s Maduro como presidente electo de Venezuela?","author":"","date":"enero 8, 2025","format":false,"excerpt":"Los controvertidos resultados de las elecciones presidenciales en Venezuela causaron divisi\u00f3n entre los pa\u00edses que cuestionan los resultados oficiales que dieron como ganador a Nicol\u00e1s Maduro, los que reconocieron su victoria para empezar un tercer mandato y los pa\u00edses que esperaban evidencias de la votaci\u00f3n para fijar su postura.El Consejo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451385,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/24\/votacion-ultimas-dos-elecciones-presidenciales-venezuela-orix\/","url_meta":{"origin":1451140,"position":2},"title":"As\u00ed fue la votaci\u00f3n en las \u00faltimas dos elecciones presidenciales de Venezuela","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los venezolanos acuden a votar por un nuevo presidente el 28 de julio. Seg\u00fan las encuestas, la intenci\u00f3n de voto est\u00e1 entre el candidato de la oposici\u00f3n mayoritaria, Edmundo Gonz\u00e1lez Urrutia, y el presidente Nicol\u00e1s Maduro, quien va por su tercer mandato. Es la tercera vez que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450819,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/01\/maduro-venezuela-como-llego-al-poder-orix\/","url_meta":{"origin":1451140,"position":3},"title":"\u00bfC\u00f3mo lleg\u00f3 Nicol\u00e1s Maduro al poder en Venezuela?","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Nicol\u00e1s Maduro es candidato para las elecciones presidenciales del 28 de julio. Si su candidatura logra el apoyo popular en las urnas frente al aspirante apoyado por la mayor\u00eda de la oposici\u00f3n, Edmundo Gonz\u00e1lez Urrutia, el actual presidente lograr\u00eda su segunda reelecci\u00f3n y en 2025 empezar\u00eda un tercer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449333,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/09\/venezuela-tarjeton-presidente-orix\/","url_meta":{"origin":1451140,"position":4},"title":"As\u00ed ser\u00e1 el tarjet\u00f3n con el que los venezolanos elegir\u00e1n nuevo presidente para los pr\u00f3ximos seis a\u00f1os","author":"","date":"mayo 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Consejo Nacional Electoral de Venezuela (CNE) devel\u00f3 el mi\u00e9rcoles el tarjet\u00f3n electoral que mostrar\u00e1n las m\u00e1quinas el 28 de julio, trav\u00e9s del cual los electores podr\u00e1n elegir entre los 10 candidatos un presidente para un per\u00edodo de 6 a\u00f1os que iniciar\u00e1 el 10 de enero de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451022,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","url_meta":{"origin":1451140,"position":5},"title":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El canciller de Venezuela, Yv\u00e1n Gil, dijo este mi\u00e9rcoles que el presidente Nicol\u00e1s Maduro parte en \u201cclara desventaja\u201d rumbo a las elecciones del 28 de julio, debido a las sanciones internacionales.\u201cSon unas elecciones que vamos en clara distorsi\u00f3n, desventaja, que tiene el candidato a la reelecci\u00f3n (el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1451140"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1451140\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1451140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1451140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1451140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}