{"id":1457274,"date":"2025-01-06T10:03:45","date_gmt":"2025-01-06T18:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/"},"modified":"2025-01-06T10:03:45","modified_gmt":"2025-01-06T18:03:45","slug":"eta-reino-unido-48-paises-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","title":{"rendered":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje"},"content":{"rendered":"<p>Si 2024 fue el a\u00f1o en que los viajeros se libraron de la introducci\u00f3n de la burocracia para viajar sin visado a Europa, 2025 es el a\u00f1o en que se impone la realidad.<\/p>\n<p>La exenci\u00f3n de visado ETIAS de la Uni\u00f3n Europea, que se ha pospuesto hasta ahora, est\u00e1 prevista para 2025.<\/p>\n<p>Antes, el Reino Unido introducir\u00e1 su sistema ETA el 8 de enero.<\/p>\n<p>ETA, siglas de Electronic Travel Authorisation (autorizaci\u00f3n electr\u00f3nica de viaje), es un nuevo sistema de registro digital para viajeros que no necesitan visado para entrar en el Reino Unido.<\/p>\n<p>Mientras que antes pod\u00edan subirse a un avi\u00f3n y presentarse en el control de pasaportes al aterrizar, ahora, los viajeros tendr\u00e1n que obtener una autorizaci\u00f3n previa de viaje para volar al Reino Unido.<\/p>\n<p>Esto es lo que hay que saber sobre las nuevas normas.<\/p>\n<p>Cualquiera que no necesite visado para viajar al Reino Unido pronto necesitar\u00e1 una ETA, una \u201cautorizaci\u00f3n electr\u00f3nica de viaje\u201d que le autoriza a entrar en el pa\u00eds antes de viajar. Se trata del equivalente brit\u00e1nico de la ESTA estadounidense: una autorizaci\u00f3n de viaje obligatoria y de pago, con autorizaci\u00f3n de seguridad previa.<\/p>\n<p>El sistema se estren\u00f3 para los nacionales del Consejo de Cooperaci\u00f3n del Golfo en 2024, y la siguiente fase es extenderlo a otros viajeros no europeos, incluidos los seis millones de viajeros de Estados Unidos, Canad\u00e1 y Australia que entran en el Reino Unido cada a\u00f1o. La lista completa de los 48 estados que exigen la ETA est\u00e1 <a href=\"https:\/\/www.gov.uk\/guidance\/check-when-you-can-get-an-electronic-travel-authorisation-eta\">aqu\u00ed<\/a>.<\/p>\n<p>Los viajeros de estos pa\u00edses necesitar\u00e1n una ETA para entrar en el Reino Unido a partir del 8 de enero. La \u00fanica excepci\u00f3n son los ciudadanos de la Uni\u00f3n Europea, que necesitar\u00e1n una ETA para entrar en el Reino Unido a partir del 2 de abril de 2025.<\/p>\n<p>Los ciudadanos de estos pa\u00edses que ya residan en el Reino Unido no necesitar\u00e1n una ETA.<\/p>\n<p>El permiso es para visitas \u201ccortas\u201d al Reino Unido, de menos de seis meses, por turismo y negocios. Existen otras categor\u00edas de permisos ETA, como los de estudios de corta duraci\u00f3n y los que permiten estancias remuneradas. Estas categor\u00edas figuran en la <a href=\"https:\/\/www.gov.uk\/guidance\/apply-for-an-electronic-travel-authorisation-eta\">p\u00e1gina web del Gobierno brit\u00e1nico<\/a>.<\/p>\n<p>Aunque algunos lo llaman visado, en realidad se trata de una exenci\u00f3n de visado. Los viajeros que, por su nacionalidad, necesiten un visado para entrar en el Reino Unido tendr\u00e1n que solicitarlo igualmente. (No necesitar\u00e1n, sin embargo, obtener adem\u00e1s el ETA).<\/p>\n<p>Los pa\u00edses se basan en la reciprocidad en materia de inmigraci\u00f3n. Cuando Estados Unidos introdujo su exenci\u00f3n de visado ESTA en 2009, era inevitable que los pa\u00edses ahora sujetos a ella introdujeran sus propios sistemas similares.<\/p>\n<p>El costo es de 10 libras esterlinas (poco menos de US$ 12,50), no reembolsables, y se puede solicitar a trav\u00e9s de la aplicaci\u00f3n oficial que aparece en el <a href=\"https:\/\/www.gov.uk\/guidance\/check-when-you-can-get-an-electronic-travel-authorisation-eta\">sitio web del gobierno del Reino Unido<\/a>, o directamente <a href=\"https:\/\/apply-for-an-eta.homeoffice.gov.uk\/apply\/electronic-travel-authorisation\/easier-on-the-app\">en l\u00ednea<\/a>.<\/p>\n<p>Las aplicaciones, disponibles para iPhone y Android, presumen de ser m\u00e1s r\u00e1pidas, con tiempos de tramitaci\u00f3n de 10 minutos. Eso s\u00ed, aseg\u00farese de presentar la solicitud a trav\u00e9s de los canales oficiales, en lugar de hacerlo a trav\u00e9s de sitios web de terceros, que pueden cobrar tasas adicionales y es menos probable que manejen sus datos de forma seguras.<\/p>\n<p>Tendr\u00e1 que subir una foto de su pasaporte, escanearlo y fotografiarse mientras presenta la solicitud, subir la foto y responder a varias preguntas sobre sus planes. La solicitud en l\u00ednea tarda unos 20 minutos y hay que completar el proceso de una sola vez: no hay posibilidad de guardar sobre la marcha.<\/p>\n<p>La decisi\u00f3n suele tomarse en un plazo de tres d\u00edas, aunque el Gobierno advierte que puede tardar m\u00e1s. Puede viajar al Reino Unido mientras espera la decisi\u00f3n, si necesita hacer una visita urgente; sin embargo, debes haber hecho la solicitud antes de viajar.<\/p>\n<p>Tenga en cuenta que tener una ETA no garantiza la entrada en el Reino Unido. Deber\u00e1 pasar por el control de pasaportes y los funcionarios de la Fuerza de Fronteras seguir\u00e1n teniendo la \u00faltima palabra sobre si puede entrar en el pa\u00eds.<\/p>\n<p>La validez es de dos a\u00f1os y m\u00faltiples entradas, por lo que puede visitar el pa\u00eds tantas veces como quiera. Sin embargo, debe tener en cuenta que estar\u00e1 vinculado digitalmente a su pasaporte, por lo que si durante esos dos a\u00f1os obtiene un nuevo pasaporte, dejar\u00e1 de ser v\u00e1lido y deber\u00e1 solicitar uno nuevo.<\/p>\n<p>Todas las personas que entran en el Reino Unido necesitan su propia autorizaci\u00f3n de estancia, incluidos ni\u00f1os y beb\u00e9s. Pero puede solicitarla en nombre de otra persona.<\/p>\n<p>El visado ETA est\u00e1 pensado para estancias cortas de hasta seis meses.<\/p>\n<p>Todas las personas que entren en territorio brit\u00e1nico, incluso para una conexi\u00f3n r\u00e1pida, deben tener una ETA. (Lo mismo ocurre con los viajeros en tr\u00e1nsito por EE.UU., que necesitan un ESTA). No se le permitir\u00e1 pasar el control de pasaportes a la zona de tr\u00e1nsito sin uno.<\/p>\n<p>Para entrar en Europa, necesitar\u00e1 un <a href=\"https:\/\/www.cnn.com\/travel\/article\/etias-europe-tourist-taxes-explained\/index.html\">ETIAS<\/a>, la exenci\u00f3n de viaje de la UE, que se ha retrasado mucho pero que actualmente est\u00e1 previsto que comience en alg\u00fan momento de 2025. Mant\u00e9ngase al tanto de los detalles a medida que se acerca esa fecha.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si 2024 fue el a\u00f1o en que los viajeros se libraron de la introducci\u00f3n de la burocracia para viajar sin visado a Europa, 2025 es el a\u00f1o en que se impone la realidad. La exenci\u00f3n de visado ETIAS de la Uni\u00f3n Europea, que se ha pospuesto hasta ahora, est\u00e1 prevista para 2025. Antes, el Reino [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457274","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias\" \/>\n<meta property=\"og:description\" content=\"Si 2024 fue el a\u00f1o en que los viajeros se libraron de la introducci\u00f3n de la burocracia para viajar sin visado a Europa, 2025 es el a\u00f1o en que se impone la realidad. La exenci\u00f3n de visado ETIAS de la Uni\u00f3n Europea, que se ha pospuesto hasta ahora, est\u00e1 prevista para 2025. Antes, el Reino [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-06T18:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje\",\"datePublished\":\"2025-01-06T18:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\"},\"wordCount\":947,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\",\"name\":\"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-06T18:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias","og_description":"Si 2024 fue el a\u00f1o en que los viajeros se libraron de la introducci\u00f3n de la burocracia para viajar sin visado a Europa, 2025 es el a\u00f1o en que se impone la realidad. La exenci\u00f3n de visado ETIAS de la Uni\u00f3n Europea, que se ha pospuesto hasta ahora, est\u00e1 prevista para 2025. Antes, el Reino [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-06T18:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/"},"author":{"name":"","@id":""},"headline":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje","datePublished":"2025-01-06T18:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/"},"wordCount":947,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","name":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-06T18:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los viajeros al Reino Unido procedentes de 48 pa\u00edses ahora deben solicitar y pagar una tasa antes del viaje","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/eta-reino-unido-48-paises-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-06T18:03:45Z","datePublished":"2025-01-06T18:03:45Z","dateModified":"2025-01-06T18:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los viajeros al Reino Unido procedentes de 48 pa\\u00edses ahora deben solicitar y pagar una tasa antes del viaje\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/06\\\/eta-reino-unido-48-paises-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/06\\\/eta-reino-unido-48-paises-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-06T18:03:45Z\",\"datePublished\":\"2025-01-06T18:03:45Z\",\"dateModified\":\"2025-01-06T18:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447992,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/04\/11\/quiere-visitar-brasil-2025-viajeros-ee-uu-tendran-compartir-primero-estados-bancarios-trax\/","url_meta":{"origin":1457274,"position":0},"title":"\u00bfQuieres visitar Brasil? En 2025, los viajeros de EE.UU. tendr\u00e1n que compartir primero sus estados bancarios","author":"","date":"abril 11, 2024","format":false,"excerpt":"(CNN) -- 2024 se perfila como el a\u00f1o de las pr\u00f3rrogas de viaje.Poco despu\u00e9s de que la Uni\u00f3n Europea pospusiera (de nuevo) su controvertido programa ETIAS, que obligar\u00e1 a los visitantes de la mayor\u00eda de los pa\u00edses no pertenecientes a la UE a obtener una autorizaci\u00f3n previa de viaje, Brasil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466990,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/30\/desde-este-martes-viajar-a-ee-uu-es-doblemente-mas-caro-para-mas-de-40-paises-entre-ellos-chile-y-espana\/","url_meta":{"origin":1457274,"position":1},"title":"Desde este martes, viajar a EE.UU. es doblemente m\u00e1s caro para m\u00e1s de 40 pa\u00edses, entre ellos Chile y Espa\u00f1a","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Hasta antes de este martes, los pa\u00edses dentro del programa de exenci\u00f3n de visas de Estados Unidos ten\u00edan una ventaja notoria: pod\u00edan viajar a EE.UU. tramitando un permiso de US$ 21. Sin embargo, desde hoy, la tarifa es doblemente m\u00e1s cara.Este d\u00eda entraron en vigor una serie de aumentos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470575,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/01\/28\/viajeros-podrian-dejar-visitar-eeuu-redes-sociales-trax\/","url_meta":{"origin":1457274,"position":2},"title":"Millones de viajeros podr\u00edan dejar de visitar EE.UU. si se implementa la nueva pol\u00edtica de redes sociales, advierten expertos","author":"","date":"enero 28, 2026","format":false,"excerpt":"Ante la propuesta de cambio normativo que exigir\u00eda a algunos viajeros extranjeros que visitan Estados Unidos facilitar la informaci\u00f3n de sus cuentas en redes sociales, los expertos en viajes internacionales afirman que esta pol\u00edtica podr\u00eda disuadir a\u00fan m\u00e1s a los visitantes de acudir al pa\u00eds, lo que se traducir\u00eda en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452402,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/03\/nueva-zelandia-triplica-impuesto-turistas-trax\/","url_meta":{"origin":1457274,"position":3},"title":"Nueva Zelandia triplica su impuesto al turismo","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) -- A partir de ahora ser\u00e1 m\u00e1s caro visitar los lagos, las monta\u00f1as, las rutas en bicicleta y las bodegas de Nueva Zelandia, ya que el pa\u00eds va a aumentar su tasa tur\u00edstica y de conservaci\u00f3n para visitantes internacionales (IVL) de 35 d\u00f3lares neozelandeses (US$ 22) a 100 d\u00f3lares\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451384,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/24\/pasaportes-mas-poderosos-mundo-2024-trax\/","url_meta":{"origin":1457274,"position":4},"title":"Estos son los 10 pasaportes m\u00e1s poderosos del mundo en 2024, seg\u00fan Henley &#038; Partners","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- \u00bfQu\u00e9 es rojo por fuera, morado por dentro y te otorga acceso a 195 destinos alrededor del mundo sin visa?Es el pasaporte de Singapur, y acaba de ser nombrado el documento de viaje m\u00e1s poderoso del mundo en una clasificaci\u00f3n trimestral de los pasaportes con mayor influencia internacional.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457019,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/27\/nuevos-aviones-horarios-rutas-2025-trax\/","url_meta":{"origin":1457274,"position":5},"title":"Nuevos aviones, nuevos horarios, nuevas rutas:   \u00bfC\u00f3mo cambiar\u00e1 el transporte a\u00e9reo en 2025?","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"\u00bfCrees que est\u00e1s listo para los cambios que vienen en el transporte a\u00e9reo en 2025? No, no lo est\u00e1s.Estamos entrando firmemente en una nueva era de viajes, liderada por innovaciones y exploraciones que parec\u00edan imposibles o, en el mejor de los casos, altamente improbables hace solo unos a\u00f1os. Nuevos aviones,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457274"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457274\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}