{"id":1457320,"date":"2025-01-07T15:03:43","date_gmt":"2025-01-07T23:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/"},"modified":"2025-01-07T15:03:43","modified_gmt":"2025-01-07T23:03:43","slug":"policia-argentina-arresta-empleado-drogas-liam-payne-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","title":{"rendered":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne"},"content":{"rendered":"<p>La polic\u00eda de Argentina arrest\u00f3 a un hombre de 21 a\u00f1os acusado de suministrar coca\u00edna al cantante Liam Payne, quien <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/10\/16\/liam-payne-one-direction-muere-buenos-aires-trax\">muri\u00f3 al caer del balc\u00f3n<\/a> de un hotel de Buenos Aires en octubre de 2024 bajo los efectos de las drogas.<\/p>\n<p>El sospechoso, un empleado del hotel Casa Sur, se entreg\u00f3 a las autoridades el lunes despu\u00e9s de que su abogado dijera que se entregar\u00eda, afirm\u00f3 la polic\u00eda local en un comunicado a CNN. La polic\u00eda no lo identific\u00f3 por su nombre.<\/p>\n<p>El empleado del hotel es una de las dos personas acusadas de suministrar coca\u00edna a Payne durante su estad\u00eda en el hotel. Un juez orden\u00f3 que sean encarcelados antes de su juicio. Podr\u00edan enfrentar hasta 15 a\u00f1os de prisi\u00f3n.<\/p>\n<p>Una persona identificada como el \u201crepresentante\u201d de Payne, as\u00ed como el gerente del hotel y su jefe de recepci\u00f3n, fueron acusados \u200b\u200bde homicidio, dijo la fiscal\u00eda. Si son condenados, enfrentan hasta cinco a\u00f1os de prisi\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda de Argentina arrest\u00f3 a un hombre de 21 a\u00f1os acusado de suministrar coca\u00edna al cantante Liam Payne, quien muri\u00f3 al caer del balc\u00f3n de un hotel de Buenos Aires en octubre de 2024 bajo los efectos de las drogas. El sospechoso, un empleado del hotel Casa Sur, se entreg\u00f3 a las autoridades el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457320","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias\" \/>\n<meta property=\"og:description\" content=\"La polic\u00eda de Argentina arrest\u00f3 a un hombre de 21 a\u00f1os acusado de suministrar coca\u00edna al cantante Liam Payne, quien muri\u00f3 al caer del balc\u00f3n de un hotel de Buenos Aires en octubre de 2024 bajo los efectos de las drogas. El sospechoso, un empleado del hotel Casa Sur, se entreg\u00f3 a las autoridades el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T23:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne\",\"datePublished\":\"2025-01-07T23:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\",\"name\":\"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-07T23:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias","og_description":"La polic\u00eda de Argentina arrest\u00f3 a un hombre de 21 a\u00f1os acusado de suministrar coca\u00edna al cantante Liam Payne, quien muri\u00f3 al caer del balc\u00f3n de un hotel de Buenos Aires en octubre de 2024 bajo los efectos de las drogas. El sospechoso, un empleado del hotel Casa Sur, se entreg\u00f3 a las autoridades el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-07T23:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/"},"author":{"name":"","@id":""},"headline":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne","datePublished":"2025-01-07T23:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","name":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-07T23:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Polic\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-07T23:03:43Z","datePublished":"2025-01-07T23:03:43Z","dateModified":"2025-01-07T23:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Polic\\u00eda de Argentina arresta a empleado de hotel acusado de suministrar drogas a Liam Payne\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/07\\\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/07\\\/policia-argentina-arresta-empleado-drogas-liam-payne-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-07T23:03:43Z\",\"datePublished\":\"2025-01-07T23:03:43Z\",\"dateModified\":\"2025-01-07T23:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457079,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/30\/cinco-personas-cargos-penales-muerte-liam-payne-orix\/","url_meta":{"origin":1457320,"position":0},"title":"Cinco personas enfrentan cargos penales por la muerte de Liam Payne; dos de ellos deben cumplir prisi\u00f3n preventiva","author":"","date":"diciembre 30, 2024","format":false,"excerpt":"Tres personas fueron procesadas el viernes por la Justicia argentina y enfrentan cargos de homicidio culposo. Otras dos est\u00e1n acusadas de suministro de estupefacientes a Liam Payne, el m\u00fasico brit\u00e1nico que falleci\u00f3 a los 31 a\u00f1os tras caer del tercer piso del hotel Casa Sur en Buenos Aires, seg\u00fan un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459852,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/03\/12\/amigo-liam-payne-seres-queridos-ayudarlo-trax\/","url_meta":{"origin":1457320,"position":1},"title":"Amigo de Liam Payne que estuvo con \u00e9l antes de su muerte dice que sus seres queridos intentaron ayudarlo con su sobriedad","author":"","date":"marzo 12, 2025","format":false,"excerpt":"Rogelio \u201cRoger\u201d Nores, un amigo cercano de Liam Payne y una de las \u00faltimas personas en ver con vida al exintegrante de One Direction, cree que la muerte del cantante fue el resultado de una serie de eventos \u201cextremadamente desafortunados\u201d.Payne cay\u00f3 desde el tercer piso de un hotel en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455191,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/17\/liam-payne-informe-autopsia-preliminar-causa-muerte-orix\/","url_meta":{"origin":1457320,"position":2},"title":"Informe preliminar de la autopsia de Liam Payne revela causa de muerte","author":"","date":"octubre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Liam Payne muri\u00f3 por \u201cpolitraumatismo\u201d con \u201chemorragia interna y externa\u201d, seg\u00fan el informe preliminar de la autopsia realizada el mi\u00e9rcoles por el cuerpo forense argentino que investiga el caso y que CNN obtuvo de la Polic\u00eda de la ciudad de Buenos Aires. A\u00fan falta por conocer el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458594,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/02\/11\/caso-liam-payne-justicia-audiencia-clave-acusados-muerte-orix\/","url_meta":{"origin":1457320,"position":3},"title":"Caso Liam Payne: la Justicia de Argentina realiz\u00f3 una audiencia clave para los acusados por su muerte","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Los cinco acusados en relaci\u00f3n con la muerte del excantante de One Direction, Liam Payne, tuvieron una audiencia ante la Justicia de Argentina este martes.En esta instancia se trataron los pedidos de apelaciones de las defensas a las acusaciones formalizadas a fines de diciembre por la jueza Laura Bruniard.Una fuente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455215,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/18\/que-sabemos-muerte-liam-payne-one-direction-argentina-trax\/","url_meta":{"origin":1457320,"position":4},"title":"A\u00fan quedan interrogantes sobre la muerte de Liam Payne. Esto es lo que sabemos","author":"","date":"octubre 18, 2024","format":false,"excerpt":"(CNN) -- Liam Payne, exintegrante de la banda One Direction, muri\u00f3 a los 31 a\u00f1os despu\u00e9s de caer del tercer piso del Hotel CasaSur Palermo en Buenos Aires, Argentina, seg\u00fan la polic\u00eda. Las circunstancias exactas que rodearon su muerte a\u00fan no est\u00e1n claras.Esto es lo que sabemos:Llamada al 911El personal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455171,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/16\/liam-payne-one-direction-muere-buenos-aires-trax\/","url_meta":{"origin":1457320,"position":5},"title":"Liam Payne, exintegrante de One Direction, muere a los 31 a\u00f1os tras caer desde el tercer piso de un hotel en Buenos Aires","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN) -- Liam Payne, un exmiembro de la banda musical One Direction, muri\u00f3 tras caer desde el tercer piso de un hotel en Buenos Aires, de acuerdo con la polic\u00eda local. Ten\u00eda 31 a\u00f1os.La muerte de Payne ocurri\u00f3 en un hotel en la calle Costa Rica en el barrio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457320"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457320\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}