{"id":1457366,"date":"2025-01-08T16:03:49","date_gmt":"2025-01-09T00:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/"},"modified":"2025-01-08T16:03:49","modified_gmt":"2025-01-09T00:03:49","slug":"contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","title":{"rendered":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?"},"content":{"rendered":"<p>Muchos padres ya estaban preocupados por la exposici\u00f3n de sus hijos a informaci\u00f3n falsa y otros contenidos da\u00f1inos en las redes sociales antes de <a href=\"https:\/\/www.cnn.com\/2025\/01\/07\/tech\/meta-censorship-moderation\/index.html\">la sorprendente decisi\u00f3n de Meta<\/a> de eliminar a sus verificadores de datos.<\/p>\n<p>Ahora hay motivos para temer que las cosas empeoren a\u00fan m\u00e1s.<\/p>\n<p>El martes, Meta <a href=\"https:\/\/www.cnn.com\/2025\/01\/07\/tech\/meta-censorship-moderation\/index.html\">anunci\u00f3<\/a> que pondr\u00e1 fin a sus colaboraciones de verificaci\u00f3n de datos con Instagram y Facebook en Estados Unidos. En su lugar, los usuarios podr\u00e1n escribir \u201cnotas comunitarias\u201d sobre publicaciones problem\u00e1ticas. El director ejecutivo de Meta, Mark Zuckerberg, <a href=\"https:\/\/www.cnn.com\/2025\/01\/07\/tech\/meta-censorship-moderation\/index.html\">reconoci\u00f3<\/a> que, como resultado, la empresa detectar\u00e1 menos \u201ccosas malas\u201d publicadas en sus plataformas.<\/p>\n<p>No es que antes todas las plataformas de redes sociales estuvieran controladas y tuvieran fuentes s\u00f3lidas para las publicaciones de los usuarios. Pero la decisi\u00f3n de Zuckerberg hace que sea a\u00fan m\u00e1s importante que se les ense\u00f1e a los ni\u00f1os a distinguir lo que deben y no deben creer en las redes sociales. Los padres tambi\u00e9n pueden aprovechar esta oportunidad para hablar con sus hijos sobre por qu\u00e9 nunca deben compartir ni actuar en funci\u00f3n de las afirmaciones que ven en l\u00ednea sin verificarlas primero.<\/p>\n<p>Esto es lo que debemos ense\u00f1arles.<\/p>\n<p>Para determinar si una publicaci\u00f3n en las redes sociales es precisa, los medios de comunicaci\u00f3n tradicionales son un buen punto de partida. \u201cConsidere si otros medios de comunicaci\u00f3n tradicionales y cre\u00edbles est\u00e1n informando sobre la misma noticia\u201d, dijo James P. Steyer, fundador y director ejecutivo de <a href=\"https:\/\/www.commonsensemedia.org\/\">Common Sense Media<\/a>, una organizaci\u00f3n sin fines de lucro que ayuda a padres y maestros a inculcar habilidades de pensamiento cr\u00edtico en los ni\u00f1os. \u201cSi no es as\u00ed, no significa que no sea cierto, pero s\u00ed significa que debe investigar m\u00e1s a fondo\u201d.<\/p>\n<p>Para saber c\u00f3mo entender la cobertura medi\u00e1tica, los padres deben alentar a los ni\u00f1os a \u201cconsumir m\u00e1s noticias, no menos\u201d, dijo por correo electr\u00f3nico la Dra. Jingsi Christina Wu, profesora adjunta de estudios de medios en la Universidad Hofstra en Long Island, Nueva York. Pueden hacerlo leyendo o viendo las noticias juntos y luego discuti\u00e9ndolas. Wu dijo que cuanto m\u00e1s consumen noticias los ni\u00f1os, m\u00e1s adquieren la capacidad cognitiva para interpretarlas.<\/p>\n<p>Al evaluar las publicaciones, Steyer dijo que a los ni\u00f1os tambi\u00e9n se les debe ense\u00f1ar a considerar qui\u00e9n hizo el contenido, si parece confiable, cu\u00e1les podr\u00edan ser sus motivaciones y qui\u00e9n podr\u00eda beneficiarse o verse perjudicado por ello.<\/p>\n<p>En particular, dijo Wu, a los ni\u00f1os se les debe decir que \u201csus influencers favoritos no son expertos\u201d. Los padres pueden explicarles que \u201cest\u00e1 bien ver a sus tiktokers o youtubers favoritos por su valor de entretenimiento o experiencias especiales, pero no son expertos acreditados en hechos y tienen sus propios prejuicios sobre el mundo\u201d.<\/p>\n<p>De la misma manera, los ni\u00f1os (y sus padres) no deber\u00edan asumir que algo es verdad simplemente porque ha tenido muchas visitas o ha recibido muchos \u201cme gusta\u201d. \u201cLa viralidad no es igual a la verdad\u201d, advirti\u00f3 Wu. De hecho, dijo, \u201clas noticias falsas se propagan m\u00e1s r\u00e1pido al aprovechar los instintos humanos para compartir historias anormales\u201d.<\/p>\n<p>Wu dijo que buscar peque\u00f1os errores en aspectos como la ortograf\u00eda y la gram\u00e1tica es otra forma de detectar publicaciones poco fiables. Tambi\u00e9n sugiri\u00f3 animar a los ni\u00f1os a que observen los detalles de las im\u00e1genes y los v\u00eddeos en busca de se\u00f1ales de que han sido manipulados. Por ejemplo, una mano con el n\u00famero incorrecto de dedos podr\u00eda ser un indicio de que la inteligencia artificial la ha generado, dijo.<\/p>\n<p>Steyer dijo que los ni\u00f1os tambi\u00e9n deber\u00edan considerar una se\u00f1al de alerta si un contenido les provoca emociones fuertes. \u201cLa informaci\u00f3n err\u00f3nea y la desinformaci\u00f3n se crean para provocar reacciones extremas en las personas\u201d.<\/p>\n<p>A los ni\u00f1os se les debe ense\u00f1ar a no consumir contenido inexacto o extremista porque los algoritmos est\u00e1n dise\u00f1ados para mostrar a las personas lo que creen que les gusta, por lo que cuanto m\u00e1s miran o interact\u00faan con determinados tipos de publicaciones, m\u00e1s probabilidades hay de que reciban m\u00e1s contenido similar.<\/p>\n<p>Los ni\u00f1os deben saber que, cuando consumen contenido, los creadores a menudo se benefician de sus visualizaciones, dijo la Dra. Devorah Heitner, autora de \u201c <a href=\"https:\/\/www.amazon.com\/Growing-Up-Public-Coming-Digital\/dp\/0593420969\/ref=sr_1_1?crid=1IM1ZNIT75FWA&#038;dib=eyJ2IjoiMSJ9.EQQa2O7EopnfJ-x4z9NAeDIjUm-BQ7Ffxd5eiobH-uN1CGHrxnHHKrVdzD-7XMylqSsDYAkJ_rfRiHSUozHy5M4mZb0tinK7nVysNzf1pQIDHgZESlIEZ8FExBUZNB65R7lz-CXM6tXmaaWGjnjfsuE34D7sNrrquuLJDYmz2N46iqYnTH-O9BC6xPnp4R-fxWpO-9Pm0PRs3lKIZI3sMfkn3EyD8rewQTL0WJHiqJY.KVKiYJ4QUKXZbxVZVKf5enOuAV9J2iRBEIwmmuKRiDI&#038;dib_tag=se&#038;keywords=growing+up+in+public&#038;qid=1736304681&#038;sprefix=growing+up+in+public%2Caps%2C137&#038;sr=8-1\">Growing Up in Public:<\/a> Coming of Age in a Digital World\u201d, con sede en Chicago. Esto sucede <strong><\/strong>porque un mayor n\u00famero de visualizaciones a menudo permite a los creadores ganar m\u00e1s dinero con los anuncios. Es otra raz\u00f3n para mantenerse alejado del contenido que es falso o problem\u00e1tico de alguna otra manera.<\/p>\n<p>Cuando hablo con padres en las escuelas sobre c\u00f3mo manejar el uso de las redes sociales por parte de sus hijos, les sugiero que consuman juntos contenido de las redes sociales sobre temas que interesen a sus hijos. Por ejemplo, si un ni\u00f1o est\u00e1 interesado en convertirse en veterinario, puede ver videos de zool\u00f3gicos de todo el mundo. Entonces, incluso cuando el padre no est\u00e9 presente, es probable que los algoritmos le env\u00eden publicaciones similares.<\/p>\n<p>Wu dijo que los padres tambi\u00e9n deber\u00edan animar a sus hijos a hablar con ellos cuando no est\u00e9n seguros de c\u00f3mo juzgar si un contenido es correcto. Incluso si los padres sospechan que es falso, no es una buena idea decirlo de inmediato. \u201cLos ni\u00f1os pueden sentirse juzgados o desestimados si los padres simplemente se r\u00eden de las cosas o descartan directamente todo el contenido en l\u00ednea como falso o poco confiable\u201d, advirti\u00f3.<\/p>\n<p>En cambio, Wu sugiri\u00f3 que los padres investiguen con sus hijos. \u201cEste enfoque mantiene abierto el di\u00e1logo y tambi\u00e9n alivia\u2026 el estr\u00e9s de saberlo todo en todo momento\u201d, dijo. \u201cTambi\u00e9n demuestra a los ni\u00f1os que el aprendizaje nunca se detiene y que la alfabetizaci\u00f3n medi\u00e1tica es un m\u00fasculo que necesita ejercitarse\u201d.<\/p>\n<p>Gracias a la nueva pol\u00edtica de Meta, espero que los ni\u00f1os est\u00e9n expuestos a contenidos a\u00fan m\u00e1s peligrosos en las redes sociales. Pero los padres pueden proteger a sus hijos ense\u00f1\u00e1ndoles a evaluar lo que ven en l\u00ednea, para que sepan qu\u00e9 creer y c\u00f3mo evitar publicaciones problem\u00e1ticas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos padres ya estaban preocupados por la exposici\u00f3n de sus hijos a informaci\u00f3n falsa y otros contenidos da\u00f1inos en las redes sociales antes de la sorprendente decisi\u00f3n de Meta de eliminar a sus verificadores de datos. Ahora hay motivos para temer que las cosas empeoren a\u00fan m\u00e1s. El martes, Meta anunci\u00f3 que pondr\u00e1 fin a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457366","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Muchos padres ya estaban preocupados por la exposici\u00f3n de sus hijos a informaci\u00f3n falsa y otros contenidos da\u00f1inos en las redes sociales antes de la sorprendente decisi\u00f3n de Meta de eliminar a sus verificadores de datos. Ahora hay motivos para temer que las cosas empeoren a\u00fan m\u00e1s. El martes, Meta anunci\u00f3 que pondr\u00e1 fin a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T00:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?\",\"datePublished\":\"2025-01-09T00:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\"},\"wordCount\":1127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\",\"name\":\"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-09T00:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias","og_description":"Muchos padres ya estaban preocupados por la exposici\u00f3n de sus hijos a informaci\u00f3n falsa y otros contenidos da\u00f1inos en las redes sociales antes de la sorprendente decisi\u00f3n de Meta de eliminar a sus verificadores de datos. Ahora hay motivos para temer que las cosas empeoren a\u00fan m\u00e1s. El martes, Meta anunci\u00f3 que pondr\u00e1 fin a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-09T00:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/"},"author":{"name":"","@id":""},"headline":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?","datePublished":"2025-01-09T00:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/"},"wordCount":1127,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","name":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-09T00:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Habr\u00e1 m\u00e1s contenido da\u00f1ino en redes con la eliminaci\u00f3n de verificadores de Meta: \u00bfqu\u00e9 decirle a tus hijos?","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-09T00:03:49Z","datePublished":"2025-01-09T00:03:49Z","dateModified":"2025-01-09T00:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Habr\\u00e1 m\\u00e1s contenido da\\u00f1ino en redes con la eliminaci\\u00f3n de verificadores de Meta: \\u00bfqu\\u00e9 decirle a tus hijos?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/08\\\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/08\\\/contenido-danino-redes-meta-elimine-verificadores-datos-ninos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-09T00:03:49Z\",\"datePublished\":\"2025-01-09T00:03:49Z\",\"dateModified\":\"2025-01-09T00:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457299,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/meta-quita-verificadores-datos-moderacion-trax\/","url_meta":{"origin":1457366,"position":0},"title":"Meta se deshace de los verificadores de datos y dice que reducir\u00e1 la &#171;censura&#187;","author":"","date":"enero 7, 2025","format":false,"excerpt":"Meta realizar\u00e1 cambios importantes en su pol\u00edtica de moderaci\u00f3n de contenido en Facebook e Instagram ya que eliminar\u00e1 a los verificadores de informaci\u00f3n y los reemplazar\u00e1 con \u201cnotas comunitarias\u201d generadas por los usuarios, similares a las X de Elon Musk, anunci\u00f3 este martes el CEO Mark Zuckerberg.Los cambios se producen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457463,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/12\/copresidente-supervision-meta-presion-politica-programa-verificacion-trax\/","url_meta":{"origin":1457366,"position":1},"title":"Copresidente de supervisi\u00f3n de Meta dice que la empresa &#171;cede a la presi\u00f3n pol\u00edtica&#187; al acabar con programa de verificaci\u00f3n","author":"","date":"enero 12, 2025","format":false,"excerpt":"La decisi\u00f3n de Meta de poner fin a su programa de verificaci\u00f3n de datos parece indicar que la empresa est\u00e1 \u201ccediendo\u201d ante presiones pol\u00edticas, dijo el copresidente del consejo de supervisi\u00f3n de Meta, Michael McConnell.McConnell, profesor de derecho en la Universidad de Stanford, dijo a NPR el viernes que le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457326,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/analisis-maga-zuckerberg-transformara-internet-trax\/","url_meta":{"origin":1457366,"position":2},"title":"AN\u00c1LISIS | El nuevo estilo &#171;MAGA&#187; de Zuckerberg transformar\u00e1 el internet","author":"","date":"enero 7, 2025","format":false,"excerpt":"El CEO de Meta, Mark Zuckerberg, est\u00e1 introduciendo cambios radicales en las redes de internet, todos ellos en consonancia con los deseos del presidente electo Donald Trump y sus partidarios.Ech\u00f3 a los verificadores de hechos que los conservadores ridiculizan. E introdujo normas m\u00e1s permisivas para publicar opiniones conservadoras.Las recientes elecciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471374,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/18\/mark-zuckerberg-juicio-adiccion-redes-sociales-trax\/","url_meta":{"origin":1457366,"position":3},"title":"Mark Zuckerberg testificar\u00e1 en juicio por adicci\u00f3n a las redes sociales","author":"","date":"febrero 18, 2026","format":false,"excerpt":"Mark Zuckerberg se dispone a testificar el mi\u00e9rcoles por primera vez ante un jurado sobre las acusaciones de que sus plataformas de redes sociales perjudicaron a ni\u00f1os y adolescentes.El testimonio de Zuckerberg como testigo en un juicio hist\u00f3rico por adicci\u00f3n a las redes sociales le dar\u00e1 al CEO de Meta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452246,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/28\/zuckerberg-meta-biden-censura-covid-trax\/","url_meta":{"origin":1457366,"position":4},"title":"Mark Zuckerberg asegura que el Gobierno de Biden &#171;presion\u00f3&#187; a Meta a censurar contenidos relacionados con el covid-19 en 2021","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN) -- Mark Zuckerberg, presidente y CEO de Meta, afirm\u00f3 el lunes en una carta a la Comisi\u00f3n judicial de la C\u00e1mara de Representantes que sus equipos fueron \"presionados\" por la Casa Blanca durante el Gobierno de Biden para censurar algunos contenidos en torno a la pandemia de covid-19.\"En 2021,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472546,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/03\/25\/jurado-responsables-meta-youtube-adiccion-trax\/","url_meta":{"origin":1457366,"position":5},"title":"Un jurado declara responsables a Meta y YouTube en un juicio por adicci\u00f3n en redes sociales","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Un jurado en California declar\u00f3 a Meta y YouTube responsables en todos los cargos en un caso hist\u00f3rico que acus\u00f3 a los gigantes tecnol\u00f3gicos de volver intencionalmente adicta a una joven y perjudicar su salud mental.Meta y YouTube actuaron con negligencia en el dise\u00f1o de sus plataformas, sab\u00edan que ese\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457366"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457366\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}