{"id":1457377,"date":"2025-01-09T00:03:38","date_gmt":"2025-01-09T08:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/"},"modified":"2025-01-09T00:03:38","modified_gmt":"2025-01-09T08:03:38","slug":"trump-newsom-los-angeles-incendios-analisis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","title":{"rendered":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom"},"content":{"rendered":"<p>Los muros de fuego devoraron barrios, obligando a decenas de miles de residentes a huir para salvar sus vidas. Mientras un cataclismo alimentado por poderosos vendavales carbonizaba vastas zonas de Los \u00c1ngeles, Donald Trump vio una oportunidad.<\/p>\n<p>El presidente electo de EE.UU. respondi\u00f3 a <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/08\/noticias-incendios-california-2025-en-vivo-trax\/\">seis colosales incendios forestales <\/a>reabriendo su larga disputa con el gobernador de California, Gavin Newsom, y lanzando un primer golpe a un gobernador dem\u00f3crata y a un estado que probablemente se convierta en un importante oponente a sus planes para un segundo mandato.<\/p>\n<p>Trump y Newsom se han enfrentado duramente en el pasado, incluso sobre la prevenci\u00f3n de incendios, las pol\u00edticas ambientales, el cambio clim\u00e1tico, los veh\u00edculos ecol\u00f3gicos y la inmigraci\u00f3n.<\/p>\n<p>Y el presidente entrante no perdi\u00f3 el tiempo en echarle la culpa de los incendios forestales simult\u00e1neos que asolan la zona de Los \u00c1ngeles y que hasta ahora causaron la muerte de al menos cinco personas.<\/p>\n<p>Trump critic\u00f3 \u201cla incompetencia y la mala gesti\u00f3n del d\u00fao Biden\/Newscum\u201d en un post en su red social Truth. Afirm\u00f3 que las pol\u00edticas medioambientales de California que desv\u00edan agua dulce para preservar los humedales y la vida silvestre eran las culpables de que los hidrantes se secaran. \u201cExigir\u00e9 que este gobernador incompetente permita que el agua dulce, limpia y hermosa FLUYA HACIA CALIFORNIA. \u00c9l es el culpable de esto\u201d, escribi\u00f3 Trump como parte de una avalancha de mensajes en las redes sociales, escribiendo m\u00e1s tarde que Newsom deber\u00eda dimitir.<\/p>\n<p>En el juego de la desinformaci\u00f3n de Trump, no importa realmente si es cierto que Newsom sea responsable de desviar agua para proteger al pejerrey del delta \u2014\u201cun pez sin valor\u201d, en palabras de Trump\u2014 y que, como resultado, se incendiaron hogares de angelinos. El presidente electo solo necesita que un n\u00famero suficiente de personas crean que podr\u00eda ser as\u00ed para infligir da\u00f1o pol\u00edtico al gobernador, uno de los dem\u00f3cratas de m\u00e1s alto perfil del pa\u00eds y posible aspirante a la presidencia en 2028.<\/p>\n<p>California es tambi\u00e9n un blanco perfecto como estado liberal que se decant\u00f3 por la vicepresidenta Kamala Harris en las elecciones del a\u00f1o pasado. La idea de un estado y una ciudad que aplican pol\u00edticas medioambientales autodestructivas encaja perfectamente con la narrativa de Trump de que el Gobierno liberal en estados y ciudades azules invita al caos, el crimen y la miseria.<\/p>\n<p>\u201cEsto no es Gobierno. \u00a1No puedo esperar hasta el 20 de enero!\u201d escribi\u00f3 Trump en Truth Social.<\/p>\n<p>Habr\u00e1 preguntas leg\u00edtimas sobre el nivel de preparaci\u00f3n de California y Los \u00c1ngeles para los incendios. Newsom y los funcionarios municipales tendr\u00e1n que rendir cuentas por cualquier fallo, como muchos pol\u00edticos puestos a prueba en el crisol de las cat\u00e1strofes naturales. Pero en situaciones tan terribles, la culpa suele esperar a que amaine la crisis.<\/p>\n<p>Newsom dijo a Anderson Cooper, de CNN, que \u201cni siquiera se puede responder\u201d a los ataques de Trump. \u201cLa gente est\u00e1 literalmente huyendo, la gente ha perdido la vida, los ni\u00f1os han perdido sus escuelas, las familias completamente destrozadas, las iglesias quemadas\u2026 este tipo quer\u00eda politizarlo\u201d.<\/p>\n<p>\u201cTengo muchas ideas sobre lo que quiero decir, y no lo har\u00e9\u201d, a\u00f1adi\u00f3 el gobernador.<\/p>\n<p>En este caso concreto, las quejas de Trump sobre el problema del agua dulce como culpable de las dificultades de respuesta parec\u00edan, en el mejor de los casos, una gran simplificaci\u00f3n de los complejos factores en juego.<\/p>\n<p>Pero tras una reuni\u00f3n con senadores republicanos este jueves, el presidente electo redobl\u00f3 la apuesta.<\/p>\n<p>\u201cEs una verdadera tragedia y un error del gobernador\u201d, dijo Trump a los periodistas. \u201cNo tienen agua. Millones y millones de galones de agua que tienen, y la env\u00edan al Pac\u00edfico\u201d.<\/p>\n<p>Sin embargo, las autoridades de agua informaron que, aunque los hidrantes en Pacific Palisades se quedaron sin suministro temprano el mi\u00e9rcoles, hab\u00eda suficiente agua disponible en el sur de California para combatir los incendios. No obstante, la log\u00edstica para transportar el volumen necesario hasta Pacific Palisades \u2014y hacerlo al ritmo que los bomberos, ya sobrecargados, requieren para controlar las llamas\u2014 resultaba inviable.<\/p>\n<p>Aun as\u00ed, los ataques de Trump fueron un intento caracter\u00edstico de politizar una cat\u00e1strofe natural cuando todav\u00eda se est\u00e1 produciendo. El portavoz de Newsom, Anthony York, dijo a CNN que \u201cestamos centrados en proteger vidas y combatir estas llamas, no en hacer pol\u00edtica\u201d.<\/p>\n<p>La pr\u00e1ctica normal para un l\u00edder nacional cuando ocurre un desastre es enterrar las quejas partidistas, unirse a los estadounidenses necesitados y prometer estar junto a las v\u00edctimas el tiempo que sea necesario.<\/p>\n<p>Incluso el gobernador republicano de Florida, Ron DeSantis, que a menudo se ha enfrentado a Newsom y a California en el pasado \u2014especialmente por los confinamientos durante la pandemia\u2014, ofreci\u00f3 oraciones y ayuda a California. \u201cCuando ocurre un desastre, debemos unirnos para ayudar a nuestros compatriotas de cualquier manera que podamos\u201d, escribi\u00f3 DeSantis en X.<\/p>\n<p>Newsom elogi\u00f3 a su colega dem\u00f3crata, el presidente Joe Biden, por haber recurrido r\u00e1pidamente al poder\u00edo del Gobierno federal cuando los infiernos cobraron fuerza con una declaraci\u00f3n de cat\u00e1strofe grave.<\/p>\n<p>\u201cMe resulta imposible expresar el nivel de agradecimiento y cooperaci\u00f3n que recibimos de la Casa Blanca en esta administraci\u00f3n\u201d, dijo Newsom, junto al presidente en Santa Monica este mi\u00e9rcoles. \u201cAs\u00ed que en nombre de todos nosotros, se\u00f1or presidente, gracias por estar aqu\u00ed\u201d.<\/p>\n<p>Biden dijo que el Gobierno federal estaba preparado para hacer \u201ctodo lo posible\u201d para contener los incendios y enumer\u00f3 m\u00faltiples despliegues militares para luchar contra el desastre. Sin embargo, puso fin a su comparecencia ante los medios de comunicaci\u00f3n con una nota discordante al se\u00f1alar la llegada de un nuevo miembro a la familia, despu\u00e9s de que su nieta Naomi diera a luz en un hospital de la zona. \u201cLa buena noticia es que desde hoy soy bisabuelo\u201d, dijo.<\/p>\n<p>La Casa Blanca anunci\u00f3 a \u00faltima hora de este mi\u00e9rcoles que Biden ya no viajar\u00e1 a Roma, Italia, esta semana como estaba previsto, cancelando el viaje en los \u00faltimos d\u00edas de su presidencia para vigilar los incendios forestales.<\/p>\n<p>Los ataques de Trump contra Biden y Newsom son su \u00faltimo intento de presentar a la administraci\u00f3n saliente como incompetente, aparentemente dise\u00f1ados para halagar en comparaci\u00f3n a su propio equipo entrante de la Casa Blanca.<\/p>\n<p>Sus comentarios sugieren que su segunda administraci\u00f3n, que comienza dentro de 11 d\u00edas, ser\u00e1 tan poco ortodoxa y turbulenta como la primera, y estar\u00e1 salpicada de airados ataques en las redes sociales contra sus oponentes incluso durante las crisis.<\/p>\n<p>Trump y Newsom mantienen una relaci\u00f3n profundamente antag\u00f3nica, exacerbada por sus ideolog\u00edas marcadamente divergentes y por el hecho de que la poderosa California tiene el poder de frustrar algunas de las prioridades pol\u00edticas del presidente electo.<\/p>\n<p>Trump tambi\u00e9n tiene una fijaci\u00f3n con la gesti\u00f3n de los bosques y la prevenci\u00f3n de incendios, incluida su opini\u00f3n de que las jurisdicciones dem\u00f3cratas realizan una limpieza insuficiente del follaje ca\u00eddo, que insiste en que es el culpable de muchos incendios.<\/p>\n<p>\u201cEl gobernador de California, @GavinNewsom, ha hecho un trabajo terrible en la gesti\u00f3n forestal\u201d, escribi\u00f3 Trump en lo que entonces era Twitter, en noviembre de 2019. \u201cLe dije desde el primer d\u00eda que nos conocimos que deb\u00eda \u2018limpiar\u2019 los suelos de los bosques, sin importar lo que sus jefes, los ambientalistas, LE EXIJAN. Tambi\u00e9n debe realizar quemas y cortar barreras contra incendios\u2026\u201d.<\/p>\n<p>El posteo de Trump, durante una crisis anterior de incendios forestales en California, pareci\u00f3 incongruente en su momento, ya que sigui\u00f3 a los elogios de Newsom por sus esfuerzos para ayudar a su estado.<\/p>\n<p>Los ecologistas sostienen que el verdadero problema que hace que California sea tan susceptible de empeorar las temporadas de incendios es algo que Trump se niega a aceptar que exista: el cambio clim\u00e1tico. En la crisis actual, la tierra reseca y el calor fuera de temporada hicieron de Los \u00c1ngeles un polvor\u00edn muy vulnerable al catalizador a\u00f1adido de los fuertes vientos rugientes que propagan los incendios.<\/p>\n<p>Durante otra crisis de incendios forestales en California, mientras ard\u00edan millones de hect\u00e1reas en 2020, Trump desestim\u00f3 un llamamiento de Wade Crowfoot, secretario de Recursos Naturales del estado, para que reconociera el impacto del calentamiento global.<\/p>\n<p>\u201cEmpezar\u00e1 a refrescar. No hay m\u00e1s que verlo\u201d, dijo Trump. Cuando Crowfoot le pidi\u00f3 que examinara la ciencia, a\u00f1adi\u00f3: \u201cNo creo que la ciencia lo sepa, la verdad\u201d.<\/p>\n<p>Trump insisti\u00f3 este mi\u00e9rcoles en el Capitolio en que \u201cse llevaba bien\u201d con Newsom a pesar de sus diferencias.<\/p>\n<p>Pero su renovado distanciamiento podr\u00eda ser un problema para California, ya que potencialmente pronto buscar\u00e1 cientos de millones de d\u00f3lares en ayuda federal para desastres de la Casa Blanca y el Congreso, controlados por los republicanos.<\/p>\n<p>\u201cParece que vamos a ser nosotros los que tengamos que reconstruirlo\u201d, dijo Trump tras reunirse con los senadores.<\/p>\n<p>Trump y Newsom no solo se enfrentar\u00e1n por los incendios. El gobernador ya se ha comprometido a actuar si Trump pretende eliminar los cr\u00e9ditos fiscales a los veh\u00edculos el\u00e9ctricos. Y es probable que su estado est\u00e9 a la vanguardia de los esfuerzos legales para frustrar las pol\u00edticas de la administraci\u00f3n Trump en muchas \u00e1reas, incluyendo la inmigraci\u00f3n y los derechos reproductivos.<\/p>\n<p>Hay muchos ejemplos anteriores de Trump politizando las crisis nacionales.<\/p>\n<p>En 2017, fue criticado por su manejo del hurac\u00e1n Mar\u00eda, que devast\u00f3 Puerto Rico y mat\u00f3 a casi 3.000 personas. Hay culpa para todos cuando los esfuerzos de socorro se quedan cortos, y el entonces presidente no fue el \u00fanico responsable de los errores en las respuestas federales y locales. Pero culp\u00f3 repetidamente a los l\u00edderes locales y se quej\u00f3 del nivel de ayuda que se requer\u00eda, afirmando falsamente que la operaci\u00f3n fue un \u201c\u00e9xito incre\u00edble y desconocido\u201d.<\/p>\n<p>Y la gesti\u00f3n de Trump de la pandemia de covid-19 conten\u00eda m\u00faltiples ejemplos de \u00e9l tratando de preservar sus fortunas pol\u00edticas, que ir\u00f3nicamente ayudaron a sellar su derrota en las elecciones de 2020.<\/p>\n<p>M\u00e1s recientemente, Trump aprovech\u00f3 el ataque terrorista que mat\u00f3 a 14 personas en Nueva Orleans el 1 de enero, insinuando falsamente en las redes sociales que el sospechoso era un inmigrante indocumentado que hab\u00eda cruzado recientemente la frontera sur.<\/p>\n<p>Fue un recordatorio de que, en tiempos de tensi\u00f3n nacional, la primera respuesta del presidente electo ha sido a veces buscar beneficios pol\u00edticos en lugar de promover la unidad y respuestas basadas en hechos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los muros de fuego devoraron barrios, obligando a decenas de miles de residentes a huir para salvar sus vidas. Mientras un cataclismo alimentado por poderosos vendavales carbonizaba vastas zonas de Los \u00c1ngeles, Donald Trump vio una oportunidad. El presidente electo de EE.UU. respondi\u00f3 a seis colosales incendios forestales reabriendo su larga disputa con el gobernador [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457377","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los muros de fuego devoraron barrios, obligando a decenas de miles de residentes a huir para salvar sus vidas. Mientras un cataclismo alimentado por poderosos vendavales carbonizaba vastas zonas de Los \u00c1ngeles, Donald Trump vio una oportunidad. El presidente electo de EE.UU. respondi\u00f3 a seis colosales incendios forestales reabriendo su larga disputa con el gobernador [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T08:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom\",\"datePublished\":\"2025-01-09T08:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\"},\"wordCount\":1826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\",\"name\":\"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-09T08:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias","og_description":"Los muros de fuego devoraron barrios, obligando a decenas de miles de residentes a huir para salvar sus vidas. Mientras un cataclismo alimentado por poderosos vendavales carbonizaba vastas zonas de Los \u00c1ngeles, Donald Trump vio una oportunidad. El presidente electo de EE.UU. respondi\u00f3 a seis colosales incendios forestales reabriendo su larga disputa con el gobernador [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-09T08:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom","datePublished":"2025-01-09T08:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/"},"wordCount":1826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","name":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-09T08:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Trump aprovecha los infiernos de Los \u00c1ngeles para reabrir su pugna con Newsom","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/trump-newsom-los-angeles-incendios-analisis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-09T08:03:38Z","datePublished":"2025-01-09T08:03:38Z","dateModified":"2025-01-09T08:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Trump aprovecha los infiernos de Los \\u00c1ngeles para reabrir su pugna con Newsom\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/trump-newsom-los-angeles-incendios-analisis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/trump-newsom-los-angeles-incendios-analisis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-09T08:03:38Z\",\"datePublished\":\"2025-01-09T08:03:38Z\",\"dateModified\":\"2025-01-09T08:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457408,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/trump-afirmaciones-falsas-california-incendios-trax\/","url_meta":{"origin":1457377,"position":0},"title":"CNN verifica: Trump arremete con afirmaciones falsas sobre la FEMA y la pol\u00edtica h\u00eddrica de California ante los incendios","author":"","date":"enero 9, 2025","format":false,"excerpt":"Otro desastre natural, otra serie de afirmaciones falsas del presidente electo Donald Trump.Durante a\u00f1os, Trump ha plagado sus declaraciones sobre los incendios forestales de California y otros desastres con afirmaciones inexactas. Lo hizo de nuevo el mi\u00e9rcoles mientras los incendios forestales arrasaban el condado de Los \u00c1ngeles.He aqu\u00ed una comprobaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457853,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/24\/trump-incendios-mala-gestion-california-trax\/","url_meta":{"origin":1457377,"position":1},"title":"Trump dice que la mala gesti\u00f3n en los bosques y el agua en California es culpable de los incendios forestales. \u00bfEs cierto?","author":"","date":"enero 24, 2025","format":false,"excerpt":"A principios de este mes, cuando m\u00e1s de 96 kil\u00f3metros cuadrados de Los \u00c1ngeles ardieron violentamente, el entonces presidente electo de Estados Unidos, Donald Trump, culp\u00f3 a un pez.Trump insinu\u00f3 falsamente en una publicaci\u00f3n de Truth Social que Los \u00c1ngeles carec\u00eda de agua para apagar los incendios porque el gobernador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463458,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/06\/11\/newsom-california-enfrentan-trump-accion-democratas-trax\/","url_meta":{"origin":1457377,"position":2},"title":"Newsom y California enfrentan a Trump con un posible plan de acci\u00f3n para los dem\u00f3cratas","author":"","date":"junio 11, 2025","format":false,"excerpt":"Durante los \u00faltimos meses, los pol\u00edticos dem\u00f3cratas han hablado de enfrentar al presidente Donald Trump en su segundo mandato. El gobernador de California, Gavin Newsom, es uno de los primeros en tener que definir c\u00f3mo se ve realmente ese desaf\u00edo.Aliados y opositores coinciden en que la forma en que Newsom\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457375,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/biden-cancela-viaje-roma-italia-incendios-california-trax\/","url_meta":{"origin":1457377,"position":3},"title":"Biden cancela su viaje a Italia para centrarse en la respuesta federal a los incendios de Los \u00c1ngeles","author":"","date":"enero 8, 2025","format":false,"excerpt":"El presidente de EE.UU., Joe Biden, ya no viajar\u00e1 a Italia esta semana como estaba previsto, seg\u00fan anunci\u00f3 la Casa Blanca a \u00faltima hora de este mi\u00e9rcoles, cancelando el viaje en los \u00faltimos d\u00edas de su presidencia para supervisar los voraces incendios forestales en la zona de Los \u00c1ngeles.\u201cTras regresar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457804,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/23\/trump-recortar-financiacion-ciudades-santuario-trax\/","url_meta":{"origin":1457377,"position":4},"title":"Trump dice a Fox News que &#171;podr\u00eda tener que&#187; recortar la financiaci\u00f3n a las ciudades santuario","author":"","date":"enero 23, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo el mi\u00e9rcoles que podr\u00eda recortar la financiaci\u00f3n federal a las llamadas ciudades santuario si no cumplen con sus \u00f3rdenes de inmigraci\u00f3n.Cuando Sean Hannity de Fox le pregunt\u00f3 si Trump considerar\u00eda recortar la financiaci\u00f3n, Trump respondi\u00f3: \u201cPodr\u00eda tener que hacerlo\u201d.Trump dijo que California\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451693,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/08\/trump-falso-aterrizaje-emergencia-helicoptero-nunca-ocurrio-trax\/","url_meta":{"origin":1457377,"position":5},"title":"Trump dijo que &#8216;cay\u00f3&#8217; en un &#8216;aterrizaje de emergencia&#8217; en un helic\u00f3ptero con el exalcalde de San Francisco, pero este dice que nunca ocurri\u00f3","author":"","date":"agosto 8, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump relat\u00f3 este jueves a los periodistas una an\u00e9cdota sobre su participaci\u00f3n en un aterrizaje de emergencia en helic\u00f3ptero con el exalcalde de San Francisco, Willie Brown.Cuando un reportero le pregunt\u00f3 sobre la relaci\u00f3n previa de la vicepresidenta Kamala Harris con Brown y si ayud\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457377"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457377\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}