{"id":1457394,"date":"2025-01-09T08:03:43","date_gmt":"2025-01-09T16:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/"},"modified":"2025-01-09T08:03:43","modified_gmt":"2025-01-09T16:03:43","slug":"diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","title":{"rendered":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela"},"content":{"rendered":"<p>El ministro del Interior de Venezuela, Diosdado Cabello, acus\u00f3 este mi\u00e9rcoles al excandidato presidencial Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en el pa\u00eds. El funcionario dijo que M\u00e1rquez fue detenido.<\/p>\n<p>Cabello hizo los se\u00f1alamientos durante su programa televisivo semanal, \u201cCon el mazo dando\u201d, un d\u00eda despu\u00e9s de que M\u00e1rquez fuera \u201csecuestrado por grupos parapoliciales\u201d, seg\u00fan denunci\u00f3 su familia.<\/p>\n<p>Al referirse al caso, Cabello dijo que M\u00e1rquez fue arrestado porque \u201cforma parte de un complot\u201d con el cual \u2014asegur\u00f3\u2014 tambi\u00e9n estar\u00edan relacionados un ciudadano estadounidense del FBI y el yerno del l\u00edder opositor Edmundo Gonz\u00e1lez Urrutia, ambos detenidos recientemente.<\/p>\n<p>CNN est\u00e1 intentado contactar a la Fiscal\u00eda General de Venezuela para conocer el estatus legal de Enrique M\u00e1rquez.<\/p>\n<p>Cabello mostr\u00f3 un documento que \u2014sostuvo\u2014 expone una propuesta impulsada por M\u00e1rquez para que Gonz\u00e1lez sea juramentado presidente de Venezuela ante una asamblea de ciudadanos venezolanos, en una sede diplom\u00e1tica del pa\u00eds.<\/p>\n<p>CNN no puede verificar que el documento mostrado por el ministro sea aut\u00e9ntico. Tambi\u00e9n contact\u00f3 al partido Centrados, que postul\u00f3 a M\u00e1rquez, para pedir comentarios sobre las acusaciones del ministro del Interior.<\/p>\n<p>\u201cEl que estaba al frente de esto se llama Enrique M\u00e1rquez, parte del golpe de Estado que quieren dar en Venezuela. Aqu\u00ed no hay \u00e1ngeles y menos entre los opositores. A los que andan defendiendo, \u00bflo o\u00edste, Petro? Defi\u00e9ndelo, est\u00e1s defendiendo a un ni\u00f1o de pecho. Puede ser tu amigo, pero es un delincuente\u201d, dijo Cabello, al referirse a una publicaci\u00f3n en X en la que el presidente de Colombia, Gustavo Petro, critica la detenci\u00f3n del excandidato presidencial.<\/p>\n<p>La oposici\u00f3n mayoritaria venezolana afirma que Gonz\u00e1lez  gan\u00f3 las controvertidas elecciones del 28 de julio y ha mostrado las actas que recab\u00f3 en las mesas de votaci\u00f3n. El Consejo Nacional Electoral, dominado por el chavismo, proclam\u00f3 ganador al presidente Nicol\u00e1s Maduro, sin publicar los resultados desglosados por estados o mesas. Tanto Maduro como Gonz\u00e1lez aseguran que tomar\u00e1n posesi\u00f3n de la Presidencia de Venezuela este viernes.<\/p>\n<p>Para este jueves, la oposici\u00f3n ha convocado a todos los venezolanos dentro y fuera del pa\u00eds a que salgan a las calles para rechazar el Gobierno de Maduro y apoyar la intenci\u00f3n de Gonz\u00e1lez de asumir la Presidencia.<\/p>\n<p>Como parte de su gira internacional, Gonz\u00e1lez Urrutia est\u00e1 este jueves en Rep\u00fablica Dominicana y asegura que entrar\u00e1 en Venezuela. En esa iniciativa lo respaldan varios Gobiernos y expresidentes del grupo Iniciativa Democr\u00e1tica de Espa\u00f1a y las Am\u00e9ricas (IDEA).<\/p>\n<p>Maduro y altos funcionarios del oficialismo dicen que los opositores quieren desestabilizar a Venezuela y que los extranjeros no deben intervenir en la soberan\u00eda nacional.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro del Interior de Venezuela, Diosdado Cabello, acus\u00f3 este mi\u00e9rcoles al excandidato presidencial Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en el pa\u00eds. El funcionario dijo que M\u00e1rquez fue detenido. Cabello hizo los se\u00f1alamientos durante su programa televisivo semanal, \u201cCon el mazo dando\u201d, un d\u00eda despu\u00e9s de que M\u00e1rquez [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457394","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ministro del Interior de Venezuela, Diosdado Cabello, acus\u00f3 este mi\u00e9rcoles al excandidato presidencial Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en el pa\u00eds. El funcionario dijo que M\u00e1rquez fue detenido. Cabello hizo los se\u00f1alamientos durante su programa televisivo semanal, \u201cCon el mazo dando\u201d, un d\u00eda despu\u00e9s de que M\u00e1rquez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T16:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela\",\"datePublished\":\"2025-01-09T16:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\",\"name\":\"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-09T16:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias","og_description":"El ministro del Interior de Venezuela, Diosdado Cabello, acus\u00f3 este mi\u00e9rcoles al excandidato presidencial Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en el pa\u00eds. El funcionario dijo que M\u00e1rquez fue detenido. Cabello hizo los se\u00f1alamientos durante su programa televisivo semanal, \u201cCon el mazo dando\u201d, un d\u00eda despu\u00e9s de que M\u00e1rquez [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-09T16:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/"},"author":{"name":"","@id":""},"headline":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela","datePublished":"2025-01-09T16:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","name":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-09T16:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Diosdado Cabello acusa a Enrique M\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-09T16:03:43Z","datePublished":"2025-01-09T16:03:43Z","dateModified":"2025-01-09T16:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Diosdado Cabello acusa a Enrique M\\u00e1rquez de estar involucrado en un intento de golpe de Estado en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/diosdado-cabello-acusa-enrique-marquez-intento-golpe-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-09T16:03:43Z\",\"datePublished\":\"2025-01-09T16:03:43Z\",\"dateModified\":\"2025-01-09T16:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471745,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/27\/entrevista-enrique-marquez-pais-cambios-orix\/","url_meta":{"origin":1457394,"position":0},"title":"Enrique M\u00e1rquez dice que Venezuela &#171;es otro pa\u00eds&#187; tras la captura de Maduro: &#171;Estamos listos para seguir los cambios&#187;","author":"","date":"febrero 27, 2026","format":false,"excerpt":"El l\u00edder opositor venezolano Enrique M\u00e1rquez, quien fue excarcelado en Venezuela en enero tras haber estado detenido un a\u00f1o por razones pol\u00edticas, consider\u00f3 este viernes que su pa\u00eds vive cambios acelerados tras la captura del derrocado presidente Nicol\u00e1s Maduro y que los venezolanos est\u00e1n preparados para encarar esas transformaciones.\u201cVenezuela es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471621,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/25\/enrique-marquez-reune-sobrina-discurso-estado-union-trump-trax\/","url_meta":{"origin":1457394,"position":1},"title":"El expreso pol\u00edtico de Venezuela, Enrique M\u00e1rquez, se re\u00fane con su sobrina en discurso del Estado de la Uni\u00f3n de Trump","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Un l\u00edder de la oposici\u00f3n venezolana recientemente liberado de prisi\u00f3n se reuni\u00f3 con su sobrina el martes durante el discurso del Estado de la Uni\u00f3n, mientras el presidente Donald Trump promocionaba la operaci\u00f3n militar estadounidense que derroc\u00f3 al presidente Nicol\u00e1s Maduro.En su discurso, Trump llam\u00f3 la atenci\u00f3n sobre Alejandra Gonz\u00e1lez,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471638,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/02\/25\/enrique-marquez-invitado-trump-orix\/","url_meta":{"origin":1457394,"position":2},"title":"Qui\u00e9n es Enrique M\u00e1rquez, exrector del CNE de Venezuela que sali\u00f3 de prisi\u00f3n en enero y fue invitado sorpresa de Trump","author":"","date":"febrero 25, 2026","format":false,"excerpt":"A un mes de su excarcelaci\u00f3n en Venezuela, luego de pasar un a\u00f1o como preso pol\u00edtico, el exdiputado Enrique M\u00e1rquez fue uno de los invitados sorpresa en el discurso del martes del presidente de Estados Unidos, Donald Trump, quien destac\u00f3 las liberaciones en el pa\u00eds sudamericano.M\u00e1rquez fue una de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451916,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/16\/excandidato-presidencial-enrique-marquez-solicita-al-tribunal-supremo-de-justicia-un-conteo-voto-por-voto-de-las-elecciones-de-venezuela\/","url_meta":{"origin":1457394,"position":3},"title":"Excandidato presidencial Enrique M\u00e1rquez solicita al Tribunal Supremo de Justicia un conteo voto por voto de las elecciones de Venezuela","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El excandidato presidencial y exvicepresidente del Consejo Nacional Electoral de Venezuela, Enrique M\u00e1rquez, dijo este mi\u00e9rcoles que solicit\u00f3 a la Sala Electoral del Tribunal Supremo de Justicia (TSJ) que ordene el conteo voto por voto de las elecciones del 28 de julio y que se declare nulo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450704,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/06\/25\/partido-comunista-venezuela-apoyo-enrique-marquez-orix\/","url_meta":{"origin":1457394,"position":4},"title":"El Partido Comunista de Venezuela anuncia apoyo a la candidatura presidencial de Enrique M\u00e1rquez","author":"","date":"junio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Partido Comunista de Venezuela (PCV) apoyar\u00e1 la candidatura presidencial de Enrique M\u00e1rquez en las elecciones del 28 de julio, inform\u00f3 el instituto pol\u00edtico en un comunicado.El secretario general del Comit\u00e9 Central del PCV, Oscar Figuera, dijo que el partido rechaza la candidatura del presidente Nicol\u00e1s Maduro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469873,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/01\/07\/diosdado-cabello-poder-gobierno-perfil-orix\/","url_meta":{"origin":1457394,"position":5},"title":"Diosdado Cabello, el presunto poder en las sombras que se las ha arreglado para sobrevivir a todos en el chavismo","author":"","date":"enero 7, 2026","format":false,"excerpt":"Durante a\u00f1os, Diosdado Cabello Rond\u00f3n fue para muchos el poder en las sombras en Venezuela. Al mismo tiempo, fue el eterno n\u00famero dos del chavismo y quien qued\u00f3 apartado del sill\u00f3n presidencial cuando Hugo Ch\u00e1vez, entonces presidente y enfermo con c\u00e1ncer, eligi\u00f3 a Nicol\u00e1s Maduro para sucederlo. Esta aparente contradicci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457394"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457394\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}