{"id":1457395,"date":"2025-01-09T08:03:43","date_gmt":"2025-01-09T16:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/"},"modified":"2025-01-09T08:03:43","modified_gmt":"2025-01-09T16:03:43","slug":"carteles-se-busca-expresidentes-gonzalez-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","title":{"rendered":"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela"},"content":{"rendered":"<p>El Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas (CICPC) de Venezuela public\u00f3 en Instagram carteles de \u201cSe busca por invasor\u201d con los nombres y rostros de los expresidentes latinoamericanos Mario Abdo Ben\u00edtez (Paraguay), Jorge Jamil Mahuad (Ecuador), Mireya Moscoso (Panam\u00e1), Felipe Calder\u00f3n (M\u00e9xico), Vicente Fox Quesada (M\u00e9xico), Ernesto Perez-Balladares (Panam\u00e1) y Andr\u00e9s Pastrana Arango (Colombia).<\/p>\n<p>CNN est\u00e1 buscando la reacci\u00f3n de los expresidentes que aparecen en estos carteles.<\/p>\n<p>El CICPC a\u00f1adi\u00f3 que los busca por \u201cdelitos de conspiraci\u00f3n y complicidad en actos terroristas y atentar contra la paz de Venezuela\u201d.<\/p>\n<p>CNN est\u00e1 contactando a la Fiscal\u00eda General de Venezuela para indagar si hay cargos penales u \u00f3rdenes de captura contra estos expresidentes que la Polic\u00eda Cient\u00edfica dice estar buscando.<\/p>\n<p>El expresidente de Colombia, Andr\u00e9s Pastrana, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/07\/venezuela\/pastrana-exmandatarios-gonzalez-venezuela-orix\">le reiter\u00f3 el martes a CNN<\/a> que acompa\u00f1ar\u00e1 al l\u00edder opositor venezolano Edmundo Gonz\u00e1lez Urrutia en su plan de viajar este viernes a Caracas, aunque no precis\u00f3 detalles de c\u00f3mo ser\u00e1 ese desplazamiento.<\/p>\n<p>Pastrana a\u00f1adi\u00f3 que entre los exmandatarios que le han manifestado que formar\u00e1n parte del grupo de acompa\u00f1amiento figuran Vicente Fox y Felipe Calder\u00f3n, de M\u00e9xico; Jamil Mahuad, de Ecuador; Jorge Quiroga, de Bolivia; Mario Abdo Ben\u00edtez, de Paraguay; Ernesto P\u00e9rez Balladares y Mireya Moscoso, de Panam\u00e1; y Laura Chinchilla, de Costa Rica.<\/p>\n<p>La Asamblea Nacional de Venezuela, de mayor\u00eda oficialista, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/08\/venezuela\/asamblea-venezuela-personas-no-gratas-expresidentes-orix\">declar\u00f3 este mi\u00e9rcoles \u201cpersonas non gratas\u201d<\/a> a los nueve expresidentes que forman parte del grupo Iniciativa Democr\u00e1tica de Espa\u00f1a y las Am\u00e9ricas (IDEA) y que buscan acompa\u00f1ar al l\u00edder opositor Edmundo Gonz\u00e1lez Urrutia en su intento por regresar al pa\u00eds sudamericano para asumir la Presidencia el 10 de enero.<\/p>\n<p>Este mismo mi\u00e9rcoles, los 32 ex jefes de Estado y de gobierno de la IDEA publicaron una declaraci\u00f3n en la que respaldan al l\u00edder opositor venezolano Edmundo Gonz\u00e1lez consider\u00e1ndolo presidente electo de Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas (CICPC) de Venezuela public\u00f3 en Instagram carteles de \u201cSe busca por invasor\u201d con los nombres y rostros de los expresidentes latinoamericanos Mario Abdo Ben\u00edtez (Paraguay), Jorge Jamil Mahuad (Ecuador), Mireya Moscoso (Panam\u00e1), Felipe Calder\u00f3n (M\u00e9xico), Vicente Fox Quesada (M\u00e9xico), Ernesto Perez-Balladares (Panam\u00e1) y Andr\u00e9s Pastrana Arango (Colombia). [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457395","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Publican carteles de &quot;Se busca por invasor&quot; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publican carteles de &quot;Se busca por invasor&quot; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas (CICPC) de Venezuela public\u00f3 en Instagram carteles de \u201cSe busca por invasor\u201d con los nombres y rostros de los expresidentes latinoamericanos Mario Abdo Ben\u00edtez (Paraguay), Jorge Jamil Mahuad (Ecuador), Mireya Moscoso (Panam\u00e1), Felipe Calder\u00f3n (M\u00e9xico), Vicente Fox Quesada (M\u00e9xico), Ernesto Perez-Balladares (Panam\u00e1) y Andr\u00e9s Pastrana Arango (Colombia). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T16:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela\",\"datePublished\":\"2025-01-09T16:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\",\"name\":\"Publican carteles de \\\"Se busca por invasor\\\" a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-09T16:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publican carteles de \"Se busca por invasor\" a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Publican carteles de \"Se busca por invasor\" a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias","og_description":"El Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas (CICPC) de Venezuela public\u00f3 en Instagram carteles de \u201cSe busca por invasor\u201d con los nombres y rostros de los expresidentes latinoamericanos Mario Abdo Ben\u00edtez (Paraguay), Jorge Jamil Mahuad (Ecuador), Mireya Moscoso (Panam\u00e1), Felipe Calder\u00f3n (M\u00e9xico), Vicente Fox Quesada (M\u00e9xico), Ernesto Perez-Balladares (Panam\u00e1) y Andr\u00e9s Pastrana Arango (Colombia). [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-09T16:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela","datePublished":"2025-01-09T16:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","name":"Publican carteles de \"Se busca por invasor\" a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-09T16:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\u00e1lez en Venezuela","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-09T16:03:43Z","datePublished":"2025-01-09T16:03:43Z","dateModified":"2025-01-09T16:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Publican carteles de &#171;Se busca por invasor&#187; a expresidentes que apoyan a Edmundo Gonz\\u00e1lez en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/carteles-se-busca-expresidentes-gonzalez-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-09T16:03:43Z\",\"datePublished\":\"2025-01-09T16:03:43Z\",\"dateModified\":\"2025-01-09T16:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457332,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/asamblea-venezuela-personas-no-gratas-expresidentes-orix\/","url_meta":{"origin":1457395,"position":0},"title":"Asamblea de Venezuela declara &#171;personas no gratas&#187; a expresidentes que buscan acompa\u00f1ar a Edmundo Gonz\u00e1lez en su regreso","author":"","date":"enero 7, 2025","format":false,"excerpt":"La Asamblea Nacional de Venezuela, de mayor\u00eda oficialista, declar\u00f3 \u201cpersonas no gratas\u201d a los nueve expresidentes que forman parte del grupo Iniciativa Democr\u00e1tica de Espa\u00f1a y las Am\u00e9ricas (IDEA) y que buscan acompa\u00f1ar al l\u00edder opositor Edmundo Gonz\u00e1lez Urrutia en su intento por regresar al pa\u00eds sudamericano para, seg\u00fan afirma,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452054,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/21\/petro-dialoga-expresidentes-colombia-venezuela-orix\/","url_meta":{"origin":1457395,"position":1},"title":"El Gobierno de Petro dialoga con expresidentes de Colombia sobre el conflicto poselectoral en Venezuela","author":"","date":"agosto 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El Gobierno de Gustavo Petro dialog\u00f3 este mi\u00e9rcoles con expresidentes de Colombia sobre el conflicto poselectoral en Venezuela y sobre las v\u00edas en las que el pa\u00eds podr\u00eda ayudar a buscar una soluci\u00f3n, seg\u00fan dijo a periodistas el canciller Luis Gilberto Murillo.Las conversaciones se produjeron este d\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451453,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/delcy-rodriguez-no-cualquiera-entrar-venezuela-orix\/","url_meta":{"origin":1457395,"position":2},"title":"\u201cNo cualquiera puede entrar a Venezuela\u201d, dice vicepresidenta Delcy Rodr\u00edguez mientras el Gobierno impide entrada al pa\u00eds de varios exmandatarios","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La vicepresidenta de Venezuela, Delcy Rodr\u00edguez, dijo este viernes que \u201cno cualquiera\u201d puede entrar al pa\u00eds, en referencia al grupo de expresidentes latinoamericanos que quisieron volar a territorio venezolano desde Panam\u00e1.\u201cLes advertimos: solamente gente con dignidad puede entrar en esta tierra sagrada, cualquiera que quiera entrar a Venezuela\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451449,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/26\/gobierno-venezuela-retrasa-vuelo-mireya-moscoso-panama-orix\/","url_meta":{"origin":1457395,"position":3},"title":"Gobierno de Venezuela retrasa despegue de vuelo a Caracas con Mireya Moscoso a bordo, denuncia el presidente de Panam\u00e1","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Venezuela ha retrasado este viernes el despegue de un avi\u00f3n de la aerol\u00ednea Copa que cubre el tramo Ciudad de Panam\u00e1-Caracas y que lleva entre sus pasajeros a la expresidenta de Panam\u00e1 Mireya Moscoso y a otros exmandatarios, inform\u00f3 en X\u00a0el presidente del pa\u00eds centroamericano,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457160,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/02\/gobierno-recompensa-arresto-edmundo-gonzalez-orix\/","url_meta":{"origin":1457395,"position":4},"title":"El Gobierno de Venezuela ofrece recompensa de US$ 100.000 por informaci\u00f3n que lleve al arresto de Edmundo Gonz\u00e1lez Urrutia","author":"","date":"enero 2, 2025","format":false,"excerpt":"El Cuerpo de Investigaciones Cient\u00edficas, Penales y Criminal\u00edsticas de Venezuela (CICPC) ofreci\u00f3 este jueves una recompensa de US$ 100.000 por informaci\u00f3n que lleve al arresto del l\u00edder opositor Edmundo Gonz\u00e1lez Urrutia, quien en las elecciones presidenciales del 28 de julio compiti\u00f3 contra el presidente Nicol\u00e1s Maduro y en septiembre se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468278,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/11\/12\/vuelo-migrantes-deportados-texas-orix\/","url_meta":{"origin":1457395,"position":5},"title":"En plena tensi\u00f3n con EE.UU., llega a Venezuela otro vuelo con casi 300 migrantes deportados desde Texas","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Casi 300 migrantes venezolanos llegaron este mi\u00e9rcoles a Venezuela en un vuelo de repatriaci\u00f3n procedente de Estados Unidos, entre ellos 14 menores de edad, inform\u00f3 el Ministerio de Relaciones Interiores, Justicia y Paz de Venezuela.El vuelo, proveniente del estado de Texas, aterriz\u00f3 en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar de Maiquet\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457395"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457395\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}