{"id":1457415,"date":"2025-01-09T19:03:43","date_gmt":"2025-01-10T03:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/"},"modified":"2025-01-09T19:03:43","modified_gmt":"2025-01-10T03:03:43","slug":"corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","title":{"rendered":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio"},"content":{"rendered":"<p>El presidente electo, Donald Trump, puede ser sentenciado el viernes en su caso de pago de dinero por silencio en Nueva York, dijo la Corte Suprema en un fallo de 5-4.<\/p>\n<p> El alto tribunal rechaz\u00f3 el jueves la petici\u00f3n de emergencia de Trump para retrasar el proceso, preparando el escenario para que sea sentenciado pocos d\u00edas antes de su investidura el 20 de enero para un segundo mandato.<\/p>\n<p>Cuatro jueces conservadores, Clarence Thomas, Samuel Alito, Neil Gorsuch y Brett Kavanaugh, dijeron que habr\u00edan accedido a la petici\u00f3n de Trump. El presidente de la Corte Suprema, John Roberts, y la jueza Amy Coney Barrett se unieron a los tres liberales del tribunal.<\/p>\n<p>El juez Juan Merchan, el magistrado de Nueva York que supervis\u00f3 el juicio de Trump, hab\u00eda ordenado que se dictara sentencia en el caso el viernes por la ma\u00f1ana, pero ha se\u00f1alado que Trump no se enfrentar\u00e1 ni a penas ni a penas de prisi\u00f3n.<\/p>\n<p>La audiencia de sentencia est\u00e1 programada para el viernes a las 9:30 de la ma\u00f1ana.<\/p>\n<p>En una breve declaraci\u00f3n de un p\u00e1rrafo, el tribunal dijo que algunas de las preocupaciones de Trump podr\u00edan ser manejadas \u201cen el curso ordinario en la apelaci\u00f3n\u201d. El tribunal tambi\u00e9n razon\u00f3 que la carga que la sentencia impondr\u00eda sobre las responsabilidades de Trump es \u201crelativamente insustancial\u201d a la luz de la intenci\u00f3n declarada del tribunal de primera instancia de no imponer ninguna pena.<\/p>\n<p>La petici\u00f3n del presidente electo ante la Corte Suprema de EE.UU. fue un recurso extraordinario porque los magistrados rara vez se sumergen en un caso penal estatal antes de que se hayan agotado todos los recursos en los tribunales estatales.<\/p>\n<p>El recurso subyacente de Trump contra su condena sigue pendiente y el fiscal del distrito de Manhattan, Alvin Bragg, argument\u00f3 que la Corte Suprema ni siquiera ten\u00eda jurisdicci\u00f3n para considerar la petici\u00f3n de emergencia de retrasar la sentencia.<\/p>\n<p>Trump fue declarado culpable en mayo de falsificar registros comerciales sobre los pagos a su entonces abogado Michael Cohen para reembolsar un pago de US$ 130.000 por silencio hecho a la estrella de cine para adultos Stormy Daniels, con el fin de evitar que hablara sobre una supuesta aventura antes de las elecciones de 2016. (Trump ha negado la relaci\u00f3n).<\/p>\n<p>El presidente entrante, que tomar\u00e1 posesi\u00f3n en menos de dos semanas, est\u00e1 luchando contra su condena, alegando que deber\u00eda ser anulada porque una mayor\u00eda conservadora de la Corte Suprema dictamin\u00f3 en julio que los expresidentes tienen derecho a una amplia inmunidad por acciones oficiales.<\/p>\n<p>Parte del argumento de Trump era que su juicio inclu\u00eda pruebas sobre actos oficiales de su mandato que, seg\u00fan la decisi\u00f3n de inmunidad de la Corte Suprema, normalmente no podr\u00edan llegar a un jurado. Los fiscales replicaron que esas preocupaciones podr\u00edan resolverse en apelaci\u00f3n.<\/p>\n<p>Merchan rechaz\u00f3 ese argumento en diciembre, dictaminando que las pruebas presentadas por la Fiscal\u00eda del distrito de Manhattan no estaban relacionadas con la conducta oficial de Trump como presidente.<\/p>\n<p>Los abogados de Trump dijeron a la Corte Suprema que tener que lidiar con la sentencia distraer\u00eda de su transici\u00f3n al poder y potencialmente pondr\u00eda en peligro la seguridad nacional.<\/p>\n<p>\u201cDefender la litigaci\u00f3n criminal en todas las etapas, especialmente, como aqu\u00ed, defender una sentencia criminal, es \u00fanica y excepcionalmente agotador y molesto para un acusado criminal\u201d, dijeron los abogados de Trump.<\/p>\n<p>\u201cEl presidente Trump est\u00e1 actualmente comprometido con las tareas m\u00e1s cruciales y sensibles de prepararse para asumir el poder ejecutivo en menos de dos semanas, todas las cuales son esenciales para la seguridad nacional y los intereses vitales de Estados Unidos\u201d, escribieron.<\/p>\n<p>Los fiscales de Nueva York regenaron ese argumento en su propia presentaci\u00f3n el jueves.<\/p>\n<p>\u201cHay un inter\u00e9s p\u00fablico apremiante en proceder a la sentencia\u201d, dijo Bragg a la Corte Suprema. \u201cEl acusado no ha proporcionado ning\u00fan apoyo documental para su afirmaci\u00f3n de que sus deberes como presidente electo le impiden pr\u00e1cticamente asistir a una sentencia que probablemente no tomar\u00e1 m\u00e1s de una hora\u201d.<\/p>\n<p>En una \u00faltima presentaci\u00f3n el jueves, Trump argument\u00f3 que el caso involucraba preocupaciones de \u201cgran importancia nacional\u201d y que \u201cla estructura constitucional y la naci\u00f3n\u201d ser\u00edan \u201cda\u00f1adas irreparablemente si se permite que la sentencia siga adelante\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo, Donald Trump, puede ser sentenciado el viernes en su caso de pago de dinero por silencio en Nueva York, dijo la Corte Suprema en un fallo de 5-4. El alto tribunal rechaz\u00f3 el jueves la petici\u00f3n de emergencia de Trump para retrasar el proceso, preparando el escenario para que sea sentenciado pocos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457415","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente electo, Donald Trump, puede ser sentenciado el viernes en su caso de pago de dinero por silencio en Nueva York, dijo la Corte Suprema en un fallo de 5-4. El alto tribunal rechaz\u00f3 el jueves la petici\u00f3n de emergencia de Trump para retrasar el proceso, preparando el escenario para que sea sentenciado pocos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-10T03:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio\",\"datePublished\":\"2025-01-10T03:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\"},\"wordCount\":771,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\",\"name\":\"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-10T03:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias","og_description":"El presidente electo, Donald Trump, puede ser sentenciado el viernes en su caso de pago de dinero por silencio en Nueva York, dijo la Corte Suprema en un fallo de 5-4. El alto tribunal rechaz\u00f3 el jueves la petici\u00f3n de emergencia de Trump para retrasar el proceso, preparando el escenario para que sea sentenciado pocos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-10T03:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/"},"author":{"name":"","@id":""},"headline":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio","datePublished":"2025-01-10T03:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/"},"wordCount":771,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","name":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-10T03:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-10T03:03:43Z","datePublished":"2025-01-10T03:03:43Z","dateModified":"2025-01-10T03:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Corte Suprema confirma que Donald Trump puede ser sentenciado el viernes en caso de pagos de dinero por silencio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/corte-suprema-confirma-donald-trump-puede-ser-sentenciado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-10T03:03:43Z\",\"datePublished\":\"2025-01-10T03:03:43Z\",\"dateModified\":\"2025-01-10T03:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452301,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/30\/trump-solicita-aplazar-sentencia-pago-dinero-silencio-trax\/","url_meta":{"origin":1457415,"position":0},"title":"Trump solicita aplazar de nuevo la sentencia por el pago de dinero por silencio en Nueva York, esta vez citando una nueva acusaci\u00f3n de subversi\u00f3n electoral","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) --\u00a0El equipo legal de Donald Trump est\u00e1 pidiendo que se retrase la sentencia y cualquier otra acci\u00f3n sustantiva en el caso de los pagos por silencio mientras se desarrolla un nuevo esfuerzo para trasladar el caso a un tribunal federal, seg\u00fan una carta obtenida por CNN.La petici\u00f3n al juez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457355,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/trump-corte-suprema-suspenda-sentencia-caso-dinero-silenciar-sospechosos-trax\/","url_meta":{"origin":1457415,"position":1},"title":"Trump pide a la Corte Suprema que suspenda la sentencia en el caso de pagos de dinero por silencio","author":"","date":"enero 8, 2025","format":false,"excerpt":"El presidente electo Donald Trump inst\u00f3 el mi\u00e9rcoles a la Corte Suprema de Estados Unidos a pausar su sentencia en el caso de dinero para silenciar a sus seguidores, una solicitud altamente inusual que se basa en parte en la decisi\u00f3n de la corte, el a\u00f1o pasado, de otorgarle amplia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457272,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/06\/trump-pide-retrasar-sentencia-trax\/","url_meta":{"origin":1457415,"position":2},"title":"Trump pide a la corte retrasar sentencia del viernes por su condena en caso de pagos de dinero por silencio","author":"","date":"enero 6, 2025","format":false,"excerpt":"Donald Trump est\u00e1 apelando los dos fallos del juez Juan Merchan que desestimaron sus intentos de anular su condena en el caso de pagos de dinero por silencio, y el presidente electo est\u00e1 buscando una suspensi\u00f3n de la sentencia programada para el viernes.La apelaci\u00f3n de Trump llega el mismo d\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452480,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/06\/juez-retrasa-sentencia-trump-trax\/","url_meta":{"origin":1457415,"position":3},"title":"Juez retrasa la sentencia de Trump en caso penal hasta despu\u00e9s de las elecciones","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump no ser\u00e1 sentenciado en su caso penal de Nueva York hasta despu\u00e9s de las elecciones de 2024, seg\u00fan una nueva decisi\u00f3n del juez Juan Merchan.Merchan escribi\u00f3 en una nueva carta que sentenciar\u00eda a Trump el 26 de noviembre \u2013si fuera necesario\u2013 en respuesta a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452287,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/30\/trump-caso-penal-nueva-york-tribunal-federal-retrasar-sentencia-trax\/","url_meta":{"origin":1457415,"position":4},"title":"Trump busca trasladar su caso penal en el estado de Nueva York a un tribunal federal y retrasar la sentencia","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- Donald Trump present\u00f3 una demanda para trasladar su caso penal del estado de Nueva York a un tribunal federal en Manhattan y retrasar la pr\u00f3xima sentencia por su condena por 34 cargos de falsificaci\u00f3n de registros de negocios.La demanda presentada este jueves pide al tribunal federal que confirme\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457435,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/conclusiones-audiencia-sentencia-de-donald-trump-trax\/","url_meta":{"origin":1457415,"position":5},"title":"Conclusiones de la audiencia de sentencia de Donald Trump","author":"","date":"enero 10, 2025","format":false,"excerpt":"Donald Trump fue sentenciado sin pena en el caso del pago de dinero por silencio en Nueva York el viernes despu\u00e9s de una audiencia simb\u00f3lica, hist\u00f3rica y sin precedentes, tras la primera condena por delito grave de un expresidente y pronto presidente en ejercicio.El juez Juan Merchan se dirigi\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457415"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457415\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}