{"id":1457417,"date":"2025-01-09T20:03:49","date_gmt":"2025-01-10T04:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/"},"modified":"2025-01-09T20:03:49","modified_gmt":"2025-01-10T04:03:49","slug":"hallan-restos-avioneta-recuperacion-cuerpos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","title":{"rendered":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo"},"content":{"rendered":"<p>Autoridades de Colombia hallaron este jueves los <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/08\/colombia\/busqueda-avioneta-jurado-medellin-orix\">restos de la avioneta con 10 personas<\/a> que se extravi\u00f3 el mi\u00e9rcoles mientras volaba entre las ciudades de Jurad\u00f3 y Medell\u00edn, y comenzaron la recuperaci\u00f3n de los cuerpos, inform\u00f3 en un comunicado la Aeron\u00e1utica Civil del pa\u00eds sudamericano.<\/p>\n<p>El hallazgo de la aeronave tipo Cessna 402 ocurri\u00f3 en el municipio de Urrao, departamento de Antioqu\u00eda, donde el veh\u00edculo fue localizado por un helic\u00f3ptero que participaba en las labores de b\u00fasqueda, agreg\u00f3 la instituci\u00f3n.<\/p>\n<p>Ahora, funcionarios de Aeron\u00e1utica Civil, la Fuerza Aeroespacial Colombiana, la Defensa Civil y el departamento de Antioqu\u00eda buscan llegar al sitio exacto donde se encuentran los restos de la avioneta.<\/p>\n<p>La aeronave perdi\u00f3 comunicaci\u00f3n con el control de tr\u00e1nsito a\u00e9reo durante la tarde del mi\u00e9rcoles.<\/p>\n<p>El recorrido que cubr\u00eda entre Jurad\u00f3 y Medell\u00edn se extiende unos 330 kil\u00f3metros. Por la ma\u00f1ana de este jueves, la Aeron\u00e1utica Civil inform\u00f3 en un comunicado que la zona de b\u00fasqueda se hab\u00eda delimitado a un \u00e1rea de unos 40 kil\u00f3metros cuadrados.<\/p>\n<p>En otro comunicado, dijo que, de las 10 personas que iban en la avioneta, ocho eran pasajeros \u2014entre los que hab\u00eda tres menores de edad\u2014 y los dos restantes eran la tripulaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades de Colombia hallaron este jueves los restos de la avioneta con 10 personas que se extravi\u00f3 el mi\u00e9rcoles mientras volaba entre las ciudades de Jurad\u00f3 y Medell\u00edn, y comenzaron la recuperaci\u00f3n de los cuerpos, inform\u00f3 en un comunicado la Aeron\u00e1utica Civil del pa\u00eds sudamericano. El hallazgo de la aeronave tipo Cessna 402 ocurri\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457417","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Autoridades de Colombia hallaron este jueves los restos de la avioneta con 10 personas que se extravi\u00f3 el mi\u00e9rcoles mientras volaba entre las ciudades de Jurad\u00f3 y Medell\u00edn, y comenzaron la recuperaci\u00f3n de los cuerpos, inform\u00f3 en un comunicado la Aeron\u00e1utica Civil del pa\u00eds sudamericano. El hallazgo de la aeronave tipo Cessna 402 ocurri\u00f3 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-10T04:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo\",\"datePublished\":\"2025-01-10T04:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\",\"name\":\"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-10T04:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias","og_description":"Autoridades de Colombia hallaron este jueves los restos de la avioneta con 10 personas que se extravi\u00f3 el mi\u00e9rcoles mientras volaba entre las ciudades de Jurad\u00f3 y Medell\u00edn, y comenzaron la recuperaci\u00f3n de los cuerpos, inform\u00f3 en un comunicado la Aeron\u00e1utica Civil del pa\u00eds sudamericano. El hallazgo de la aeronave tipo Cessna 402 ocurri\u00f3 en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-10T04:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/"},"author":{"name":"","@id":""},"headline":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo","datePublished":"2025-01-10T04:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","name":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-10T04:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\u00f3n de cuerpos de 10 personas que iban a bordo","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/hallan-restos-avioneta-recuperacion-cuerpos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-10T04:03:49Z","datePublished":"2025-01-10T04:03:49Z","dateModified":"2025-01-10T04:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hallan los restos de avioneta extraviada en Colombia; empiezan recuperaci\\u00f3n de cuerpos de 10 personas que iban a bordo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/hallan-restos-avioneta-recuperacion-cuerpos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/09\\\/hallan-restos-avioneta-recuperacion-cuerpos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-10T04:03:49Z\",\"datePublished\":\"2025-01-10T04:03:49Z\",\"dateModified\":\"2025-01-10T04:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457374,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/08\/busqueda-avioneta-jurado-medellin-orix\/","url_meta":{"origin":1457417,"position":0},"title":"Inician la b\u00fasqueda de una avioneta con 10 personas que volaba entre Jurad\u00f3 y Medell\u00edn, en Colombia","author":"","date":"enero 8, 2025","format":false,"excerpt":"Una avioneta con 10 personas \u2014entre pasajeros y tripulantes\u2014 se extravi\u00f3 este mi\u00e9rcoles mientras realizaba un vuelo entre las ciudades de Jurad\u00f3 y Medell\u00edn, en Colombia, inform\u00f3 la Aeron\u00e1utica Civil del pa\u00eds sudamericano en un comunicado publicado en X.La aeronave, tipo Cessna 402, perdi\u00f3 comunicaci\u00f3n con el control de tr\u00e1nsito\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449396,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/05\/10\/autoridades-venezuela-encuentran-cuerpos-personas-avioneta-extraviada-zulia-orix\/","url_meta":{"origin":1457417,"position":1},"title":"Autoridades de Venezuela encuentran los cuerpos de 2 de las 8 personas que viajaban en una avioneta extraviada en Zulia","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Autoridades de b\u00fasqueda y rescate de Venezuela encontraron este viernes los cuerpos de dos de las ocho personas que viajaban en una avioneta que se extravi\u00f3 el jueves mientras volaba sobre el estado Zulia, inform\u00f3 el viceministro para la Gesti\u00f3n de Riesgo y Protecci\u00f3n Civil de Venezuela, Carlos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456867,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/22\/muertos-accidente-avioneta-jalisco-orix\/","url_meta":{"origin":1457417,"position":2},"title":"Al menos siete muertos al estrellarse avioneta en Jalisco","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"Al menos siete personas murieron este domingo luego de que la avioneta en la que viajaban se estrellara en una zona boscosa del municipio de Quitupan, Jalisco, en el occidente mexicano, inform\u00f3 en X la Unidad Estatal de Protecci\u00f3n Civil y Bomberos.Seg\u00fan la entidad, la aeronave, una avioneta tipo Cessna\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451729,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/08\/11\/hospitalizada-aterrizaje-emergencia-avioneta-jalisco-orix\/","url_meta":{"origin":1457417,"position":3},"title":"Una persona hospitalizada tras aterrizaje de emergencia de avioneta en carretera de Jalisco, M\u00e9xico","author":"","date":"agosto 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una persona termin\u00f3 hospitalizada este domingo luego de que la avioneta en la que viajaba realizara un aterrizaje de emergencia en una carretera cercana al municipio de Tala, en el estado mexicano de Jalisco, inform\u00f3 a CNN la comandante Tania Lemus, de la Unidad Municipal de Protecci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458393,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/02\/07\/choque-avioneta-autobus-sao-paulo-brasil-al-menos-2-muertos-trax\/","url_meta":{"origin":1457417,"position":4},"title":"Mueren dos personas al estrellarse una avioneta contra un autob\u00fas en una avenida de Sao Paulo","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Al menos dos personas murieron este viernes despu\u00e9s de que una avioneta se precipitara sobre una carretera muy transitada y chocara con un autob\u00fas en Sao Paulo, en el sur de Brasil, dejando heridas a varias personas m\u00e1s.El accidente tuvo lugar alrededor de las 7:20 a.m. hora local (5:20 a.m.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446026,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/02\/26\/helicoptero-accidente-medellin-orix\/","url_meta":{"origin":1457417,"position":5},"title":"Helic\u00f3ptero se accidenta en una zona residencial de Medell\u00edn: no se reportan personas muertas","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN) -- Un helic\u00f3ptero se accident\u00f3 este lunes en una zona residencial del barrio de Manrique en Medell\u00edn, Colombia, sin que el hecho dejara personas muertas, informaron el alcalde de la ciudad, Federico Guti\u00e9rrez, y el Departamento Administrativo de Gesti\u00f3n del Riesgo de Desastres.La aeronave, un helic\u00f3ptero tipo Bell, trasladaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457417"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457417\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}