{"id":1457423,"date":"2025-01-10T09:03:58","date_gmt":"2025-01-10T17:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/"},"modified":"2025-01-10T09:03:58","modified_gmt":"2025-01-10T17:03:58","slug":"nicolas-maduro-toma-posesion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","title":{"rendered":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela"},"content":{"rendered":"<p>Nicol\u00e1s Maduro jur\u00f3 como presidente para un tercer mandato a pesar de las protestas opositras, cerrando m\u00e1s de cinco meses de disputa sobre las cuestionadas elecciones de julio.<\/p>\n<p>La ceremonia tuvo lugar este viernes en una peque\u00f1a sala de la Asamblea Nacional, lo que contrasta con las ceremonias anteriores que se llevaron a cabo en el sal\u00f3n principal del edificio.<\/p>\n<p>La coalici\u00f3n opositora venezolana conden\u00f3 este viernes la investidura de Maduro, calific\u00e1ndola de \u201cgolpe de Estado\u201d y diciendo que es su rival Edmundo Gonz\u00e1lez \u201cquien debe juramentar como presidente\u201d.<\/p>\n<p>Unidad Venezuela, coalici\u00f3n amplia que apoya a la l\u00edder opositora Mar\u00eda Corina Machado, dijo que \u201choy comienza una nueva etapa en esta lucha por la libertad de Venezuela en todo el territorio nacional y en todos los sectores que forman nuestra naci\u00f3n\u201d.<\/p>\n<p>Las autoridades electorales, bajo el estricto control del Partido Socialista (PSUV) en el poder, proclamaron ganador de la elecci\u00f3n presidencial el 28 de julio a Nicol\u00e1s Maduro.<\/p>\n<p>Sin embargo, la oposici\u00f3n venezolana public\u00f3 miles de actas de votaci\u00f3n afirmando que su candidato, Edmundo Gonz\u00e1lez, hab\u00eda ganado en realidad la elecci\u00f3n con un 67% de apoyos frente al 30% de Maduro.<\/p>\n<p>Observadores independientes como el Centro Carter y la Misi\u00f3n Electoral Colombiana, as\u00ed como el propio <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/08\/07\/actas-resultados-venezuela-oposicion-cne-comprobar-orix\/\">an\u00e1lisis de CNN<\/a>, han llegado a la conclusi\u00f3n de que las actas de la oposici\u00f3n son leg\u00edtimas. Y varias naciones, incluidos Estados Unidos, han reconocido desde entonces a Gonz\u00e1lez como el leg\u00edtimo presidente electo de Venezuela.<\/p>\n<p>Gonz\u00e1lez, que ha estado en el exilio desde septiembre (las autoridades venezolanas ofrecen una recompensa por su captura), hab\u00eda prometido regresar a Caracas esta semana en un posible \u00faltimo desaf\u00edo a la juramentaci\u00f3n de Maduro. Su \u00faltima ubicaci\u00f3n conocida este viernes era Rep\u00fablica Dominicana, donde hab\u00eda mantenido recientemente reuniones con l\u00edderes regionales.<\/p>\n<p>Antes de la investidura, Venezuela cerr\u00f3 su frontera terrestre y suspendi\u00f3 los vuelos hacia Colombia, un movimiento que Freddie Bernal, el gobernador del estado fronterizo venezolano de T\u00e1chira, afirm\u00f3 que era en reacci\u00f3n a una \u201cconspiraci\u00f3n internacional\u201d contra Venezuela en una publicaci\u00f3n de Instagram. No present\u00f3 pruebas que respalden su afirmaci\u00f3n.<\/p>\n<p>El cierre de la frontera se produjo pocas horas despu\u00e9s de que el Gobierno de Colombia anunciara que no reconocer\u00eda los resultados de las elecciones de julio, afirmando que no fueron libres.<\/p>\n<p>Protestas estallaron en Caracas y otras ciudades venezolanas el jueves antes de la investidura, con Mar\u00eda Corina Machado saliendo de su escondite para hablar en un evento.<\/p>\n<p>Machado fue \u201cinterceptada violentamente\u201d en el evento, seg\u00fan su equipo, que dijo que \u201cdurante el per\u00edodo de su secuestro fue obligada a grabar varios videos y luego fue liberada\u201d. El gobierno venezolano ha negado haber detenido a Machado.<\/p>\n<p><em>Esta es una historia en desarrollo y ser\u00e1 actualizada.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicol\u00e1s Maduro jur\u00f3 como presidente para un tercer mandato a pesar de las protestas opositras, cerrando m\u00e1s de cinco meses de disputa sobre las cuestionadas elecciones de julio. La ceremonia tuvo lugar este viernes en una peque\u00f1a sala de la Asamblea Nacional, lo que contrasta con las ceremonias anteriores que se llevaron a cabo en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457423","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nicol\u00e1s Maduro jur\u00f3 como presidente para un tercer mandato a pesar de las protestas opositras, cerrando m\u00e1s de cinco meses de disputa sobre las cuestionadas elecciones de julio. La ceremonia tuvo lugar este viernes en una peque\u00f1a sala de la Asamblea Nacional, lo que contrasta con las ceremonias anteriores que se llevaron a cabo en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-10T17:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela\",\"datePublished\":\"2025-01-10T17:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\",\"name\":\"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-10T17:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias","og_description":"Nicol\u00e1s Maduro jur\u00f3 como presidente para un tercer mandato a pesar de las protestas opositras, cerrando m\u00e1s de cinco meses de disputa sobre las cuestionadas elecciones de julio. La ceremonia tuvo lugar este viernes en una peque\u00f1a sala de la Asamblea Nacional, lo que contrasta con las ceremonias anteriores que se llevaron a cabo en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-10T17:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/"},"author":{"name":"","@id":""},"headline":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela","datePublished":"2025-01-10T17:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","name":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-10T17:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nicol\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/nicolas-maduro-toma-posesion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-10T17:03:58Z","datePublished":"2025-01-10T17:03:58Z","dateModified":"2025-01-10T17:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nicol\\u00e1s Maduro se juramenta para un tercer mandato presidencial en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/10\\\/nicolas-maduro-toma-posesion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/10\\\/nicolas-maduro-toma-posesion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-10T17:03:58Z\",\"datePublished\":\"2025-01-10T17:03:58Z\",\"dateModified\":\"2025-01-10T17:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457434,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/machado-pide-edmundo-gonzalez-no-entrar-venezuela-orix\/","url_meta":{"origin":1457423,"position":0},"title":"Mar\u00eda Corina Machado pide a Edmundo Gonz\u00e1lez no entrar a Venezuela este viernes: &#171;Su integridad es fundamental&#187;","author":"","date":"enero 10, 2025","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo este viernes que pidi\u00f3 a Edmundo Gonz\u00e1lez Urrutia, excandidato de la Plataforma Unitaria Democr\u00e1tica (PUD), que no se presente en Venezuela para evitar ponerse en riesgo.En un mensaje en video, Machado dijo que la oposici\u00f3n evalu\u00f3 la situaci\u00f3n y concluy\u00f3 que Gonz\u00e1lez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458073,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/31\/gobierno-trump-reunira-maduro-trax\/","url_meta":{"origin":1457423,"position":1},"title":"Exclusivo: representante del Gobierno de Trump se reunir\u00e1 con el presidente Nicol\u00e1s Maduro este viernes","author":"","date":"enero 31, 2025","format":false,"excerpt":"Se espera que Richard Grenell, enviado del presidente Donald Trump a misiones especiales, se re\u00fana este viernes con el presidente de Venezuela, Nicol\u00e1s Maduro, dijo a CNN una fuente familiarizada con el asunto.Se espera que Grenell discuta con el l\u00edder venezolano los vuelos de deportaci\u00f3n, entre otras cosas. Trump ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457438,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/gonzalez-urrutia-dice-prepara-regreso-venezuela-orix\/","url_meta":{"origin":1457423,"position":2},"title":"Gonz\u00e1lez Urrutia dice que prepara su regreso a Venezuela: &#171;Hagan lo que hagan, lograremos entrar&#187;","author":"","date":"enero 10, 2025","format":false,"excerpt":"El excandidato presidencial opositor venezolano Edmundo Gonz\u00e1lez Urrutia dijo este viernes que est\u00e1 preparando las condiciones para regresar a su pa\u00eds y poner fin al Gobierno de Nicol\u00e1s Maduro, al que calific\u00f3 de \u201ctragedia\u201d.\u201cPronto, muy pronto, aunque ellos hagan lo que hagan, lograremos entrar a Venezuela y le pondremos fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447349,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/03\/25\/maduro-candidato-oposicion-elecciones-orix\/","url_meta":{"origin":1457423,"position":3},"title":"Maduro se registra como candidato y le dice a la oposici\u00f3n: \u201cHabr\u00e1 elecciones con ustedes o sin ustedes\u201d","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, no tuvo contratiempos este lunes para registrarse como candidato presidencial del Partido Socialista Unido de Venezuela (PSUV), en un acto p\u00fablico en el que dijo que el 28 de julio habr\u00e1 elecciones con o sin la oposici\u00f3n.El oficialismo en Venezuela nombra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451381,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/24\/opositores-que-no-ganaron-a-maduro-orix\/","url_meta":{"origin":1457423,"position":4},"title":"Los opositores que no le pudieron ganar a Maduro en elecciones anteriores","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Venezuela elegir\u00e1 a un nuevo presidente el 28 de julio entre diez candidatos, aunque, seg\u00fan las encuestas, hay dos aspirantes claramente despegados del resto: el presidente Nicol\u00e1s Maduro y el abanderado de la oposici\u00f3n mayoritaria, Edmundo Gonz\u00e1lez Urrutia.Maduro va por su tercer mandato y tambi\u00e9n por tercera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451385,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/07\/24\/votacion-ultimas-dos-elecciones-presidenciales-venezuela-orix\/","url_meta":{"origin":1457423,"position":5},"title":"As\u00ed fue la votaci\u00f3n en las \u00faltimas dos elecciones presidenciales de Venezuela","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los venezolanos acuden a votar por un nuevo presidente el 28 de julio. Seg\u00fan las encuestas, la intenci\u00f3n de voto est\u00e1 entre el candidato de la oposici\u00f3n mayoritaria, Edmundo Gonz\u00e1lez Urrutia, y el presidente Nicol\u00e1s Maduro, quien va por su tercer mandato. Es la tercera vez que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457423"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457423\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}