{"id":1457430,"date":"2025-01-10T12:03:49","date_gmt":"2025-01-10T20:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/"},"modified":"2025-01-10T12:03:49","modified_gmt":"2025-01-10T20:03:49","slug":"que-es-la-uma-multas-impuestos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","title":{"rendered":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?"},"content":{"rendered":"<p>En M\u00e9xico existe un valor econ\u00f3mico que sirve como medida o referencia econ\u00f3mica para el pago de obligaciones y derechos establecidos en las leyes mexicanas, la Unidad de Medida y Actualizaci\u00f3n (UMA).<\/p>\n<p>La UMA fue creada en 2016 para sustituir al salario m\u00ednimo como referencia en el c\u00e1lculo de obligaciones legales, multas o impuestos, y as\u00ed evitar que los aumentos al salario m\u00ednimo generen aumentos a todos los montos que estaban indexados a \u00e9ste, como los cr\u00e9ditos hipotecarios, las pensiones, multas y cuotas.<\/p>\n<p>El valor de la UMA se actualiza cada a\u00f1o. Para 2025, la UMA diaria tendr\u00e1 un valor de $113,14 pesos mexicanos (US$5,48), entrar\u00e1 en vigor a partir del 1 de febrero de 2025 y estar\u00e1 vigente hasta el 31 de enero de 2026, inform\u00f3 el Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), organismo encargado de su c\u00e1lculo.<\/p>\n<p>Este a\u00f1o, la variaci\u00f3n de la UMA ser\u00e1 de 4,21%, en comparaci\u00f3n a 2024, cuyo valor fue de 108,57 pesos diarios (US$5,26).<\/p>\n<p>De acuerdo con el INEGI, se puede calcular el valor mensual de la UMA multiplicando su valor diario por 30,4 veces. Para 2025, la UMA mensual ser\u00e1 de 3.439,46 pesos mexicanos (US$166.53). El valor anual se obtiene multiplicando su valor mensual por 12, y ser\u00e1 de $41.273,52 pesos mexicanos (US$1.998,32).<\/p>\n<p>La UMA se usa para determinar el monto de multas, pagos y sanciones econ\u00f3micas, por lo que cada a\u00f1o el monto de \u00e9stas aumenta.<\/p>\n<p>Por ejemplo, la multa por insultar a un polic\u00eda de tr\u00e1nsito en Ciudad de M\u00e9xico va de las 20 a las 30 veces la UMA vigente. Aunque el valor de veces no cambia en la ley, s\u00ed el monto de esta, por lo que una multa en 2024 era m\u00e1s barata que si se calcula a partir del 1 de febrero.<\/p>\n<p>Un ciudadano estar\u00eda pagando en 2025 entre 2.262 (US$109,21) y 3.771 pesos mexicanos (US$182,06).<\/p>\n<p>Tambi\u00e9n se utiliza para el pago de impuestos como el predial, Impuesto Sobre la Renta (ISR), y para calcular el valor de cr\u00e9ditos hipotecarios del INFONAVIT y Fovissste, para evitar aumentos desmedidos con la inflaci\u00f3n, as\u00ed como pensiones y jubilaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En M\u00e9xico existe un valor econ\u00f3mico que sirve como medida o referencia econ\u00f3mica para el pago de obligaciones y derechos establecidos en las leyes mexicanas, la Unidad de Medida y Actualizaci\u00f3n (UMA). La UMA fue creada en 2016 para sustituir al salario m\u00ednimo como referencia en el c\u00e1lculo de obligaciones legales, multas o impuestos, y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457430","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias\" \/>\n<meta property=\"og:description\" content=\"En M\u00e9xico existe un valor econ\u00f3mico que sirve como medida o referencia econ\u00f3mica para el pago de obligaciones y derechos establecidos en las leyes mexicanas, la Unidad de Medida y Actualizaci\u00f3n (UMA). La UMA fue creada en 2016 para sustituir al salario m\u00ednimo como referencia en el c\u00e1lculo de obligaciones legales, multas o impuestos, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-10T20:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?\",\"datePublished\":\"2025-01-10T20:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\"},\"wordCount\":386,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\",\"name\":\"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-10T20:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias","og_description":"En M\u00e9xico existe un valor econ\u00f3mico que sirve como medida o referencia econ\u00f3mica para el pago de obligaciones y derechos establecidos en las leyes mexicanas, la Unidad de Medida y Actualizaci\u00f3n (UMA). La UMA fue creada en 2016 para sustituir al salario m\u00ednimo como referencia en el c\u00e1lculo de obligaciones legales, multas o impuestos, y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-10T20:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?","datePublished":"2025-01-10T20:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/"},"wordCount":386,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","name":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-10T20:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es la UMA y c\u00f3mo impacta en multas e impuestos de M\u00e9xico en 2025?","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/10\/que-es-la-uma-multas-impuestos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-10T20:03:49Z","datePublished":"2025-01-10T20:03:49Z","dateModified":"2025-01-10T20:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es la UMA y c\\u00f3mo impacta en multas e impuestos de M\\u00e9xico en 2025?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/10\\\/que-es-la-uma-multas-impuestos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/10\\\/que-es-la-uma-multas-impuestos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-10T20:03:49Z\",\"datePublished\":\"2025-01-10T20:03:49Z\",\"dateModified\":\"2025-01-10T20:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465049,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/08\/01\/que-caro-aumentos-aranceles-trump-trax\/","url_meta":{"origin":1457430,"position":0},"title":"Esto es lo que podr\u00eda ser m\u00e1s caro debido a los enormes aumentos de aranceles de Trump","author":"","date":"agosto 1, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, ha dicho que los aranceles no conducir\u00e1n a precios m\u00e1s altos. Pero la econom\u00eda de EE.UU. parece estar en desacuerdo: la inflaci\u00f3n, que se ha mantenido bastante moderada, est\u00e1 aumentando lentamente debido a los aranceles.La m\u00e1s reciente ronda de aumentos de impuestos a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443009,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/01\/01\/desde-prohibiciones-de-cuidados-para-afirmacion-de-genero-hasta-aumentos-al-salario-minimo-estas-nuevas-leyes-entraran-en-vigor-el-1-de-enero-en-ee-uu\/","url_meta":{"origin":1457430,"position":1},"title":"Desde prohibiciones de cuidados para afirmaci\u00f3n de g\u00e9nero hasta aumentos al salario m\u00ednimo, estas nuevas leyes entrar\u00e1n en vigor el 1 de enero en EE.UU.","author":"","date":"enero 1, 2024","format":false,"excerpt":"(CNN) -- Varios estados de EE.UU. presenciaron una sesi\u00f3n legislativa polarizada el a\u00f1o pasado cuando los legisladores abordaron medidas de alto perfil, algunas de las cuales entrar\u00e1n en vigor este a\u00f1o.Si bien muchos estados liderados por dem\u00f3cratas y republicanos aprobaron medidas para aliviar los efectos de la inflaci\u00f3n, ya que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457405,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/realidad-detras-promesa-trump-impuestos-propinas-trax\/","url_meta":{"origin":1457430,"position":2},"title":"La dura realidad detr\u00e1s de la promesa de Trump de reducir los impuestos a las propinas","author":"","date":"enero 9, 2025","format":false,"excerpt":"Cindy Kramer, de 38 a\u00f1os, trabaja m\u00e1s de 60 horas a la semana y hace malabares con cuatro empleos diferentes en Staten Island, Nueva York, para mantener a su hijo y llegar a fin de mes. Trabaja atendiendo bares en dos de ellos.Al igual que muchos en la industria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447610,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/04\/01\/calendario-declaracion-impuestos-anual-sat-2024-mexico-fechas-limites-orix\/","url_meta":{"origin":1457430,"position":3},"title":"Calendario de la declaraci\u00f3n anual ante el SAT 2024 en M\u00e9xico: fechas y l\u00edmites","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La mayor\u00eda de las personas que reciben un ingreso por una actividad econ\u00f3mica en M\u00e9xico debe presentar su declaraci\u00f3n anual de impuestos\u00a0 del ejercicio 2023 ante el Servicio de Administraci\u00f3n Tributaria (SAT) a partir del 1 de abril de 2024.Tu declaraci\u00f3n anual debe incluir la informaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470520,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/01\/27\/como-presentar-declaracion-impuestos-ee-uu-orix\/","url_meta":{"origin":1457430,"position":4},"title":"C\u00f3mo presentar tu declaraci\u00f3n de impuestos en EE.UU. en 2026: link, formularios, documentos y m\u00e1s","author":"","date":"enero 27, 2026","format":false,"excerpt":"Si pagas a alguien para que prepare tu declaraci\u00f3n de impuestos, puedes ahorrarte ese gasto y hacerlo t\u00fa mismo con las herramientas gratuitas del Servicio de Impuestos Internos (IRS, por sus siglas en ingl\u00e9s). Adem\u00e1s, si lo haces en l\u00ednea, evitar\u00e1s demoras en los reembolsos.El IRS abri\u00f3 la temporada de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456882,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/12\/23\/salario-minimo-2025-orix\/","url_meta":{"origin":1457430,"position":5},"title":"No hubo acuerdo sobre el salario m\u00ednimo 2025 en Argentina y el Gobierno deber\u00e1 definirlo","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Luego de una reuni\u00f3n del Consejo del Salario en la Argentina con el objetivo de actualizar el Salario M\u00ednimo, Vital y M\u00f3vil (SMVyM), las partes no lograron llegar a un acuerdo y ahora ser\u00e1 el Gobierno el encargado de definir el monto para los pr\u00f3ximos meses, seg\u00fan inform\u00f3 el viernes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457430"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457430\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}