{"id":1457448,"date":"2025-01-11T04:03:46","date_gmt":"2025-01-11T12:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/"},"modified":"2025-01-11T04:03:46","modified_gmt":"2025-01-11T12:03:46","slug":"libano-aoun-presidente-impulso-saudi-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","title":{"rendered":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed"},"content":{"rendered":"<p>Fue un empuj\u00f3n de \u00faltima hora de Arabia Saudita lo que decidi\u00f3 el destino de L\u00edbano este jueves.<\/p>\n<p>Faltaban menos de 24 horas para que el Parlamento eligiera al pr\u00f3ximo presidente. Pero el accidentado panorama pol\u00edtico liban\u00e9s estaba totalmente desorganizado.<\/p>\n<p>La \u00e9lite pol\u00edtica sectaria parec\u00eda atascada en la mesa de dibujo. En L\u00edbano, los presidentes llegan al poder casi por consenso pol\u00edtico, pero m\u00e1s de seis aspirantes segu\u00edan en juego. Los debates fueron acalorados y el jefe del Ej\u00e9rcito, Joseph Aoun, fue tachado por muchos pol\u00edticos de no estar constitucionalmente cualificado para la presidencia debido a su cargo militar.<\/p>\n<p>Parec\u00eda que el Parlamento se encaminaba a su 13\u00ba intento fallido de elegir presidente en m\u00e1s de dos a\u00f1os.<\/p>\n<p>Entonces, una delegaci\u00f3n saud\u00ed encabezada por el enviado del reino, el pr\u00edncipe Yazid bin Farhan, vol\u00f3 a Beirut por segunda vez en una semana. Celebr\u00f3 una serie de reuniones con diversos partidos pol\u00edticos. Cuando se marcharon, solo quedaba un candidato: Aoun, respaldado por Estados Unidos.<\/p>\n<p>Noventa y nueve legisladores votaron a favor de Aoun, superando el requisito de dos tercios del Parlamento. Las 29 papeletas restantes estaban en su mayor\u00eda en blanco o descalificadas (uno de los legisladores vot\u00f3 por \u201cBernie Sanders\u201d, el senador estadounidense por Vermont).<\/p>\n<p>A los pocos minutos, Aoun lleg\u00f3 al Parlamento, tras cambiar su uniforme militar por un traje y corbata. Prest\u00f3 juramento y pronunci\u00f3 un discurso demoledor, aparentemente bien ensayado, prometiendo marcar el comienzo de la \u201cnueva era\u201d del L\u00edbano y monopolizar las armas bajo la \u00e9gida del Estado. En otras palabras, Hezbollah, uno de los grupos militantes mejor armados del mundo durante la mayor parte de los \u00faltimos 40 a\u00f1os, iba a ser desarmado.<\/p>\n<p>Las calles se llenaron de j\u00fabilo. Se hab\u00eda llenado un vac\u00edo presidencial. Se hab\u00eda roto, al menos de momento, un estancamiento de a\u00f1os entre las \u00e9lites confesionales.<\/p>\n<p>Sin embargo, este acontecimiento plante\u00f3 interrogantes de mayor envergadura. \u00bfPor qu\u00e9 Arabia Saudita hab\u00eda gastado tanto capital diplom\u00e1tico para que hubiese un presidente, poniendo fin a casi ocho a\u00f1os de desentendimiento del L\u00edbano, al que daba por \u201cperdido\u201d ante el dominio iran\u00ed a trav\u00e9s de Hezbollah?<\/p>\n<p>Tambi\u00e9n es significativo otro factor que desbloque\u00f3 la designaci\u00f3n de Joseph Aoun como presidente del L\u00edbano: Hezbollah y sus aliados del partido Amal votaron por \u00e9l.<\/p>\n<p>Fue un asunto muy coreografiado. Hezbollah y Amal, conocidos como el d\u00fao chi\u00ed, votaron en blanco en la primera ronda de votaciones, de la que no sali\u00f3 ning\u00fan presidente. Durante un receso de dos horas, los jefes de sus respectivos bloques parlamentarios mantuvieron una reuni\u00f3n con Aoun, cuyos detalles se desconocen. Tras regresar al parlamento, votaron por Aoun, rompiendo el bloqueo y abriendo el camino a la presidencia.<\/p>\n<p>El mensaje era claro. Puede que Hezbollah se haya visto gravemente debilitado por su guerra con Israel en oto\u00f1o y por el reciente derrocamiento de su aliado clave, el presidente de Siria, Bashar al-Assad, pero a\u00fan pod\u00eda prolongar el estancamiento o acabar con \u00e9l.<\/p>\n<p>Sin embargo, \u00bfpor qu\u00e9 hab\u00edan votado a un presidente con el mandato de desarmarlos?<\/p>\n<p>No est\u00e1 claro qu\u00e9 ocurri\u00f3 durante las reuniones en las que Arabia Saudita consigui\u00f3 un apoyo abrumador para Aoun. Pero fue un esfuerzo en toda regla que coincidi\u00f3 con las conversaciones diplom\u00e1ticas occidentales. El enviado especial de Francia en el L\u00edbano, Jean-Yves Le Drian, tambi\u00e9n se hab\u00eda reunido con legisladores de Hezbollah.<\/p>\n<p>Francia es uno de los pocos pa\u00edses occidentales que no tiene una designaci\u00f3n terrorista generalizada sobre Hezbollah, manteniendo un canal diplom\u00e1tico con el brazo pol\u00edtico del grupo militante. Es uno de los \u00fanicos v\u00ednculos que quedan entre Occidente y el grupo respaldado por Ir\u00e1n.<\/p>\n<p>A principios de esta semana, el enviado especial de Estados Unidos en el L\u00edbano, Amos Hochstein, tambi\u00e9n contribuy\u00f3 a reforzar las posibilidades de Aoun con una serie de reuniones.<\/p>\n<p>Todo esto no pas\u00f3 desapercibido para los legisladores libaneses. \u201cNo estamos aqu\u00ed para elegir a un presidente\u201d, declar\u00f3 el martes el diputado independiente Jamil el-Sayyed a la cadena de televisi\u00f3n local Al-Jadeed desde el Parlamento. \u201cEstamos aqu\u00ed para certificar el nombramiento de un presidente\u201d.<\/p>\n<p>En declaraciones antes de la votaci\u00f3n, el legislador antisistema Halime El Kaakour se\u00f1al\u00f3 a la tribuna superior, donde se sentaban dignatarios extranjeros, entre ellos los embajadores de Estados Unidos, Francia, Egipto e Ir\u00e1n. \u201cNadie debe imponernos su voluntad, ni la tutela de los iran\u00edes, ni la de los sirios, ni la de los estadounidenses. No debemos sustituir una tutela (externa) por otra\u201d, dijo.<\/p>\n<p>\u201cNadie debe interferir en nuestros asuntos internos, con todo mi respeto a los embajadores aqu\u00ed presentes\u201d, prosigui\u00f3. \u201cApoyamos la cooperaci\u00f3n internacional\u2026 pero nadie debe interferir en nuestra soberan\u00eda\u201d.<\/p>\n<p>El predecesor de Aoun es el expresidente Michel Aoun, respaldado por Hezbollah (ambos no est\u00e1n emparentados). Su mandato, que finaliz\u00f3 hace m\u00e1s de dos a\u00f1os, se consider\u00f3 una \u00e9poca de dominio iran\u00ed en L\u00edbano, que vio un aumento sin precedentes del poder pol\u00edtico de Hezbollah. Ese cambio en el respaldo exterior entre los dos presidentes Aoun supone un cambio s\u00edsmico para el pa\u00eds.<\/p>\n<p>Sin embargo, Hezbollah parece estar afrontando este momento con una silenciosa y misteriosa resignaci\u00f3n. En declaraciones a los periodistas tras la elecci\u00f3n de Aoun, el l\u00edder del bloque parlamentario de Hezbollah, Mohammad Raad, dijo que hab\u00edan votado por \u00e9l para promover el \u201centendimiento nacional\u201d.<\/p>\n<p>No votaron en la primera vuelta, a\u00f1adi\u00f3 ambiguamente, porque \u201cquer\u00edan enviar un mensaje\u2026 de que somos protectores de la soberan\u00eda\u201d.<\/p>\n<p>La ambig\u00fcedad estrat\u00e9gica puede ser su mejor baza en este momento crucial. El grupo militante recibi\u00f3 una r\u00e1pida sucesi\u00f3n de golpes durante la guerra de dos meses con Israel en oto\u00f1o, incluida la muerte de su l\u00edder de toda la vida, Hassan Nasrallah. El derrocamiento de Assad, que hab\u00eda abierto su territorio a las l\u00edneas de suministro del grupo con Ir\u00e1n, limit\u00f3 seriamente su capacidad de rearme.<\/p>\n<p>El grupo tambi\u00e9n acord\u00f3 retirar a sus combatientes del sur de L\u00edbano, su base de poder durante cuatro d\u00e9cadas y su principal campo de batalla con Israel, que ocup\u00f3 la zona de 1978 a 2000, y que sigue siendo considerado un Estado enemigo por L\u00edbano.<\/p>\n<p>Sin embargo, el desarme dista mucho de ser completo. Se cree que Hezbollah a\u00fan posee misiles de medio y largo alcance, y sigue contando con una amplia base de apoyo chi\u00ed. Esto significa que es probable que se prolonguen las negociaciones sobre sus armas, en las que sin duda intervendr\u00e1n fuerzas externas.<\/p>\n<p>Tambi\u00e9n ser\u00e1 una prueba para el acercamiento de casi dos a\u00f1os entre Riad y Teher\u00e1n. En el plano interno, el reci\u00e9n estrenado presidente liban\u00e9s deber\u00e1 supervisar este proceso y, al mismo tiempo, evitar el estallido de enfrentamientos civiles, algo que insinu\u00f3 en su discurso de investidura cuando prometi\u00f3 impedir que las facciones del pa\u00eds intentaran \u201cromperse la cabeza unas a otras\u201d.<\/p>\n<p>Mientras tanto, las fuerzas israel\u00edes siguen operando en algunas partes del sur de L\u00edbano. El Gobierno de Israel amenaz\u00f3 con mantener all\u00ed a los militares m\u00e1s all\u00e1 de la fecha l\u00edmite, a finales de este mes, estipulada en el acuerdo de alto el fuego mediado por Estados Unidos que puso fin a la guerra a finales de noviembre.<\/p>\n<p>Aoun ha prometido forzar su retirada, una responsabilidad que, seg\u00fan \u00e9l, recaer\u00eda exclusivamente en el Estado.<\/p>\n<p>Estas son aguas desconocidas para el peque\u00f1o y conflictivo pa\u00eds del Mediterr\u00e1neo oriental. Pero para muchos hay motivos para el optimismo.<\/p>\n<p>\u201cL\u00edbano tiene por fin un presidente que aporta al pueblo liban\u00e9s y a la comunidad internacional un liderazgo humano y la legitimidad de un Estado\u201d, afirm\u00f3 Lynn Zovighian, columnista, fil\u00e1ntropa y fundadora de la plataforma de inversi\u00f3n social Zovighian Partnership.<\/p>\n<p>\u201cHa llegado la hora del liderazgo, el orden constitucional, el fortalecimiento del Estado y la humanizaci\u00f3n para que por fin podamos alcanzar la prosperidad socioecon\u00f3mica, la justicia y la rendici\u00f3n de cuentas\u201d, declar\u00f3 Zovighian a CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue un empuj\u00f3n de \u00faltima hora de Arabia Saudita lo que decidi\u00f3 el destino de L\u00edbano este jueves. Faltaban menos de 24 horas para que el Parlamento eligiera al pr\u00f3ximo presidente. Pero el accidentado panorama pol\u00edtico liban\u00e9s estaba totalmente desorganizado. La \u00e9lite pol\u00edtica sectaria parec\u00eda atascada en la mesa de dibujo. En L\u00edbano, los presidentes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457448","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias\" \/>\n<meta property=\"og:description\" content=\"Fue un empuj\u00f3n de \u00faltima hora de Arabia Saudita lo que decidi\u00f3 el destino de L\u00edbano este jueves. Faltaban menos de 24 horas para que el Parlamento eligiera al pr\u00f3ximo presidente. Pero el accidentado panorama pol\u00edtico liban\u00e9s estaba totalmente desorganizado. La \u00e9lite pol\u00edtica sectaria parec\u00eda atascada en la mesa de dibujo. En L\u00edbano, los presidentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-11T12:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed\",\"datePublished\":\"2025-01-11T12:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\"},\"wordCount\":1430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\",\"name\":\"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-11T12:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias","og_description":"Fue un empuj\u00f3n de \u00faltima hora de Arabia Saudita lo que decidi\u00f3 el destino de L\u00edbano este jueves. Faltaban menos de 24 horas para que el Parlamento eligiera al pr\u00f3ximo presidente. Pero el accidentado panorama pol\u00edtico liban\u00e9s estaba totalmente desorganizado. La \u00e9lite pol\u00edtica sectaria parec\u00eda atascada en la mesa de dibujo. En L\u00edbano, los presidentes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-11T12:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed","datePublished":"2025-01-11T12:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/"},"wordCount":1430,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","name":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-11T12:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\u00f3n de un nuevo presidente en L\u00edbano, con un impulso saud\u00ed","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/11\/libano-aoun-presidente-impulso-saudi-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-11T12:03:46Z","datePublished":"2025-01-11T12:03:46Z","dateModified":"2025-01-11T12:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Momento decisivo para Medio Oriente tras la elecci\\u00f3n de un nuevo presidente en L\\u00edbano, con un impulso saud\\u00ed\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/11\\\/libano-aoun-presidente-impulso-saudi-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/11\\\/libano-aoun-presidente-impulso-saudi-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-11T12:03:46Z\",\"datePublished\":\"2025-01-11T12:03:46Z\",\"dateModified\":\"2025-01-11T12:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457399,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/09\/joseph-aoun-presidente-libano-trax\/","url_meta":{"origin":1457448,"position":0},"title":"Eligen al jefe del Ej\u00e9rcito liban\u00e9s, que cuenta con el respaldo de EE.UU., como presidente del L\u00edbano","author":"","date":"enero 9, 2025","format":false,"excerpt":"El parlamento del L\u00edbano eligi\u00f3 al jefe del Ej\u00e9rcito \u2013que cuenta con el respaldado de Estados Unidos\u2013 como nuevo presidente del pa\u00eds, poniendo fin a un estancamiento pol\u00edtico de varios a\u00f1os y a un vac\u00edo presidencial.Joseph Aoun fue elegido presidente despu\u00e9s de dos rondas de votaci\u00f3n. Esto se produjo despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473030,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/04\/10\/que-implica-alto-el-fuego-iran-trax\/","url_meta":{"origin":1457448,"position":1},"title":"\u00bfQu\u00e9 implica el alto el fuego en la guerra con Ir\u00e1n? Ni siquiera en eso logran ponerse de acuerdo","author":"","date":"abril 10, 2026","format":false,"excerpt":"Las conversaciones de este fin de semana para poner fin a la guerra con Ir\u00e1n son de las negociaciones m\u00e1s cruciales, no solo de la presidencia de Donald Trump, sino de la historia reciente de Estados Unidos.Sin embargo, existe un gran problema: Estados Unidos ni siquiera logra ponerse de acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466671,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/21\/cinco-estadounidenses-tres-ninos-murieron-ataque-israeli-libano-trax\/","url_meta":{"origin":1457448,"position":2},"title":"Cinco ciudadanos estadounidenses, incluidos tres ni\u00f1os, murieron en un ataque israel\u00ed en L\u00edbano, seg\u00fan el Gobierno liban\u00e9s","author":"","date":"septiembre 21, 2025","format":false,"excerpt":"Cinco personas murieron, incluidos tres ni\u00f1os, en un ataque a\u00e9reo israel\u00ed en el sur de L\u00edbano este domingo, seg\u00fan el Gobierno liban\u00e9s.Las v\u00edctimas eran una familia con ciudadan\u00eda estadounidense, seg\u00fan el presidente del Parlamento, Nabih Berri, en un comunicado en el que lament\u00f3 la muerte de la madre, el padre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473023,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/04\/10\/mundo-espera-ansiedad-conversaciones-paz-ee-uu-iran-trax\/","url_meta":{"origin":1457448,"position":3},"title":"El mundo espera con ansiedad para ver si las conversaciones de paz entre EE.UU. e Ir\u00e1n dan resultado. Esta es la situaci\u00f3n","author":"","date":"abril 10, 2026","format":false,"excerpt":"La vida de millones de personas en todo Medio Oriente, y el destino de la econom\u00eda mundial, depender\u00e1n del resultado de las cruciales conversaciones que mantendr\u00e1n este fin de semana Estados Unidos e Ir\u00e1n en Pakist\u00e1n.Las calles de la capital, Islamabad, han quedado desiertas debido a un repentino feriado p\u00fablico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473292,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/04\/17\/alto-fuego-libano-trump-netanyahu-trax\/","url_meta":{"origin":1457448,"position":4},"title":"Con el alto el fuego en L\u00edbano, Trump ha impuesto otra decisi\u00f3n a Netanyahu, una vez m\u00e1s","author":"","date":"abril 17, 2026","format":false,"excerpt":"La llamada que predijo el presidente Donald Trump no se produjo, pero dej\u00f3 pocas dudas sobre lo que vendr\u00eda despu\u00e9s.El jueves por la ma\u00f1ana, Trump anunci\u00f3 que el primer ministro de Israel, Benjamin Netanyahu, hablar\u00eda con el presidente del L\u00edbano, Joseph Aoun.Este habr\u00eda sido el primer contacto directo en d\u00e9cadas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467189,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/10\/07\/papa-leon-xiv-viaje-turquia-libano-trax\/","url_meta":{"origin":1457448,"position":5},"title":"El papa Le\u00f3n XIV viajar\u00e1 a Turqu\u00eda y al L\u00edbano en su primera gira internacional","author":"","date":"octubre 7, 2025","format":false,"excerpt":"El papa Le\u00f3n XIV realizar\u00e1 su primer viaje internacional con una visita Turqu\u00eda y al L\u00edbano, donde se espera que enfoque su mensaje en la paz en Medio Oriente, se re\u00fana con l\u00edderes pol\u00edticos y muestre su apoyo a los cristianos de la regi\u00f3n.El primer papa estadounidense viajar\u00e1 a Turqu\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457448"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457448\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}