{"id":1457499,"date":"2025-01-14T04:03:50","date_gmt":"2025-01-14T12:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/"},"modified":"2025-01-14T04:03:50","modified_gmt":"2025-01-14T12:03:50","slug":"5-cosas-14-enero-maduro-trump-ley-laken-riley-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o"},"content":{"rendered":"<p>Se abre una nueva etapa de la relaci\u00f3n (o tensi\u00f3n) entre Maduro y Trump. \u00bfQu\u00e9 es la Ley Laken Riley? Los mapas que muestran el alcance de los incendios en Los \u00c1ngeles. <em>Esto es lo que debes saber para comenzar el d\u00eda.<\/em><strong> Primero la verdad.<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.cnn.com\/newsletters\/5-cosas\">Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/a><\/li>\n<li><a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/5-cosas\">\ud83c\udf99 Escucha las 5 cosas de CNN<\/a><\/li>\n<\/ul>\n<p>Tras la toma de posesi\u00f3n de Nicol\u00e1s Maduro para un tercer mandato en un contexto plagado de controversia \u2014debido a que el Gobierno nunca present\u00f3 las actas detalladas que respaldan su victoria electoral\u2014, se espera ahora la juramentaci\u00f3n de Donald Trump, quien asumir\u00e1 la presidencia de Estados Unidos con una diferencia de apenas d\u00edas, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/latinoamerica\/vinculo-maduro-trump-que-esperar-orix\">abriendo un nuevo periodo en las relaciones entre ambos pa\u00edses<\/a>. Mientras que algunos expertos consideran que Trump sostendr\u00e1 su pol\u00edtica de m\u00e1xima presi\u00f3n hacia Venezuela, otros esperan un segundo mandato con un foco m\u00e1s pragm\u00e1tico, en el que se busque alg\u00fan tipo de acuerdo con el Gobierno de Venezuela.<\/p>\n<ul>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/venezuela\/reabre-frontera-colombia-efe\">Venezuela reabre la frontera con Colombia<\/a><\/li>\n<\/ul>\n<p>El proyecto de la Ley Laken Riley en EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/estados-unidos\/que-es-ley-laken-riley-estados-inmigracion-detener-migrantes-trax\">pretende dar m\u00e1s poder a funcionarios estatales antiinmigraci\u00f3n y jueces federales para hacer cumplir las leyes de inmigraci\u00f3n<\/a>, incluida la posibilidad de detener a migrantes individuales. Este proyecto de ley del Partido Republicano fue aprobado en la C\u00e1mara de Representantes de EE.UU. y avanza en el Senado con apoyo bipartidista. Es probable que los republicanos necesiten los votos de siete dem\u00f3cratas para la aprobaci\u00f3n final.<\/p>\n<p>Hamas est\u00e1 \u201cmuy cerca de un acuerdo\u201d con Israel para un alto el fuego en Gaza y el intercambio de rehenes por prisioneros palestinos, seg\u00fan un funcionario del grupo. El ministro de Asuntos Exteriores israel\u00ed, Gideon Saar, dijo este lunes que hab\u00eda habido avances en las negociaciones. Sin embargo, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mundo\/hamas-cerca-acuerdo-israel-persiste-conflicto-puntos-clave-trax\">a\u00fan quedan varios puntos conflictivos en las negociaciones en curso en Doha<\/a>, la capital de Qatar, dijo a CNN el funcionario de Hamas.<\/p>\n<ul>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mundo\/hamas-libere-33-rehenes-acuerdo-funcionario-israeli-trax\">Se espera que Hamas libere a 33 rehenes en la primera fase de un acuerdo emergente, dice funcionario israel\u00ed<\/a><\/li>\n<\/ul>\n<p>El Kremlin dijo que si bien existe voluntad pol\u00edtica para una reuni\u00f3n entre el presidente de Rusia, Vladimir Putin, y el presidente electo de Estados Unidos, Donald Trump, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mundo\/putin-esta-listo-para-hablar-con-trump-pero-aun-no-hay-planes-en-marcha-dice-el-kremlin\">no se han iniciado preparativos sustanciales para una cumbre<\/a>.<\/p>\n<p>Una serie de incendios amenazantes, el mayor de ellos en Pacific Palisades, est\u00e1n destruyendo hogares mientras avanzan r\u00e1pidamente por el condado de Los \u00c1ngeles y \u00e1reas circundantes. CNN est\u00e1 monitoreando los incendios a trav\u00e9s de mapas y gr\u00e1ficos. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/08\/estados-unidos\/incendios-forestales-los-angeles-mapas-graficos-trax\">Aqu\u00ed tienes un vistazo al mapa m\u00e1s reciente del incendio Palisades<\/a>, el cual se actualizar\u00e1 autom\u00e1ticamente a medida que haya nuevos datos disponibles.<\/p>\n<ul>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/estados-unidos\/incendios-forestales-los-angeles-cuando-terminaran-trax\">\u00bfCu\u00e1ndo terminar\u00e1n los incendios en Los \u00c1ngeles? Esto es lo que sabemos<\/a><\/li>\n<\/ul>\n<p><strong>Blue Origin cancela otra vez el lanzamiento de su primer cohete orbital<\/strong><\/p>\n<p>El lanzamiento del cohete New Glenn estaba previsto para temprano el lunes, pero la compa\u00f1\u00eda cancel\u00f3 ese plan. Este lunes por la noche, despu\u00e9s de aproximadamente 16 horas sin actualizaciones y sin informaci\u00f3n sobre cu\u00e1l era exactamente el problema, Blue Origin recurri\u00f3 a las redes sociales para declarar que podr\u00eda hacer un segundo intento la madrugada de este martes. Sin embargo, solo un par de horas despu\u00e9s, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/ciencia\/blue-origin-jeff-bezos-lanza-primer-cohete-orbital-trax\">Blue Origin revel\u00f3 que no intentar\u00eda el despegue nocturno despu\u00e9s de todo<\/a>.<\/p>\n<p><strong>Rusia crea un grupo de trabajo de emergencia ante la propagaci\u00f3n del derrame de petr\u00f3leo <\/strong><\/p>\n<p>Un equipo de emergencia lleg\u00f3 el domingo a la regi\u00f3n sure\u00f1a rusa de Krasnodar mientras un derrame de petr\u00f3leo en el estrecho de Kerch <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mundo\/rusia-grupo-trabajo-emergencia-derrame-petroleo-trax\">proveniente de dos petroleros afectados por una tormenta contin\u00faa propag\u00e1ndose un mes despu\u00e9s<\/a> de que fue detectado por primera vez, dijeron funcionarios.<\/p>\n<p><strong>Brasil restringe el uso de tel\u00e9fonos inteligentes en escuelas primarias y secundarias<\/strong><\/p>\n<p>El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, firm\u00f3 este lunes un proyecto de ley que restringe el uso de tel\u00e9fonos inteligentes en las escuelas, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/latinoamerica\/brasil-restringe-telefonos-inteligentes-escuelas-ap\">siguiendo una tendencia global hacia tales limitaciones<\/a>.<\/p>\n<p><strong>Activistas pintan la tumba de Charles Darwin con una advertencia medioambiental <\/strong><\/p>\n<p>Activistas ambientales en el Reino Unido pintaron este lunes la tumba de Charles Darwin con una frase <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mundo\/vandalizan-tumba-charles-darwin-activistas-just-stop-oil-trax\">en referencia al umbral clim\u00e1tico cr\u00edtico que el mundo super\u00f3 temporalmente en 2024<\/a>.<\/p>\n<p><strong>10 personas<\/strong><\/p>\n<p>La oficina del fiscal del distrito de Los \u00c1ngeles present\u00f3 cargos contra 10 personas en relaci\u00f3n con delitos cometidos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/incendios-los-angeles-california-en-vivo-ultima-hora-noticias-trax\/#liveblog-db218f92-15b2-455c-96c3-ca846ac861de\">durante los incendios forestales en el condado<\/a>.<\/p>\n<p><strong>\u201cVenezuela se prepara por si alg\u00fan d\u00eda hay que tomar las armas\u201d<\/strong><\/p>\n<p>Venezuela cumple los primeros d\u00edas del nuevo mandato de Nicol\u00e1s Maduro. Esta situaci\u00f3n est\u00e1 rodeada de cuestionamientos al no haberse presentado las pruebas desglosadas del resultado electoral. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/12\/venezuela\/video\/venezuela-dos-dias-de-mandato-nicolas-maduro-mirador-mundial-tv\">Este fue el mensaje que env\u00edo Maduro en la cumbre del antifascismo.<\/a><\/p>\n<p><strong>Los volcanes Popocat\u00e9petl e Iztacc\u00edhuatl regalan hermosas im\u00e1genes invernales<\/strong><\/p>\n<p>La nieve, que se extendi\u00f3 por las laderas de ambos volcanes, cre\u00f3 un paisaje invernal impresionante. El Popocat\u00e9petl mostr\u00f3 su imponente silueta cubierta de blanco, mientras que el Iztacc\u00edhuatl, con sus cuatro picos, parec\u00eda una gigantesca estatua de hielo. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/13\/mexico\/video\/postales-invernales-popocatepetl-iztaccihuatl-fotos-viral-perspectivas-mexico-tv\">La nieve en estos volcanes es com\u00fan durante los meses de invierno y siempre es un espect\u00e1culo<\/a>. Cabe recordar que la subida a los volcanes puede ser peligrosa y requiere experiencia y equipo adecuado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se abre una nueva etapa de la relaci\u00f3n (o tensi\u00f3n) entre Maduro y Trump. \u00bfQu\u00e9 es la Ley Laken Riley? Los mapas que muestran el alcance de los incendios en Los \u00c1ngeles. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457499","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se abre una nueva etapa de la relaci\u00f3n (o tensi\u00f3n) entre Maduro y Trump. \u00bfQu\u00e9 es la Ley Laken Riley? Los mapas que muestran el alcance de los incendios en Los \u00c1ngeles. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T12:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o\",\"datePublished\":\"2025-01-14T12:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\"},\"wordCount\":949,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\",\"name\":\"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-14T12:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias","og_description":"Se abre una nueva etapa de la relaci\u00f3n (o tensi\u00f3n) entre Maduro y Trump. \u00bfQu\u00e9 es la Ley Laken Riley? Los mapas que muestran el alcance de los incendios en Los \u00c1ngeles. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-14T12:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o","datePublished":"2025-01-14T12:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/"},"wordCount":949,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","name":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-14T12:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\u00f1o","url":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/01\/14\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-14T12:03:50Z","datePublished":"2025-01-14T12:03:50Z","dateModified":"2025-01-14T12:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 14 de enero 2025: Maduro y Trump, Ley Laken Riley, la primera luna llena del a\\u00f1o\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/14\\\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/01\\\/14\\\/5-cosas-14-enero-maduro-trump-ley-laken-riley-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-14T12:03:50Z\",\"datePublished\":\"2025-01-14T12:03:50Z\",\"dateModified\":\"2025-01-14T12:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455103,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/10\/15\/trump-inmigracion-comentarios-bill-clinton-laken-riley-trax\/","url_meta":{"origin":1457499,"position":0},"title":"La campa\u00f1a de Trump intenta aprovechar a su favor el tema de la inmigraci\u00f3n tras los comentarios de Bill Clinton sobre Laken Riley","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN) -- La campa\u00f1a del expresidente Donald Trump est\u00e1 tratando de utilizar en su favor el comentario del expresidente Bill Clinton el domingo de que la muerte de la estudiante de enfermer\u00eda de Georgia, Laken Riley, \"probablemente no habr\u00eda ocurrido\" si los migrantes, incluido su presunto asesino, hubieran sido \"debidamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457478,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/13\/que-es-ley-laken-riley-estados-inmigracion-detener-migrantes-trax\/","url_meta":{"origin":1457499,"position":1},"title":"\u00bfQu\u00e9 es la Ley Laken Riley? M\u00e1s poder a estados en inmigraci\u00f3n, ampliaci\u00f3n de causas de detenci\u00f3n y otros detalles","author":"","date":"enero 13, 2025","format":false,"excerpt":"El proyecto de la Ley Laken Riley pretende dar m\u00e1s poder a funcionarios estatales antiinmigraci\u00f3n y jueces federales para dictar la aplicaci\u00f3n de las leyes de inmigraci\u00f3n de Estados Unidos, incluida la posibilidad de detener a migrantes individuales.Este proyecto de ley del Partido Republicano fue aprobado en la C\u00e1mara de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457598,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/17\/ley-inmigracion-laken-riley-senado-votacion-trax\/","url_meta":{"origin":1457499,"position":2},"title":"La ley de inmigraci\u00f3n &#171;Laken Riley&#187; podr\u00eda ser aprobada en el Senado tras votaci\u00f3n clave","author":"","date":"enero 17, 2025","format":false,"excerpt":"Un proyecto de ley liderado por el Partido Republicano para exigir la detenci\u00f3n de inmigrantes indocumentados acusados de ciertos delitos est\u00e1 a punto de ser aprobado en el Senado despu\u00e9s de que un n\u00famero significativo de dem\u00f3cratas se unieran a los republicanos para avanzar en la medida en una votaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457316,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/07\/ley-inmigracion-laken-riley-futuro-senado-trax\/","url_meta":{"origin":1457499,"position":3},"title":"C\u00e1mara de Representantes aprueba ley de inmigraci\u00f3n &#171;Laken Riley&#187;, pero se enfrenta a un futuro incierto en el Senado","author":"","date":"enero 7, 2025","format":false,"excerpt":"La C\u00e1mara de Representantes vot\u00f3 el martes a favor de un proyecto de ley liderado por el Partido Republicano para exigir la detenci\u00f3n de inmigrantes indocumentados acusados de ciertos delitos, pero la medida enfrenta un futuro incierto en el Senado, en una se\u00f1al de los desaf\u00edos que enfrentan los republicanos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469789,"url":"https:\/\/noticiasya.com\/sacramento\/2026\/01\/05\/5-cosas-5-enero-orix\/","url_meta":{"origin":1457499,"position":4},"title":"Las 5 cosas que debes saber este 5 de enero: Delcy Rodr\u00edguez asume en Venezuela, Maduro ante un tribunal de EE.UU.","author":"","date":"enero 5, 2026","format":false,"excerpt":"Trump lanza advertencias a otros pa\u00edses de Am\u00e9rica Latina. Maduro har\u00e1 su primera aparici\u00f3n ante un tribunal en Nueva York. La oposici\u00f3n venezolana pide que se respeten los resultados de las elecciones de 2024. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455959,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/11\/20\/juez-sentencia-jose-ibarra-cadena-perpetua-asesinato-laken-riley-trax\/","url_meta":{"origin":1457499,"position":5},"title":"El juez sentencia a Jos\u00e9 Ibarra a cadena perpetua por el asesinato de Laken Riley","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) \u2014 El juez H. Patrick Haggard sentenci\u00f3 este mi\u00e9rcoles a Jos\u00e9 Ibarra a cadena perpetua sin posibilidad de libertad condicional por el asesinato de Laken Riley mientras corr\u00eda por el bosque en la Universidad de Georgia.Haggard determin\u00f3 que Ibarra era culpable de cada uno de los 10 cargos que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1457499"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1457499\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1457499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1457499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1457499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}