{"id":1466473,"date":"2025-09-15T09:03:41","date_gmt":"2025-09-15T16:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/"},"modified":"2025-09-15T09:03:41","modified_gmt":"2025-09-15T16:03:41","slug":"origen-independencia-septiembre-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/15\/origen-independencia-septiembre-orix\/","title":{"rendered":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810"},"content":{"rendered":"<p>M\u00e9xico celebra un a\u00f1o m\u00e1s de su independencia con el tradicional grito de Dolores, que marc\u00f3 el inicio de la guerra de independencia de la colonia espa\u00f1ola hace 215 a\u00f1os. Los mexicanos salen a las plazas p\u00fablicas y reviven lo que, seg\u00fan la historia oficial, ocurri\u00f3 la madrugada del 16 de septiembre cuando el cura Miguel Hidalgo y Costilla llam\u00f3 a los feligreses a levantarse en armas.<\/p>\n<p>Se trata de una celebraci\u00f3n nacional profundamente arraigada en el imaginario colectivo de la sociedad, pero \u00bfpor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Aqu\u00ed hacemos un breve repaso de los acontecimientos hist\u00f3ricos.<\/p>\n<p>Tradicionalmente, la celebraci\u00f3n de esta fiesta patria empieza el 15 de septiembre, cuando \u2014alrededor de las 23:00 horas\u2014 el presidente de la Rep\u00fablica da el Grito de Independencia desde Palacio Nacional y hace sonar la campana de Dolores, la misma que son\u00f3 durante la arenga que pronunci\u00f3 el cura Hidalgo\u2026 aunque esto ocurri\u00f3, seg\u00fan la historia oficial, cerca de las dos de la madrugada del 16 de septiembre de 1810.<\/p>\n<p>Los historiadores aseguran que en realidad todo ocurri\u00f3 la ma\u00f1ana del 16 de septiembre (no la noche del 15 ni la madrugada del 16) cuando un grupo de conspiradores encabezado por Ignacio Allende, un comandante de milicias, fueron descubiertos y decidieron lanzarse a la revoluci\u00f3n.<\/p>\n<p>En una <a href=\"https:\/\/cnnespanol.cnn.com\/video\/grito-independencia-mexico-alfredo-avila-alejandro-torres-sot-aristegui\/\">entrevista con CNN en Espa\u00f1ol<\/a> el historiador Alfredo \u00c1vila cuenta que el momento en el que se empiezan a tomar las decisiones sobre los siguientes pasos a seguir el protagonismo pasa a Miguel Hidalgo, el cura del pueblo de Dolores que areng\u00f3 a los feligreses frente a la Parroquia del pueblo y junto a la c\u00e1rcel, de donde liber\u00f3 a los presos \u201cpara decirles que a partir de ese momento se acababa la tiran\u00eda, la opresi\u00f3n y la Nueva Espa\u00f1a quedar\u00eda libre de las amenazas extranjeras\u201d.<\/p>\n<p>Esta idea colectiva de lo que sucedi\u00f3 esos d\u00edas se da principalmente gracias \u201ca la historia que se teji\u00f3 en el siglo XIX y principios del XX\u201d, se\u00f1ala el historiador Alejandro Torres en una entrevista con CNN en Espa\u00f1ol. Existe la creencia de que el inicio del festejo es obra de Porfirio D\u00edaz, quien habr\u00eda movido el Grito a la noche del 15 para hacerlo coincidir con su cumplea\u00f1os. La realidad es que desde la d\u00e9cada de 1840, cuando el general ten\u00eda apenas 10 a\u00f1os de edad, la fiesta c\u00edvica ya iniciaba el d\u00eda 15 con una serenata, bandas de m\u00fasica, fuegos artificiales y fuego de salvas de artiller\u00eda.<\/p>\n<p>\u201cHemos venido a dar cuenta de que lo que en fue en realidad fue una arenga. De que en realidad Hidalgo estaba pidi\u00e9ndole a los feligreses de ese tiempo que lo ayudaran a salvar la patria y a partir de ah\u00ed comienza este movimiento de Independencia, que era un movimiento al principio de autonom\u00eda y despu\u00e9s poco a poco se fue considerando la Independencia\u201d, dice Torre.<\/p>\n<p>No existe una versi\u00f3n oficial de las palabras que pronunci\u00f3 Miguel Hidalgo, considerado como el padre de la patria y la cara m\u00e1s visible de la Independencia de M\u00e9xico, en la noche del 15 y la madrugada del 16 de septiembre, aunque los mitos construidos alrededor de estos d\u00edas consignan varias versiones.<\/p>\n<p>Algunos testimonios coinciden en que el cura Hidalgo pronunci\u00f3 \u201cvivas\u201d a la Virgen de Guadalupe, a la religi\u00f3n cat\u00f3lica y al rey Fernando VII, as\u00ed como algunos \u201cmuera\u201d al \u201cmal gobierno\u201d, durante el discurso con el cual areng\u00f3 a la poblaci\u00f3n a levantarse en armas.<\/p>\n<p>\u201cNo hay un grito original, hay una arenga\u2026 nunca hubo un viva \u2018algo\u2019, ni siquiera un \u2018viva Fernando VII\u2019. Mucha gente lo interpreta as\u00ed porque hay muchos documentos que muestran que s\u00ed hubo gente que favorec\u00eda al rey. Las vivas es una cosa que inicia ya muy avanzado el siglo XIX, particularmente en el Porfiriato ya es toda una tradici\u00f3n que el presidente salga al balc\u00f3n\u201d, se\u00f1ala por su parte \u00c1vila.<\/p>\n<p>La guerra con la que M\u00e9xico obtuvo su independencia del Imperio espa\u00f1ol comenz\u00f3 el 16 de septiembre de 1810 y concluy\u00f3 el 27 de septiembre de 1821. El \u201cGrito de Dolores\u201d anim\u00f3 a miles de personas a rebelarse contra la clase dominante con la imagen de la Virgen de Guadalupe, primer estandarte de la lucha por la independencia.<\/p>\n<p>Aunque la insurgencia se derrumb\u00f3 en cuesti\u00f3n de meses despu\u00e9s de que apresaron y fusilaron a Hidalgo colgando su cabeza en las esquinas de la Alh\u00f3ndiga de Granaditas, se hab\u00edan plantado las semillas de la revoluci\u00f3n.<\/p>\n<p>La causa fue retomada por otro sacerdote, Jos\u00e9 Mar\u00eda Morelos y Pav\u00f3n, quien hizo una declaraci\u00f3n formal de independencia en 1813 en el Congreso de Chilpancingo. Sin embargo, dos a\u00f1os m\u00e1s tarde, \u00e9l tambi\u00e9n fue capturado y asesinado, y el movimiento que dirig\u00eda se disip\u00f3.<\/p>\n<p>En 1817, Francisco Xavier Mina, Mier y Ter\u00e1n, Vicente Guerrero y Torres se alzaron en la lucha por la Independencia.<\/p>\n<p>Once a\u00f1os despu\u00e9s, en 1821, el ej\u00e9rcito Trigarante, encabezado por Agust\u00edn de Iturbide y Vicente Guerrero, entr\u00f3 triunfal a la Ciudad de M\u00e9xico y el pa\u00eds firma el Acta de Independencia. Espa\u00f1a no reconoci\u00f3 la Independencia de M\u00e9xico hasta 15 a\u00f1os despu\u00e9s.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico celebra un a\u00f1o m\u00e1s de su independencia con el tradicional grito de Dolores, que marc\u00f3 el inicio de la guerra de independencia de la colonia espa\u00f1ola hace 215 a\u00f1os. Los mexicanos salen a las plazas p\u00fablicas y reviven lo que, seg\u00fan la historia oficial, ocurri\u00f3 la madrugada del 16 de septiembre cuando el cura [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466473","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico celebra un a\u00f1o m\u00e1s de su independencia con el tradicional grito de Dolores, que marc\u00f3 el inicio de la guerra de independencia de la colonia espa\u00f1ola hace 215 a\u00f1os. Los mexicanos salen a las plazas p\u00fablicas y reviven lo que, seg\u00fan la historia oficial, ocurri\u00f3 la madrugada del 16 de septiembre cuando el cura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T16:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810\",\"datePublished\":\"2025-09-15T16:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\"},\"wordCount\":934,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\",\"name\":\"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-15T16:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias","og_description":"M\u00e9xico celebra un a\u00f1o m\u00e1s de su independencia con el tradicional grito de Dolores, que marc\u00f3 el inicio de la guerra de independencia de la colonia espa\u00f1ola hace 215 a\u00f1os. Los mexicanos salen a las plazas p\u00fablicas y reviven lo que, seg\u00fan la historia oficial, ocurri\u00f3 la madrugada del 16 de septiembre cuando el cura [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-15T16:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810","datePublished":"2025-09-15T16:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/"},"wordCount":934,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/","name":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-15T16:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/origen-independencia-septiembre-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/15\/origen-independencia-septiembre-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810","url":"http:\/\/noticiasya.com\/sacramento\/2025\/09\/15\/origen-independencia-septiembre-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/sacramento\/2025\/09\/15\/origen-independencia-septiembre-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-15T16:03:41Z","datePublished":"2025-09-15T16:03:41Z","dateModified":"2025-09-15T16:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 se celebra el 16 de septiembre la Independencia de M\\u00e9xico? Esto fue lo que ocurri\\u00f3 en 1810\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/09\\\/15\\\/origen-independencia-septiembre-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/sacramento\\\/2025\\\/09\\\/15\\\/origen-independencia-septiembre-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-15T16:03:41Z\",\"datePublished\":\"2025-09-15T16:03:41Z\",\"dateModified\":\"2025-09-15T16:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452713,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/15\/16-septiembre-independencia-mexico-orix\/","url_meta":{"origin":1466473,"position":0},"title":"\u00bfPor qu\u00e9 se celebra el 16 de septiembre la Independencia de M\u00e9xico? Esto fue lo que ocurri\u00f3 en 1810","author":"","date":"septiembre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e9xico celebra un a\u00f1o m\u00e1s de su independencia con el tradicional grito de Dolores, que marc\u00f3 el inicio de la guerra de independencia de la colonia espa\u00f1ola hace 212 a\u00f1os. Los mexicanos salen a las plazas p\u00fablicas y reviven lo que, seg\u00fan la historia oficial, ocurri\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452720,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/16\/grito-independencia-2024-ciudad-de-mexico-horarios-programacion-conciertos-orix\/","url_meta":{"origin":1466473,"position":1},"title":"Grito de Independencia 2024 en Ciudad de M\u00e9xico: horarios, programaci\u00f3n y conciertos","author":"","date":"septiembre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los festejos por el D\u00eda de la Independencia en la Ciudad de M\u00e9xico se concentrar\u00e1n en el Z\u00f3calo, la principal plaza p\u00fablica del pa\u00eds, donde Andr\u00e9s Manuel L\u00f3pez Obrador dar\u00e1 su \u00faltimo \u201cGrito de Dolores\u201d como presidente de M\u00e9xico, unas semanas antes de que termine su sexenio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466212,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","url_meta":{"origin":1466473,"position":2},"title":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Uno de los eventos m\u00e1s grandes del D\u00eda de la Independencia de M\u00e9xico que suele celebrarse en el \u00e1rea de Chicago a mediados de septiembre se est\u00e1 posponiendo, confirmaron los organizadores a CNN el jueves, ya que se espera que aumenten las acciones de control migratorio en la zona, posiblemente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452704,"url":"https:\/\/noticiasya.com\/sacramento\/2024\/09\/15\/mes-herencia-hispana-que-es-comienza-septiembre-trax\/","url_meta":{"origin":1466473,"position":3},"title":"Mes de la Herencia Hispana: \u00bfqu\u00e9 es, por qu\u00e9 es importante y por qu\u00e9 se celebra desde mediados de septiembre?","author":"","date":"septiembre 15, 2024","format":false,"excerpt":"(CNN) -- El Mes Nacional de la Herencia Hispana comienza este 15 de septiembre y se extender\u00e1 hasta el 15 de octubre, dando a Estados Unidos la oportunidad de reconocer y celebrar a los miembros de nuestras comunidades y a sus antepasados que proceden de M\u00e9xico, partes del Caribe, Centroam\u00e9rica,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466686,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/09\/22\/mes-herencia-hispana-temor-inmigrantes-ee-uu-trax\/","url_meta":{"origin":1466473,"position":4},"title":"Las celebraciones del Mes de la Herencia Hispana contin\u00faan en EE.UU. a pesar del temor de los inmigrantes","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"Una campana son\u00f3 mientras Christian Tonatiuh Gonz\u00e1lez Jim\u00e9nez ondeaba una gran bandera mexicana en el balc\u00f3n del Capitolio de California.\u201c\u00a1Viva M\u00e9xico!, \u00a1Viva M\u00e9xico!\u201d, grit\u00f3 varias veces el c\u00f3nsul general de M\u00e9xico en Sacramento, recreando el grito que desencaden\u00f3 la lucha por la independencia de M\u00e9xico en 1810.A diferencia de a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457645,"url":"https:\/\/noticiasya.com\/sacramento\/2025\/01\/19\/dias-festivos-ee-uu-2025-orix\/","url_meta":{"origin":1466473,"position":5},"title":"Estos son los d\u00edas festivos en EE.UU. para 2025","author":"","date":"enero 19, 2025","format":false,"excerpt":"Estados Unidos reconoce 11 d\u00edas festivos federales, sin embargo el \u00faltimo en agregarse a la lista es el de la Emancipaci\u00f3n, (o Juneteenth, como se le conoce en ingl\u00e9s) celebrado el 19 de junio.Durante los d\u00edas festivos federales, varias oficinas gubernamentales y algunas compa\u00f1\u00edas privadas permanecen cerradas. No obstante, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/sacramento\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1466473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/comments?post=1466473"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/posts\/1466473\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/media?parent=1466473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/categories?post=1466473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/sacramento\/wp-json\/wp\/v2\/tags?post=1466473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}