{"id":1448463,"date":"2024-04-24T10:03:46","date_gmt":"2024-04-24T17:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/"},"modified":"2024-04-24T10:03:46","modified_gmt":"2024-04-24T17:03:46","slug":"reforma-pensional-petro-colombia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","title":{"rendered":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente Gustavo Petro tuvo una victoria pol\u00edtica cuando la plenaria del Senado aprob\u00f3 la propuesta de reforma a las pensiones, uno de sus proyectos bandera, lo que le da un nuevo aire tras del hundimiento de la reforma a la salud semanas antes y las movilizaciones contra el mandatario el 21 de abril. Ahora el proyecto va consideraci\u00f3n en la Comisi\u00f3n S\u00e9ptima de la C\u00e1mara de Representantes.<\/p>\n<p>El ministro del Interior, Luis Fernando Velasco, dijo que \u201cse acaba de aprobar la posibilidad de que cerca de tres millones de adultos mayores que no tienen ning\u00fan ingreso para tener una vejez digna, a partir del primero de julio del 2025, lo tengan&#187;.<\/p>\n<p>AN\u00c1LISIS | Petro se juega su mandato en las calles<\/p>\n<p>Estas son los pilares de la reforma.<\/p>\n<p>El presidente de Colombia Gustavo Petro (C) conversa con el Secretario General del Senado de la Rep\u00fablica, Gregorio Eljach (a la izquierda), mientras la ministra de Trabajo Gloria Ram\u00edrez observa durante la presentaci\u00f3n de un proyecto de ley de reforma de pensiones en el Congreso en Bogot\u00e1 el 22 de marzo. 2023. (Foto de Juan Barreto \/ AFP)<\/p>\n<p>Esquema por pilares<\/p>\n<p>La reforma est\u00e1 basada en tres pilares: el solidario, semicontributivo y contributivo. Este \u00faltimo a su vez est\u00e1 dividido en un plan de Prima Media (para quienes tengan ingresos entre 1 y 2,3 salarios m\u00ednimos mensuales vigentes) y otro, el de Ahorro Voluntario, para quienes tengan ingresos de 2,3 hasta 25 salarios m\u00ednimos mensuales.<\/p>\n<p>Y esta es una de las discusiones m\u00e1s importantes aqu\u00ed, pues el sistema de pilares que es la principal transformaci\u00f3n del sistema pensional que propone el Gobierno.<\/p>\n<p>&#171;La gran discusi\u00f3n que se tiene es cu\u00e1l es el umbral para el ahorro y qui\u00e9n maneja ese ahorro&#187;, dijo la ministra de Trabajo Gloria In\u00e9s Ram\u00edrez luego de aprobarse la discusi\u00f3n en el Senado de la reforma impulsada por el Gobierno.<\/p>\n<p>Petro dice que lo que busca la reforma es &#171;eliminar la competencia entre los sistemas de pensi\u00f3n actuales&#187;.<\/p>\n<p>Actualmente los colombianos pueden decidir libremente si ponen sus ahorros de pensi\u00f3n en el fondo p\u00fablico de Colpensiones, o a administradoras privadas. El cambio que se propone con esta reforma es la obligatoriedad para ir al fondo p\u00fablico o privado seg\u00fan los ingresos de los trabajadores, as\u00ed:<\/p>\n<p>&#8211; Quienes tengan ingresos entre 1 y 2,3 salarios m\u00ednimos mensuales est\u00e1n obligados a cotizar en Colpensiones. La propuesta del Gobierno inicialmente era que el tope fuera hasta 3 salarios m\u00ednimos mensuales. La oposici\u00f3n ped\u00eda 1 salario para la obligatoriedad de ir al sistema p\u00fablico. Tras un consenso se lleg\u00f3 al tope de los 2,3 salarios m\u00ednimos para ir al fondo p\u00fablico.<\/p>\n<p>&#8211; Las personas que ganen m\u00e1s de 2,3 y hasta 25 salarios m\u00ednimos mensuales vigentes deber\u00e1n cotizar su ahorro pensional en los fondos privados.<\/p>\n<p>&#8211; La ministra Ram\u00edrez dice que es necesario este cambio pues en la actualidad un 70% de los ahorros de pensiones est\u00e1n en los fondos privados y el 30% en el fondo p\u00fablico. Los fondos privados, dijo la ministra, tienen 18 millones de afiliados y solo han pensionado a 318.000 personas. El otro 30% est\u00e1n ahorrando en el p\u00fablico.<\/p>\n<p>&#171;El 77,7% de los afiliados de privados pasar\u00e1n al Estado, que son los que est\u00e1n entre 1 y 2,3 salarios m\u00ednimos y quedar\u00edan en fondos privados el 32,7%&#187;, dijo Ram\u00edrez en Noticias Caracol.<\/p>\n<p>Se cae la reforma a la salud en Colombia: duro rev\u00e9s para el Gobierno de Petro<\/p>\n<p>Un ni\u00f1o empuja la silla de ruedas de un anciano en un colegio electoral durante la segunda vuelta de las elecciones presidenciales en Bucaramanga, Colombia, el 19 de junio de 2022. (Cr\u00e9dito: Ra\u00fal ARBOLEDA\/AFP)<\/p>\n<p>El presidente Petro dijo que el actual r\u00e9gimen de fondos privados &#171;no le entrega a la mayor\u00eda de los cotizantes una pensi\u00f3n en el futuro&#187;, por eso miles de trabajadores cotizan durante a\u00f1os en los fondos privados y se pasan a Colpensiones &#171;que s\u00ed garantiza una pensi\u00f3n&#187;.<\/p>\n<p>&#171;Si no se aprueba la reforma har\u00eda que en el corto plazo se quebrar\u00edan los fondos privados al pasar otros centenares de miles de trabajadores de los fondos a Colpensiones, no solo con sus cotizaciones sino con el acumulado de sus ahorros&#187;, advirti\u00f3 Petro.<\/p>\n<p>Lo que se busca es que la gran mayor\u00eda de colombianos, que ganan entre 1 y 2,3 salarios m\u00ednimos, ahorren en el fondo estatal, financien el sistema pensional y el Estado con ese dinero pueda garantizar las pensiones por montos m\u00e1s bajos, que son los de la gran mayor\u00eda.<\/p>\n<p>&#171;El Estado los quiere proteger y para protegerlos es que estamos hablando de esos tres salarios m\u00ednimos que nos dan una robustez en el fondo del ahorro y claramente una suficiencia para la pensi\u00f3n&#187;, dijo Ram\u00edrez.<\/p>\n<p>Pilar semicontributivo<\/p>\n<p>Este pilar est\u00e1 pensado para entregar un &#171;beneficio econ\u00f3mico&#187;, seg\u00fan el proyecto de ley, a quienes a los 65 a\u00f1os no hayan cumplido los requisitos para una pensi\u00f3n vitalicia. Actualmente algunas personas cotizan en fondos privados un &#171;ahorro&#187; que no les es suficiente para pensionarse, de manera que los fondos privados devuelven un &#171;bono pensional&#187; que no representa una cuota vitalicia y los ahorros de toda la vida se gastan en otros rubros, pero la persona no queda protegida en su vejez. Esto pasa a ser obligatorio.<\/p>\n<p>&#171;La esencia del pilar semicontributivo es hacer un redbull para que la gente tenga protecci\u00f3n en la vejez&#187;, dijo la ministra. &#171;Entonces si usted ahorra y yo le devuelvo la plata eso se le vuelve un viaje de turismo, eso se le vuelve educaci\u00f3n para sus hijos, pero no la protecci\u00f3n a la vejez&#187;.<\/p>\n<p>La propuesta del Gobierno es transformar ese ahorro en una renta vitalicia para que la persona pueda tener un ingreso de por vida despu\u00e9s de pensionarse.<\/p>\n<p>Aplica para quienes hayan ahorrado entre 150 y 999 semanas. Es decir, que la cotizaci\u00f3n no alcance para obtener la pensi\u00f3n.<\/p>\n<p>Tras la aprobaci\u00f3n en el Senado, la ministra Ram\u00edrez dijo que el Gobierno &#171;acepta los fondos pensionales como un elemento que permite la complementariedad y el mejoramiento de la pensi\u00f3n de colombianos y colombianas&#187; y asegur\u00f3 que adem\u00e1s de los 3 millones de adultos mayores que saldr\u00edan de la extrema pobreza con esta reforma, &#171;cerca de 12 millones al a\u00f1o 2052 de personas que hoy cotizan pero no tienen pensi\u00f3n puedan tener(la) a trav\u00e9s de la renta vitalicia\u201d.<\/p>\n<p>Protecci\u00f3n a la vejez<\/p>\n<p>La propuesta tambi\u00e9n busca, a trav\u00e9s del pilar solidario, sacar de la pobreza extrema a millones de ancianos que no tienen una pensi\u00f3n, garantiz\u00e1ndoles una renta b\u00e1sica para &#171;amparar las condiciones m\u00ednimas de subsistencia&#187; de los adultos mayores. La promesa es entregarles un bono mensual de 223.800 pesos, unos US$ 57 al cambio actual. Esto se financiar\u00e1 con recursos del Estado.<\/p>\n<p>&#171;Con el pilar solidario tal como est\u00e1 vamos a poder atender a 2.700.000 de abuelos en la primera fase de este proceso. Luego vamos a llegar hasta los 3 millones. Es decir, vamos a trabajar para que los abuelos salgan de la extrema pobreza&#187;, dijo la ministra.<\/p>\n<p>&#171;Fundamentalmente blindamos un ahorro que permita que las futuras generaciones en el a\u00f1o 2052 puedan tener garantizada la pensi\u00f3n y la sostenibilidad del mismo&#187;, a\u00f1adi\u00f3<\/p>\n<p>Beneficio para las mujeres con hijos<\/p>\n<p>El art\u00edculo 36 de esta reforma propone que a las mujeres se les reconozcan 50 semanas de cotizaci\u00f3n por cada hijo nacido vivo o adoptivo, lo que podr\u00eda darles 150 semanas para alcanzar su pensi\u00f3n en caso de que no alcancen a cumplir el requisito de semanas m\u00ednimas para su pensi\u00f3n.<\/p>\n<p>El Gobierno de Petro da marcha atr\u00e1s con el impuesto a las pensiones de la reforma tributaria en Colombia<\/p>\n<p>Reducci\u00f3n de semanas para las mujeres<\/p>\n<p>La reforma incluir\u00e1 un fallo de la Corte Constitucional emitido hace unos d\u00edas, que reduce las semanas de cotizaci\u00f3n para las mujeres de 1.300 a 1.000. La ley le otorga una reducci\u00f3n en las semanas m\u00ednimas requeridas para que las mujeres sean pensionadas: se les reconocer\u00e1 la pensi\u00f3n, de 50 semanas por cada hijo, sin que supere de 3 hijos, dice el Gobierno.<\/p>\n<p>Lo que sigue igual y otras modificaciones<\/p>\n<p>Las pensiones de invalidez y de sobrevivientes no sufrir\u00e1n modificaciones con la nueva ley, tendr\u00e1n las mismas contin\u00faen igual, con los mismos requisitos, pero ahora ser\u00e1n reconocidas por Colpensiones.<\/p>\n<p>As\u00ed mismo, define que se respetar\u00e1n los derechos adquiridos como por ejemplo pensi\u00f3n por invalidez y de sobrevivientes, aunque estas ser\u00e1n asumidas por Colpensiones.<\/p>\n<p>Adem\u00e1s, dice el Gobierno, &#171;se respetar\u00e1n los derechos adquiridos&#187;, lo que significa que las condiciones para los ya pensionados continuar\u00e1n igual.<\/p>\n<p>Adem\u00e1s, seg\u00fan el Gobierno, el proyecto de Ley propone la creaci\u00f3n de &#171;un fondo para el ahorro, que evitar\u00e1 cualquier impacto al mercado de valores y adquisici\u00f3n de TES&#187;.<\/p>\n<p>Una mujer muestra un cartel que dice &#171;#Sin Robar mi Pensi\u00f3n, es mi Derecho Adquirido&#187;, durante una protesta contra una reforma tributaria propuesta por el gobierno del presidente de izquierda Gustavo Petro, en Cali, Colombia, el 26 de septiembre de 2022. (Cr\u00e9dito: JOAQUIN SARMIENTO\/AFP v\u00eda Getty Images)<\/p>\n<p>Las cr\u00edticas de la oposici\u00f3n<\/p>\n<p>Los senadores de la oposici\u00f3n criticaron la aprobaci\u00f3n de este proyecto para su discusi\u00f3n y rechazaron la reforma pensional del Gobierno, asegurando que el proyecto no es viable fiscalmente y otros dijeron que las aseguradoras privadas de fondos de pensiones quedar\u00e1n desfinanciadas.<\/p>\n<p>El senador David Luna, del opositor Cambio Radical, dijo que la reforma en curso &#171;acaba con la libertad de elecci\u00f3n&#187; pues los colombianos ya no tendr\u00e1n la libertad de elegir si ahorrar en un fondo privado o p\u00fablico que le pueda generar m\u00e1s confianza.<\/p>\n<p>&#171;Votamos negativamente esta reforma porque atenta frontalmente contra el derecho a la propiedad, no a la propiedad de una casa, de un carro, de una casa, de una finca: a la propiedad de sus ahorros&#187;, dijo Luna en el Senado. Dijo que los ahorros de las personas que no alcancen una pensi\u00f3n bajar\u00e1 los intereses (en los fondos privados) de 3% a 0%.<\/p>\n<p>La senadora del Centro Democr\u00e1tico Paloma Valencia dijo que la reforma har\u00e1 que el pa\u00eds sea inviable fiscalmente, y dice que lo que el pa\u00eds va a tener es una &#171;deuda pensional&#187;.<\/p>\n<p>&#171;El gran problema es que esta reforma crece la bomba pensional y la convierte en una bomba at\u00f3mica&#187;. Valencia dice que el dinero se va acabar en 2070 y entonces habr\u00e1 un d\u00e9ficit en el PIB.<\/p>\n<p>La ministra Ram\u00edrez dijo Ram\u00edrez en Noticias Caracol que el proyecto tiene &#171;sostenibilidad fiscal que permite que los j\u00f3venes de hoy se pensionen de 2052 a 2070&#187;.<\/p>\n<p>Nota del editor: este art\u00edculo fue publicado en junio de 2023 y actualizado en abril 2024<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente Gustavo Petro tuvo una victoria pol\u00edtica cuando la plenaria del Senado aprob\u00f3 la propuesta de reforma a las pensiones, uno de sus proyectos bandera, lo que le da un nuevo aire tras del hundimiento de la reforma a la salud semanas antes y las movilizaciones contra el mandatario [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448463","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente Gustavo Petro tuvo una victoria pol\u00edtica cuando la plenaria del Senado aprob\u00f3 la propuesta de reforma a las pensiones, uno de sus proyectos bandera, lo que le da un nuevo aire tras del hundimiento de la reforma a la salud semanas antes y las movilizaciones contra el mandatario [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T17:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?\",\"datePublished\":\"2024-04-24T17:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\"},\"wordCount\":1874,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\",\"name\":\"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-24T17:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Gobierno del presidente Gustavo Petro tuvo una victoria pol\u00edtica cuando la plenaria del Senado aprob\u00f3 la propuesta de reforma a las pensiones, uno de sus proyectos bandera, lo que le da un nuevo aire tras del hundimiento de la reforma a la salud semanas antes y las movilizaciones contra el mandatario [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-24T17:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?","datePublished":"2024-04-24T17:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/"},"wordCount":1874,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","name":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-24T17:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 propone cambiar la reforma pensional de Petro en Colombia?","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/reforma-pensional-petro-colombia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-24T17:03:46Z","datePublished":"2024-04-24T17:03:46Z","dateModified":"2024-04-24T17:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 propone cambiar la reforma pensional de Petro en Colombia?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/24\\\/reforma-pensional-petro-colombia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/24\\\/reforma-pensional-petro-colombia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-24T17:03:46Z\",\"datePublished\":\"2024-04-24T17:03:46Z\",\"dateModified\":\"2024-04-24T17:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452839,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/19\/petro-manifestacion-reforma-pensional-colombia-orix\/","url_meta":{"origin":1448463,"position":0},"title":"Petro convoca a manifestaci\u00f3n para defender la reforma pensional en Colombia","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Colombia, Gustavo Petro, convoc\u00f3 a participar este jueves en una manifestaci\u00f3n para \u201cdefender la reforma pensional\u201d, seg\u00fan anunci\u00f3 en sus historias de Instagram, en d\u00edas donde crecen los reclamos para que sea revisada por la Corte Constitucional colombiana.Petro firm\u00f3 en julio la reforma pensional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463678,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/06\/17\/senado-colombia-aprueba-reforma-laboral-petro-consulta-popular-orix\/","url_meta":{"origin":1448463,"position":1},"title":"El Senado de Colombia aprueba la reforma laboral, un tema que Petro plante\u00f3 llevar a consulta popular","author":"","date":"junio 17, 2025","format":false,"excerpt":"El Senado de Colombia aprob\u00f3 este martes la reforma laboral que se discut\u00eda desde 2023, un tema que el presidente Gustavo Petro plante\u00f3 someter a una consulta popular y por el que ha tenido tensiones con el Poder Legislativo.La \u00faltima votaci\u00f3n termin\u00f3 con 56 votos a favor y 31 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463952,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/06\/25\/petro-firma-reforma-laboral-vigilar-cumplir-orix\/","url_meta":{"origin":1448463,"position":2},"title":"Petro firma la reforma laboral y llama a vigilar que se cumpla","author":"","date":"junio 25, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, firm\u00f3 este mi\u00e9rcoles la reforma laboral que su Gobierno impuls\u00f3 durante los \u00faltimos dos a\u00f1os y que la semana pasada finalmente qued\u00f3 aprobada por el Congreso.Petro sign\u00f3 el documento durante un acto p\u00fablico en Bogot\u00e1, acompa\u00f1ado de algunos funcionarios de su gobierno, l\u00edderes sindicales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463717,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/06\/18\/consejo-estado-colombia-suspende-decreto-petro-consulta-popular-orix\/","url_meta":{"origin":1448463,"position":3},"title":"El Consejo de Estado de Colombia suspende provisionalmente decreto de Petro sobre consulta popular para sus reformas sociales","author":"","date":"junio 18, 2025","format":false,"excerpt":"El Consejo de Estado de Colombia, el m\u00e1ximo tribunal del pa\u00eds para asuntos contencioso administrativos, resolvi\u00f3 este mi\u00e9rcoles suspender provisionalmente el decreto del presidente Gustavo Petro que busca convocar a una consulta popular sobre sus reformas sociales.El Consejo consider\u00f3 que el decreto de Petro contradice la ley que establece que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463782,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/06\/20\/reforma-laboral-ley-orix\/","url_meta":{"origin":1448463,"position":4},"title":"Reforma laboral en Colombia, a un paso de convertirse en ley","author":"","date":"junio 20, 2025","format":false,"excerpt":"En reuni\u00f3n plenaria, el Senado de Colombia aprob\u00f3 la conciliaci\u00f3n de la reforma laboral propuesta por el Gobierno del presidente Gustavo Petro y que se hab\u00eda convertido en un pulso pol\u00edtico entre el poder Ejecutivo y sectores de la oposici\u00f3n en el Legislativo. Ahora pasa a sanci\u00f3n presidencial.\u201cLo que ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460102,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/18\/senado-rechaza-reforma-laboral-petro-consulta-popular-orix\/","url_meta":{"origin":1448463,"position":5},"title":"El Senado rechaza la reforma laboral el mismo d\u00eda en que Petro convoca a movilizaciones para respaldar su consulta popular","author":"","date":"marzo 18, 2025","format":false,"excerpt":"La Comisi\u00f3n S\u00e9ptima del Senado colombiano rechaz\u00f3 este martes el texto de la reforma laboral por ocho votos a favor y seis en contra.La C\u00e1mara alta del Poder Legislativo de Colombia aprob\u00f3 archivar la iniciativa, una de las que forman parte del paquete de reformas sociales del presidente Gustavo Petro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448463"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448463\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}