{"id":1448674,"date":"2024-04-29T15:03:39","date_gmt":"2024-04-29T22:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/"},"modified":"2024-04-29T15:03:39","modified_gmt":"2024-04-29T22:03:39","slug":"venezolanos-argentina-votar-elecciones-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","title":{"rendered":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En Argentina viven alrededor de 220.000 venezolanos, seg\u00fan las estimaciones m\u00e1s recientes publicadas por el ministerio del Interior a 2023 y al menos el 70% est\u00e1 en edad de votar.<\/p>\n<p>Un venezolano que lleg\u00f3 al pa\u00eds en los \u00faltimos dos a\u00f1os no cumple los requisitos para empadronarse y votar en las elecciones presidenciales de Venezuela el 28 de julio.<\/p>\n<p>Un venezolano que no pudo pagar los US$ 280 que, seg\u00fan testimonios recabados por CNN, cuesta la renovaci\u00f3n del pasaporte en el consulado, no cumple los requisitos para empadronarse y votar en las elecciones del 28 de julio.<\/p>\n<p>Un venezolano que puede pagar la renovaci\u00f3n de su pasaporte, pero tiene su identificaci\u00f3n de usuario bloqueada en el sistema y no puede viajar a Venezuela a desbloquearla, seg\u00fan otro de los testimonios recogidos por CNN, tampoco puede inscribirse para votar en las elecciones del 28 de julio.<\/p>\n<p>Si perdi\u00f3 su c\u00e9dula y no volvi\u00f3 a Venezuela a tramitar una nueva, tampoco.<\/p>\n<p>M\u00e1s de 215.000 venezolanos en Argentina no van a poder votar en las elecciones presidenciales de su pa\u00eds en julio.<\/p>\n<p>Elecciones en Venezuela 2024: c\u00f3mo registrarse para votar en el pa\u00eds y desde el exterior<\/p>\n<p>Seg\u00fan estimaciones del partido opositor Vente Venezuela, solo 2.500 podr\u00e1n.<\/p>\n<p>\u201cYo logr\u00e9 empadronarme, pero fui la \u00fanica de mi familia, de ocho personas que somos, que pudo hacerlo\u201d \u2014dice a CNN Yaritza Loyo de 43 a\u00f1os\u2014. \u201cLo frustrante es que, en nuestro caso, todos tenemos la documentaci\u00f3n requerida y sin embargo no pudimos\u201d.<\/p>\n<p>La documentaci\u00f3n a la que hace referencia Loyo es el primer impedimento con el que se chocan en el camino. As\u00ed lo describe cada persona entrevistada por CNN.<\/p>\n<p>Lo principal: el pasaporte vigente. Pero tambi\u00e9n la c\u00e9dula venezolana, vigente o vencida, de acuerdo con la Ley org\u00e1nica de procesos electorales, y el DNI argentino con residencia permanente, tal cual figura en el art\u00edculo 124 de la misma legislaci\u00f3n para votantes en el exterior. En Argentina este \u00faltimo requisito solo pueden cumplirlo los extranjeros con m\u00e1s de tres a\u00f1os de residencia temporal.<\/p>\n<p>El proceso para renovar el pasaporte tiene un valor de entre US$ 200 y US$ 400, seg\u00fan los testimonios y, dependiendo de la experiencia de cada ciudadano, puede demorar meses o a\u00f1os.<\/p>\n<p>\u201cEstos \u00faltimos meses se ve que necesitan plata y lo est\u00e1n haciendo m\u00e1s r\u00e1pido\u201d, explica V\u00edctor Faza, integrante de la asociaci\u00f3n civil Alianza por Venezuela, una organizaci\u00f3n en Argentina que defiende los derechos de los venezolanos.<\/p>\n<p>Faza tambi\u00e9n forma parte del equipo de enlace de la opositora Mar\u00eda Corina Machado en el pa\u00eds, y asocia la facilitaci\u00f3n circunstancial para obtener el pasaporte con los tiempos electorales. \u201cTener 8 millones de venezolanos afuera pidiendo documentaci\u00f3n y pagando en d\u00f3lares es un mont\u00f3n de plata y ahora la necesitan porque vienen elecciones. Imag\u00ednate la cantidad de dinero que va a repartir (Nicol\u00e1s) Maduro en los sectores m\u00e1s populares. Va a ser la campa\u00f1a m\u00e1s millonaria en estos \u00faltimos tiempos\u201d, dice.<\/p>\n<p>CNN consult\u00f3 a la Embajada de Venezuela en Argentina para saber cu\u00e1ntos ciudadanos venezolanos han pedido renovar su pasaporte y cu\u00e1ntos de esos documentos est\u00e1n pendientes de entregar. Hasta ahora no hemos recibido respuesta.<\/p>\n<p>En la p\u00e1gina web de la Embajada figura que el costo del tr\u00e1mite es de US$ 200 con tarjeta de cr\u00e9dito internacional, pero los entrevistados dicen que a la hora de retirar la libreta hay que pagar unos US$ 80 m\u00e1s por gastos de env\u00edo.<\/p>\n<p>El Consejo Nacional Electoral y el consulado local no respondieron las consultas respecto a las distintas dificultades para el proceso de empadronamiento. Por ese motivo, esta historia est\u00e1 principalmente construida con base en testimonios de ciudadanos de la comunidad venezolana en Argentina, informaci\u00f3n recabada o estimada por organizaciones y Vente Venezuela, el partido pol\u00edtico de la opositora Mar\u00eda Corina Machado.<\/p>\n<p>Seg\u00fan datos de la Plataforma de Coordinaci\u00f3n Interagencial para Refugiados y Migrantes de Venezuela (R4V) con base en cifras oficiales emitidas por los respectivos gobiernos, hasta noviembre de 2023, 7.722.579 venezolanos viv\u00edan fuera de su pa\u00eds. 6.538.756 est\u00e1n en Am\u00e9rica Latina y 217.742, en Argentina.<\/p>\n<p>Venezolanos en Argentina se preparan para votar en las elecciones presidenciales<\/p>\n<p>De ese n\u00famero, poco m\u00e1s de 150.000 est\u00e1n en edad de votar, pero solo el 1,5% est\u00e1 habilitado para hacerlo y, de acuerdo con estimaciones del partido opositor Vente Venezuela, de ese 1,5% son solo 500 los que se pudieron inscribir este a\u00f1o. Los otros 2.000 est\u00e1n empadronados desde las elecciones de 2018. Las organizaciones no pudieron confirmar a CNN si estos \u00faltimos esos empadronados de 2018 contin\u00faan en el pa\u00eds.<\/p>\n<p>\u201cUn chico periodista venezolano (\u2026) manda las noticias por Instagram a diario y as\u00ed me entero de las cosas\u201d, dice Morela M\u00e1rquez de 66 a\u00f1os. Otras personas cuentan que se informan mediante grupos de WhatsApp y distintas redes sociales. Hace 6 a\u00f1os que M\u00e1rquez se fue de su pa\u00eds y dice que logr\u00f3 empadronarse la segunda vez que fue a la embajada. \u201cLa primera esper\u00e9 seis horas y se terminaron los turnos antes de que me tocara; la segunda llegu\u00e9 a las seis y media de la ma\u00f1ana y tard\u00e9 nueve horas\u201d, agrega, \u201cel resto de mi familia ni lo intent\u00f3\u201d.<\/p>\n<p>\u00c1ngel Cabrera tiene 70 a\u00f1os y dice que fue tres veces. \u201cLas primeras dos resultaron un poco infructuosas porque la fila era muy larga\u201d. Pero finalmente el \u00faltimo d\u00eda pudo: \u201cDecid\u00ed ir muy temprano, a las cinco y media de la ma\u00f1ana\u201d.<\/p>\n<p>El empadronamiento estaba previsto entre el 18 de marzo y el 16 de abril, pero termin\u00f3 comenzando el primero de este mes y no se prorrog\u00f3 su cierre, explica Faza de Alianza por Venezuela.<\/p>\n<p>Trece candidatos se registraron para las elecciones presidenciales de Venezuela<\/p>\n<p>El horario de atenci\u00f3n del consulado venezolano en Argentina es de lunes a viernes de 8:00 am a 4:00 pm hora local, y todas las personas con las que habl\u00f3 CNN afirman que hab\u00eda un solo puesto de atenci\u00f3n y se otorgaban entre 40 y 50 turnos por d\u00eda. De ah\u00ed sale el dato de los 500 empadronados que estiman las organizaciones: 12 d\u00edas h\u00e1biles, entre 40 y 50 personas por d\u00eda, se llega a ese aproximado.<\/p>\n<p>\u201cMuy pocos j\u00f3venes se inscribieron\u201d, dice Faza. \u201cEn la fila ve\u00edamos, m\u00e1s que todo, gente mayor a 40, 50, 60 a\u00f1os. Los j\u00f3venes sienten una total desesperanza, tienen el objetivo de irse a Estados Unidos, Europa y comenzar una nueva vida. Seguir conectado con un pa\u00eds que no te dio oportunidades y que pr\u00e1cticamente te ech\u00f3 genera un total desprendimiento\u201d, opina.<\/p>\n<p>Una encuesta realizada en enero de 2024 en Venezuela concluy\u00f3 que, si el chavismo gana las elecciones, el 39,6% de la poblaci\u00f3n pensar\u00eda en irse del pa\u00eds, m\u00e1s del 45% no sabe si se ir\u00eda y solo el 14,5% dice que se quedar\u00eda.<\/p>\n<p>En cambio, Yaritza Loyo dice que, si Nicol\u00e1s Maduro pierde, vuelve: \u201cTengo fe, por eso fui a empadronarme, tengo esa ilusi\u00f3n\u201d. Morela M\u00e1rquez no tiene una respuesta tan determinante sobre regresar a vivir all\u00e1 porque su hijo ya est\u00e1 establecido en Argentina. Sin embargo, cuenta que tiene boletos a\u00e9reos para visitar Venezuela despu\u00e9s de las elecciones. \u201cVoy a ir a festejar\u201d, dice convencida de que esta vez llegar\u00e1 el cambio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En Argentina viven alrededor de 220.000 venezolanos, seg\u00fan las estimaciones m\u00e1s recientes publicadas por el ministerio del Interior a 2023 y al menos el 70% est\u00e1 en edad de votar. Un venezolano que lleg\u00f3 al pa\u00eds en los \u00faltimos dos a\u00f1os no cumple los requisitos para empadronarse y votar en las elecciones [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448674","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; En Argentina viven alrededor de 220.000 venezolanos, seg\u00fan las estimaciones m\u00e1s recientes publicadas por el ministerio del Interior a 2023 y al menos el 70% est\u00e1 en edad de votar. Un venezolano que lleg\u00f3 al pa\u00eds en los \u00faltimos dos a\u00f1os no cumple los requisitos para empadronarse y votar en las elecciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T22:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones\",\"datePublished\":\"2024-04-29T22:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\"},\"wordCount\":1286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\",\"name\":\"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-29T22:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; En Argentina viven alrededor de 220.000 venezolanos, seg\u00fan las estimaciones m\u00e1s recientes publicadas por el ministerio del Interior a 2023 y al menos el 70% est\u00e1 en edad de votar. Un venezolano que lleg\u00f3 al pa\u00eds en los \u00faltimos dos a\u00f1os no cumple los requisitos para empadronarse y votar en las elecciones [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-29T22:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/"},"author":{"name":"","@id":""},"headline":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones","datePublished":"2024-04-29T22:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/"},"wordCount":1286,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","name":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-29T22:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-29T22:03:39Z","datePublished":"2024-04-29T22:03:39Z","dateModified":"2024-04-29T22:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venezolanos en Argentina: son m\\u00e1s de 200.000 y solo un peque\\u00f1o porcentaje podr\\u00e1 votar en las elecciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/29\\\/venezolanos-argentina-votar-elecciones-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/29\\\/venezolanos-argentina-votar-elecciones-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-29T22:03:39Z\",\"datePublished\":\"2024-04-29T22:03:39Z\",\"dateModified\":\"2024-04-29T22:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451379,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/24\/venezolanos-peru-viajar-venezuela-votar-elecciones-2024-orix\/","url_meta":{"origin":1448674,"position":0},"title":"Por qu\u00e9 muchos venezolanos que viven en Per\u00fa deben viajar a Venezuela a votar","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Mariluz Santana y Ghenry Navarro son dos venezolanos que viven y trabajan en Per\u00fa desde hace varios a\u00f1os. No se conocen, pero han decidido tomar el mismo rumbo: viajar a Venezuela para votar en las elecciones del 28 de julio. Ambos creen que es un momento hist\u00f3rico para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451066,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/12\/como-votar-extranjero-elecciones-venezuela-2024-fecha-requisitos-orix\/","url_meta":{"origin":1448674,"position":1},"title":"C\u00f3mo votar desde el extranjero para las elecciones presidenciales de Venezuela: fecha y requisitos","author":"","date":"julio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Miles de venezolanos en el extranjero participar\u00e1n en las elecciones presidenciales del 28 de julio para elegir, entre 10 candidatos, a quien ser\u00e1 su pr\u00f3ximo presidente.Para estos comicios solo pueden participar aquellos venezolanos que sean mayores de 18 a\u00f1os, que posean residencia o cualquier otro estatus que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450219,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/11\/venezuela-elecciones-quienes-podran-votar-orix\/","url_meta":{"origin":1448674,"position":2},"title":"\u00bfQui\u00e9nes podr\u00e1n votar en las elecciones presidenciales del 28 de julio en Venezuela?","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e1s de 21 millones de venezolanos est\u00e1n habilitados para votar en las elecciones presidenciales del 28 de julio, seg\u00fan el corte definitivo de datos del 16 de abril de 2024, publicado en junio por el Consejo Nacional Electoral (CNE). En total hay 21.620.705 electores en Venezuela, incluidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447121,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/19\/elecciones-venezuela-2024-como-registrarse-orix\/","url_meta":{"origin":1448674,"position":3},"title":"Elecciones en Venezuela 2024:  c\u00f3mo registrarse para votar en el pa\u00eds y desde el exterior","author":"","date":"marzo 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Venezuela celebra sus elecciones presidenciales el pr\u00f3ximo 28 de julio, de acuerdo con el anuncio del Consejo Nacional Electoral (CNE) del pasado 5 de marzo. Y, tal como se establece en el cronograma electoral difundido por el presidente del CNE, Elvis Amoroso, desde este lunes y hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451283,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/20\/elecciones-presidenciales-venezuela-claves-orix\/","url_meta":{"origin":1448674,"position":4},"title":"Las 10 claves de las elecciones presidenciales en Venezuela","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 28 de julio se llevar\u00e1n a cabo en Venezuela unas elecciones que mantienen en vilo al pa\u00eds y a la regi\u00f3n. Aqu\u00ed te contamos las claves.\u00bfQu\u00e9 se vota?Los venezolanos deber\u00e1n elegir entre 10 candidatos al pr\u00f3ximo presidente para el periodo 2025-2031Nicol\u00e1s Maduro (Cr\u00e9dito: Getty Images)\u00bfQui\u00e9nes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451428,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/25\/jovenes-opositores-venezolanos-abandonar-pais-maduro-reeleccion-trax\/","url_meta":{"origin":1448674,"position":5},"title":"J\u00f3venes opositores venezolanos se preparan para abandonar el pa\u00eds si Maduro es reelegido","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- Ambar Le\u00e1\u00f1ez se calla cuando piensa en un futuro m\u00e1s all\u00e1 de este fin de semana.Partidaria incondicional del movimiento opositor venezolano, se muestra optimista ante las posibilidades de que su coalici\u00f3n gane las elecciones presidenciales de este domingo. La idea de pasar otros seis a\u00f1os bajo el mandato\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448674"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448674\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}