{"id":1448691,"date":"2024-04-30T04:03:39","date_gmt":"2024-04-30T11:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/"},"modified":"2024-04-30T04:03:39","modified_gmt":"2024-04-30T11:03:39","slug":"canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","title":{"rendered":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas"},"content":{"rendered":"<p>(CNN) &#8212; La Guardia Costera de China\u00a0dispar\u00f3 ca\u00f1ones de agua que da\u00f1aron un barco filipino este martes, marcando el \u00faltimo estallido de violencia entre los dos pa\u00edses en el disputado Mar de China Meridional, dijeron las autoridades filipinas.<\/p>\n<p>La Guardia Costera de Filipinas dijo que el incidente ocurri\u00f3 cuando uno de sus barcos y un buque de la agencia de pesca realizaban una \u201cpatrulla leg\u00edtima\u201d cerca de Scarborough Shoal, un afloramiento rocoso controlado por China a 200 kil\u00f3metros al oeste de la principal isla filipina de Luz\u00f3n y dentro de la zona econ\u00f3mica exclusiva de Manila.<\/p>\n<p>Un video proporcionado por la Guardia Costera de Filipinas mostr\u00f3 a dos buques chinos m\u00e1s grandes disparando ca\u00f1ones de agua desde lados opuestos del barco filipino.<\/p>\n<p>&#171;Los buques filipinos encontraron maniobras peligrosas y obstrucciones por parte de cuatro buques de la Guardia Costera de China y seis buques de la Milicia Mar\u00edtima China&#187;, dijo en el comunicado el portavoz de la Guardia Costera de Filipinas, el comodoro Jay Tarriela.<\/p>\n<p>Exclusiva: CNN presencia la confrontaci\u00f3n entre naves de Filipinas y de China<\/p>\n<p>Una captura de pantalla tomada de un video proporcionado por la Guardia Costera de Filipinas muestra a la Guardia Costera de China usando ca\u00f1ones de agua contra embarcaciones filipinas cerca de Scarborough Shoal el martes 30 de abril. (Cr\u00e9dito: Folleto\/Guardia Costera de Filipinas)<\/p>\n<p>El barco de la Guardia Costera de Filipinas sufri\u00f3 \u201cda\u00f1os en la barandilla y la cubierta\u201d, seg\u00fan su comunicado. No se reportaron heridos.<\/p>\n<p>En una publicaci\u00f3n en la plataforma social Weibo este martes, la Guardia Costera de China dijo que hab\u00eda expulsado a los barcos filipinos por \u201cinvadir\u201d las aguas, \u201cde conformidad con la ley\u201d.<\/p>\n<p>Beijing afirma ser due\u00f1o de casi todo el Mar de China Meridional desafiando un fallo de un tribunal internacional. Durante las \u00faltimas dos d\u00e9cadas, China ha ocupado varios arrecifes y atolones oscuros lejos de su costa a lo largo del Mar de China Meridional, construyendo instalaciones militares, incluidas pistas de aterrizaje y puertos.<\/p>\n<p>Scarborough Shoal, que China llama Isla Huangyan y tambi\u00e9n se conoce como Bajo de Masinloc, es un arrecife peque\u00f1o pero estrat\u00e9gico y una zona de pesca f\u00e9rtil.<\/p>\n<p>No hay estructuras en el banco de arena, pero China ha mantenido una presencia continua de guardacostas a su alrededor desde 2012, seg\u00fan la Iniciativa de Transparencia Mar\u00edtima de Asia.<\/p>\n<p>Filipinas y China se acusan mutuamente de incidentes &#171;peligrosos&#187; que involucraron a varios buques en el Mar de China Meridional<\/p>\n<p>Filipinas tambi\u00e9n dijo este martes que China hab\u00eda reinstalado una barrera flotante de 380 metros que \u201ccubre toda la entrada del banco de arena, restringiendo efectivamente el acceso al \u00e1rea\u201d.<\/p>\n<p>Scarborough Shoal es una de varias islas y arrecifes en disputa en el Mar de China Meridional, que durante mucho tiempo han sido un punto \u00e1lgido de disputas territoriales entre las dos naciones.<\/p>\n<p>En marzo, barcos de la Guardia Costera china dispararon ca\u00f1ones de agua contra un barco filipino en una misi\u00f3n de reabastecimiento a un contingente de infantes de Marina filipinos en otra zona disputada del Mar de China Meridional, Second Thomas Shoal, causando \u201cgrandes da\u00f1os\u201d.<\/p>\n<p>Ese banco de arena se encuentra a unos 200 kil\u00f3metros de la costa de la isla filipina de Palawan. En la d\u00e9cada de 1990, Filipinas dej\u00f3 en tierra un viejo barco de transporte de la Segunda Guerra Mundial llamado BRP Sierra Madre en el banco de arena, para ayudar a hacer cumplir su reclamo sobre el \u00e1rea. El barco ahora es en su mayor parte unos restos oxidados y est\u00e1 atendido por infantes de Marina estacionados en rotaci\u00f3n.<\/p>\n<p>Filipinas acusa a China de instalar barrera flotante en el disputado mar de China Meridional<\/p>\n<p>Despu\u00e9s de ese incidente, la Guardia Costera de China dijo en Weibo que hab\u00eda tomado &#171;medidas de control de acuerdo con la ley&#187; contra los barcos filipinos, que, seg\u00fan dijo, hab\u00edan &#171;entrado ilegalmente en las aguas adyacentes al arrecife Ren&#8217;ai&#187;, como Beijing llama a Second Thomas.<\/p>\n<p>A principios de marzo, un ca\u00f1\u00f3n de agua chino alcanz\u00f3 un barco de reabastecimiento filipino que se dirig\u00eda a Second Thomas Shoal, rompiendo ventanas e hiriendo a cuatro marineros filipinos.<\/p>\n<p>Las disputas entre Beijing y Manila en el Mar de China Meridional se han intensificado desde la elecci\u00f3n en 2022 del presidente filipino Ferdinand Marcos Jr., quien adopt\u00f3 una l\u00ednea m\u00e1s dura contra China que su predecesor Rodrigo Duterte.<\/p>\n<p>Los enfrentamientos tambi\u00e9n han generado temores de que puedan conducir a un conflicto m\u00e1s amplio, ya que Manila mantiene un tratado de defensa mutua con Estados Unidos, que seg\u00fan Washington cubre a los buques filipinos en la v\u00eda fluvial en disputa.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La Guardia Costera de China\u00a0dispar\u00f3 ca\u00f1ones de agua que da\u00f1aron un barco filipino este martes, marcando el \u00faltimo estallido de violencia entre los dos pa\u00edses en el disputado Mar de China Meridional, dijeron las autoridades filipinas. La Guardia Costera de Filipinas dijo que el incidente ocurri\u00f3 cuando uno de sus barcos y un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448691","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La Guardia Costera de China\u00a0dispar\u00f3 ca\u00f1ones de agua que da\u00f1aron un barco filipino este martes, marcando el \u00faltimo estallido de violencia entre los dos pa\u00edses en el disputado Mar de China Meridional, dijeron las autoridades filipinas. La Guardia Costera de Filipinas dijo que el incidente ocurri\u00f3 cuando uno de sus barcos y un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T11:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas\",\"datePublished\":\"2024-04-30T11:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\"},\"wordCount\":841,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\",\"name\":\"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T11:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias","og_description":"(CNN) &#8212; La Guardia Costera de China\u00a0dispar\u00f3 ca\u00f1ones de agua que da\u00f1aron un barco filipino este martes, marcando el \u00faltimo estallido de violencia entre los dos pa\u00edses en el disputado Mar de China Meridional, dijeron las autoridades filipinas. La Guardia Costera de Filipinas dijo que el incidente ocurri\u00f3 cuando uno de sus barcos y un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-30T11:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/"},"author":{"name":"","@id":""},"headline":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas","datePublished":"2024-04-30T11:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/"},"wordCount":841,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","name":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T11:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un ca\u00f1\u00f3n de agua chino da\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T11:03:39Z","datePublished":"2024-04-30T11:03:39Z","dateModified":"2024-04-30T11:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un ca\\u00f1\\u00f3n de agua chino da\\u00f1a un barco en un nuevo incendio en el Mar de China Meridional, dice Filipinas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/canon-agua-chino-dana-barco-mar-china-meridional-filipinas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T11:03:39Z\",\"datePublished\":\"2024-04-30T11:03:39Z\",\"dateModified\":\"2024-04-30T11:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465408,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/12\/exceso-china-disputa-filipinas-trax\/","url_meta":{"origin":1448691,"position":0},"title":"El &#171;exceso&#187; de China en disputa con Filipinas da\u00f1\u00f3 dos de sus propios buques. Por qu\u00e9 pudo ser mucho peor","author":"","date":"agosto 12, 2025","format":false,"excerpt":"Es dif\u00edcil calificar de \u201cafortunada\u201d la colisi\u00f3n de dos buques militares de varios miles de toneladas, pero as\u00ed exactamente consideran los analistas el incidente de esta semana en el Mar de China Meridional que dej\u00f3 a un barco de la Guardia Costera de China con la proa gravemente da\u00f1ada tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450546,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/20\/filipinas-acusa-china-armas-blancas-mar-china-meridional-trax\/","url_meta":{"origin":1448691,"position":1},"title":"&#171;S\u00f3lo los piratas hacen esto&#187;: Filipinas acusa a China de utilizar armas blancas en una importante escalada en el mar de China Meridional","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Filipinas acus\u00f3 a la Guardia Costera de China de lanzar un \"asalto brutal\" con armas blancas durante un enfrentamiento en el mar de China Meridional a principios de esta semana, una escalada importante en una disputa que amenaza con arrastrar a Estados Unidos a otro conflicto global.Las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448014,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/12\/biden-japon-filipinas-compromiso-tensiones-trax\/","url_meta":{"origin":1448691,"position":2},"title":"Biden afirma que los compromisos de defensa de EE.UU. con Jap\u00f3n y Filipinas est\u00e1n &#171;blindados&#187; al presidir una reuni\u00f3n clave en medio de las tensiones con China","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN) -- El compromiso de Estados Unidos con la defensa de Jap\u00f3n y Filipinas sigue estando \"blindado\", declar\u00f3 el jueves el presidente Joe Biden al recibir a los l\u00edderes de esos pa\u00edses en medio de sus disputas territoriales con China.Biden fue el anfitri\u00f3n de la primera cumbre trilateral entre los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447894,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/09\/analisis-china-unidad-eeuu-japon-filipinas-trax\/","url_meta":{"origin":1448691,"position":3},"title":"AN\u00c1LISIS | Las inquietudes sobre China aportan una nueva unidad a la relaci\u00f3n, otrora turbulenta, entre EE.UU., Jap\u00f3n y Filipinas, de cara a una importante cumbre de la Casa Blanca","author":"","date":"abril 9, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- Colonizaci\u00f3n, derramamiento de sangre, cr\u00edmenes de guerra, ocupaci\u00f3n, bases militares controvertidas. Todos estos son temas imbricados en la historia colectiva de Estados Unidos, Jap\u00f3n y Filipinas.Pero cuando los l\u00edderes de los tres pa\u00edses se sienten en la Casa Blanca el jueves, un tema clave\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445842,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/21\/guardia-costera-china-provoco-panico-taiwan-trax\/","url_meta":{"origin":1448691,"position":4},"title":"La guardia costera china caus\u00f3 el &#171;p\u00e1nico&#187; en Taiw\u00e1n. Esto es solo una parte del plan de Beijing","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- King Xia, un barco tur\u00edstico taiwan\u00e9s, llevaba a 23 pasajeros en un viaje por las islas Kinmen, en las afueras de Taiw\u00e1n, a solo kil\u00f3metros de la costa sureste de China, cuando fue interceptado por dos barcos de la guardia costera china.Seis oficiales chinos subieron a bordo y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445760,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/21\/la-guardia-costera-china-provoco-el-panico-en-taiwan-esto-es-solo-una-parte-del-plan-de-beijing\/","url_meta":{"origin":1448691,"position":5},"title":"La guardia costera china provoc\u00f3 el &#171;p\u00e1nico&#187; en Taiw\u00e1n. Esto es solo una parte del plan de Beijing","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- King Xia, un barco tur\u00edstico taiwan\u00e9s, llevaba a 23 pasajeros en un viaje por las islas Kinmen, en las afueras de Taiw\u00e1n, a solo kil\u00f3metros de la costa sureste de China, cuando fue interceptado por dos barcos de la guardia costera china.Seis oficiales chinos subieron a bordo y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448691"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448691\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}