{"id":1448709,"date":"2024-04-30T16:03:43","date_gmt":"2024-04-30T23:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/"},"modified":"2024-04-30T16:03:43","modified_gmt":"2024-04-30T23:03:43","slug":"que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","title":{"rendered":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Las tensiones entre M\u00e9xico y Ecuador siguen latentes, y las \u00faltimas 24 horas son prueba de ello. El lunes, el Gobierno ecuatoriano present\u00f3 ante la Corte Internacional de Justicia (CIJ) una demanda contra M\u00e9xico, al que acusa de violaciones a convenciones, acuerdos y obligaciones internacionales tras haber recibido como hu\u00e9sped en su embajada en Quito en diciembre pasado al exvicepresidente Jorge Glas, a quien posteriormente concedi\u00f3 asilo pol\u00edtico.<\/p>\n<p>En tanto, este martes el Gobierno mexicano present\u00f3 sus argumentos ante la CIJ en la primera audiencia p\u00fablica de su demanda presentada el pasado 11 de abril por la irrupci\u00f3n de la Polic\u00eda de Ecuador en su embajada en Quito el 5 de abril para detener a Glas.<\/p>\n<p>Ante este contexto en el que la demanda mexicana ya est\u00e1 en proceso y la de Ecuador acaba de presentarse, \u00bfqu\u00e9 podr\u00eda pasar?<\/p>\n<p>\u00bfQu\u00e9 dice Ecuador en su demanda ante la CIJ?<\/p>\n<p>Como se se\u00f1al\u00f3 antes, Ecuador acusa a M\u00e9xico ante la CIJ de violaciones a varios tratados internacionales por dar asilo pol\u00edtico a Glas, sobre quien pesan dos condenas en firme por delitos de corrupci\u00f3n y un proceso por peculado con orden de prisi\u00f3n preventiva.<\/p>\n<p>Seg\u00fan Ecuador, su demanda pretende que se declare que M\u00e9xico incumpli\u00f3 con leyes y reglamentos que solicitan la no intervenci\u00f3n de los Estados en asuntos internos y no utilizar la legaci\u00f3n diplom\u00e1tica para funciones incompartibles con sus funciones, como otorgar asilo a personas procesadas por corrupci\u00f3n.<\/p>\n<p>Ecuador considera que M\u00e9xico ha violado el art\u00edculo 41 de la Convenci\u00f3n de Viena sobre Relaciones Diplom\u00e1ticas de 1961; el art\u00edculo 3 de la Convenci\u00f3n sobre Asilo Diplom\u00e1tico de 1954; el art\u00edculo 1 de la Convenci\u00f3n sobre Asilo Pol\u00edtico de 1933; la Carta de las Naciones Unidas; la Carta de la Organizaci\u00f3n de Estados Americanos; el art\u00edculo 14 de la Convenci\u00f3n Interamericana contra la Corrupci\u00f3n de 1966, y los art\u00edculos 43, 46 y 48 de la Convenci\u00f3n de la ONU contra la Corrupci\u00f3n de 2003, entre otros instrumentos internacionales y el derecho consuetudinario.<\/p>\n<p>CNN solicit\u00f3 al Gobierno mexicano comentarios sobre la demanda y est\u00e1 a la espera de una respuesta. La canciller de M\u00e9xico, Alicia B\u00e1rcena, ha rechazado \u201ccontundentemente\u201d las acusaciones de actuaci\u00f3n ilegal de M\u00e9xico en el caso de Glas, al insistir en que se ci\u00f1eron al derecho internacional sobre asilo diplom\u00e1tico.<\/p>\n<p>\u00bfQu\u00e9 sigue despu\u00e9s de la presentaci\u00f3n de la demanda?<\/p>\n<p>Tal como en el caso de la demanda que present\u00f3 M\u00e9xico, lo que ahora viene en la demanda de Ecuador ser\u00e1 un proceso en dos fases, confirm\u00f3 a CNN Myrhge Spross B\u00e1rcenas, acad\u00e9mica de derecho internacional en la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) y doctorada en Derecho.<\/p>\n<p>Fase escrita: aqu\u00ed se incluye la presentaci\u00f3n de la demanda y r\u00e9plicas de ambos pa\u00edses.<br \/>\nFase oral: una vez concluida la primera fase, sigue la presentaci\u00f3n oral de los alegatos de cada pa\u00eds a trav\u00e9s de audiencias.<\/p>\n<p>Cuando culminen ambas fases, la CIJ se toma un tiempo para deliberar y dar su sentencia final. A continuaci\u00f3n puedes leer a detalle c\u00f3mo es todo el proceso:<\/p>\n<p>\u00bfQu\u00e9 pasar\u00eda si la denuncia de M\u00e9xico contra Ecuador ante la CIJ procede?<\/p>\n<p>Para que lleguemos hasta la sentencia, no hay un tiempo espec\u00edfico e incluso se podr\u00eda demorar meses, dijo Spross B\u00e1rcenas.<\/p>\n<p>Tomemos el caso de la demanda de M\u00e9xico como un ejemplo de lo anterior. La querella se present\u00f3 desde el 11 de abril y ahora, luego de tres semanas, nos encontramos en la primera audiencia para los alegatos de la fase oral. (La segunda audiencia ser\u00e1 este mi\u00e9rcoles 1 de mayo y en ella Ecuador presentar\u00e1 sus alegatos).<\/p>\n<p>\u00bfQu\u00e9 podr\u00eda pasar si la denuncia de Ecuador ante la CIJ procede?<\/p>\n<p>En caso de que la CIJ le d\u00e9 la raz\u00f3n a Ecuador, la sentencia podr\u00eda contener varios puntos, entre ellos:<\/p>\n<p>Disculpa diplom\u00e1tica por escrito y ante la Asamblea General de la ONU.<br \/>\nReparaci\u00f3n del da\u00f1o e indemnizaci\u00f3n.<br \/>\nRestablecimiento de las relaciones bajo ciertos t\u00e9rminos.<br \/>\nMedidas de satisfacci\u00f3n (mejoras a la embajada, cubrir costos de algunos eventos).<br \/>\nGarant\u00edas de no repetici\u00f3n.<\/p>\n<p>La resoluci\u00f3n de la CIJ es inapelable y vinculante, lo que significa que cada pa\u00eds decide voluntariamente acatar la decisi\u00f3n de la Corte.<\/p>\n<p>En materia internacional, indica Spross B\u00e1rcenas, lo vinculante se refiere a que &#171;el Estado, desde que se somete a la decisi\u00f3n de la Corte, es su voluntad acatar lo que se decide. Por eso hay un v\u00ednculo, se crea un v\u00ednculo entre los Estados y la Corte\u201d.<\/p>\n<p>Sin embargo, a final de cuentas podr\u00edan incumplir la resoluci\u00f3n, como ocurri\u00f3 a finales del a\u00f1o pasado,\u00a0cuando la CIJ fall\u00f3 a favor de Guyana\u00a0y orden\u00f3 al gobierno del presidente de Venezuela, Nicol\u00e1s Maduro, abstenerse de tomar medidas que agravaran el diferendo sobre el Esequibo, pero\u00a0Venezuela de cualquier forma decidi\u00f3 seguir adelante\u00a0con un referendo para consultar a su poblaci\u00f3n por los derechos que dice tener sobre dicho territorio.<\/p>\n<p>&#171;Dos casos diferentes&#187;<\/p>\n<p>Debido a que la demanda de M\u00e9xico se present\u00f3 antes, la sentencia de la CIJ llegar\u00e1 primero para ese caso.<\/p>\n<p>Teniendo esto en cuenta, \u00bfse ver\u00e1 afectada la demanda de Ecuador? La acad\u00e9mica de la UNAM dijo que no, pues se trata de casos independientes.<\/p>\n<p>&#171;Son dos casos diferentes para la Corte, se deber\u00e1 realizar todo el procedimiento nuevamente para que se dicte una sentencia espec\u00edfica para ese caso (el de Ecuador)&#187;, dijo Spross B\u00e1rcenas a CNN.<\/p>\n<p>&#171;El caso que expuso M\u00e9xico se refiere solamente a la violaci\u00f3n de la Convenci\u00f3n de Viena sobre asuntos diplom\u00e1ticos. El caso de Ecuador es sobre la violaci\u00f3n de la Convenci\u00f3n de Caracas sobre asilo diplom\u00e1tico&#187;, agreg\u00f3.<\/p>\n<p>&#8212; Con informaci\u00f3n de Ana Mar\u00eda Ca\u00f1izares e Ivonne Vald\u00e9s, de CNN en Espa\u00f1ol.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Las tensiones entre M\u00e9xico y Ecuador siguen latentes, y las \u00faltimas 24 horas son prueba de ello. El lunes, el Gobierno ecuatoriano present\u00f3 ante la Corte Internacional de Justicia (CIJ) una demanda contra M\u00e9xico, al que acusa de violaciones a convenciones, acuerdos y obligaciones internacionales tras haber recibido como hu\u00e9sped en su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448709","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Las tensiones entre M\u00e9xico y Ecuador siguen latentes, y las \u00faltimas 24 horas son prueba de ello. El lunes, el Gobierno ecuatoriano present\u00f3 ante la Corte Internacional de Justicia (CIJ) una demanda contra M\u00e9xico, al que acusa de violaciones a convenciones, acuerdos y obligaciones internacionales tras haber recibido como hu\u00e9sped en su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T23:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?\",\"datePublished\":\"2024-04-30T23:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\"},\"wordCount\":1058,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\",\"name\":\"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T23:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Las tensiones entre M\u00e9xico y Ecuador siguen latentes, y las \u00faltimas 24 horas son prueba de ello. El lunes, el Gobierno ecuatoriano present\u00f3 ante la Corte Internacional de Justicia (CIJ) una demanda contra M\u00e9xico, al que acusa de violaciones a convenciones, acuerdos y obligaciones internacionales tras haber recibido como hu\u00e9sped en su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-30T23:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?","datePublished":"2024-04-30T23:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/"},"wordCount":1058,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","name":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T23:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de Ecuador contra M\u00e9xico ante la CIJ procede?","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T23:03:43Z","datePublished":"2024-04-30T23:03:43Z","dateModified":"2024-04-30T23:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 pasar\\u00eda si la denuncia de Ecuador contra M\\u00e9xico ante la CIJ procede?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/que-pasaria-si-denuncia-ecuador-mexico-cij-procede-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T23:03:43Z\",\"datePublished\":\"2024-04-30T23:03:43Z\",\"dateModified\":\"2024-04-30T23:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449563,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/17\/corte-internacional-justicia-anunciara-medidas-provisionales-mexico-ecuador-orix\/","url_meta":{"origin":1448709,"position":0},"title":"Corte Internacional de Justicia anunciar\u00e1 el 23 de mayo decisi\u00f3n sobre medidas provisionales pedidas por M\u00e9xico contra Ecuador","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Corte Internacional de Justicia (CIJ) en La Haya anunciar\u00e1 el 23 de mayo su decisi\u00f3n sobre las medidas provisionales que M\u00e9xico pidi\u00f3 contra Ecuador por la irrupci\u00f3n a su embajada en Quito, de acuerdo con un comunicado difundido este viernes.Este pedido de medidas se origin\u00f3 por el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448699,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/mexico-ecuador-argumentos-cij-orix\/","url_meta":{"origin":1448709,"position":1},"title":"M\u00e9xico presenta argumentos ante la Corte Internacional de Justicia en caso contra Ecuador","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una delegaci\u00f3n de M\u00e9xico present\u00f3 este martes sus argumentos ante la Corte Internacional de Justicia (CIJ), en la primera audiencia p\u00fablica por la irrupci\u00f3n de la Polic\u00eda de Ecuador en la Embajada de M\u00e9xico en Quito el 5 de abril.Alejandro Celorio Alc\u00e1ntara, consultor jur\u00eddico de la Secretar\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447931,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/10\/que-pasaria-denuncia-mexico-ecuador-cij-procede-orix\/","url_meta":{"origin":1448709,"position":2},"title":"\u00bfQu\u00e9 pasar\u00eda si la denuncia de M\u00e9xico contra Ecuador ante la CIJ procede?","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e9xico rompi\u00f3 sus relaciones diplom\u00e1ticas con Ecuador el viernes 5 de abril, luego de que la Polic\u00eda ecuatoriana irrumpi\u00f3 en la embajada mexicana en Quito para capturar al exvicepresidente Jorge Glas, quien hab\u00eda recibido asilo de M\u00e9xico y se encontraba a la espera de un salvoconducto para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448033,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/12\/amlo-demanda-ecuador-no-queremos-vivir-mundo-gorilas-orix\/","url_meta":{"origin":1448709,"position":3},"title":"L\u00f3pez Obrador se refiere a demanda contra Ecuador: &#171;No queremos vivir en un mundo de gorilas, con todo respeto a los gorilas&#187;","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, se refiri\u00f3 este viernes a la espera de la resoluci\u00f3n sobre la demanda contra Ecuador que su pa\u00eds present\u00f3 ante la Corte Internacional de Justicia por la irrupci\u00f3n de la polic\u00eda en la Embajada de M\u00e9xico en Quito durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448042,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/12\/mexico-formaliza-denuncia-onu-ecuador-embajada-orix\/","url_meta":{"origin":1448709,"position":4},"title":"M\u00e9xico formaliza denuncia ante la ONU por violaciones de Ecuador a su embajada en Quito","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de M\u00e9xico present\u00f3 este viernes al secretario General de Naciones Unidas una denuncia en la que acusa violaciones del Gobierno de Ecuador por la irrupci\u00f3n de sus fuerzas de seguridad en la embajada mexicana en Quito, inform\u00f3 la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico.El documento contiene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448034,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/12\/jorge-glas-denuncia-golpes-detencion-ecuador-orix\/","url_meta":{"origin":1448709,"position":5},"title":"Jorge Glas denuncia que fue golpeado durante su detenci\u00f3n tras la irrupci\u00f3n de la Polic\u00eda de Ecuador en la Embajada de M\u00e9xico en Quito","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Jorge Glas, exvicepresidente de Ecuador, denunci\u00f3 el jueves que fue golpeado durante su detenci\u00f3n tras la irrupci\u00f3n de la Polic\u00eda a la Embajada de M\u00e9xico en Quito el viernes 5 de abril. Glas hizo su declaraci\u00f3n desde la prisi\u00f3n v\u00eda internet, durante la primera parte de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448709"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448709\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}