{"id":1448711,"date":"2024-04-30T17:03:38","date_gmt":"2024-05-01T00:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/"},"modified":"2024-04-30T17:03:38","modified_gmt":"2024-05-01T00:03:38","slug":"zapatillas-samba-retro-adidas-estantes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","title":{"rendered":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro"},"content":{"rendered":"<p>(CNN) &#8212; Las zapatillas Samba y Gazelle de Adidas pueden parecer de otra d\u00e9cada, pero son el calzado m\u00e1s popular a la venta en este momento.<\/p>\n<p>La empresa alemana de ropa deportiva dijo que las ventas de zapatillas de estilo retro son &#171;muy fuertes y est\u00e1n creciendo&#187;, lo que ayud\u00f3 a aumentar la ganancia del primer trimestre de la empresa, que todav\u00eda trata de encontrar su equilibrio tras la disoluci\u00f3n de su asociaci\u00f3n comercial con el rapero Ye.<\/p>\n<p>Impulsada por el \u00e9xito de esas zapatillas, adem\u00e1s de una mayor demanda de su calzado para correr, jugar baloncesto y f\u00fatbol, \u200b\u200bAdidas registr\u00f3 una ganancia neta de alrededor de US$ 182 millones durante los primeros tres meses de 2024, un fuerte cambio con respecto al mismo per\u00edodo del a\u00f1o pasado cuando inform\u00f3 una p\u00e9rdida de US$ 26 millones.<\/p>\n<p>El cambio que Adidas har\u00e1 en la camiseta de Alemania por el dise\u00f1o que se asemeja a un s\u00edmbolo nazi<\/p>\n<p>La historia de las zapatillas Samba se remonta a la d\u00e9cada de 1950, cuando las usaba un equipo de f\u00fatbol alem\u00e1n que buscaba un zapato duradero para jugar en zonas heladas y nevadas. Si bien el dise\u00f1o real se moderniz\u00f3, las tres rayas se convirtieron en un s\u00edmbolo caracter\u00edstico de Adidas.<\/p>\n<p>Las zapatillas Gazelle, que tambi\u00e9n tienen las tres rayas, datan de la d\u00e9cada de 1960 y fueron dise\u00f1adas originalmente para deportes de interior antes de transformarse en uno de los pares de zapatos m\u00e1s reconocidos.<\/p>\n<p>En particular, las ventas en Europa se dispararon un 14% y Adidas tambi\u00e9n tuvo una fuerte demanda de sus productos en China y Am\u00e9rica Latina. Norteam\u00e9rica fue un punto delicado para la marca, ya que los ingresos cayeron un 4% debido al exceso de stock en los comercios minoristas.<\/p>\n<p>&#171;Los mercados siguen siendo vol\u00e1tiles y no son f\u00e1ciles, pero sentimos que estamos progresando en todas partes&#187;, dijo el director ejecutivo de Adidas, Bj\u00f8rn Gulden, en un comunicado. &#171;Continuaremos &#8216;invirtiendo de m\u00e1s\u2019 en el producto, la marca, las ventas y el marketing para garantizar un crecimiento continuo&#187;.<\/p>\n<p>Reci\u00e9n salidos del horno: Adidas lanza unos zapatos inspirados en un tradicional pan mexicano<\/p>\n<p>Adidas confirm\u00f3 su perspectiva positiva para 2024, particularmente con los principales eventos deportivos por delante, incluidos la Eurocopa 2024 y la Copa Am\u00e9rica de f\u00fatbol, \u200b\u200badem\u00e1s de los Juegos Ol\u00edmpicos.<\/p>\n<p>Su rival Nike recientemente consigui\u00f3 los derechos para ser el proveedor oficial de uniformes para las selecciones nacionales de f\u00fatbol alemanas desde 2027 hasta 2034, y le puso fin abruptamente a m\u00e1s de siete d\u00e9cadas de asociaci\u00f3n de este deporte con Adidas, que abarc\u00f3 cuatro victorias de la selecci\u00f3n masculina en la Copa del Mundo.<\/p>\n<p>El a\u00f1o pasado, Adidas sufri\u00f3 una p\u00e9rdida anual inusual, afectada por las consecuencias de su costosa ruptura con el rapero Ye, las d\u00e9biles ventas en Norteam\u00e9rica y una enorme factura fiscal.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las zapatillas Samba y Gazelle de Adidas pueden parecer de otra d\u00e9cada, pero son el calzado m\u00e1s popular a la venta en este momento. La empresa alemana de ropa deportiva dijo que las ventas de zapatillas de estilo retro son &#171;muy fuertes y est\u00e1n creciendo&#187;, lo que ayud\u00f3 a aumentar la ganancia del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448711","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las zapatillas Samba y Gazelle de Adidas pueden parecer de otra d\u00e9cada, pero son el calzado m\u00e1s popular a la venta en este momento. La empresa alemana de ropa deportiva dijo que las ventas de zapatillas de estilo retro son &#171;muy fuertes y est\u00e1n creciendo&#187;, lo que ayud\u00f3 a aumentar la ganancia del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T00:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro\",\"datePublished\":\"2024-05-01T00:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\",\"name\":\"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-01T00:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias","og_description":"(CNN) &#8212; Las zapatillas Samba y Gazelle de Adidas pueden parecer de otra d\u00e9cada, pero son el calzado m\u00e1s popular a la venta en este momento. La empresa alemana de ropa deportiva dijo que las ventas de zapatillas de estilo retro son &#171;muy fuertes y est\u00e1n creciendo&#187;, lo que ayud\u00f3 a aumentar la ganancia del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-01T00:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/"},"author":{"name":"","@id":""},"headline":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro","datePublished":"2024-05-01T00:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","name":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-01T00:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\u00f3n retro","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/04\/30\/zapatillas-samba-retro-adidas-estantes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-01T00:03:38Z","datePublished":"2024-05-01T00:03:38Z","dateModified":"2024-05-01T00:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Adidas incrementa sus ganancias gracias a las zapatillas de inspiraci\\u00f3n retro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/zapatillas-samba-retro-adidas-estantes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/04\\\/30\\\/zapatillas-samba-retro-adidas-estantes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-01T00:03:38Z\",\"datePublished\":\"2024-05-01T00:03:38Z\",\"dateModified\":\"2024-05-01T00:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462698,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/23\/nike-amazon-subidas-precios-trax\/","url_meta":{"origin":1448711,"position":0},"title":"Nike sube precios y regresa a Amazon","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Nike regresa a Amazon despu\u00e9s de cinco a\u00f1os y aumenta los precios de algunos productos, mientras su nuevo CEO trabaja para revertir la ca\u00edda de ingresos.La marca de ropa anunci\u00f3 en 2019 que retirar\u00eda sus productos de Amazon en Estados Unidos, centr\u00e1ndose en las ventas en su propio sitio web\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456360,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/07\/subasta-zapatos-rubi-judy-garland-28-millones-trax\/","url_meta":{"origin":1448711,"position":1},"title":"Subastan las zapatillas de rub\u00edes de Judy Garland por US$ 28 millones","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"Un par de zapatillas de rub\u00edes de Judy Garland en \u201cEl Mago de Oz\u201d, que fueron robadas de un museo de Minnesota hace casi 20 a\u00f1os, se vendieron en una subasta por US$ 28 millones este s\u00e1bado.La puja se abri\u00f3 en US$ 1,55 millones y subi\u00f3 r\u00e1pidamente. Seg\u00fan la p\u00e1gina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472189,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/03\/14\/zapatos-ansiedad-masculina-trump-rubio-vance-trax\/","url_meta":{"origin":1448711,"position":2},"title":"La ansiedad masculina por el calzado llega al Despacho Oval","author":"","date":"marzo 14, 2026","format":false,"excerpt":"En la Europa medieval, los arist\u00f3cratas desataban modas y esc\u00e1ndalos al usar poulaines, zapatos cuyas puntas alargadas y llamativas pod\u00edan extenderse mucho m\u00e1s all\u00e1 de la longitud natural de sus pies. En el Despacho Oval del presidente Donald Trump, una elecci\u00f3n de estilo llam\u00f3 la atenci\u00f3n esta semana: fotograf\u00edas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466519,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","url_meta":{"origin":1448711,"position":3},"title":"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"El ocho veces campe\u00f3n ol\u00edmpico Usain Bolt es humano como todos nosotros, y admite que, tras su retiro, se queda sin aliento al subir las escaleras.Considerado ampliamente como el mejor velocista de todos los tiempos, este atleta de 39 a\u00f1os, quien a\u00fan ostenta los r\u00e9cords mundiales de los 100 y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443287,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/07\/la-sucia-verdad-sobre-quitarse-los-zapatos-en-la-puerta-de-la-casa\/","url_meta":{"origin":1448711,"position":4},"title":"La &#171;sucia&#187; verdad sobre quitarse los zapatos en la puerta de la casa","author":"","date":"enero 7, 2024","format":false,"excerpt":"(CNN) -- Cuando reciben visitas, los anfitriones preocupados por los g\u00e9rmenes se enfrentan a un dilema: \u00bfdebo pedirles a mis invitados que se quiten los zapatos en la puerta, sobre todo si la reuni\u00f3n es de coctel o formal, o si la invitada es una adicta a los zapatos como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443306,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/07\/la-sucia-verdad-sobre-quitarse-los-zapatos-en-la-puerta-de-la-casa-2\/","url_meta":{"origin":1448711,"position":5},"title":"La &#171;sucia&#187; verdad sobre quitarse los zapatos en la puerta de la casa","author":"","date":"enero 7, 2024","format":false,"excerpt":"(CNN) -- Cuando reciben visitas, los anfitriones preocupados por los g\u00e9rmenes se enfrentan a un dilema: \u00bfdebo pedirles a mis invitados que se quiten los zapatos en la puerta, sobre todo si la reuni\u00f3n es de coctel o formal, o si la invitada es una adicta a los zapatos como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448711"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448711\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}