{"id":1448771,"date":"2024-05-02T05:04:00","date_gmt":"2024-05-02T12:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/"},"modified":"2024-05-02T05:04:00","modified_gmt":"2024-05-02T12:04:00","slug":"jaime-mungia-vida-record-carrera-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","title":{"rendered":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0\u201cEl respeto es mutuo y todos lo saben\u201d, dijo el boxeador\u00a0Jaime\u00a0Mungu\u00eda cuando estuvo frente a su compatriota Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, uno de los pugilistas a los que creci\u00f3 admirando, durante un evento de prensa en marzo.<\/p>\n<p>Mungu\u00eda, oriundo de Tijuana, se enfrentar\u00e1 a \u00c1lvarez este s\u00e1bado en un combate en el que no puede dejar intimidarse frente su experimentado rival si quiere lograr una victoria sobre el campe\u00f3n mundial indiscutido de peso supermediano.<\/p>\n<p>Para Mungu\u00eda, la afici\u00f3n al boxeo podr\u00eda ser un gusto heredado, ya que su padre tuvo una carrera profesional en la categor\u00eda de pesos pesados con dos victorias en 13 combates, de acuerdo con sitios especializados.<\/p>\n<p>Desde joven, Jaime Mungu\u00eda mostr\u00f3 que pod\u00eda llegar m\u00e1s lejos. Destac\u00f3 en su adolescencia en la Olimpiada Nacional, aunque no busc\u00f3 ir a los Juegos Ol\u00edmpicos.<\/p>\n<p>Su debut profesional lleg\u00f3 en 2013, a los 16 a\u00f1os, con una pelea que venci\u00f3 en apenas dos rounds a Manuel Mora. Ese a\u00f1o, dos meses despu\u00e9s, Canelo, con 23 a\u00f1os, ya estaba en Las Vegas enfrentando a Floyd Mayweather Jr.<\/p>\n<p>Mungu\u00eda, diestro y con su postura tradicional ortodoxa en el cuadril\u00e1tero, continuaba progresando sin conocer la derrota y dejando su sello de nocaut.<\/p>\n<p>En 2016 tuvo siete peleas, varias de ellas con rivales m\u00e1s experimentados, y por primera vez combates fuera de Baja California, con duelos en Sonora y Nuevo Le\u00f3n. Su fama iba creciendo y en 2017 tuvo su primer combate en el extranjero, cuando venci\u00f3 a Paul Valenzuela Jr. en dos rounds en Las Vegas.<\/p>\n<p>En 2018 estuvo cerca de conseguir una pelea estelar, cuando fue invitado para ser el rival del kazajo Gennady Golovkin. Sin embargo, la Comisi\u00f3n de Boxeo de Nevada no dio su visto bueno y no le otorg\u00f3 la licencia para el enfrentamiento en Las Vegas, seg\u00fan repasa la biograf\u00eda de Mungu\u00eda en la p\u00e1gina de su copromotora Golden Boy.<\/p>\n<p>Pese a esta situaci\u00f3n, Mungu\u00eda gan\u00f3 ese mismo a\u00f1o su primer t\u00edtulo, el vacante s\u00faper welter (hasta 154 libras, 69,85 kg) del Consejo Mundial de Boxeo (CMB) al vencer en tres rounds al argentino Jos\u00e9 Carlos Paz en Canc\u00fan. Adem\u00e1s, se llev\u00f3 el campeonato mundial s\u00faper welter de la Organizaci\u00f3n Mundial de Boxeo (WBO) en Nueva York ante el estadounidense Sadam Ali.<\/p>\n<p>Mungu\u00eda retuvo el cintur\u00f3n cinco veces hasta que renunci\u00f3 a \u00e9l para subir a la categor\u00eda mediana (hasta 160 libras, 72,56 kg) y buscar nuevas oportunidades.<\/p>\n<p>Varias de sus \u00faltimas peleas las realiz\u00f3 en la categor\u00eda supermediano (hasta 168 libras, 76,2 kg), incluso venci\u00f3, por decisi\u00f3n un\u00e1nime, al experimentado ucraniano Sergiy Derevyanchenko para conquistar el t\u00edtulo vacante de cintur\u00f3n de plata supermediano del CMB, en una de las peleas m\u00e1s importantes de su carrera.<\/p>\n<p>En enero de este a\u00f1o defendi\u00f3 con \u00e9xito esa corona en un combate estelar en Phoenix, Arizona, ante el brit\u00e1nico John Ryder, a quien derrib\u00f3 cuatro veces y le propin\u00f3 su segundo nocaut en 13 a\u00f1os de carrera, algo que no logr\u00f3 \u00c1lvarez cuando lo enfrent\u00f3 hace un a\u00f1o, ya que el triunfo de Canelo fue por decisi\u00f3n un\u00e1nime del jurado tras los 12 rounds.<\/p>\n<p>Con 27 a\u00f1os y 1,83m (10 cent\u00edmetros m\u00e1s que su rival del s\u00e1bado), Jaime Mungu\u00eda se siente preparado para dar el gran salto. Su historial todav\u00eda invicto marca 43 victorias, 34 por nocaut: es decir, casi 4 de cada 5 peleas. Son cinco nocauts menos que \u00c1lvarez, aunque el boxeador tapat\u00edo, de 33 a\u00f1os, tiene 21 peleas m\u00e1s en su historial.<\/p>\n<p>\u201cDisciplina, esfuerzo y perseverancia\u201d son las tres palabras que eligi\u00f3 para definirse en una\u00a0publicaci\u00f3n\u00a0reciente en Instagram. Adem\u00e1s, cuenta con el respaldo de su entrenador, Freddie Roach, que ha estado en la esquina de grandes boxeadores como los ex campeones Manny\u00a0Pacquiao\u00a0o\u00a0Julio C\u00e9sar Ch\u00e1vez Jr.<\/p>\n<p>\u201cEs el mayor compromiso que he tenido en toda mi carrera\u201d, dijo en la conferencia de marzo. \u201cEs una gran oportunidad y la vamos a aprovechar muy bien\u201d, prometi\u00f3<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0\u201cEl respeto es mutuo y todos lo saben\u201d, dijo el boxeador\u00a0Jaime\u00a0Mungu\u00eda cuando estuvo frente a su compatriota Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, uno de los pugilistas a los que creci\u00f3 admirando, durante un evento de prensa en marzo. Mungu\u00eda, oriundo de Tijuana, se enfrentar\u00e1 a \u00c1lvarez este s\u00e1bado en un combate en el que no [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448771","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0\u201cEl respeto es mutuo y todos lo saben\u201d, dijo el boxeador\u00a0Jaime\u00a0Mungu\u00eda cuando estuvo frente a su compatriota Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, uno de los pugilistas a los que creci\u00f3 admirando, durante un evento de prensa en marzo. Mungu\u00eda, oriundo de Tijuana, se enfrentar\u00e1 a \u00c1lvarez este s\u00e1bado en un combate en el que no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T12:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano\",\"datePublished\":\"2024-05-02T12:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\"},\"wordCount\":730,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\",\"name\":\"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T12:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0\u201cEl respeto es mutuo y todos lo saben\u201d, dijo el boxeador\u00a0Jaime\u00a0Mungu\u00eda cuando estuvo frente a su compatriota Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, uno de los pugilistas a los que creci\u00f3 admirando, durante un evento de prensa en marzo. Mungu\u00eda, oriundo de Tijuana, se enfrentar\u00e1 a \u00c1lvarez este s\u00e1bado en un combate en el que no [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-02T12:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano","datePublished":"2024-05-02T12:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/"},"wordCount":730,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","name":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T12:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T12:04:00Z","datePublished":"2024-05-02T12:04:00Z","dateModified":"2024-05-02T12:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es\\u00a0Jaime\\u00a0Mungu\\u00eda? As\\u00ed es la vida, r\\u00e9cord y carrera del boxeador mexicano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/02\\\/jaime-mungia-vida-record-carrera-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/02\\\/jaime-mungia-vida-record-carrera-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T12:04:00Z\",\"datePublished\":\"2024-05-02T12:04:00Z\",\"dateModified\":\"2024-05-02T12:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448885,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","url_meta":{"origin":1448771,"position":0},"title":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano","author":"","date":"mayo 4, 2024","format":false,"excerpt":"(CNN En Espa\u00f1ol) -- El oriundo de Jalisco, M\u00e9xico, Sa\u00fal \"Canelo\" \u00c1lvarez, campe\u00f3n mundial de peso s\u00faper mediano, logr\u00f3 retener sus cuatro cetros tras derrotar a su compatriota Jaime Mungu\u00eda este s\u00e1bado en el T-Mobile Arena de Las Vegas, por decisi\u00f3n un\u00e1nime.Durante los doce rounds de la pelea, los dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448775,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/canelo-alvarez-vs-jaime-munguia-cartelera-horarios-como-ver-combate-en-vivo-trax\/","url_meta":{"origin":1448771,"position":1},"title":"Canelo \u00c1lvarez vs Jaime Mungu\u00eda: cartelera, horarios y c\u00f3mo ver el combate en vivo","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfListo para las celebraciones del 5 de mayo? Si a\u00fan no lo est\u00e1s, prep\u00e1rate porque los mexicanos Sa\u00fal \"Canelo\" \u00c1lvarez y Jaime Mungu\u00eda s\u00ed.Este fin de semana festivo para los mexicanos \u2014sobre todo para los que viven en Estados Unidos\u2014\u00a0traer\u00e1 consigo la esperada pelea entre Canelo y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466485,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/15\/canelo-alvarez-futuro-analisis-boxeo-orix\/","url_meta":{"origin":1448771,"position":2},"title":"\u00bfQu\u00e9 sigue en la carrera de Canelo \u00c1lvarez despu\u00e9s de su derrota ante Terence Crawford?","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"\u201cLa pelea confirma que \u2018Canelo\u2019 ha dejado atr\u00e1s sus mejores tiempos\u201d. Con esa frase contundente contesta al tel\u00e9fono Eduardo Lamaz\u00f3n, toda una leyenda en el an\u00e1lisis de boxeo, casi 48 horas despu\u00e9s de que el p\u00fagil mexicano perdiera con claridad ante el estadounidense Terence Crawford en Las Vegas, cediendo sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452675,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/14\/canelo-alvarez-vs-edgar-berlanga-cartelera-previa-hora-como-ver-en-vivo-orix\/","url_meta":{"origin":1448771,"position":3},"title":"Canelo \u00c1lvarez vs. Edgar Berlanga: cartelera, previa, a qu\u00e9 hora y c\u00f3mo ver en vivo el combate","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Sa\u00fal \u201cCanelo\u201d \u00c1lvarez regresar\u00e1 al ring durante el fin de semana de la Independencia de M\u00e9xico para defender al menos uno de los cinturones de campeonato de peso supermediano.Ahora puedes seguirnos en\u00a0WhatsApp ChannelSe medir\u00e1 el s\u00e1bado 14 de septiembre ante Edgar Berlanga, boxeador estadounidense de 27 a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452684,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/14\/canelo-alvarez-dice-que-esta-100-listo-para-enfrentar-al-invicto-edgar-berlanga-quien-quiere-sorprender-al-mundo\/","url_meta":{"origin":1448771,"position":4},"title":"&#171;Canelo&#187; \u00c1lvarez dice que est\u00e1 &#171;100% listo&#187; para enfrentar al invicto Edgar Berlanga, quien quiere &#171;sorprender al mundo&#187;","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN) -- La superestrella mexicana Sa\u00fal \"Canelo\" \u00c1lvarez pondr\u00e1 en juego sus campeonatos de peso supermediano del Consejo Mundial de Boxeo (WBC, por sus siglas en ingl\u00e9s), la Asociaci\u00f3n Mundial de Boxeo (WBA, por sus siglas en ingl\u00e9s) y la Organizaci\u00f3n Mundial de Boxeo (WBO, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461925,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/03\/pelea-canelo-alvarez-william-scull-cartelera-previa-horarios-como-ver-en-vivo-orix\/","url_meta":{"origin":1448771,"position":5},"title":"Pelea entre Canelo \u00c1lvarez y William Scull: cartelera, previa, horarios y c\u00f3mo ver en vivo","author":"","date":"mayo 3, 2025","format":false,"excerpt":"El multicampe\u00f3n mexicano Sa\u00fal \u201cCanelo\u201d \u00c1lvarez tendr\u00e1 el s\u00e1bado su primera pelea de 2025, en la que enfrentar\u00e1 a otro campe\u00f3n, el cubano William Scull, durante la funci\u00f3n estelar de box en la ANB Arena de Arabia Saudita.Se trata de la primera vez en la que ambos pugilistas se enfrentan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448771"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448771\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}