{"id":1448779,"date":"2024-05-02T14:03:40","date_gmt":"2024-05-02T21:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/"},"modified":"2024-05-02T14:03:40","modified_gmt":"2024-05-02T21:03:40","slug":"derechos-humanos-sentencias-prision-manifestantes-cuba-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","title":{"rendered":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Observatorio Cubano de Derechos Humanos (OCDH) conden\u00f3 las sentencias de hasta 15 a\u00f1os de prisi\u00f3n que un tribunal de Cuba dict\u00f3 contra 13 ciudadanos que, seg\u00fan el OCDH, participaron de las manifestaciones en Nuevitas en 2022. CNN obtuvo una copia de la sentencia, enviada por familiares de los condenados al Observatorio.<\/p>\n<p>El Tribunal Provincial Popular de Camag\u00fcey, una ciudad en el centro-este de la isla, dict\u00f3 las sentencias por hechos que van desde la creaci\u00f3n de grupos en redes sociales para compartir &#171;publicaciones en contra del sistema sociopol\u00edtico&#187;, hasta convocar a &#171;protestas violentas&#187;, publicar &#171;noticias falsas&#187; y vincularse a otros manifestantes mediante grupos de WhatsApp.<\/p>\n<p>La Polic\u00eda cubana arresta a manifestantes que protestan por la escasez generalizada<\/p>\n<p>El Observatorio dice que estas personas sentenciadas participaron en las manifestaciones que se registraron en Nuevitas en agosto de 2022 debido a los cortes de electricidad que &#171;alcanzaban hasta 16 horas&#187;.<\/p>\n<p>El OCDH dice que mantiene contacto con algunos familiares de los sentenciados, a los que les ha sugerido asesor\u00eda legal y brindado apoyo, explic\u00f3 un dirigente del Observatorio a CNN. &#171;Es nuestra labor denunciar estos casos ante instituciones internacionales y gobiernos, y ese es nuestro compromiso y ser\u00e1 nuestra acci\u00f3n&#187;, dijo el director del OCDH.<\/p>\n<p>CNN est\u00e1 intentando contactar a familiares de los detenidos as\u00ed como a la embajada de Cuba en Estados Unidos para obtener una respuesta a los se\u00f1alamientos.<\/p>\n<p>Estados Unidos tambi\u00e9n relacion\u00f3 estas sentencias con las protestas. &#171;La dura sentencia de esta semana de hasta 15 a\u00f1os de prisi\u00f3n para los cubanos que se reunieron pac\u00edficamente en Nuevitas en 2022 es indignante&#187;, se\u00f1al\u00f3 el lunes en X, Brian A. Nichols, subsecretario del Departamento de Estado de EE.UU. para Asuntos del Hemisferio Occidental.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Observatorio Cubano de Derechos Humanos (OCDH) conden\u00f3 las sentencias de hasta 15 a\u00f1os de prisi\u00f3n que un tribunal de Cuba dict\u00f3 contra 13 ciudadanos que, seg\u00fan el OCDH, participaron de las manifestaciones en Nuevitas en 2022. CNN obtuvo una copia de la sentencia, enviada por familiares de los condenados al Observatorio. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448779","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Observatorio Cubano de Derechos Humanos (OCDH) conden\u00f3 las sentencias de hasta 15 a\u00f1os de prisi\u00f3n que un tribunal de Cuba dict\u00f3 contra 13 ciudadanos que, seg\u00fan el OCDH, participaron de las manifestaciones en Nuevitas en 2022. CNN obtuvo una copia de la sentencia, enviada por familiares de los condenados al Observatorio. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T21:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba\",\"datePublished\":\"2024-05-02T21:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\",\"name\":\"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T21:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Observatorio Cubano de Derechos Humanos (OCDH) conden\u00f3 las sentencias de hasta 15 a\u00f1os de prisi\u00f3n que un tribunal de Cuba dict\u00f3 contra 13 ciudadanos que, seg\u00fan el OCDH, participaron de las manifestaciones en Nuevitas en 2022. CNN obtuvo una copia de la sentencia, enviada por familiares de los condenados al Observatorio. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-02T21:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/"},"author":{"name":"","@id":""},"headline":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba","datePublished":"2024-05-02T21:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","name":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T21:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Organizaci\u00f3n de derechos humanos condena sentencias de hasta 15 a\u00f1os de prisi\u00f3n contra manifestantes en Cuba","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/02\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T21:03:40Z","datePublished":"2024-05-02T21:03:40Z","dateModified":"2024-05-02T21:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Organizaci\\u00f3n de derechos humanos condena sentencias de hasta 15 a\\u00f1os de prisi\\u00f3n contra manifestantes en Cuba\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/02\\\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/02\\\/derechos-humanos-sentencias-prision-manifestantes-cuba-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T21:03:40Z\",\"datePublished\":\"2024-05-02T21:03:40Z\",\"dateModified\":\"2024-05-02T21:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470111,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/15\/pospuso-ejecucion-manifestante-iran-soltani-trax\/","url_meta":{"origin":1448779,"position":0},"title":"Familiares dicen que la ejecuci\u00f3n del manifestante iran\u00ed Erfan Soltani fue postergada, y lo atribuyen a la presi\u00f3n de Trump","author":"","date":"enero 15, 2026","format":false,"excerpt":"La familia del manifestante iran\u00ed detenido Erfan Soltani indic\u00f3 que su ejecuci\u00f3n fue pospuesta, mientras que el presidente de Estados Unidos, Donald Trump, dijo que hab\u00eda recibido garant\u00edas de que \u201clas matanzas han cesado\u201d.\u201cNos dijeron que las matanzas en Ir\u00e1n est\u00e1n cesando y que no hay planes de ejecuciones\u201d, declar\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456582,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url_meta":{"origin":1448779,"position":1},"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444645,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/30\/noboa-decreta-la-repatriacion-de-los-extranjeros-que-cumplen-sentencias-en-carceles-de-ecuador\/","url_meta":{"origin":1448779,"position":2},"title":"Noboa decreta la repatriaci\u00f3n de los extranjeros que cumplen sentencias en c\u00e1rceles de Ecuador","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de Ecuador, Daniel Noboa, emiti\u00f3 este lunes un decreto por el que ordena que las personas extranjeras que cumplen sentencia en c\u00e1rceles ecuatorianas sean repatriadas a sus pa\u00edses de origen para que cumplan all\u00ed sus condenas.Pandillas, pistoleros y carteles desbocados: mientras el terror se apodera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455991,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/21\/tribunal-tailandes-condena-muerte-mujer-acusada-asesinatos-en-serie-cianuro-trax\/","url_meta":{"origin":1448779,"position":3},"title":"Un tribunal tailand\u00e9s condena a muerte a una mujer acusada de asesinatos en serie con cianuro","author":"","date":"noviembre 21, 2024","format":false,"excerpt":"(CNN) -- Un tribunal tailand\u00e9s dict\u00f3 la pena de muerte a una mujer acusada de envenenar fatalmente al menos a decenas de personas, el primer fallo en un caso de asesinatos en serie de alto perfil que conmovi\u00f3 a la naci\u00f3n.Sararat Rangsiwuthaporn mat\u00f3 a su amiga el a\u00f1o pasado echando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458322,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/australia-aprueba-penas-prision-delitos-odio-antisemitismo-trax\/","url_meta":{"origin":1448779,"position":4},"title":"Australia introduce penas de prisi\u00f3n obligatorias para delitos de odio tras aumento del antisemitismo","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Australia introdujo leyes estrictas para combatir los cr\u00edmenes de odio, introduciendo sentencias m\u00ednimas obligatorias para una variedad de delitos de terrorismo y la exhibici\u00f3n de s\u00edmbolos de odio, luego de una serie de ataques antisemitas en Sydney y Melbourne.Las nuevas leyes aprobadas este jueves endurecen el castigo por cr\u00edmenes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470844,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/04\/represion-opositores-2025-informe-human-rights-watch-orix\/","url_meta":{"origin":1448779,"position":5},"title":"Detenciones arbitrarias, abusos, intimidaci\u00f3n: la &#171;brutal represi\u00f3n&#187; a opositores prevaleci\u00f3 en Venezuela en 2025, dice HRW","author":"","date":"febrero 4, 2026","format":false,"excerpt":"A lo largo de 2025, mientras el hoy derrocado Nicol\u00e1s Maduro comenzaba su tercer per\u00edodo como presidente de Venezuela, la \u201cbrutal represi\u00f3n\u201d a los opositores pol\u00edticos se mantuvo como un rasgo constante en el pa\u00eds sudamericano, de acuerdo con el reporte anual sobre los derechos humanos en el mundo elaborado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448779"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448779\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}