{"id":1448813,"date":"2024-05-03T05:03:47","date_gmt":"2024-05-03T12:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/"},"modified":"2024-05-03T05:03:47","modified_gmt":"2024-05-03T12:03:47","slug":"enamorarse-cambiar-estados-unidos-riviera-francesa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","title":{"rendered":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa"},"content":{"rendered":"<p>(CNN) &#8212; Ella hab\u00eda viajado a una isla paradis\u00edaca durante unos meses para hacer introspecci\u00f3n. All\u00ed, Niki Benjamin, de EE.UU., descubri\u00f3 que su vida tomar\u00eda una direcci\u00f3n completamente nueva cuando su perro corri\u00f3 hacia un extra\u00f1o.<\/p>\n<p>Todo comenz\u00f3 a finales de 2014, cuando Benjamin, una exejecutiva musical, realiz\u00f3 un largo viaje al destino caribe\u00f1o de St. Martin (Sint Maarten en neerland\u00e9s), uno de sus lugares favoritos, \u201cpara resolver las cosas\u201d.<\/p>\n<p>\u201cA menudo encontr\u00e9 refugio y consuelo, y tom\u00e9 algunas decisiones de vida bastante importantes simplemente por estar de vacaciones (all\u00ed)\u201d, le dice a CNN Travel. &#171;As\u00ed que es como mi lugar seguro&#187;.<\/p>\n<p>Encuentro en la playa<\/p>\n<p>Niki Benjamin conoci\u00f3 a su marido en St. Martin y se mud\u00f3 a St. Maxime en el sur de Francia. Cr\u00e9dito: Niki Benjamin.<\/p>\n<p>Benjamin estaba caminando por la playa con su amado perro Dylan cuando un hombre en un restaurante cercano llam\u00f3 su atenci\u00f3n.<\/p>\n<p>&#171;Lo vi (a Dylan) lamiendo unos zapatos&#187;, le dice Benjamin a CNN Travel. \u201cY luego mir\u00e9 hacia arriba y vi a este hombre que se convirti\u00f3 en mi esposo\u201d.<\/p>\n<p>Benjamin dice que al instante \u201cse sinti\u00f3 muy c\u00f3moda\u201d con Sandro Scarafile, un chef franc\u00e9s que hab\u00eda vivido en el Caribe durante dos d\u00e9cadas.<\/p>\n<p>&#171;No lo sab\u00eda, (pero) hab\u00eda probado su comida antes de conocerlo&#187;, agrega, recordando que estuvieron &#171;siempre juntos&#187; despu\u00e9s de ese encuentro casual.<\/p>\n<p>Ella le dio una pulsera t\u00edpica de M\u00e9xico y \u00e9l nunca se la quit\u00f3. As\u00ed empez\u00f3 la historia de amor de una mexicana y un ucraniano<\/p>\n<p>Ella y Scarafile pasaron alrededor de cuatro meses juntos en St. Martin antes de que Benjamin decidiera irse a Houston, Texas, para cuidar a su anciana madre en agosto de 2015.<\/p>\n<p>\u201c\u00c9l me dijo: &#8216;Yo voy&#8217;\u201d, recuerda Benjamin. \u201cY yo dije: &#8216;Est\u00e1 bien&#8217;\u201d.<\/p>\n<p>Poco despu\u00e9s de llegar a Houston, Scarafile llam\u00f3 a la madre de Benjamin y le dijo que esperaba casarse con su hija.<\/p>\n<p>La pareja se cas\u00f3 en 2015 y vivieron juntos en Houston durante unos ocho a\u00f1os.<\/p>\n<p>Sin embargo, a medida que pas\u00f3 el tiempo y los padres de Scarafile, que viven en Niza, crecieron, sinti\u00f3 la necesidad de estar m\u00e1s cerca de ellos.<\/p>\n<p>Benjamin y Scarafile, que dicen que \u201cHouston nunca fue el final del juego\u201d, comenzaron a considerar seriamente mudarse a Francia.<\/p>\n<p>\u201cSiempre fui una persona con ganas de moverse, explorar y sentir lugares diferentes\u201d, dice Benjamin, quien naci\u00f3 y creci\u00f3 en Nueva York.<\/p>\n<p>Afortunadamente, el hermano de Benjamin se ofreci\u00f3 a mudarse a Houston para ayudar a su madre, y le dio la libertad de mudarse si as\u00ed lo deseaba.<\/p>\n<p>Llamado a la naturaleza<\/p>\n<p>Benjamin vive felizmente en St. Maxime desde hace dos a\u00f1os. Cr\u00e9dito: Niki Benjamin.<\/p>\n<p>Durante una visita al sur de Francia para visitar a los padres de Scarafile en la primavera de 2022, a \u00e9l le ofrecieron un puesto en un restaurante en St. Maxime, situado en la Riviera Francesa, entre St. Tropez y Cannes.<\/p>\n<p>\u201c\u00c9l realmente lo sinti\u00f3 como un &#8216;este es mi momento, necesito estar aqu\u00ed&#8217;, y estuve de acuerdo con \u00e9l\u201d, dice.<\/p>\n<p>Cuando Benjamin condujo para visitar la ciudad, inmediatamente qued\u00f3 impresionada por su belleza y tranquilidad.<\/p>\n<p>\u201cNo sab\u00eda mucho sobre St. Maxime\u201d, admite. \u201cDimos la vuelta y cruzamos el puente, y el agua estaba brillante. Las flores eran tan abundantes. Y me sent\u00ed relajada y tranquila\u201d.<\/p>\n<p>Benjamin qued\u00f3 encantada con el ambiente relajado de la ciudad y se dio cuenta de que era exactamente lo que necesitaba.<\/p>\n<p>&#171;Sent\u00ed el llamado a la naturaleza&#187;, dice. \u201cEl llamado a estar m\u00e1s cerca del mar. Era simplemente un estilo de vida que realmente me gustaba tener\u201d.<\/p>\n<p>Se conocieron en un autob\u00fas Greyhound el d\u00eda de Navidad. Llevan casados 60 a\u00f1os<\/p>\n<p>\u201cAs\u00ed que no fue dif\u00edcil la decisi\u00f3n para m\u00ed. Yo estaba como &#8216;est\u00e1 bien, v\u00e1monos&#8217;. As\u00ed que fue una especie de amor a primera vista\u201d.<\/p>\n<p>Poco despu\u00e9s de esa visita, Benjamin dej\u00f3 a Scarafile en Francia para regresar a Estados Unidos y comenzar con los preparativos para su gran mudanza.<\/p>\n<p>&#171;Acept\u00f3 el trabajo, se aclimat\u00f3 y consigui\u00f3 un apartamento&#187;, dice. \u201cY volv\u00ed, empaqu\u00e9 nuestras cosas y regres\u00e9 aqu\u00ed un mes despu\u00e9s\u201d.<\/p>\n<p>La pareja ha estado viviendo felizmente en St. Maxime junto con Dylan desde entonces.<\/p>\n<p>Seg\u00fan Benjamin, r\u00e1pidamente se corri\u00f3 la voz de que un estadounidense viv\u00eda en la ciudad porque \u201cno hay una gran comunidad de expatriados\u201d, y los locales quedaron fascinados de que alguien de EE.UU. hubiera elegido mudarse all\u00ed.<\/p>\n<p>\u201cMe dicen: &#8216;\u00bfPor qu\u00e9 te mudar\u00edas de Nueva York, Los \u00c1ngeles o Texas para venir aqu\u00ed?&#8217;\u201d, dice. \u201cY yo digo: &#8216;\u00bfPor qu\u00e9 no lo har\u00eda?&#8217;\u201d<\/p>\n<p>Benjamin se ha adaptado a la vida en St. Maxime y destac\u00f3 que poder reducir el ritmo hizo maravillas por su bienestar.<\/p>\n<p>\u201cAqu\u00ed hay un ritmo y una forma de vida diferentes que realmente me llaman la atenci\u00f3n\u201d, explica.<\/p>\n<p>A ritmo lento<\/p>\n<p>\u201cAqu\u00ed hay un ritmo y una forma de vida diferentes que realmente me llaman la atenci\u00f3n\u201d, dice Benjamin. Cr\u00e9dito: Niki Benjamin.<\/p>\n<p>\u201cHay un gran enfoque en la naturaleza. Se celebra. Y me gusta sentirme mucho m\u00e1s arraigada aqu\u00ed gracias a ello\u201d.<\/p>\n<p>Otras de las cosas que m\u00e1s disfruta de vivir en esta pintoresca ciudad, adem\u00e1s de la uni\u00f3n de la comunidad, es el tiempo que todos pasan al aire libre.<\/p>\n<p>\u201cLa gente aqu\u00ed es muy activa hasta los 80 a\u00f1os\u201d, afirma. \u201cTengo vecinos que est\u00e1n acarreando seis paquetes de agua y sus propias compras de la tienda y un peque\u00f1o carrito con ruedas en buen estado de salud. Luego se suben a su bicicleta y se van a nadar al mar.<\/p>\n<p>&#171;Siento que es una gran calidad de vida y no importa la edad que tengas&#187;.<\/p>\n<p>Solo estuvo tres d\u00edas en Par\u00eds, pero conoci\u00f3 al amor de su vida en el metro<\/p>\n<p>Benjamin y Scarafile se trasladaron a una propiedad m\u00e1s grande desde que se mudaron por primera vez a St. Maxime, y ella dice que cuesta aproximadamente un tercio de lo que hab\u00eda estado pagando mientras estaba en EE.UU.<\/p>\n<p>&#171;Es mucho m\u00e1s accesible&#187;, a\u00f1ade. \u201cVivo probablemente a 500 metros del mar, con vistas al r\u00edo, y es s\u00f3lo una fracci\u00f3n del costo de mi alquiler con el que viv\u00eda en ciudades, sin el mar a la vista&#187;.<\/p>\n<p>&#171;Y adem\u00e1s, la comida&#8230; aqu\u00ed todo es un poco m\u00e1s accesible&#187;.<\/p>\n<p>Benjamin tambi\u00e9n descubri\u00f3 que la comida en la regi\u00f3n es m\u00e1s fresca y agreg\u00f3 que el \u00e1rea tiene varios restaurantes con comida casera.<\/p>\n<p>\u201cCuando llegu\u00e9 aqu\u00ed me di cuenta de que autom\u00e1ticamente perd\u00ed mucho exceso de peso, probablemente por estar mucho tiempo al aire libre y simplemente por la calidad de la comida\u201d, a\u00f1ade.<\/p>\n<p>Durante su estad\u00eda en St. Maxime, Benjamin redescubri\u00f3 su amor por el tenis, un pasatiempo que disfrut\u00f3 durante su juventud, y ahora es miembro de un club de tenis local.<\/p>\n<p>Le encanta el hecho de que no parece haber tanta atenci\u00f3n en el trabajo y que la gente est\u00e1 m\u00e1s avocada a conocer los intereses personales de alguien.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Ella hab\u00eda viajado a una isla paradis\u00edaca durante unos meses para hacer introspecci\u00f3n. All\u00ed, Niki Benjamin, de EE.UU., descubri\u00f3 que su vida tomar\u00eda una direcci\u00f3n completamente nueva cuando su perro corri\u00f3 hacia un extra\u00f1o. Todo comenz\u00f3 a finales de 2014, cuando Benjamin, una exejecutiva musical, realiz\u00f3 un largo viaje al destino caribe\u00f1o de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448813","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Ella hab\u00eda viajado a una isla paradis\u00edaca durante unos meses para hacer introspecci\u00f3n. All\u00ed, Niki Benjamin, de EE.UU., descubri\u00f3 que su vida tomar\u00eda una direcci\u00f3n completamente nueva cuando su perro corri\u00f3 hacia un extra\u00f1o. Todo comenz\u00f3 a finales de 2014, cuando Benjamin, una exejecutiva musical, realiz\u00f3 un largo viaje al destino caribe\u00f1o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T12:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa\",\"datePublished\":\"2024-05-03T12:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\"},\"wordCount\":1251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\",\"name\":\"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-03T12:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias","og_description":"(CNN) &#8212; Ella hab\u00eda viajado a una isla paradis\u00edaca durante unos meses para hacer introspecci\u00f3n. All\u00ed, Niki Benjamin, de EE.UU., descubri\u00f3 que su vida tomar\u00eda una direcci\u00f3n completamente nueva cuando su perro corri\u00f3 hacia un extra\u00f1o. Todo comenz\u00f3 a finales de 2014, cuando Benjamin, una exejecutiva musical, realiz\u00f3 un largo viaje al destino caribe\u00f1o de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-03T12:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/"},"author":{"name":"","@id":""},"headline":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa","datePublished":"2024-05-03T12:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/"},"wordCount":1251,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","name":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-03T12:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se enamor\u00f3 de un extra\u00f1o que conoci\u00f3 en la playa y cambi\u00f3 Estados Unidos por la Riviera Francesa","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-03T12:03:47Z","datePublished":"2024-05-03T12:03:47Z","dateModified":"2024-05-03T12:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se enamor\\u00f3 de un extra\\u00f1o que conoci\\u00f3 en la playa y cambi\\u00f3 Estados Unidos por la Riviera Francesa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/enamorarse-cambiar-estados-unidos-riviera-francesa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-03T12:03:47Z\",\"datePublished\":\"2024-05-03T12:03:47Z\",\"dateModified\":\"2024-05-03T12:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470943,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/06\/hermanas-atrapadas-castillo-escocia-trax\/","url_meta":{"origin":1448813,"position":0},"title":"Las hermanas que quedaron atrapadas en un castillo escoc\u00e9s","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Niki Ghofranian contempl\u00f3 la vista desde lo alto de los muros de piedra del castillo de Dunstaffnage, con la esperanza, contra todo pron\u00f3stico, de encontrar una salida.Los muros se alzaban unos 18 metros por encima de la hierba. Saltar ser\u00eda imprudente, quiz\u00e1s fatal.A lo lejos: colinas, lagos, islas. Cerca: bosque,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456302,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/05\/mato-exnovia-florida-captura-mexico-tiktok-trax\/","url_meta":{"origin":1448813,"position":1},"title":"Un hombre mat\u00f3 a su exnovia en Florida. Una publicaci\u00f3n en TikTok condujo a su captura en M\u00e9xico 3 a\u00f1os despu\u00e9s","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"El tel\u00e9fono de Eleni Peca vibr\u00f3 con una llamada que tem\u00eda que nunca llegara.El hombre acusado de matar a su \u00fanica hija, Joana Peca, hace tres a\u00f1os en St. Petersburg, Florida, finalmente hab\u00eda sido capturado. Los alguaciles de EE.UU. lo arrestaron en la Ciudad de M\u00e9xico despu\u00e9s de que un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456471,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/11\/campeonato-espanol-scrabble-espanol-trax\/","url_meta":{"origin":1448813,"position":2},"title":"Gan\u00f3 el campeonato espa\u00f1ol de Scrabble, pero no habla espa\u00f1ol","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Un neozeland\u00e9s aclamado como un fen\u00f3meno del Scrabble se qued\u00f3 con el Campeonato Mundial de Scrabble en espa\u00f1ol, a pesar de que, seg\u00fan se informa, no habla el idioma.Nigel Richards result\u00f3 victorioso en el torneo de este a\u00f1o en Granada, Espa\u00f1a, el mes pasado, inform\u00f3 Reuters, mostrando una vez m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445943,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/22\/muere-hydeia-broadbent-trax\/","url_meta":{"origin":1448813,"position":3},"title":"Muere a los 39 a\u00f1os Hydeia Broadbent, activista contra el VIH\/sida desde su ni\u00f1ez","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN) -- Hydeia Broadbent, conocida por generar consciencia sobre el VIH\/sida desde que era una ni\u00f1a, falleci\u00f3, seg\u00fan anunci\u00f3 su padre en Facebook. Ten\u00eda 39 a\u00f1os.\"Con gran tristeza debo informarles a todos que nuestra querida amiga, mentora e hija Hydeia falleci\u00f3 hoy tras vivir con VIH desde su nacimiento. A\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452908,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/20\/israel-hamas-eden-yerushalmi-hermanas-entrevista-trax\/","url_meta":{"origin":1448813,"position":4},"title":"Hamas retuvo a una reh\u00e9n israel\u00ed en condiciones \u201cinhumanas\u201d bajo Gaza, seg\u00fan cuentan sus hermanas a CNN","author":"","date":"septiembre 20, 2024","format":false,"excerpt":"(CNN) -- Las hermanas de una mujer israel\u00ed secuestrada y asesinada por Hamas han descrito las condiciones \"inhumanas\" en las que estuvo cautiva, y declararon a CNN que vivieron \"una pesadilla\" desde que el ej\u00e9rcito israel\u00ed recuper\u00f3 su cad\u00e1ver en un t\u00fanel subterr\u00e1neo de Gaza.Eden Yerushalmi fue secuestrada en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465773,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/22\/martin-vizcarra-traslado-carcel-comun-peru-orix\/","url_meta":{"origin":1448813,"position":5},"title":"Expresidente Mart\u00edn Vizcarra ser\u00e1 trasladado a una c\u00e1rcel com\u00fan en Per\u00fa","author":"","date":"agosto 22, 2025","format":false,"excerpt":"El Gobierno de Per\u00fa dispuso este viernes el traslado del expresidente Martin Vizcarra Cornejo del establecimiento penal especial de Barbadillo a la penitenciar\u00eda denominada Anc\u00f3n II, en el extremo norte de Lima.Esta decisi\u00f3n se dio a conocer mediante un comunicado oficial, en su cuenta de X, del Instituto Nacional Penitenciario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448813"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448813\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}