{"id":1448814,"date":"2024-05-03T06:03:49","date_gmt":"2024-05-03T13:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/"},"modified":"2024-05-03T06:03:49","modified_gmt":"2024-05-03T13:03:49","slug":"turquia-comercio-israel-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","title":{"rendered":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza"},"content":{"rendered":"<p>(CNN) &#8212; Turqu\u00eda suspendi\u00f3 todas las transacciones de importaci\u00f3n y exportaci\u00f3n con Israel en protesta por la guerra en Gaza.<\/p>\n<p>&#171;Todas las transacciones de importaci\u00f3n y exportaci\u00f3n relacionadas con Israel, incluidos todos los productos, han sido detenidas&#187;, dijo el Ministerio de Comercio de Turqu\u00eda en un comunicado el jueves. &#171;Turqu\u00eda implementar\u00e1 estricta y decisivamente estas nuevas medidas hasta que el Gobierno israel\u00ed permita un flujo ininterrumpido y suficiente de ayuda humanitaria a Gaza&#187;.<\/p>\n<p>Un alto miembro del Gobierno de Israel acus\u00f3 al presidente de Turqu\u00eda, Recep Tayyip Erdogan, de violar acuerdos comerciales \u201cal bloquear puertos para las importaciones y exportaciones israel\u00edes\u201d.<\/p>\n<p>\u201cAs\u00ed es como se comporta un dictador, ignorando los intereses del pueblo y de los empresarios turcos e ignorando los acuerdos comerciales internacionales\u201d, public\u00f3 el ministro de Asuntos Exteriores israel\u00ed, Israel Katz, el jueves X.<\/p>\n<p>El comercio entre Turqu\u00eda e Israel ascendi\u00f3 a US$ 7.000 millones el a\u00f1o pasado, seg\u00fan datos oficiales. Israel estuvo entre los 20 principales destinos de las exportaciones turcas, comprando bienes y servicios por valor de US$ 5.400 millones. Seg\u00fan Reuters, las principales exportaciones turcas a Israel son acero, veh\u00edculos, pl\u00e1sticos, aparatos el\u00e9ctricos y maquinaria.<\/p>\n<p>Mientras tanto, las importaciones de Turqu\u00eda desde Israel ascendieron a US$ 1.600 millones.<\/p>\n<p>Katz a\u00f1adi\u00f3 que hab\u00eda ordenado al director general del Ministerio de Asuntos Exteriores de Israel que \u201cinvolucrara inmediatamente a todas las partes relevantes del Gobierno para crear alternativas para el comercio con Turqu\u00eda, centr\u00e1ndose en la producci\u00f3n local y las importaciones de otros pa\u00edses\u201d.<\/p>\n<p>&#171;Israel surgir\u00e1 con una econom\u00eda fuerte y audaz&#187;, escribi\u00f3.<\/p>\n<p>Las medidas del jueves por parte de Turqu\u00eda siguen a la introducci\u00f3n el mes pasado de restricciones a sus exportaciones a Israel despu\u00e9s de que el Ministro de Relaciones Exteriores turco acus\u00f3 a Israel de negar una solicitud de lanzar ayuda a\u00e9rea a Gaza.<\/p>\n<p>En una declaraci\u00f3n de ese momento, el Ministerio de Comercio conden\u00f3 las acciones de Israel que impiden el acceso a \u201clos alimentos, la atenci\u00f3n m\u00e9dica y los suministros m\u00e1s b\u00e1sicos\u201d para el pueblo de Gaza y dijo que hab\u00eda prohibido la exportaci\u00f3n de 54 productos, incluidos muchos que podr\u00edan ser utilizado para fines militares o de construcci\u00f3n.<\/p>\n<p>Turqu\u00eda es uno de los mayores donantes de ayuda a Gaza, seg\u00fan el Coordinador de Actividades Gubernamentales en los Territorios de Israel.<\/p>\n<p>Israel lanz\u00f3 un ataque militar contra Gaza el 7 de octubre despu\u00e9s de que el grupo militante Hamas, que gobierna el territorio, matara al menos a 1.200 personas en Israel y secuestrara a m\u00e1s de 250. Despu\u00e9s de m\u00e1s de 200 d\u00edas de guerra, los bombardeos israel\u00edes han convertido los barrios en escombros y la amenaza de hambruna acecha.<\/p>\n<p>Los ataques israel\u00edes en Gaza han matado a m\u00e1s de 34.600 palestinos hasta el 1 de mayo, seg\u00fan el Ministerio de Salud de Gaza. De los muertos, aproximadamente siete de cada 10 son mujeres y ni\u00f1os, dijo el ministerio. CNN no puede confirmar las cifras de forma independiente debido a la falta de acceso de los medios internacionales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Turqu\u00eda suspendi\u00f3 todas las transacciones de importaci\u00f3n y exportaci\u00f3n con Israel en protesta por la guerra en Gaza. &#171;Todas las transacciones de importaci\u00f3n y exportaci\u00f3n relacionadas con Israel, incluidos todos los productos, han sido detenidas&#187;, dijo el Ministerio de Comercio de Turqu\u00eda en un comunicado el jueves. &#171;Turqu\u00eda implementar\u00e1 estricta y decisivamente estas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448814","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Turqu\u00eda suspendi\u00f3 todas las transacciones de importaci\u00f3n y exportaci\u00f3n con Israel en protesta por la guerra en Gaza. &#171;Todas las transacciones de importaci\u00f3n y exportaci\u00f3n relacionadas con Israel, incluidos todos los productos, han sido detenidas&#187;, dijo el Ministerio de Comercio de Turqu\u00eda en un comunicado el jueves. &#171;Turqu\u00eda implementar\u00e1 estricta y decisivamente estas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T13:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza\",\"datePublished\":\"2024-05-03T13:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\"},\"wordCount\":561,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\",\"name\":\"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-03T13:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias","og_description":"(CNN) &#8212; Turqu\u00eda suspendi\u00f3 todas las transacciones de importaci\u00f3n y exportaci\u00f3n con Israel en protesta por la guerra en Gaza. &#171;Todas las transacciones de importaci\u00f3n y exportaci\u00f3n relacionadas con Israel, incluidos todos los productos, han sido detenidas&#187;, dijo el Ministerio de Comercio de Turqu\u00eda en un comunicado el jueves. &#171;Turqu\u00eda implementar\u00e1 estricta y decisivamente estas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-03T13:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza","datePublished":"2024-05-03T13:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/"},"wordCount":561,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","name":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-03T13:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-03T13:03:49Z","datePublished":"2024-05-03T13:03:49Z","dateModified":"2024-05-03T13:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Turqu\\u00eda suspende el comercio con Israel por la guerra en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/turquia-comercio-israel-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/turquia-comercio-israel-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-03T13:03:49Z\",\"datePublished\":\"2024-05-03T13:03:49Z\",\"dateModified\":\"2024-05-03T13:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452400,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/03\/organizacion-juvenil-turca-agreden-infantes-marina-estadounidenses-trax\/","url_meta":{"origin":1448814,"position":0},"title":"Miembros de una organizaci\u00f3n juvenil nacionalista de Turqu\u00eda son detenidos tras agredir a infantes de Marina estadounidenses","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 M\u00e1s de una decena de miembros de una organizaci\u00f3n juvenil nacionalista de Turqu\u00eda fueron detenidos en la ciudad turca de Esmirna despu\u00e9s de que, seg\u00fan las autoridades locales, agredieran a dos infantes de Marina estadounidenses.Los infantes de Marina, asignados a la 24\u00aa Unidad Expedicionaria de Marines, estaban en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467754,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/26\/netanyahu-israel-determinara-fuerzas-internacionales-gaza-trax\/","url_meta":{"origin":1448814,"position":1},"title":"Netanyahu afirma que Israel determinar\u00e1 qu\u00e9 fuerzas internacionales pueden entrar en Gaza","author":"","date":"octubre 26, 2025","format":false,"excerpt":"El primer ministro de Israel, Benjamin Netanyahu, declar\u00f3 este domingo que Israel determinar\u00e1 qu\u00e9 fuerzas internacionales considera aceptables para entrar en Gaza despu\u00e9s de la guerra.\u201cIsrael es un pa\u00eds independiente; nuestra pol\u00edtica de seguridad est\u00e1 en nuestras manos\u201d, declar\u00f3 Netanyahu en su discurso inaugural de la reuni\u00f3n semanal de gabinete,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460891,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/04\/06\/netanyahu-trump-aranceles-iran-gaza-trax\/","url_meta":{"origin":1448814,"position":2},"title":"Netanyahu se dirige a Washington para hablar con Trump sobre aranceles, Ir\u00e1n y rehenes en Gaza","author":"","date":"abril 6, 2025","format":false,"excerpt":"El primer ministro de Israel, Benjamin Netanyahu, se dirige a Estados Unidos despu\u00e9s de una visita de cuatro d\u00edas a Hungr\u00eda.Al salir de Budapest, Netanyahu dijo que el lunes ir\u00eda a la Casa Blanca por invitaci\u00f3n del presidente Trump para hablar sobre \u201clos rehenes, la culminaci\u00f3n de la victoria en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456178,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/30\/gaza-peligra-alto-el-fuego-hamas-esfuerzos-estados-unidos-trax\/","url_meta":{"origin":1448814,"position":3},"title":"Disminuyen las esperanzas de alto el fuego en Gaza pese a los renovados esfuerzos de EE.UU. tras la tregua del L\u00edbano","author":"","date":"noviembre 30, 2024","format":false,"excerpt":"(CNN) -- Mientras una tregua entre Israel y Hezbollah ofrece a los libaneses un respiro que necesitan desesperadamente, los palestinos de Gaza se sienten abandonados, a pesar de los renovados esfuerzos de Estados Unidos por poner fin a los combates en el enclave.Durante casi un a\u00f1o, Hezbollah prometi\u00f3 no dejar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470217,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/18\/junta-paz-trump-gaza-pago-1000-millones-trax\/","url_meta":{"origin":1448814,"position":4},"title":"La &#171;Junta de Paz&#187; de Trump para Gaza exigir\u00e1 un pago de US$ 1.000 millones para la membres\u00eda permanente","author":"","date":"enero 18, 2026","format":false,"excerpt":"Los miembros de la \u201cJunta de Paz\u201d del presidente Donald Trump, la comisi\u00f3n que supervisar\u00e1 la reconstrucci\u00f3n de Gaza, recibir\u00e1n un puesto permanente si pagan US$ 1.000 millones, seg\u00fan un funcionario de EE.UU.Todos los fondos recaudados se destinar\u00e1n a la reconstrucci\u00f3n de Gaza, a\u00f1adi\u00f3 el funcionario, se\u00f1alando que \u201cno habr\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456717,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/18\/por-que-otros-paises-atacan-siria-assad-isis-trax\/","url_meta":{"origin":1448814,"position":5},"title":"Por qu\u00e9 las potencias extranjeras siguen apuntando a Siria tras la ca\u00edda del r\u00e9gimen de Assad","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Pese a que Bashar al-Assad y su r\u00e9gimen de a\u00f1os de duraci\u00f3n cay\u00f3 en Siria, el pa\u00eds sigue siendo un campo de batalla para una serie de actores que buscan asegurar sus intereses en lo que puede convertirse en un peligroso vac\u00edo de poder.Mientras el Hayat Tahrir al-Sham (HTS) asume\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448814"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448814\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}