{"id":1448839,"date":"2024-05-03T16:03:45","date_gmt":"2024-05-03T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/"},"modified":"2024-05-03T16:03:45","modified_gmt":"2024-05-03T23:03:45","slug":"donde-protestas-universitarias-propalestinas-mundo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","title":{"rendered":"Se realizan protestas universitarias propalestinas alrededor del mundo"},"content":{"rendered":"<p>(CNN) &#8212; Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas.<\/p>\n<p>M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados debates sobre el derecho a la protesta, los l\u00edmites de la libertad de expresi\u00f3n y las acusaciones de antisemitismo.<\/p>\n<p>Pero mientras los enfrentamientos con la polic\u00eda en la Universidad de Columbia (Nueva York), la Universidad de Estatal de Portland y la Universidad de California en Los \u00c1ngeles (UCLA) han acaparado la atenci\u00f3n mundial, tambi\u00e9n se est\u00e1n celebrando manifestaciones y sentadas en universidades de Europa, Asia y Medio Oriente.<\/p>\n<p>Primero COVID, ahora protestas, estos egresados de la Universidad del Sur de California nunca han tenido una graduaci\u00f3n tradicional<\/p>\n<p>Y aunque las demandas de los manifestantes var\u00edan en cada universidad, la mayor\u00eda de las manifestaciones han pedido que las universidades desinviertan de las empresas que apoyan a Israel y la guerra en Gaza.<\/p>\n<p>La guerra actual comenz\u00f3 el 7 de octubre, cuando militantes de Hamas mataron a m\u00e1s de 1.200 personas en el sur de Israel y tomaron como rehenes a m\u00e1s de 200 personas. Desde entonces, la respuesta militar de Israel ha desencadenado una cat\u00e1strofe humanitaria en Gaza que ha exacerbado la opini\u00f3n p\u00fablica en todo el mundo.<\/p>\n<p>El bombardeo israel\u00ed de Gaza durante siete meses ha matado a m\u00e1s de 34.600 personas, seg\u00fan el Ministerio de Sanidad de Gaza. La mitad de los 2,2 millones de habitantes de Gaza est\u00e1n al borde de la inanici\u00f3n y la hambruna es inminente, seg\u00fan una escala utilizada por las agencias de Naciones Unidas. Tambi\u00e9n ha aumentado la preocupaci\u00f3n por una operaci\u00f3n militar israel\u00ed prevista en Rafah, al sur de Gaza, lo que ha provocado nuevos llamamientos al alto el fuego.<\/p>\n<p>A continuaci\u00f3n, un repaso a algunas de las protestas propalestinas en los campus universitarios en el mundo.<\/p>\n<p>Australia<\/p>\n<p>En las \u00faltimas semanas han aparecido campamentos de protesta propalestinos en al menos siete universidades de Australia.<\/p>\n<p>La Universidad de Queensland, en Brisbane, se ha convertido en un punto de encuentro de campamentos rivales situados a unos 100 metros el uno del otro: uno poblado por simpatizantes de Students for Palestine UQ, y otro grupo m\u00e1s peque\u00f1o de tiendas con la bandera israel\u00ed, entre otras, colgadas entre los \u00e1rboles.<\/p>\n<p>Fueron instalados en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza y los manifestantes estudiantiles en Estados Unidos, pero algunos grupos jud\u00edos dicen que est\u00e1n causando tensiones innecesarias en el campus y el l\u00edder de la oposici\u00f3n australiana los ha calificado de &#171;racistas&#187; y &#171;antisemitas&#187;.<\/p>\n<p>Students for Palestine UQ quiere que la universidad revele todos sus v\u00ednculos con empresas y universidades israel\u00edes y que corte lazos con empresas de armamento.<\/p>\n<p>Desde el 23 de abril, han surgido campamentos en varios campus universitarios de Australia. (Hilary Whiteman\/CNN)<\/p>\n<p>De momento, las escenas violentas que han estallado en algunas universidades de Estados Unidos no se han repetido en Australia.<\/p>\n<p>En la Universidad de Sydney, unas 50 tiendas de campa\u00f1a se alinean en el cuadril\u00e1tero donde hasta 100 manifestantes duermen cada noche. El 3 de mayo, grupos jud\u00edos organizaron una contraprotesta frente a lo que calificaron de &#171;preocupante tendencia de actividades antisemitas y antiisrael\u00edes&#187; en la universidad.<\/p>\n<p>M\u00e1s de 200 personas, algunas con banderas israel\u00edes y australianas, se congregaron en el campus de Sydney, pero no hubo ning\u00fan encuentro directo con el grupo propalestino, que hab\u00eda instado a sus seguidores a ayudarles a &#171;defender&#187; su campamento.<\/p>\n<p>Reino Unido<\/p>\n<p>Se han realizado protestas propalestinas en universidades de todo el Reino Unido desde los primeros d\u00edas de la guerra de Israel en Gaza, y algunas de ellas han establecido campamentos en los \u00faltimos d\u00edas.<\/p>\n<p>En la Universidad de Newcastle se ha levantado un peque\u00f1o campamento propalestino en un jard\u00edn frente a los edificios de la universidad, seg\u00fan mostraron v\u00eddeos e im\u00e1genes en las redes sociales.<\/p>\n<p>La cuenta en X &#171;Newcastle Apartheid Off Campus&#187; comparti\u00f3 im\u00e1genes de su campamento, que muestra alrededor de una decena de tiendas en el c\u00e9sped, algunas adornadas con banderas palestinas.<\/p>\n<p>Campamento en los terrenos de la Universidad de Newcastle en protesta contra la guerra en Gaza, el 2 de mayo de 2024. (Owen Humphreys\/AP)<\/p>\n<p>El grupo se describe a s\u00ed mismo como una &#171;coalici\u00f3n liderada por estudiantes que lucha por el fin de la asociaci\u00f3n de la Universidad de Newcastle con empresas de defensa que suministran a Israel&#187;.<\/p>\n<p>Estudiantes de las ciudades inglesas de Leeds, Bristol y Warwick tambi\u00e9n han instalado tiendas de campa\u00f1a frente a sus edificios universitarios para protestar por la guerra en Gaza, seg\u00fan la agencia de noticias PA.<\/p>\n<p>Las protestas en los campus del Reino Unido han recibido cr\u00edticas de algunos grupos de estudiantes jud\u00edos, en medio de llamamientos para que las universidades se tomen m\u00e1s en serio su deber de atender a los estudiantes jud\u00edos.<\/p>\n<p>Francia<\/p>\n<p>En Par\u00eds, las protestas propalestinas estallaron en la universidad Sciences Po y en la universidad de la Sorbona a finales de abril.<\/p>\n<p>La polic\u00eda francesa desaloj\u00f3 a los manifestantes de la Sorbona -una de las universidades m\u00e1s prestigiosas del pa\u00eds- el 29 de abril, y un video geolocalizado por CNN muestra a agentes arrastrando a dos manifestantes fuera de las tiendas de campa\u00f1a y por el suelo.<\/p>\n<p>Atormentados por la muerte de sus colegas: los periodistas que arriesgan su vida para informar sobre Gaza<\/p>\n<p>El viernes, la polic\u00eda antidisturbios desaloj\u00f3 la sala principal de Sciences Po, mientras los manifestantes gritaban &#171;\u00a1verg\u00fcenza!&#187; y &#187; \u00a1libertad para Palestina!&#187;, aunque por lo dem\u00e1s el desalojo pareci\u00f3 desarrollarse con calma.<\/p>\n<p>Decenas de estudiantes hab\u00edan iniciado una sentada en el interior de la universidad el d\u00eda anterior, lo que provoc\u00f3 el cierre del campus, dijo un portavoz de Sciences Po. Un manifestante dijo que un estudiante hab\u00eda iniciado una huelga de hambre en protesta por la respuesta de la universidad a &#171;los estudiantes que desean apoyar a Palestina.&#187;<\/p>\n<p>Un video de CNN mostr\u00f3 a los estudiantes portando pancartas que ped\u00edan el fin del &#171;genocidio&#187; en Gaza y el boicot a las universidades israel\u00edes.<\/p>\n<p>La polic\u00eda antidisturbios hace guardia al margen de una manifestaci\u00f3n de estudiantes universitarios en apoyo del pueblo palestino despu\u00e9s de que la polic\u00eda dispersara un campamento improvisado frente a la universidad de la Sorbona en Par\u00eds el 2 de mayo. (Miguel Medina\/AFP\/Getty Images)<\/p>\n<p>Sciences Po es una de las universidades m\u00e1s prestigiosas de Francia y el alma mater de una serie de presidentes, incluido el actual mandatario Emmanuel Macron. Tiene fuertes v\u00ednculos con la Universidad de Columbia, donde los estudiantes han estado organizando protestas generalizadas a favor de Palestina.<\/p>\n<p>&#171;Estamos inspirados por Columbia, Harvard, Yale, UNC, Vanderbilt&#187;, dijo Louise, una estudiante de Sciences Po, a CNN. &#171;Todas estas universidades que se han movilizado, pero nuestra solidaridad sigue siendo ante todo con el pueblo palestino&#187;.<\/p>\n<p>En medio de las protestas, el presidente de la regi\u00f3n de \u00cele-de-France dijo que la universidad dejar\u00e1 de recibir financiaci\u00f3n de la autoridad regional parisina &#171;hasta que se restablezcan la serenidad y la seguridad en la escuela.&#187;<\/p>\n<p>Samuel Lejoyeaux, presidente de la Uni\u00f3n de Estudiantes Jud\u00edos de Francia, pidi\u00f3 m\u00e1s di\u00e1logo entre los manifestantes de ambos lados de la divisi\u00f3n ideol\u00f3gica.<\/p>\n<p>En un art\u00edculo publicado el jueves en el diario Le Monde, afirm\u00f3 que los manifestantes propalestinos deb\u00edan hacer m\u00e1s para &#171;denunciar claramente el antisemitismo&#187;, pero que enviar a la polic\u00eda no era la respuesta.<\/p>\n<p>&#171;Nunca me alegrar\u00e9 de ver a la polic\u00eda antidisturbios entrar en un campus&#187;, escribi\u00f3, y a\u00f1adi\u00f3: &#171;M\u00e1s que nada, creo en el di\u00e1logo. Los grandes avances sociales en Francia siempre han sido fruto de la militancia y el debate&#187;, a\u00f1adi\u00f3.<\/p>\n<p>India<\/p>\n<p>Se han celebrado protestas en la prestigiosa Universidad Jawaharlal Nehru (JNU) de Nueva Delhi, en solidaridad con los estudiantes que protestan en Columbia.<\/p>\n<p>Las protestas coincidieron con una esperada visita al campus del embajador de Estados Unidos en India, Eric Garcetti, que fue aplazada.<\/p>\n<p>&#171;Las instalaciones de la JNU no deben servir de plataforma a administraciones y personal que representen a naciones c\u00f3mplices del terrorismo y el genocidio cometidos por Israel&#187;, dec\u00eda una declaraci\u00f3n del organizaci\u00f3n de estudiantes de la JNU el 29 de abril. El grupo tambi\u00e9n expres\u00f3 su solidaridad con los manifestantes de Columbia.<\/p>\n<p>La JNU, una de las principales universidades de la India, ha estado a la vanguardia de varios movimientos de protesta, incluidas las manifestaciones de 2019 contra una pol\u00e9mica ley que, seg\u00fan los cr\u00edticos, discrimina a los musulmanes.<\/p>\n<p>Dos partidos pol\u00edticos estudiantiles de la Universidad Jamia Milia Islamia de Nueva Delhi tambi\u00e9n expresaron su solidaridad con los manifestantes propalestinos.<\/p>\n<p>&#171;Tambi\u00e9n denunciamos la postura adoptada por nuestro gobierno liderado por el BJP (Partido Bharatiya Janata) al apoyar a Israel, que se desv\u00eda de la posici\u00f3n hist\u00f3rica de la India&#187;, dijo una declaraci\u00f3n de la Federaci\u00f3n de Estudiantes de la India, afiliada al Partido Comunista.<\/p>\n<p>Canad\u00e1<\/p>\n<p>Las protestas contra la guerra de Israel en Gaza se han extendido por los campus de diversos puntos de Canad\u00e1.<\/p>\n<p>En la Universidad McGill, en el centro de Montreal, estudiantes propalestinos han instalado un campamento en el jard\u00edn de entrada.<\/p>\n<p>Al igual que sus hom\u00f3logos estadounidenses, los estudiantes exigen a la universidad que desinvierta de empresas vinculadas a Israel.<\/p>\n<p>Agentes de la polic\u00eda montada pasan junto a activistas propalestinos en un campamento instalado en el campus de la Universidad McGill en Montreal, el 2 de mayo. (Christinne Muschi\/AP)<\/p>\n<p>La universidad ha intentado dispersar a los manifestantes, diciendo que hab\u00eda pedido ayuda a la Polic\u00eda despu\u00e9s de que el di\u00e1logo con los representantes de los estudiantes no llegara a una soluci\u00f3n.<\/p>\n<p>Este jueves, un juez del Tribunal Superior de Quebec rechaz\u00f3 una solicitud de medida cautelar que habr\u00eda obligado a los manifestantes propalestinos a abandonar su campamento.<\/p>\n<p>Los manifestantes propalestinos tambi\u00e9n han instalado campamentos en el campus del centro de la Universidad de Toronto y en la Universidad de Columbia Brit\u00e1nica en Vancouver, entre otros, seg\u00fan la cadena p\u00fablica CBC News.<\/p>\n<p>M\u00e9xico<\/p>\n<p>Estudiantes de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) iniciaron el jueves un campamento en apoyo a los estudiantes en casas de estudios estadounidenses que reclaman el cese al conflicto armado en contra de los palestinos.<\/p>\n<p>Campamento en la UNAM iniciado este jueves (CNN)<\/p>\n<p>La UNAM inform\u00f3 este viernes que, ante el campamento instalado, la casa de estudios ser\u00e1 respetuosa de la protesta siempre que se conduzca con el respeto a los derechos de los dem\u00e1s miembros de la comunidad universitaria.<\/p>\n<p>&#171;Reconocemos la diversidad de pensamiento existente en nuestros campus. En ellos hay muchas y muchos universitarios que coinciden con los manifestantes, pero tambi\u00e9n hay quienes discrepan y pueden llegar a sentirse ofendidos. En este caso debe prevalecer el respeto&#187;, dijo la instituci\u00f3n en un comunicado.<\/p>\n<p>L\u00edbano<\/p>\n<p>Cientos de estudiantes se concentraron a finales de abril en los campus del L\u00edbano, enarbolando banderas palestinas y exigiendo a sus universidades que boicotearan a las empresas que hacen negocios en Israel, inform\u00f3 Reuters.<\/p>\n<p>En la capital, las im\u00e1genes mostraban a estudiantes de la Universidad Americana de Beirut protestando contra la guerra en Gaza ante las puertas.<\/p>\n<p>Algunos manifestantes dijeron que se hab\u00edan inspirado en las protestas de los campus estadounidenses.<\/p>\n<p>&#171;Queremos mostrarle al mundo entero que no hemos olvidado la causa palestina y que la generaci\u00f3n joven, que es consciente y culta, todav\u00eda est\u00e1 con la causa palestina&#187;, dijo Ali al-Muslem, de 19 a\u00f1os, a Reuters.<\/p>\n<p>El ej\u00e9rcito de Israel y los militantes de Hezbollah en el L\u00edbano, respaldados por Ir\u00e1n, han intercambiado disparos de forma rutinaria desde el 7 de octubre. M\u00e1s de 300 personas, en su mayor\u00eda combatientes, han muerto en ataques israel\u00edes. Ocho civiles han muerto en ataques de Hezbollah en el norte de Israel desde octubre pasado.<\/p>\n<p>Con informaci\u00f3n de Jos\u00e9 \u00c1lvarez de CNN en Espa\u00f1ol.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas. M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados debates sobre el derecho [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448839","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas. M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados debates sobre el derecho [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se realizan protestas universitarias propalestinas alrededor del mundo\",\"datePublished\":\"2024-05-03T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\"},\"wordCount\":2101,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\",\"name\":\"Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-03T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se realizan protestas universitarias propalestinas alrededor del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias","og_description":"(CNN) &#8212; Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas. M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados debates sobre el derecho [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-03T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/"},"author":{"name":"","@id":""},"headline":"Se realizan protestas universitarias propalestinas alrededor del mundo","datePublished":"2024-05-03T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/"},"wordCount":2101,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","name":"Se realizan protestas universitarias propalestinas alrededor del mundo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-03T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se realizan protestas universitarias propalestinas alrededor del mundo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se realizan protestas universitarias propalestinas alrededor del mundo","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-03T23:03:45Z","datePublished":"2024-05-03T23:03:45Z","dateModified":"2024-05-03T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se realizan protestas universitarias propalestinas alrededor del mundo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/donde-protestas-universitarias-propalestinas-mundo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/03\\\/donde-protestas-universitarias-propalestinas-mundo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-03T23:03:45Z\",\"datePublished\":\"2024-05-03T23:03:45Z\",\"dateModified\":\"2024-05-03T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448391,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","url_meta":{"origin":1448839,"position":0},"title":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448652,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/universidad-politecnica-california-insta-a-estudiantes-que-participan-en-manifestaciones-a-que-abandonen-el-campus-pacificamente-trax\/","url_meta":{"origin":1448839,"position":1},"title":"Universidad Polit\u00e9cnica de California insta a estudiantes que participan en manifestaciones a que &#171;abandonen el campus pac\u00edficamente ahora&#187;","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- La Universidad Polit\u00e9cnica del Estado de California, Humbolt est\u00e1 pidiendo a los estudiantes que est\u00e1n tomando parte en las manifestaciones en curso y la ocupaci\u00f3n de al menos dos edificios que \"abandonen el campus pac\u00edficamente\".\"Se insta a las personas que est\u00e1n ocupando Siemens Hall y Nelson Hall East,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448359,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/21\/rabino-recomienda-judios-volver-casa-protestas-universidad-columbia-trax\/","url_meta":{"origin":1448839,"position":2},"title":"La Universidad de Columbia enfrenta una grave crisis mientras un rabino pide a los estudiantes jud\u00edos que \u201cregresen a casa\u201d","author":"","date":"abril 21, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia se enfrenta a una crisis en toda regla de cara a la Pascua, cuando un rabino vinculado a la escuela de la Ivy League inst\u00f3 a los estudiantes jud\u00edos a quedarse en casa y los tensos enfrentamientos en el campus generaron la condena de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462697,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/22\/universidad-columbia-violacion-derechos-civiles-trax\/","url_meta":{"origin":1448839,"position":3},"title":"Gobierno de Trump denuncia a la Universidad de Columbia por no proteger a estudiantes jud\u00edos y violar derechos civiles","author":"","date":"mayo 22, 2025","format":false,"excerpt":"La administraci\u00f3n Trump aleg\u00f3 este jueves que la Universidad de Columbia viol\u00f3 la ley federal de derechos civiles al actuar con \u201cindiferencia deliberada\u201d ante el acoso a estudiantes jud\u00edos en el campus desde octubre de 2023.La Oficina de Derechos Civiles del Departamento de Salud y Servicios Humanos de EE.UU. acus\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448457,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/manifestantes-universidad-columbia-fecha-limite-desmantelar-campamento-trax\/","url_meta":{"origin":1448839,"position":4},"title":"Universidad de Columbia extiende negociaciones con estudiantes que protestan por el campamento despu\u00e9s del &#171;di\u00e1logo constructivo&#187; durante la noche","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --La Universidad de Columbia y los estudiantes que protestan continuar\u00e1n las negociaciones sobre el desmantelamiento del campamento propalestino durante las pr\u00f3ximas 48 horas, seg\u00fan un portavoz de la universidad.\"Estamos logrando avances importantes con los representantes del campamento de estudiantes en el c\u00e9sped oeste\", afirm\u00f3 un portavoz de la universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460584,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/29\/katrina-armstrong-renuncia-universidad-columbia-trax\/","url_meta":{"origin":1448839,"position":5},"title":"Renunci\u00f3 la presidenta interina de la Universidad de Columbia una semana despu\u00e9s de anunciar cambios radicales de pol\u00edticas","author":"","date":"marzo 29, 2025","format":false,"excerpt":"La presidenta interina de la Universidad de Columbia dimiti\u00f3, seg\u00fan inform\u00f3 la instituci\u00f3n el viernes, una semana despu\u00e9s de anunciar cambios radicales en su pol\u00edtica, aparentemente cediendo a las exigencias de la administraci\u00f3n Trump condicionadas a la financiaci\u00f3n federal.La Dra. Katrina Armstrong tom\u00f3 el tim\u00f3n de una de las universidades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448839"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448839\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}