{"id":1448874,"date":"2024-05-04T16:03:44","date_gmt":"2024-05-04T23:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/"},"modified":"2024-05-04T16:03:44","modified_gmt":"2024-05-04T23:03:44","slug":"que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","title":{"rendered":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La banda delincuencial El Tren de Aragua se encuentra en el centro de atenci\u00f3n luego de conocerse un documento judicial que consigna las sospechas de la posible presencia en\u00a0Venezuela del l\u00edder de la organizaci\u00f3n.<\/p>\n<p>Seg\u00fan detalla un documento del Tribunal Supremo de Justicia de Venezuela fechado el 21 de marzo de 2024, las autoridades venezolanas creen que H\u00e9ctor Rusthenford Guerrero Flores, conocido como el \u201cNi\u00f1o Guerrero\u201d y l\u00edder de El Tren de Aragua, \u201cpudiera estar refugiado en inmuebles que posee en la ciudad de Valencia, estado Carabobo\u201d, en el centro del pa\u00eds.<\/p>\n<p>Tambi\u00e9n se consigna que el tribunal\u00a0emiti\u00f3 una orden de allanamiento tras la cual se desarroll\u00f3 un operativo en dos viviendas que podr\u00edan ser de la madre y de la pareja de Guerrero Flores, y que en ellas hallaron \u201cevidencias de inter\u00e9s criminal\u00edstico\u201d. El documento no especifica en qu\u00e9 momento se realiz\u00f3 este operativo.<\/p>\n<p>\u00bfQu\u00e9 es El Tren de Aragua?<\/p>\n<p>El Tren de Aragua est\u00e1 catalogada como la banda criminal m\u00e1s grande y poderosa de Venezuela, de acuerdo con informes de la organizaci\u00f3n\u00a0Insight Crime\u00a0y el\u00a0Gobierno de Estados Unidos.<\/p>\n<p>Insight Crime agrega que el origen de esta megabanda, que, al menos hasta el desalojo, ten\u00eda su base en la c\u00e1rcel de Tocor\u00f3n, se remonta al a\u00f1o 2005 con el sindicato de obreros que laboraban en la construcci\u00f3n de un proyecto ferroviario que unir\u00eda a los estados Aragua y Carabobo.<\/p>\n<p>De ah\u00ed su nombre, &#8216;Tren de Aragua&#8217;. De acuerdo con el informe de la ONG, el sindicato comenz\u00f3 cobrando por la asignaci\u00f3n de puestos de trabajo y extorsionaba a contratistas a cambio de seguridad. Gradualmente, fue ampliando sus actividades criminales. En 2013, con el encarcelamiento de H\u00e9ctor Rustherford Guerrero Flores, alias \u201cNi\u00f1o Guerrero\u201d, en la prisi\u00f3n de Tocor\u00f3n, el Tren de Aragua comenz\u00f3 a aliarse con otras bandas criminales para expandir sus dominios. Llegaron a controlar el barrio San Vicente, ubicado en Maracay, la capital del estado Aragua, seg\u00fan Insight Crime y reportes del \u00a0Observatorio Venezolano de Violencia.<\/p>\n<p>En su proyecto de expansi\u00f3n, El Tren de Aragua ha tenido conflictos desde 2017 con bandas como El Tren del Llano en el estado Sucre, en el oriente de Venezuela, por el tr\u00e1fico de drogas al Caribe, seg\u00fan Insight Crime, e incluso con la guerrilla colombiana Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) en el departamento de Norte de Santander, por delitos como la trata de personas.<\/p>\n<p>De hecho, el Gobierno de EE.UU. indica que, seg\u00fan un informe de investigaci\u00f3n publicado este a\u00f1o, El Tren de Aragua y el ELN operan redes de tr\u00e1fico sexual en las fronteras del pueblo de Villa del Rosario, en Norte de Santander.<\/p>\n<p>Transparencia Venezuela, el brazo venezolano de la organizaci\u00f3n no gubernamental Transparencia Internacional, reporta que, desde 2021, El Tren de Aragua se encuentra en conflicto con el ELN por el control de la frontera con Colombia.<\/p>\n<p>Miembros de la Guardia Nacional Bolivariana (GNB) montan guardia mientras los familiares esperan noticias despu\u00e9s de que las autoridades tomaran el control de la prisi\u00f3n de Tocor\u00f3n en Tocor\u00f3n, estado de Aragua, Venezuela, el 20 de septiembre de 2023. (Foto: YURI CORTEZ\/AFP v\u00eda Getty Images)<\/p>\n<p>\u00bfD\u00f3nde opera?<\/p>\n<p>Insight Crime se\u00f1ala que El Tren de Aragua tiene presencia en Colombia, Ecuador, Per\u00fa, Bolivia y Chile.<\/p>\n<p>En tanto, Transparencia Venezuela dice que tambi\u00e9n tiene presencia en Brasil y Costa Rica.<\/p>\n<p>Agrega Transparencia Venezuela que El Tren de Aragua se encuentra en los siguientes estados del pa\u00eds:<\/p>\n<p>Aragua<br \/>\nLara<br \/>\nYaracuy<br \/>\nBol\u00edvar<br \/>\nSucre<br \/>\nMiranda<br \/>\nT\u00e1chira<br \/>\nGu\u00e1rico<br \/>\nCarabobo<br \/>\nTrujillo<br \/>\nApure<br \/>\nZulia<\/p>\n<p>\u00bfQui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y cu\u00e1les son sus principales cr\u00edmenes?<\/p>\n<p>Transparencia Venezuela explica que la organizaci\u00f3n se dedica a la extracci\u00f3n ilegal de minerales, al tr\u00e1fico il\u00edcito de drogas, de armas y de chatarra, al cobro de \u201cla causa\u201d -la cuota que, al parecer, debe pagar cada preso dentro de las c\u00e1rceles venezolanas- al robo, al secuestro y a la trata de personas.<\/p>\n<p>Este \u00faltimo delito, se\u00f1alan tanto la oeneg\u00e9 como Insight Crime, ha potenciado la expansi\u00f3n de El Tren de Aragua, al seguir los pasos de los\u00a0millones de migrantes venezolanos\u00a0hasta otros pa\u00edses.<\/p>\n<p>Transparencia Venezuela asegura que la megabanda criminal tiene m\u00e1s de 4.000 miembros. De entre todos ellos, H\u00e9ctor Rustherford Guerrero Flores, alias \u201cNi\u00f1o Guerrero\u201d, es el principal l\u00edder.<\/p>\n<p>La organizaci\u00f3n explica que se tienen reportes de la carrera delictiva de &#171;Ni\u00f1o Guerrero&#187; desde 2005, cuando fue detenido por el homicidio de un funcionario.<\/p>\n<p>En septiembre de 2012, cuando se encontraba detenido en la c\u00e1rcel de Tocor\u00f3n, se report\u00f3 su fuga. &#171;Ni\u00f1o Guerrero&#187; fue recapturado en 2013 en Barquisimeto, en el centro occidente de Venezuela.<\/p>\n<p>&#171;Seg\u00fan la informaci\u00f3n publicada entonces, ten\u00eda dos meses operando en la regi\u00f3n y cargaba una falsa identidad&#187;, comenta Transparencia Venezuela, y agrega que, si bien se le envi\u00f3 en primera instancia al Centro Penitenciario de Los Llanos, poco despu\u00e9s regres\u00f3 a la c\u00e1rcel de Tocor\u00f3n.<\/p>\n<p>El 15 de diciembre de 2016 un tribunal de juicio del estado Aragua conden\u00f3 a Guerrero a 17 a\u00f1os y dos meses de prisi\u00f3n como responsable de\u00a0doce delitos, entre ellos homicidio intencional, fuga de detenido, ocultamiento de arma de guerra, tr\u00e1fico de drogas y asociaci\u00f3n para delinquir.<\/p>\n<p>Guerrero nunca ha dado entrevistas, ni se ha referido a las condenas de la justicia venezolana.<\/p>\n<p>Insight Crime\u00a0se\u00f1ala que &#171;Ni\u00f1o Guerrero&#187; se encontraba en la prisi\u00f3n de Tocor\u00f3n; sin embargo, habr\u00eda salido del centro penitenciario d\u00edas antes de la operaci\u00f3n del Gobierno, seg\u00fan el Observatorio Venezolano de Prisiones.<\/p>\n<p>El Observatorio Venezolano de Prisiones asegura\u00a0que la operaci\u00f3n del Gobierno para tomar la c\u00e1rcel de Tocor\u00f3n se convers\u00f3 y negoci\u00f3 con antelaci\u00f3n con &#171;Ni\u00f1o Guerrero&#187; y otros colaboradores cercanos, quienes, siempre seg\u00fan esa versi\u00f3n, habr\u00edan salido de la instalaci\u00f3n d\u00edas antes de la toma sin informar a la poblaci\u00f3n penal.<\/p>\n<p>CNN no ha podido verificar este dato de forma independiente.<\/p>\n<p>En una rueda de prensa convocada este jueves, el ministro de Interior, Justicia y Paz, Remigio Ceballos, no respondi\u00f3 a esa versi\u00f3n. Cuando le preguntaron por El Tren de Aragua, el funcionario respondi\u00f3 que en la operaci\u00f3n hab\u00edan capturado a \u201cintegrantes de grupos criminales que operan en el estado Aragua y otras partes del pa\u00eds\u201d. Nunca mencion\u00f3 a la banda por su nombre.<\/p>\n<p>Con informaci\u00f3n de Osmary Hern\u00e1ndez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La banda delincuencial El Tren de Aragua se encuentra en el centro de atenci\u00f3n luego de conocerse un documento judicial que consigna las sospechas de la posible presencia en\u00a0Venezuela del l\u00edder de la organizaci\u00f3n. Seg\u00fan detalla un documento del Tribunal Supremo de Justicia de Venezuela fechado el 21 de marzo de 2024, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448874","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La banda delincuencial El Tren de Aragua se encuentra en el centro de atenci\u00f3n luego de conocerse un documento judicial que consigna las sospechas de la posible presencia en\u00a0Venezuela del l\u00edder de la organizaci\u00f3n. Seg\u00fan detalla un documento del Tribunal Supremo de Justicia de Venezuela fechado el 21 de marzo de 2024, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-04T23:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?\",\"datePublished\":\"2024-05-04T23:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\"},\"wordCount\":1160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\",\"name\":\"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-04T23:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La banda delincuencial El Tren de Aragua se encuentra en el centro de atenci\u00f3n luego de conocerse un documento judicial que consigna las sospechas de la posible presencia en\u00a0Venezuela del l\u00edder de la organizaci\u00f3n. Seg\u00fan detalla un documento del Tribunal Supremo de Justicia de Venezuela fechado el 21 de marzo de 2024, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-04T23:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?","datePublished":"2024-05-04T23:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/"},"wordCount":1160,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","name":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-04T23:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es El Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/04\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-04T23:03:44Z","datePublished":"2024-05-04T23:03:44Z","dateModified":"2024-05-04T23:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es El Tren de Aragua, qui\\u00e9n lo lidera, cu\\u00e1ntos miembros tiene y d\\u00f3nde opera?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/04\\\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/04\\\/que-es-el-tren-de-aragua-quien-lo-lidera-cuantos-miembros-tiene-donde-opera-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-04T23:03:44Z\",\"datePublished\":\"2024-05-04T23:03:44Z\",\"dateModified\":\"2024-05-04T23:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1446983,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/15\/tren-aragua-republicanos-biden-organizacion-criminal-transnacional-orix\/","url_meta":{"origin":1448874,"position":0},"title":"Republicanos piden a Biden designar al Tren de Aragua como organizaci\u00f3n criminal transnacional","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un grupo de legisladores republicanos, 8 senadores y 15 representantes, envi\u00f3 una carta al presidente de Estados Unidos, Joe Biden, para pedirle que designe al Tren de Aragua como una organizaci\u00f3n criminal transnacional. Los principales promotores de la misiva son el senador Marco Rubio y la representante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446408,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/04\/colombia-captura-a-152-miembros-tren-de-aragua-clan-del-golfo-en-operativo-orix-2\/","url_meta":{"origin":1448874,"position":1},"title":"Colombia captura a 152 miembros del Tren de Aragua y el Clan del Golfo en un operativo","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Direcci\u00f3n Antisecuestro y Antiextorsi\u00f3n de la Polic\u00eda de Colombia ejecut\u00f3 este s\u00e1bado 152 \u00f3rdenes de captura durante un operativo simult\u00e1neo en las principales ciudades de Colombia contra miembros de las bandas criminales de Tren de Aragua y el Clan del Golfo.Ahora puedes seguirnos en\u00a0WhatsApp ChannelEl director\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446242,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/03\/colombia-captura-a-152-miembros-tren-de-aragua-clan-del-golfo-en-operativo-orix\/","url_meta":{"origin":1448874,"position":2},"title":"Colombia captura a 152 miembros del Tren de Aragua y el Clan del Golfo en un operativo","author":"","date":"marzo 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Direcci\u00f3n Antisecuestro y Antiextorsi\u00f3n de la Polic\u00eda de Colombia ejecut\u00f3 este s\u00e1bado 152 \u00f3rdenes de captura durante un operativo simult\u00e1neo en las principales ciudades de Colombia contra miembros de las bandas criminales de Tren de Aragua y el Clan del Golfo.El director de la dependencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460020,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/17\/tren-de-aragua-que-es-lider-miembros-donde-opera-orix\/","url_meta":{"origin":1448874,"position":3},"title":"\u00bfQu\u00e9 es el Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?","author":"","date":"marzo 17, 2025","format":false,"excerpt":"La banda delincuencial Tren de Aragua est\u00e1 en el centro de atenci\u00f3n en medio de la ola de redadas antiinmigratorias y deportaciones del Gobierno de Donald Trump en Estados Unidos. El grupo delincuencial fue declarado en febrero por el Departamento de Estado de EE.UU. como una organizaci\u00f3n terrorista y supuestos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446981,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/15\/desalojada-carcel-tocoron-venezuela-se-preguntan-donde-esta-nino-guerrero-orix\/","url_meta":{"origin":1448874,"position":4},"title":"En Venezuela se preguntan d\u00f3nde est\u00e1 \u201cNi\u00f1o Guerrero\u201d, l\u00edder del Tren de Aragua, tras desalojo de la c\u00e1rcel de Tocor\u00f3n","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Aunque sigue envuelto en un halo misterioso, el l\u00edder de la organizaci\u00f3n criminal El Tren de Aragua ya tiene un rostro.El s\u00e1bado las autoridades venezolanas publicaron en X (antes Twitter) un aviso en el que se ofrece una recompensa a quien aporte informaci\u00f3n sobre H\u00e9ctor Guerrero Flores.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464157,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/07\/02\/matan-socio-nino-guerrero-lider-tren-de-aragua-orix\/","url_meta":{"origin":1448874,"position":5},"title":"Matan en Venezuela a socio de Ni\u00f1o Guerrero, l\u00edder del Tren de Aragua","author":"","date":"julio 2, 2025","format":false,"excerpt":"Darwin Jos\u00e9 Mart\u00ednez Oviedo, alias \u201cel Arepita\u201d, socio de H\u00e9ctor Guerrero, conocido como \u201cNi\u00f1o Guerrero\u201d e identificado por las autoridades de Venezuela como cabecilla de la banda delictiva Tren de Aragua, muri\u00f3 este domingo, confirm\u00f3 a CNN una fuente con conocimiento del asunto \u2015sin detallar c\u00f3mo lo mataron.La misma fuente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448874"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448874\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}