{"id":1448890,"date":"2024-05-05T05:03:46","date_gmt":"2024-05-05T12:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/"},"modified":"2024-05-05T05:03:46","modified_gmt":"2024-05-05T12:03:46","slug":"batalla-puebla-del-cinco-de-mayo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","title":{"rendered":"Batalla de Puebla: la verdadera historia del Cinco de Mayo"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Cinco de Mayo es una fecha muy importante en Estados Unidos, en especial en las zonas fronterizas con M\u00e9xico. Los olores de los platos tradicionales, el sonido de las rancheras y los colores envuelven las ciudades de una manera \u00fanica, pero \u2014a pesar de lo que muchos estadounidenses piensan\u2014 el 5 de mayo no es el D\u00eda de la Independencia del pa\u00eds, sino que en esta fecha se conmemora la Batalla de Puebla. Aqu\u00ed, te explicamos la verdadera historia del Cinco de Mayo.<\/p>\n<p>\u00bfQu\u00e9 pas\u00f3 en la Batalla de Puebla el 5 de mayo?<\/p>\n<p>Entre los a\u00f1os 1858 y 1861 se libr\u00f3 la Guerra de Reforma, un enfrentamiento entre conservadores y liberales que dej\u00f3 al pa\u00eds sumido en una gran crisis econ\u00f3mica, como lo registra la Comisi\u00f3n Nacional de los Derecho Humanos de M\u00e9xico.<\/p>\n<p>La falta de capital llev\u00f3 al entonces presidente Benito Ju\u00e1rez a solicitar un plazo de dos a\u00f1os para pagar las deudas que ten\u00eda con Espa\u00f1a, Inglaterra y Francia.<\/p>\n<p>Ante este panorama, los tres pa\u00edses europeos decidieron unirse para enviar tropas a M\u00e9xico y buscar su dinero a la fuerza. Para la suerte de Ju\u00e1rez, esto nunca lleg\u00f3 a pasar, pues M\u00e9xico se comprometi\u00f3, mediante los Tratados de La Soledad, a realizar los pagos pendientes y Espa\u00f1a e Inglaterra retiraron sus tropas.<\/p>\n<p>Happy Cinco de Mayo: \u00bfQu\u00e9 se celebra este d\u00eda y cu\u00e1l es su origen?<\/p>\n<p>Sin embargo, Francia rompi\u00f3 el acuerdo y el 5 de mayo de 1862 empez\u00f3 una invasi\u00f3n armada a las afueras de Puebla.<\/p>\n<p>El ej\u00e9rcito mexicano estaba liderado por el general Ignacio Zaragoza y contaba con solo 5.000 hombres, entre ellos ind\u00edgenas y voluntarios sin entrenamiento, seg\u00fan consigna la CNDH con datos de los documentos de la Secretar\u00eda de Defensa Nacional. Por su parte, las tropas francesas, dirigidas por el conde de Lorencez, los superaban no solo en n\u00famero, con unos 6.000 soldados, sino tambi\u00e9n en experiencia y armamento.<\/p>\n<p>A pesar de que todo apuntaba a que las tropas enviadas por Napoleon III iban a triunfar, el ej\u00e9rcito mexicano se impuso con coraje y valent\u00eda, lo que los llev\u00f3 a cantar victoria aquel 5 de mayo de 1862.<\/p>\n<p>Durante el conflicto b\u00e9lico el general Zaragoza le envi\u00f3 telegramas al presidente Benito Ju\u00e1rez. El \u00faltimo calculaba entre 600 y 700 franceses muertos y heridos, mientras que en las tropas mexicanas cayeron alrededor de 400 soldados.<\/p>\n<p>A pesar de que un a\u00f1o despu\u00e9s los franceses tomaron M\u00e9xico y establecieron un imperio breve en el que rein\u00f3 el emperador Maximiliano, la Batalla de Puebla fue un importante triunfo que reivindic\u00f3 la independencia del pa\u00eds a la vez que despert\u00f3 sentimientos de valent\u00eda y patriotismo en todos los mexicanos.<\/p>\n<p>Con informaci\u00f3n de Todd Leopold<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Cinco de Mayo es una fecha muy importante en Estados Unidos, en especial en las zonas fronterizas con M\u00e9xico. Los olores de los platos tradicionales, el sonido de las rancheras y los colores envuelven las ciudades de una manera \u00fanica, pero \u2014a pesar de lo que muchos estadounidenses piensan\u2014 el 5 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448890","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Cinco de Mayo es una fecha muy importante en Estados Unidos, en especial en las zonas fronterizas con M\u00e9xico. Los olores de los platos tradicionales, el sonido de las rancheras y los colores envuelven las ciudades de una manera \u00fanica, pero \u2014a pesar de lo que muchos estadounidenses piensan\u2014 el 5 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T12:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Batalla de Puebla: la verdadera historia del Cinco de Mayo\",\"datePublished\":\"2024-05-05T12:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\",\"name\":\"Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-05T12:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Batalla de Puebla: la verdadera historia del Cinco de Mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Cinco de Mayo es una fecha muy importante en Estados Unidos, en especial en las zonas fronterizas con M\u00e9xico. Los olores de los platos tradicionales, el sonido de las rancheras y los colores envuelven las ciudades de una manera \u00fanica, pero \u2014a pesar de lo que muchos estadounidenses piensan\u2014 el 5 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-05T12:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/"},"author":{"name":"","@id":""},"headline":"Batalla de Puebla: la verdadera historia del Cinco de Mayo","datePublished":"2024-05-05T12:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","name":"Batalla de Puebla: la verdadera historia del Cinco de Mayo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-05T12:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Batalla de Puebla: la verdadera historia del Cinco de Mayo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Batalla de Puebla: la verdadera historia del Cinco de Mayo","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/05\/batalla-puebla-del-cinco-de-mayo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-05T12:03:46Z","datePublished":"2024-05-05T12:03:46Z","dateModified":"2024-05-05T12:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Batalla de Puebla: la verdadera historia del Cinco de Mayo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/05\\\/batalla-puebla-del-cinco-de-mayo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/05\\\/batalla-puebla-del-cinco-de-mayo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-05T12:03:46Z\",\"datePublished\":\"2024-05-05T12:03:46Z\",\"dateModified\":\"2024-05-05T12:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461990,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/05\/batalla-de-puebla-5-de-mayo-historia-orix\/","url_meta":{"origin":1448890,"position":0},"title":"Batalla de Puebla: la verdadera historia del Cinco de Mayo","author":"","date":"mayo 5, 2025","format":false,"excerpt":"El Cinco de Mayo es una fecha muy importante en Estados Unidos, en especial en las zonas fronterizas con M\u00e9xico. Los olores de los platos tradicionales, el sonido de las rancheras y los colores envuelven las ciudades de una manera \u00fanica, pero \u2014a pesar de lo que muchos estadounidenses piensan\u2014\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448891,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/05\/cinco-de-mayo-origen-trax\/","url_meta":{"origin":1448890,"position":1},"title":"Happy Cinco de Mayo: \u00bfqu\u00e9 se celebra este d\u00eda y cu\u00e1l es su origen?","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) \u2014 Guacamole y fajitas; banderas de M\u00e9xico y mariachi; margaritas, cerveza y\u2026 m\u00e1s cerveza. En Estados Unidos la fiesta mexicana por excelencia es el Cinco de Mayo.En M\u00e9xico tambi\u00e9n se conmemora esa fecha, pero los tributos locales palidecen al lado de la enorme celebraci\u00f3n que se lleva a cabo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473778,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/05\/04\/cinco-de-mayo-origen-orix\/","url_meta":{"origin":1448890,"position":2},"title":"Cinco de Mayo: \u00bfqu\u00e9 se celebra este d\u00eda y cu\u00e1l es su origen?","author":"","date":"mayo 4, 2026","format":false,"excerpt":"Guacamole y fajitas; banderas de M\u00e9xico y mariachi; margaritas, cerveza y\u2026 m\u00e1s cerveza. En Estados Unidos la fiesta mexicana por excelencia es el Cinco de Mayo.En M\u00e9xico tambi\u00e9n se conmemora esa fecha, pero los tributos locales palidecen al lado de la enorme celebraci\u00f3n que se lleva a cabo en Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461985,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/05\/5-de-mayo-celebracion-origen-trax\/","url_meta":{"origin":1448890,"position":3},"title":"Cinco de Mayo: \u00bfqu\u00e9 se celebra este d\u00eda y cu\u00e1l es su origen?","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Guacamole y fajitas; banderas de M\u00e9xico y mariachi; margaritas, cerveza y\u2026 m\u00e1s cerveza. En Estados Unidos la fiesta mexicana por excelencia es el Cinco de Mayo.En M\u00e9xico tambi\u00e9n se conmemora esa fecha, pero los tributos locales palidecen al lado de la enorme celebraci\u00f3n que se lleva a cabo en Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473797,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/05\/05\/5-cosas-5-de-mayo-orix\/","url_meta":{"origin":1448890,"position":4},"title":"Las 5 cosas que debes saber este 5 de mayo","author":"","date":"mayo 5, 2026","format":false,"excerpt":"El trabalenguas de Trump con Cuba. El Chapo Guzm\u00e1n pide su extradici\u00f3n a M\u00e9xico. \u00bfQu\u00e9 es el hantavirus? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5 cosas de CNNLas Fuerzas Armadas estadounidenses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461100,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/04\/11\/cancelan-desfile-cinco-de-mayo-chicago-deportaciones-trax\/","url_meta":{"origin":1448890,"position":5},"title":"Organizadores cancelan desfile del Cinco de Mayo en Chicago por temor a deportaciones y dicen que no hay &#171;nada que celebrar&#187;","author":"","date":"abril 11, 2025","format":false,"excerpt":"El desfile y las festividades anuales del Cinco de Mayo en Chicago fueron cancelados en medio de temores en la comunidad mexicana sobre las deportaciones por parte de la administraci\u00f3n Trump, dijeron los organizadores.\u201cNuestra comunidad est\u00e1 muy asustada por las redadas y la amenaza que ICE ha impuesto a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448890"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448890\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}