{"id":1448944,"date":"2024-05-06T14:03:38","date_gmt":"2024-05-06T21:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/"},"modified":"2024-05-06T14:03:38","modified_gmt":"2024-05-06T21:03:38","slug":"estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","title":{"rendered":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El Departamento de Estado de Estados Unidos anunci\u00f3 este lunes que ha impuesto restricciones de visa a ejecutivos de varias empresas mar\u00edtimas colombianas a las que se\u00f1al\u00f3 de estar utilizando sus compa\u00f1\u00edas para transportar a inmigrantes a ese pa\u00eds.<\/p>\n<p>En un comunicado que no identifica a las empresas ni a los ejecutivos sancionados, el Departamento de Estado se\u00f1al\u00f3 que esas navieras supuestamente realizan estas operaciones con pleno conocimiento de que exponen a los migrantes a la explotaci\u00f3n y violencia.<\/p>\n<p>El Departamento se\u00f1al\u00f3 que esta pol\u00edtica de sanciones en visas va dirigida a ejecutivos de empresas que proveen transporte por tierra, por mar o en vuelos privados para la migraci\u00f3n irregular. Se inici\u00f3 en noviembre pasado, con ejecutivos de compa\u00f1\u00edas que fletaban vuelos desde Nicaragua.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El Departamento de Estado de Estados Unidos anunci\u00f3 este lunes que ha impuesto restricciones de visa a ejecutivos de varias empresas mar\u00edtimas colombianas a las que se\u00f1al\u00f3 de estar utilizando sus compa\u00f1\u00edas para transportar a inmigrantes a ese pa\u00eds. En un comunicado que no identifica a las empresas ni a los ejecutivos sancionados, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448944","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0El Departamento de Estado de Estados Unidos anunci\u00f3 este lunes que ha impuesto restricciones de visa a ejecutivos de varias empresas mar\u00edtimas colombianas a las que se\u00f1al\u00f3 de estar utilizando sus compa\u00f1\u00edas para transportar a inmigrantes a ese pa\u00eds. En un comunicado que no identifica a las empresas ni a los ejecutivos sancionados, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T21:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes\",\"datePublished\":\"2024-05-06T21:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\"},\"wordCount\":170,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\",\"name\":\"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-06T21:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0El Departamento de Estado de Estados Unidos anunci\u00f3 este lunes que ha impuesto restricciones de visa a ejecutivos de varias empresas mar\u00edtimas colombianas a las que se\u00f1al\u00f3 de estar utilizando sus compa\u00f1\u00edas para transportar a inmigrantes a ese pa\u00eds. En un comunicado que no identifica a las empresas ni a los ejecutivos sancionados, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-06T21:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes","datePublished":"2024-05-06T21:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/"},"wordCount":170,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","name":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-06T21:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-06T21:03:38Z","datePublished":"2024-05-06T21:03:38Z","dateModified":"2024-05-06T21:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. anuncia sanciones a ejecutivos de empresas mar\\u00edtimas colombianas por presunto transporte de migrantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/06\\\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/06\\\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-06T21:03:38Z\",\"datePublished\":\"2024-05-06T21:03:38Z\",\"dateModified\":\"2024-05-06T21:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456508,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/12\/ejecutivos-miedo-tras-asesinato-ceo-unitedhealthcare-trax\/","url_meta":{"origin":1448944,"position":0},"title":"Los altos ejecutivos tienen miedo tras el asesinato del CEO de UnitedHealthcare","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Las corporaciones se esfuerzan por proteger a sus altos ejecutivos mientras la Polic\u00eda advierte de una amenaza creciente a corto plazo contra los l\u00edderes empresariales. Los consejos directivos est\u00e1n reevaluando los presupuestos de seguridad y se les est\u00e1 pidiendo a los CEO que borren sus huellas digitales.El sorprendente asesinato del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469888,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/08\/funcionarios-trump-convencer-legisladores-ejecutivos-petroleros-trax\/","url_meta":{"origin":1448944,"position":1},"title":"Funcionarios de Trump se apresuran a convencer a legisladores y ejecutivos petroleros esc\u00e9pticos sobre el plan para Venezuela","author":"","date":"enero 8, 2026","format":false,"excerpt":"Los funcionarios de la administraci\u00f3n Trump comenzaron este mi\u00e9rcoles a delinear una estrategia improvisada para tomar el control indefinido de las ventas de petr\u00f3leo de Venezuela, mientras se apresuran a mantener la estabilidad dentro de la naci\u00f3n despu\u00e9s de derrocar a Nicol\u00e1s Maduro.El ambicioso plan de varias partes se centra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457032,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/27\/corporaciones-maxima-alerta-clientes-enojados-trax\/","url_meta":{"origin":1448944,"position":2},"title":"Las corporaciones estadounidenses nunca han sido populares, pero ahora est\u00e1n en alerta m\u00e1xima ante clientes enojados","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"Tres semanas despu\u00e9s del asesinato del CEO de UnitedHealthcare, Brian Thompson, las empresas y los ejecutivos est\u00e1n monitoreando de cerca las amenazas de los clientes y reforzando sus vulnerabilidades de seguridad.Un hombre de Texas fue arrestado este viernes por presuntamente amenazar a ejecutivos de Capital One por correo electr\u00f3nico, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456484,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/11\/directivos-empresas-temen-seguridad-asesinato-ceo-trax\/","url_meta":{"origin":1448944,"position":3},"title":"Altos ejecutivos de corporaciones aumentan su seguridad tras asesinato de CEO de UnitedHealthcare","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Las empresas luchan para garantizar la protecci\u00f3n de sus altos ejecutivos mientras la polic\u00eda advierte de una amenaza a corto plazo contra los l\u00edderes empresariales. Los consejos de administraci\u00f3n est\u00e1n reevaluando los presupuestos de seguridad. Y se est\u00e1 pidiendo a los CEO que borren sus huellas digitales.El sorprendente asesinato del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467874,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","url_meta":{"origin":1448944,"position":4},"title":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds","author":"","date":"octubre 30, 2025","format":false,"excerpt":"El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a un grupo delictivo con sede en Canc\u00fan, uno de los principales centros tur\u00edsticos de M\u00e9xico, desde donde presuntamente se dedica a traficar migrantes indocumentados desde varias partes del mundo hacia territorio estadounidense.Mediante un comunicado, el Departamento identific\u00f3 a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456301,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","url_meta":{"origin":1448944,"position":5},"title":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"El CEO de UnitedHealthcare, Brian Thompson, ten\u00eda asignado un equipo de seguridad interno durante su viaje a la ciudad de Nueva York, de acuerdo con una fuente familiarizada con la seguridad de la compa\u00f1\u00eda, pero el equipo no estaba con \u00e9l cuando fue asesinado a tiros frente a un hotel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1448944"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1448944\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1448944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1448944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1448944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}