{"id":1449197,"date":"2024-05-07T18:03:50","date_gmt":"2024-05-08T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/"},"modified":"2024-05-07T18:03:50","modified_gmt":"2024-05-08T01:03:50","slug":"boy-scouts-america-nombre-scouting-america-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","title":{"rendered":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d"},"content":{"rendered":"<p>(CNN) &#8212; Boy Scouts of America (BSA) anunci\u00f3 el martes que cambiar\u00e1 su nombre a Scouting America el pr\u00f3ximo mes de febrero, para enfatizar su compromiso con la inclusi\u00f3n.<\/p>\n<p>La organizaci\u00f3n juvenil dijo que el nuevo nombre tiene como objetivo ayudar a que todos, incluidos ni\u00f1os y ni\u00f1as, se sientan bienvenidos. El cambio entrar\u00e1 en vigor el 8 de febrero de 2025, d\u00eda del 115\u00ba aniversario de la organizaci\u00f3n, dijeron los Boy Scouts of America.<\/p>\n<p>Los Boy Scouts de EE.UU. pagar\u00e1n US$ 850 millones por denuncias de abuso sexual<\/p>\n<p>&#171;Si bien esto puede ser una sorpresa para algunos de ustedes, para nosotros es una evoluci\u00f3n sencilla y el siguiente paso natural para garantizar que todos los j\u00f3venes estadounidenses se sientan bienvenidos y reconocidos en una organizaci\u00f3n que est\u00e1 destinada a servir a todos los estadounidenses&#187;, dijo Roger A. Krone a los periodistas durante una conferencia de prensa este martes.<\/p>\n<p>Krone dijo que el cambio de nombre no cambiar\u00e1 la misi\u00f3n de la organizaci\u00f3n de preparar \u201ca los j\u00f3venes a lo largo de sus vidas para tomar decisiones \u00e9ticas y morales inculcando el juramento scout y la ley scout\u201d.<\/p>\n<p>Las ni\u00f1as pudieron unirse por primera vez a los Cub Scouts, el programa de la organizaci\u00f3n para ni\u00f1os de 7 a 10 a\u00f1os, en 2018. Al a\u00f1o siguiente, la organizaci\u00f3n dio la bienvenida a j\u00f3venes de 11 a 17 a\u00f1os, a su programa insignia Scouts BSA, seg\u00fan inform\u00f3 anteriormente CNN.<\/p>\n<p>En ese momento, BSA dijo que la expansi\u00f3n del programa fue solicitada durante a\u00f1os y ten\u00eda como objetivo ayudar a las familias ocupadas a consolidar los programas para sus hijos.<\/p>\n<p>Krone dijo que cree que es hora de que la organizaci\u00f3n tenga un nombre que refleje mejor a los j\u00f3venes que actualmente est\u00e1n inscritos en sus programas. Dijo que casi el 20% de los miembros son ni\u00f1as o mujeres j\u00f3venes.<\/p>\n<p>Selby Chipman, una Eagle Scout inaugural que es asistente de Scoutmaster en Carolina del Norte, dijo durante la conferencia de prensa que una de las mejores cosas que obtuvo del programa fueron habilidades de liderazgo.<\/p>\n<p>Dijo que espera que m\u00e1s ni\u00f1as y mujeres j\u00f3venes aprendan esas habilidades y se beneficien del programa como ella lo hizo.<\/p>\n<p>Seg\u00fan la organizaci\u00f3n, m\u00e1s de 1 mill\u00f3n de j\u00f3venes est\u00e1n actualmente inscritos en los programas ofrecidos por Boys Scouts of America, entre ellos 176.234 ni\u00f1as y mujeres j\u00f3venes. Hasta ahora, m\u00e1s de 6.000 ni\u00f1as y mujeres j\u00f3venes han obtenido el prestigioso rango de Eagle Scout, dijo BSA en un comunicado de prensa.<\/p>\n<p>Bob Brady, un abogado de Nueva Jersey que fund\u00f3 una tropa de ni\u00f1as Scouts BSA y se desempe\u00f1a como su Scoutmaster, dijo que algunas ni\u00f1as se unieron r\u00e1pidamente al programa cuando se expandi\u00f3 porque ten\u00edan hermanos varones que eran Eagle Scouts, pero es posible que la comunidad en general no est\u00e9 al tanto de los cambios.<\/p>\n<p>La lista de l\u00edderes de Boy Scouts acusados de abuso sexual tiene casi 3.000 nombres m\u00e1s que los conocidos anteriormente<\/p>\n<p>\u201cCinco a\u00f1os y medio despu\u00e9s de que empezamos, ves gente en la ciudad que nos ve marchando en un desfile, haciendo un proyecto de servicio y dicen: &#8216;\u00bfLas ni\u00f1as pueden ser Scouts? Se llama Boy Scouts&#8217;\u201d, dijo Brady en la conferencia de prensa. &#171;Se necesitan algunas explicaciones (&#8230;) as\u00ed que creo que esto ser\u00e1 fant\u00e1stico para ayudar con el reclutamiento y permitir que todos sepan el programa inclusivo en el que nos hemos convertido durante la \u00faltima d\u00e9cada&#187;.<\/p>\n<p>Desde entonces, las dos hijas de Brady han obtenido el rango de Eagle Scouts.<\/p>\n<p>\u201cNi\u00f1as, muchachos, no hay nada en el juramento scout ni en una ley que sea inherentemente masculina o inherentemente femenina y que se aplique en todos los \u00e1mbitos. A las j\u00f3venes de 2024 les gusta ir de campamento y hacer senderismo\u201d, dijo Brady. &#171;\u00bfSabes qu\u00e9? En los \u00faltimos cinco o seis a\u00f1os, m\u00e1s mam\u00e1s y mujeres me han dicho que desear\u00eda tener la oportunidad de estar en los exploradores cuando era ni\u00f1a&#187;.<\/p>\n<p>Los Boy Scouts of America se han enfrentado a una tormenta de controversia en los \u00faltimos a\u00f1os, incluidas acusaciones generalizadas de abuso sexual y mala conducta. La organizaci\u00f3n se declar\u00f3 en quiebra en 2020 despu\u00e9s de gastar m\u00e1s de US$ 150 millones para resolver demandas por abuso, inform\u00f3 anteriormente CNN.<\/p>\n<p>El a\u00f1o pasado, los Boy Scouts of America comenzaron a compensar a miles de v\u00edctimas de abuso sexual a trav\u00e9s de un Fondo de Compensaci\u00f3n para V\u00edctimas establecido por un tribunal. Se espera que el Trust pague US$ 2.400 millones a m\u00e1s de 82.000 v\u00edctimas de abusos, inform\u00f3 CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Boy Scouts of America (BSA) anunci\u00f3 el martes que cambiar\u00e1 su nombre a Scouting America el pr\u00f3ximo mes de febrero, para enfatizar su compromiso con la inclusi\u00f3n. La organizaci\u00f3n juvenil dijo que el nuevo nombre tiene como objetivo ayudar a que todos, incluidos ni\u00f1os y ni\u00f1as, se sientan bienvenidos. El cambio entrar\u00e1 en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449197","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Boy Scouts of America (BSA) anunci\u00f3 el martes que cambiar\u00e1 su nombre a Scouting America el pr\u00f3ximo mes de febrero, para enfatizar su compromiso con la inclusi\u00f3n. La organizaci\u00f3n juvenil dijo que el nuevo nombre tiene como objetivo ayudar a que todos, incluidos ni\u00f1os y ni\u00f1as, se sientan bienvenidos. El cambio entrar\u00e1 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d\",\"datePublished\":\"2024-05-08T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\"},\"wordCount\":837,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\",\"name\":\"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-08T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias","og_description":"(CNN) &#8212; Boy Scouts of America (BSA) anunci\u00f3 el martes que cambiar\u00e1 su nombre a Scouting America el pr\u00f3ximo mes de febrero, para enfatizar su compromiso con la inclusi\u00f3n. La organizaci\u00f3n juvenil dijo que el nuevo nombre tiene como objetivo ayudar a que todos, incluidos ni\u00f1os y ni\u00f1as, se sientan bienvenidos. El cambio entrar\u00e1 en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-08T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/"},"author":{"name":"","@id":""},"headline":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d","datePublished":"2024-05-08T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/"},"wordCount":837,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","name":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-08T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Boy Scouts of America cambiar\u00e1 su nombre a \u201cScouting America\u201d","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/07\/boy-scouts-america-nombre-scouting-america-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-08T01:03:50Z","datePublished":"2024-05-08T01:03:50Z","dateModified":"2024-05-08T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Boy Scouts of America cambiar\\u00e1 su nombre a \\u201cScouting America\\u201d\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/07\\\/boy-scouts-america-nombre-scouting-america-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/07\\\/boy-scouts-america-nombre-scouting-america-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-08T01:03:50Z\",\"datePublished\":\"2024-05-08T01:03:50Z\",\"dateModified\":\"2024-05-08T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457951,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/01\/28\/google-maps-golfo-de-mexico-por-el-golfo-de-america-trax\/","url_meta":{"origin":1449197,"position":0},"title":"Google Maps cambiar\u00e1 el nombre del Golfo de M\u00e9xico por el de &#171;Golfo de Am\u00e9rica&#187;","author":"","date":"enero 28, 2025","format":false,"excerpt":"Google est\u00e1 cumpliendo con el decreto del presidente Donald Trump, y anunci\u00f3 que cambi\u00f3 el nombre del Golfo de M\u00e9xico a \u201cGolfo de Am\u00e9rica\u201d. La modificaci\u00f3n aparecer\u00e1 en los pr\u00f3ximos d\u00edas en Google Maps.En una publicaci\u00f3n en X, Google explic\u00f3 que tiene una \u201cpr\u00e1ctica de larga data de aplicar cambios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1433196,"url":"https:\/\/noticiasya.com\/san-angelo\/2022\/10\/19\/chicas-exploradoras-del-noroeste-de-texas-recibio-regalo-millonario-de-mckenzie-scott\/","url_meta":{"origin":1449197,"position":1},"title":"Chicas Exploradoras del Noroeste de Texas recibi\u00f3 regalo millonario de Mckenzie Scott","author":"agomez","date":"octubre 19, 2022","format":false,"excerpt":"Scott le obsequi\u00f3 a la organizaci\u00f3n $3.8 millones de d\u00f3lares para fortalecer la misi\u00f3n de GSNETX.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450521,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/19\/feid-inauguracion-copa-america-2024-orix\/","url_meta":{"origin":1449197,"position":2},"title":"Qui\u00e9n es Feid, el cantante que se presenta en la inauguraci\u00f3n de la Copa Am\u00e9rica 2024","author":"agomez","date":"junio 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El cantante colombiano Feid, tambi\u00e9n conocido como Ferxxo, ser\u00e1 el artista encargado de la ceremonia inaugural de la Copa Am\u00e9rica 2024, que se llevar\u00e1 a cabo este jueves 20 de junio a las 8 p.m. ET en Mercedes-Benz Stadium en Atlanta, Georgia.Hace un par de d\u00edas, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462182,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/09\/sheinbaum-demando-google-nombre-golfo-de-mexico-orix\/","url_meta":{"origin":1449197,"position":3},"title":"Sheinbaum dice que M\u00e9xico demand\u00f3 a Google por el cambio de nombre del Golfo de M\u00e9xico en su plataforma","author":"","date":"mayo 9, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, inform\u00f3 este viernes que su Gobierno demand\u00f3 a Google por el cambio de nombre del Golfo de M\u00e9xico en su plataforma Maps.\u201cEst\u00e1, ya, demandado. Ya hubo una primera resoluci\u00f3n y se est\u00e1 esperando\u201d, dijo la mandataria en respuesta a una pregunta de una reportera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470628,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/29\/serie-caribe-2026-equipos-formato-orix\/","url_meta":{"origin":1449197,"position":4},"title":"Serie del Caribe 2026: equipos, formato y c\u00f3mo verla por TV e internet en todo el mundo","author":"","date":"enero 29, 2026","format":false,"excerpt":"La edici\u00f3n n\u00famero 68 de la Serie del Caribe comenzar\u00e1 este domingo 1 de febrero en el Estadio Panamericano de Guadalajara, con los representativos campeones de Puerto Rico, Rep\u00fablica Dominicana y M\u00e9xico, as\u00ed como el subcampe\u00f3n mexicano y el ganador de la liga de Panam\u00e1, compitiendo por ser el mejor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458698,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/13\/sheinbaum-demanda-google-golfo-america-orix\/","url_meta":{"origin":1449197,"position":5},"title":"Sheinbaum amenaza con demandar a Google por poner &#171;golfo de Am\u00e9rica&#187; en sus mapas","author":"","date":"febrero 13, 2025","format":false,"excerpt":"Este jueves, la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 en su conferencia de prensa diaria que podr\u00eda demandar a Google luego de que la empresa cambiara en sus mapas el nombre del golfo de M\u00e9xico y pusiera \u2018golfo de Am\u00e9rica\u2019 en su lugar.La modificaci\u00f3n en la nomenclatura se hizo luego\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449197"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449197\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}