{"id":1449362,"date":"2024-05-09T19:03:45","date_gmt":"2024-05-10T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/"},"modified":"2024-05-09T19:03:45","modified_gmt":"2024-05-10T02:03:45","slug":"venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","title":{"rendered":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En un nuevo episodio de tensi\u00f3n entre Washington, Georgetown y Caracas, el ministro de la Defensa de Venezuela, Vladimir Padrino L\u00f3pez, consider\u00f3 como una amenaza contra la paz regional la presencia del portaaviones estadounidense USS George Washington en el Caribe y, con un mensaje en su cuenta de X, rechaz\u00f3 el anuncio de un despliegue de aviones F-18 para sobrevolar Georgetown y sus alrededores.<\/p>\n<p>A juicio de Padrino L\u00f3pez, se trata de \u201cprovocaciones\u201d del Comando Sur de EE.UU., auspiciadas por el gobierno de Guyana, que en su opini\u00f3n ha asumido el rol de \u201cnueva colonia estadounidense\u201d. Y advirti\u00f3 que el Sistema de Defensa Aeroespacial Integral de Venezuela permanecer\u00e1 activado ante cualquier intento de violaci\u00f3n del espacio geogr\u00e1fico venezolano.<\/p>\n<p>Mira las im\u00e1genes del Comando Central de EE.UU. de los F-18 despegando del portaaviones<\/p>\n<p>La reacci\u00f3n del ministro de la Defensa venezolano se da luego de que la embajada de EE.UU. en Guyana anunci\u00f3 para este jueves el sobrevuelo sobre Georgetown y zonas aleda\u00f1as de dos aviones F\/A 18F Super Hornets de la Marina estadounidense desde el portaaviones USS George Washington.<\/p>\n<p>La embajada en Georgetown inform\u00f3 adem\u00e1s que la directora de Estrategia, pol\u00edticas y planes del Comando Sur de EE.UU., la general de divisi\u00f3n Julie Nethercot, realiz\u00f3 una visita a Guyana entre el 6 y el 8 de mayo, durante la cual se reuni\u00f3 con el brigadier Omar Khan, jefe de gabinete de la Fuerza de Defensa de Guyana, para conversar en torno a las iniciativas de cooperaci\u00f3n y asistencia de seguridad en curso entre ambos pa\u00edses.<\/p>\n<p>El Comando Sur destac\u00f3 sus objetivos de apoyar a sus aliados para disuadir agresiones y fortalecer la capacidad de la regi\u00f3n para garantizar un Hemisferio Occidental seguro, libre y pr\u00f3spero.<\/p>\n<p>En el comunicado emitido en el marco de la segunda visita de Nethercot a Guyana se subraya la importancia continua y el compromiso inquebrantable que Estados Unidos otorga a la asociaci\u00f3n bilateral de defensa y seguridad entre Estados Unidos y Guyana.<\/p>\n<p>En el texto se se\u00f1ala tambi\u00e9n que Estados Unidos contin\u00faa trabajando estrechamente con sus socios en todo el mundo para fortalecer alianzas y asociaciones para profundizar, entre otras cosas, el intercambio de informaci\u00f3n, as\u00ed como realizando complejos ejercicios conjuntos y combinados.<\/p>\n<p>Venezuela y Guyana han sostenido cap\u00edtulos de tensi\u00f3n recientes en medio de un diferendo territorial hist\u00f3rico que se encuentra actualmente bajo la jurisdicci\u00f3n de la Corte Internacional de Justicia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En un nuevo episodio de tensi\u00f3n entre Washington, Georgetown y Caracas, el ministro de la Defensa de Venezuela, Vladimir Padrino L\u00f3pez, consider\u00f3 como una amenaza contra la paz regional la presencia del portaaviones estadounidense USS George Washington en el Caribe y, con un mensaje en su cuenta de X, rechaz\u00f3 el anuncio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449362","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; En un nuevo episodio de tensi\u00f3n entre Washington, Georgetown y Caracas, el ministro de la Defensa de Venezuela, Vladimir Padrino L\u00f3pez, consider\u00f3 como una amenaza contra la paz regional la presencia del portaaviones estadounidense USS George Washington en el Caribe y, con un mensaje en su cuenta de X, rechaz\u00f3 el anuncio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe\",\"datePublished\":\"2024-05-10T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\"},\"wordCount\":455,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\",\"name\":\"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-10T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; En un nuevo episodio de tensi\u00f3n entre Washington, Georgetown y Caracas, el ministro de la Defensa de Venezuela, Vladimir Padrino L\u00f3pez, consider\u00f3 como una amenaza contra la paz regional la presencia del portaaviones estadounidense USS George Washington en el Caribe y, con un mensaje en su cuenta de X, rechaz\u00f3 el anuncio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-10T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/"},"author":{"name":"","@id":""},"headline":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe","datePublished":"2024-05-10T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/"},"wordCount":455,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","name":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-10T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-10T02:03:45Z","datePublished":"2024-05-10T02:03:45Z","dateModified":"2024-05-10T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/09\\\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/09\\\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-10T02:03:45Z\",\"datePublished\":\"2024-05-10T02:03:45Z\",\"dateModified\":\"2024-05-10T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467779,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/27\/venezuela-denuncia-cia-plan-falsa-bandera-orix\/","url_meta":{"origin":1449362,"position":0},"title":"Venezuela dice que capturaron a presuntos &#171;mercenarios&#187; vinculados a la CIA y denuncia un plan de &#171;ataque de falsa bandera&#187;","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El Gobierno de Venezuela calific\u00f3 el domingo de \u201cprovocaci\u00f3n militar\u201d la llegada del destructor estadounidense USS Gravely a Trinidad y Tobago para realizar ejercicios militares durante varios d\u00edas, y asegur\u00f3 que capturaron \u201cmercenarios\u201d presuntamente ligados a la CIA que planeaban un \u201cataque de falsa bandera\u201d.En un comunicado difundido por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467710,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/24\/potencial-guerra-eeuu-caribe-portaaviones-orix\/","url_meta":{"origin":1449362,"position":1},"title":"Este es el potencial de guerra de EE.UU. en el Caribe tras el env\u00edo de un portaaviones nuclear en plena tensi\u00f3n con Venezuela","author":"","date":"octubre 24, 2025","format":false,"excerpt":"En una inusual demostraci\u00f3n de poder naval, en agosto Estados Unidos comenz\u00f3 el despliegue de numerosos buques de guerra, aeronaves de combate y personal militar en aguas de Am\u00e9rica Latina y el Caribe para \u2014seg\u00fan ha dicho Washington\u2014 combatir los c\u00e1rteles de la droga, dijeron funcionarios de Defensa a CNN.Entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468397,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/11\/16\/portaaviones-us-gerald-ford-caribe-tensiones-venezuela-trax\/","url_meta":{"origin":1449362,"position":2},"title":"El portaaviones m\u00e1s grande de EE.UU. llega al Caribe en medio de las tensiones con Venezuela","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El grupo de combate del portaaviones USS Gerald R. Ford entr\u00f3 al mar Caribe, seg\u00fan la Marina de Estados Unidos, colocando al portaaviones m\u00e1s grande del mundo en el centro de las crecientes tensiones en la regi\u00f3n.El grupo se uni\u00f3 a las fuerzas estadounidenses ya presentes en el Caribe como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467792,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/27\/maduro-suspende-acuerdos-gas-trinidad-tobago-orix\/","url_meta":{"origin":1449362,"position":3},"title":"Maduro suspende acuerdos de gas con Trinidad y Tobago por la presencia militar de EE.UU. en el pa\u00eds","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 este lunes la suspensi\u00f3n \u201cinmediata\u201d de todos los acuerdos en materia de gas con Trinidad y Tobago, tras calificar como una \u201camenaza\u201d las declaraciones y acciones del Gobierno de la primera ministra Kamla Persad-Bissessar, a quien acus\u00f3 de convertir al pa\u00eds \u201cen el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465900,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/27\/padrino-despliegue-buques-aguas-territoriales-caribe-orix\/","url_meta":{"origin":1449362,"position":4},"title":"Venezuela anuncia despliegue de buques en aguas territoriales del Caribe","author":"","date":"agosto 27, 2025","format":false,"excerpt":"El ministro de Defensa de Venezuela, Vladimir Padrino L\u00f3pez, anunci\u00f3 este martes el despliegue de buques en aguas territoriales del Caribe como parte de un despliegue para combatir \u201cgrupos terroristas, armados, narcotraficantes\u201d, en medio de las tensiones entre Caracas y Washington y el despliegue de EE.UU. de naves y militares\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467062,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/02\/venezuela-aviones-combate-eeuu-caribe-trax\/","url_meta":{"origin":1449362,"position":5},"title":"Venezuela dice que cinco aviones de combate de EE.UU. volaron cerca de su costa en el Caribe","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Venezuela detect\u00f3 cinco aviones de combate de EE.UU. volando cerca de su costa sobre el Caribe, dijo este jueves el ministro de Defensa Vladimir Padrino L\u00f3pez, describiendo el incidente como una \u201cprovocaci\u00f3n\u201d de Washington.\u201cSon aviones de combate. Aviones de combate que el imperialismo estadounidense ha atrevido a acercarse a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449362"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449362\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}